{"id":61189,"date":"2016-03-03T10:18:59","date_gmt":"2016-03-03T09:18:59","guid":{"rendered":"http:\/\/e3mag.com\/?p=61189"},"modified":"2024-01-19T14:53:59","modified_gmt":"2024-01-19T13:53:59","slug":"sap-for-utilities-sur-hana","status":"publish","type":"post","link":"https:\/\/e3mag.com\/fr\/sap-for-utilities-on-hana\/","title":{"rendered":"SAP for Utilities sur Hana"},"content":{"rendered":"<p>En migrant son syst\u00e8me IS-U vers Hana, le client profite en outre de la strat\u00e9gie de licence progressive. Le gain de temps du c\u00f4t\u00e9 de la base de donn\u00e9es, le reporting et l'interaction \"en temps r\u00e9el\" font partie des principaux avantages du produit on Hana.<\/p>\n<p>Gisa pr\u00e9sentera \u00e9galement les r\u00e9sultats et les avantages de la migration r\u00e9ussie de SAP for Utilities on Hana lors du salon phare europ\u00e9en de cette ann\u00e9e pour le secteur de l'\u00e9nergie et de l'eau, E-World.<\/p>\n<p>L'entreprise pr\u00e9sentera \u00e9galement la d\u00e9termination de la valeur du client et de la probabilit\u00e9 de r\u00e9siliation en temps r\u00e9el en utilisant Hana. Ce service est particuli\u00e8rement int\u00e9ressant pour les services publics, car il permet de savoir, avec un taux de r\u00e9ussite de plus de 80 %, si un client a l'intention de r\u00e9silier son contrat prochainement.<\/p>\n<p>Sur cette base, les mesures de marketing peuvent \u00eatre cibl\u00e9es et non plus appliqu\u00e9es selon le principe co\u00fbteux de l'arrosoir. Une chose est s\u00fbre : les solutions SAP sans Hana n'existeront plus. Avec des id\u00e9es et un savoir-faire innovants, les possibilit\u00e9s offertes par le Big Data se transforment finalement en solutions pour plus d'affaires - notamment pour le secteur de l'\u00e9nergie.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les fournisseurs d'\u00e9nergie sont directement gagnants avec la migration vers SAP for Utilities on Hana. C'est ce que montrent les r\u00e9sultats du prestataire de services informatiques Gisa de Halle, qui vient de migrer avec succ\u00e8s un syst\u00e8me client IS-U vers SAP for Utilities on Hana.<\/p>","protected":false},"author":38,"featured_media":60767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[161,2,1596],"tags":[210,65],"coauthors":[19920],"class_list":["post-61189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-szene","category-sap-nachrichten","category-1596","tag-big-data","tag-hana","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",400,155,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-768x297.jpg",768,297,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-100x39.jpg",100,39,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-480x186.jpg",480,186,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-640x248.jpg",640,248,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-720x279.jpg",720,279,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-960x372.jpg",960,372,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2016-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Energieversorger gewinnen unmittelbar mit der Umstellung auf SAP for Utilities on Hana. Das zeigen die Ergebnisse des IT-Dienstleisters Gisa aus Halle, der jetzt ein IS-U-Kundensystem erfolgreich auf SAP for Utilities on Hana migriert hat.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/fr\/category\/szene\/\" rel=\"category tag\">Szene<\/a>, <a href=\"https:\/\/e3mag.com\/fr\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/fr\/category\/1602\/\" rel=\"category tag\">MAG 16-02<\/a>","author_info_v2":{"name":"Magazine E-3","url":"https:\/\/e3mag.com\/fr\/author\/e-3-magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/61189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/comments?post=61189"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/61189\/revisions"}],"predecessor-version":[{"id":138389,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/61189\/revisions\/138389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media\/60767"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media?parent=61189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/categories?post=61189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/tags?post=61189"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/coauthors?post=61189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}