{"id":164862,"date":"2026-07-15T10:00:00","date_gmt":"2026-07-15T08:00:00","guid":{"rendered":"https:\/\/e3mag.com\/?p=164862"},"modified":"2026-07-01T17:00:03","modified_gmt":"2026-07-01T15:00:03","slug":"agents-ki-dans-sap-avec-controle-des-risques","status":"publish","type":"post","link":"https:\/\/e3mag.com\/fr\/ki-agenten-in-sap-mit-risiko-check\/","title":{"rendered":"Agents IA dans SAP, avec \u00e9valuation des risques"},"content":{"rendered":"<p>SAP fait partie des pionniers dans le d\u00e9veloppement de solutions d'IA pour les entreprises. Ces technologies visent \u00e0 acc\u00e9l\u00e9rer, automatiser et faire \u00e9voluer les processus m\u00e9tier dans les domaines les plus divers. Il y a toutefois un b\u00e9mol de taille : les outils d\u2019IA natifs de SAP ne sont pleinement accessibles qu\u2019aux entreprises qui utilisent les derni\u00e8res versions du logiciel.<\/p>\n\n\n\n<p>La plupart des entreprises ne le font pas \u2013 et pour cause. Les syst\u00e8mes SAP se sont souvent d\u00e9velopp\u00e9s au fil des d\u00e9cennies et sont profond\u00e9ment int\u00e9gr\u00e9s aux processus m\u00e9tier. La mise \u00e0 jour de tous les environnements est donc une t\u00e2che particuli\u00e8rement complexe. Pour autant, les entreprises qui n\u2019envisagent pas de mise \u00e0 niveau pour le moment ne doivent pas pour autant renoncer \u00e0 l\u2019IA. Au lieu d\u2019utiliser les fonctionnalit\u00e9s d\u2019IA natives de SAP, elles peuvent d\u00e9velopper leurs propres agents d\u2019IA et les int\u00e9grer \u00e0 leur environnement SAP sous forme d\u2019extensions.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Agents IA : opportunit\u00e9s et risques<\/h2>\n\n\n\n<p>Cette approche ouvre de nouvelles perspectives, mais comporte \u00e9galement des d\u00e9fis. Le principal risque r\u00e9side dans le fait que les agents IA externes g\u00e9n\u00e8rent une dette technique suppl\u00e9mentaire et cr\u00e9ent des risques de gouvernance qui auraient \u00e9t\u00e9 plus faciles \u00e0 \u00e9viter avec des solutions SAP natives. Avec sa strat\u00e9gie \u00ab Clean Core \u00bb, SAP vise \u00e0 maintenir autant que possible les personnalisations sp\u00e9cifiques aux clients \u00e0 l\u2019\u00e9cart du c\u0153ur de la plateforme. Cela devrait faciliter la maintenance, l\u2019innovation et les mises \u00e0 niveau ult\u00e9rieures. Les entreprises qui int\u00e8grent profond\u00e9ment des agents tiers dans leurs syst\u00e8mes SAP courent toutefois le risque de contourner pr\u00e9cis\u00e9ment ce principe.<\/p>\n\n\n\n<p>\u00c0 long terme, cela pourrait avoir pour cons\u00e9quence que les futures mises \u00e0 niveau SAP deviennent encore plus complexes qu'auparavant. \u00c0 cela s\u2019ajoute le risque que les m\u00e9canismes de gouvernance, de conformit\u00e9, de s\u00e9curit\u00e9 et de protection des donn\u00e9es de SAP ne s\u2019int\u00e8grent pas sans heurts avec des agents externes, car leur architecture et leur fonctionnement ne sont pas enti\u00e8rement conformes aux sp\u00e9cifications de SAP. \u00c0 premi\u00e8re vue, le choix semble donc difficile : les entreprises doivent-elles d\u00e9ployer des agents d\u2019IA personnalis\u00e9s et accepter les risques qui y sont associ\u00e9s ? Ou devraient-elles renoncer aux avantages de l\u2019IA dans leur syst\u00e8me ERP afin d\u2019\u00e9viter la dette technique et les probl\u00e8mes de gouvernance ?<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Utiliser l'IA de mani\u00e8re contr\u00f4l\u00e9e<\/h2>\n\n\n\n<p>En r\u00e9alit\u00e9, il s'agit d'une fausse opposition. Les entreprises peuvent d\u00e9ployer des agents d'IA individuels dans SAP sans que les risques et la dette technique ne prennent des proportions d\u00e9mesur\u00e9es.<\/p>\n\n\n\n<p>La cl\u00e9 r\u00e9side dans ce qu'on appelle les \u00ab harnais IA \u00bb \u2013 c'est-\u00e0-dire des garde-fous et des m\u00e9canismes de contr\u00f4le qui s\u00e9curisent l'utilisation des agents IA au sein de SAP. Dans la pratique, cela se traduit g\u00e9n\u00e9ralement par une combinaison de fonctions natives de SAP et d'outils de contr\u00f4le suppl\u00e9mentaires propos\u00e9s par des \u00e9diteurs tiers. Il est ainsi possible, par exemple, d\u2019utiliser des politiques au sein de la SAP Business Technology Platform (BTP) pour restreindre de mani\u00e8re cibl\u00e9e l\u2019acc\u00e8s aux donn\u00e9es des agents d\u2019IA. Parall\u00e8lement, des solutions de gestion des identit\u00e9s et des acc\u00e8s propos\u00e9es par des hyperscalers tels que Microsoft Entra peuvent \u00eatre d\u00e9ploy\u00e9es pour enregistrer et authentifier ces agents.<\/p>\n\n\n\n<p>Il en r\u00e9sulte une architecture qui r\u00e9duit efficacement les risques li\u00e9s \u00e0 la gouvernance, sans cr\u00e9er de nouveaux fardeaux techniques.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La voie vers l'avenir<\/h2>\n\n\n\n<p>\u00c0 long terme, la modernisation de l'environnement SAP et l'utilisation des fonctionnalit\u00e9s d'IA natives du fournisseur restent la voie la plus judicieuse pour \u201e agentifier \u201c les processus m\u00e9tier de mani\u00e8re exhaustive. Tant que cette \u00e9tape ne sera pas encore envisageable pour de nombreuses entreprises, une approche pragmatique s\u2019impose toutefois : le recours \u00e0 des agents d\u2019IA individuels en combinaison avec la SAP Business Technology Platform. Les entreprises peuvent ainsi b\u00e9n\u00e9ficier d\u00e8s aujourd\u2019hui de fonctionnalit\u00e9s d\u2019IA modernes, sans pour autant n\u00e9gliger la s\u00e9curit\u00e9, la conformit\u00e9 et la gouvernance. (Source : Lemongrass)<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>SAP mise sur les agents IA et l'automatisation intelligente. Cependant, de nombreuses entreprises ne sont pas en mesure de mettre en \u0153uvre \u00e0 court terme les mises \u00e0 niveau syst\u00e8me n\u00e9cessaires \u00e0 cet effet. Gr\u00e2ce \u00e0 des concepts de gouvernance et de s\u00e9curit\u00e9 adapt\u00e9s, l'IA peut n\u00e9anmoins \u00eatre int\u00e9gr\u00e9e dans les environnements SAP existants.<\/p>","protected":false},"author":5848,"featured_media":164924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[4,44495],"tags":[957,44515,39,601,44514,73,8689,65,369,44326,624,4230,517,236],"coauthors":[44522],"class_list":["post-164862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-26-07","tag-bw4","tag-cli","tag-cloud","tag-digitalisierung","tag-editor","tag-erp","tag-governance","tag-hana","tag-it","tag-ki-agent","tag-ki-joule","tag-risk-management","tag-s4","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/07\/2607_bu_lemongrass-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP treibt KI-Agenten und intelligente Automatisierung voran. Doch viele Unternehmen k\u00f6nnen die daf\u00fcr erforderlichen System-Upgrades nicht kurzfristig umsetzen. Mit geeigneten Governance- und Sicherheitskonzepten l\u00e4sst sich KI dennoch in bestehende SAP-Landschaften integrieren.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/fr\/category\/management\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e3mag.com\/fr\/category\/mag-26-07\/\" rel=\"category tag\">MAG 26-07<\/a>","author_info_v2":{"name":"Eamonn O\u2019Neill, Lemongrass","url":"https:\/\/e3mag.com\/fr\/author\/eamonn-oneill\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/164862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/users\/5848"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/comments?post=164862"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/164862\/revisions"}],"predecessor-version":[{"id":164869,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/164862\/revisions\/164869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media\/164924"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media?parent=164862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/categories?post=164862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/tags?post=164862"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/coauthors?post=164862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}