{"id":162598,"date":"2026-04-23T09:47:40","date_gmt":"2026-04-23T07:47:40","guid":{"rendered":"https:\/\/e3mag.com\/?p=162598"},"modified":"2026-05-08T12:27:19","modified_gmt":"2026-05-08T10:27:19","slug":"sap-custom-code-revisite","status":"publish","type":"post","link":"https:\/\/e3mag.com\/fr\/sap-custom-code-neu-gedacht\/","title":{"rendered":"Le code personnalis\u00e9 SAP repens\u00e9"},"content":{"rendered":"<p>Au fil des ann\u00e9es, de nombreux grands environnements syst\u00e8me SAP ont accumul\u00e9 un stock important de code personnalis\u00e9, souvent mal document\u00e9. Ce qui \u00e9tait \u00e0 l'origine utile pour couvrir rapidement les processus et combler les lacunes de SAP est aujourd'hui un h\u00e9ritage technique co\u00fbteux : dans les environnements ECC fortement individualis\u00e9s, jusqu'\u00e0 80% de la base de code est constitu\u00e9e d'extensions personnalis\u00e9es - dont 60 \u00e0 80% ne sont plus utilis\u00e9es, selon des enqu\u00eates men\u00e9es notamment par SAP.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Migration S\/4 incompl\u00e8tement r\u00e9solue<\/h2>\n\n\n\n<p>Nova Intelligence est une plateforme d'intelligence artificielle agentique sp\u00e9cialement d\u00e9velopp\u00e9e pour SAP. Compte tenu de l'\u00e9ch\u00e9ance de migration de 2030, la migration vers S\/4 fait actuellement partie des domaines d'application les plus urgents - et c'est l\u00e0 que Nova a \u00e9tabli avec Cleanfield une nouvelle m\u00e9thode de migration, rendue possible uniquement par la plateforme d'IA de Nova, qui se distingue du brownfield et du greenfield en empruntant une nouvelle voie tant dans la mise en \u0153uvre technique que dans les r\u00e9sultats commerciaux. Cleanfield combine les avantages pragmatiques d'une approche brownfield avec les avantages architecturaux d'une image cible greenfield. Le paysage existant n'est pas simplement repris ou rejet\u00e9 en bloc. Au lieu de cela, l'ancienne solution est syst\u00e9matiquement analys\u00e9e, la logique pertinente pour l'entreprise est reconstruite, le code personnalis\u00e9 inutile est syst\u00e9matiquement \u00e9limin\u00e9 et le standard SAP est utilis\u00e9 au maximum. Seule la partie r\u00e9ellement diff\u00e9renciante des extensions existantes sp\u00e9cifiques au client est reconstruite en conformit\u00e9 avec Clean Core dans une architecture cible S\/4 moderne. Le point central qui fait la diff\u00e9rence avec les migrations fortement bas\u00e9es sur le consulting et les personnes dans l'approche Brownfield et Greenfield r\u00e9side dans la structure des co\u00fbts : la plateforme Nova Intelligence est propos\u00e9e sur la base d'une redevance annuelle pour la plateforme, plus une composante Pro-Seat. Les frais d'utilisation sont ainsi d\u00e9coupl\u00e9s du nombre d'objets de code personnalis\u00e9 analys\u00e9s, modernis\u00e9s ou nouvellement d\u00e9velopp\u00e9s - en bref, plus l'utilisation est intensive, plus le retour sur investissement (ROI) est \u00e9lev\u00e9.<\/p>\n\n\n\n<p>Les premiers rapports d'exp\u00e9rience des clients de Nova Intelligence sont convaincants - m\u00eame au-del\u00e0 de la simple consid\u00e9ration du retour sur investissement. Ainsi, des clients rapportent des augmentations de productivit\u00e9 sp\u00e9cifiques aux t\u00e2ches d'un facteur 4 ou plus par rapport aux m\u00e9thodes traditionnelles. Des exemples pratiques concrets prouvent l'efficacit\u00e9 de la plateforme : chez Festo, l'utilisation de Nova Intelligence a permis des gains d'efficacit\u00e9 de 50 \u00e0 90 pour cent. Le groupe Kion a pu r\u00e9duire le temps d'ex\u00e9cution du syst\u00e8me des applications Abap nettoy\u00e9es de 25 minutes \u00e0 deux ou trois minutes et la phase d'analyse du code personnalis\u00e9 de une \u00e0 deux semaines \u00e0 deux \u00e0 quatre jours.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cas d'application Festo<\/h2>\n\n\n\n<p>Les premiers t\u00e9moignages des clients de Nova Intelligence sont convaincants. \u201eSi j'avais eu Nova Intelligence plus t\u00f4t, j'aurais fait les migrations S\/4 Hana diff\u00e9remment. Pour nous, ce sera probablement un gamechanger si les connaissances acquises lors de la preuve de concept se confirment dans l'utilisation ult\u00e9rieure\u201c, d\u00e9clare par exemple J\u00f6rn Weigle, CIO chez Festo. Festo, un fabricant plus que centenaire de techniques de commande et d'automatisation dont le si\u00e8ge se trouve \u00e0 Esslingen et qui emploie plus de 20 000 personnes dans plus de 60 pays et r\u00e9alise un chiffre d'affaires annuel d'environ 3,5 milliards d'euros, a migr\u00e9 vers S\/4 Hana depuis octobre 2024, en grande partie sans support externe, actuellement dans un mod\u00e8le de d\u00e9ploiement sur site. Dans le monde h\u00e9rit\u00e9, jusqu'\u00e0 140 000 objets et tables individuels se sont accumul\u00e9s au fil des ans. Selon le comptage de SAP, il y a eu 5800 modifications importantes pour le syst\u00e8me (SAP incluant ici par exemple de simples changements de couleur dans l'interface graphique) ; selon les comptages de Festo, il y a eu environ 1800 modifications de code importantes pour le syst\u00e8me.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_weigle_joern_festo.jpg\" alt=\"\" class=\"wp-image-162626\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_weigle_joern_festo.jpg 300w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_weigle_joern_festo-100x133.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_weigle_joern_festo-9x12.jpg 9w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><em>\"<em>Il n'y a pas eu de r\u00e9ticence de la part des d\u00e9veloppeurs impliqu\u00e9s, bien au contraire : l'\u00e9quipe est convaincue par la plateforme car elle lib\u00e8re des ressources pour d'autres t\u00e2ches urgentes.<\/em>\u201c<\/em><\/p>\n\n\n\n<p><strong>J\u00f6rn Weigle,&nbsp;<\/strong><br>CIO,<br>Festo<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Actuellement, quatre mises \u00e0 jour par an sont possibles dans cet environnement ; cela doit \u00eatre augment\u00e9 \u00e0 au moins dix mises \u00e0 jour par an, accompagn\u00e9es d'une automatisation plus intensive des tests. Pour ce faire, le code personnalis\u00e9 existant a \u00e9t\u00e9 analys\u00e9 au pr\u00e9alable avec Smart-shift, compar\u00e9 au standard SAP et optimis\u00e9 ponctuellement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e3mag.com\/de\/cc-summit\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1200x675.jpg\" alt=\"\" class=\"wp-image-163272\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1200x675.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-400x225.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-768x432.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-100x56.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-480x270.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-640x360.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-720x405.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-960x540.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1168x657.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1440x810.jpg 1440w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1536x864.jpg 1536w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-18x10.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-600x338.jpg 600w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<p>Festo utilise la plateforme Nova Intelligence depuis mi-2025. Un premier essai avec une modification moyennement complexe s'est av\u00e9r\u00e9 convaincant. Les d\u00e9veloppeurs SAP exp\u00e9riment\u00e9s de Festo ont estim\u00e9 que le traitement avec les outils utilis\u00e9s jusqu'\u00e0 pr\u00e9sent durerait environ cinq semaines. Au bout de deux semaines, la plateforme Nova Intelligence avait produit un code conforme au clean core, qui r\u00e9pondait en outre \u00e0 toutes les exigences de s\u00e9curit\u00e9 et de gouvernance. En fin de compte, on a gagn\u00e9 en rapidit\u00e9 et en qualit\u00e9. Festo estime le gain d'efficacit\u00e9 entre 50 et 90 pour cent. Depuis lors, l'entreprise s'efforce de re-facturer le code restant \u00e0 l'aide de Nova Intelligence. \u201eLa particularit\u00e9 de la plateforme Nova Intelligence est son orientation cons\u00e9quente vers SAP. L'\u00e9quipe de Nova Intelligence conna\u00eet l'architecture, la technologie et les interfaces SAP et combine ces connaissances avec l'excellence de la Silicon Valley en mati\u00e8re d'IA. Cela se traduit par la qualit\u00e9 et l'efficacit\u00e9 de la refacturation du code\u201c, ajoute Weigle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cas d'application Kion Group<\/h2>\n\n\n\n<p>Le groupe Kion confirme ces impressions positives. \u201eNous suivons une approche clean core claire avec une installation centrale de S\/4. Kion a migr\u00e9 vers S\/4 Hana selon une approche Greenfield et a r\u00e9organis\u00e9 et document\u00e9 en d\u00e9tail l'ensemble des processus dans le cadre de la transformation de l'entreprise\u201c, d\u00e9crit Carsten Engelbrecht.<\/p>\n\n\n\n<p>Le groupe Kion est un leader international dans le domaine des solutions intralogistiques, avec plus de 100 filiales \u00e0 l'\u00e9tranger et environ 42.000 employ\u00e9s. L'entreprise, issue de Linde, a r\u00e9alis\u00e9 en 2025 un chiffre d'affaires d'environ 11,3 milliards d'euros avec des marques telles que Linde, Still et Dematic. Le groupe a d\u00e9j\u00e0 r\u00e9organis\u00e9 l'ensemble de ses processus dans le cadre de la migration vers S\/4-Hana. Le nouvel environnement cible pr\u00e9voit un syst\u00e8me S\/4-Hana central pour toutes les succursales dans le monde entier, exploit\u00e9 selon le principe du clean core. Toutes les extensions n\u00e9cessaires et sp\u00e9cifiques \u00e0 Kion sont d\u00e9velopp\u00e9es et int\u00e9gr\u00e9es en dehors du noyau sur SAP BTP. En principe, aucun code personnalis\u00e9 n'a \u00e9t\u00e9 transf\u00e9r\u00e9 de l'environnement ECC du groupe Kion vers l'univers S\/4-Hana. Seuls des compl\u00e9ments s\u00e9lectionn\u00e9s, dont les services sp\u00e9cialis\u00e9s avaient un besoin urgent et qui ne pouvaient pas \u00eatre red\u00e9velopp\u00e9s \u00e0 temps en conformit\u00e9 avec Clean Core, ont \u00e9t\u00e9 repris.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_engelbrecht_carsten_kion.jpg\" alt=\"\" class=\"wp-image-162630\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_engelbrecht_carsten_kion.jpg 300w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_engelbrecht_carsten_kion-100x133.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/zitat_web_engelbrecht_carsten_kion-9x12.jpg 9w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><em>\"<em>Il y a deux exigences principales que nous avons mises en \u0153uvre avec la plateforme Nova Intelligence : exploiter de v\u00e9ritables syst\u00e8mes conformes au Clean Core et garantir un niveau de performance \u00e9lev\u00e9.<\/em>\u201c<\/em><\/p>\n\n\n\n<p><strong>Carsten Engelbrecht<\/strong>,<br>Vice-pr\u00e9sident ex\u00e9cutif (CIO),<br>Groupe Kion&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>La plateforme de Nova Intelligence n'a \u00e9t\u00e9 utilis\u00e9e qu'une fois la migration S\/4-Hana effectu\u00e9e, elle n'\u00e9tait pas disponible auparavant. L'application principale est d'optimiser le code existant et de r\u00e9duire la consommation parfois \u00e9lev\u00e9e de ressources syst\u00e8me. Par exemple, la dur\u00e9e d'ex\u00e9cution d'une application Abap pour le traitement global d'une commande de vente d'un v\u00e9hicule pouvait atteindre 25 minutes, selon la charge du syst\u00e8me. Gr\u00e2ce \u00e0 la plateforme Nova Intelligence, le temps d'ex\u00e9cution a pu \u00eatre r\u00e9duit \u00e0 deux ou trois minutes.<\/p>\n\n\n\n<p>De plus, la phase d'analyse du code h\u00e9rit\u00e9 a \u00e9t\u00e9 largement automatis\u00e9e. La plateforme Nova Intelligence saisit la logique d'ex\u00e9cution du code Abap et con\u00e7oit sur cette base un nouveau code conforme au Clean Core. Celui-ci est ensuite v\u00e9rifi\u00e9 par les d\u00e9veloppeurs de Kion et transmis au test. Selon la taille du code, les d\u00e9veloppeurs exp\u00e9riment\u00e9s ont g\u00e9n\u00e9ralement besoin d'une \u00e0 deux semaines pour effectuer de telles analyses de code. Avec la plateforme Nova Intelligence, ce temps est r\u00e9duit \u00e0 deux ou quatre jours, en fonction de la dur\u00e9e de la phase de test. \u201eNous pr\u00e9voyons de continuer \u00e0 utiliser Nova Intelligence dans le d\u00e9veloppement de logiciels, et nous attendons beaucoup des capacit\u00e9s d'anticipation de la plateforme dans la gestion des exigences\u201c, souligne Engelbrecht. \u201eHabituellement, la collecte des exigences prend jusqu'\u00e0 60% du temps dans les projets de d\u00e9veloppement, car les services et les d\u00e9veloppeurs ont une compr\u00e9hension diff\u00e9rente de la situation. Nous esp\u00e9rons pouvoir r\u00e9duire consid\u00e9rablement ce processus afin de d\u00e9charger davantage nos meilleurs d\u00e9veloppeurs. Mais dans ce domaine, nous n'en sommes encore qu'au d\u00e9but\u201c.\u201c<\/p>\n\n\n\n<p>L'approche Cleanfield bas\u00e9e sur la plateforme Nova Intelligence r\u00e9sout ainsi l'un des probl\u00e8mes les plus urgents que rencontrent presque tous les clients SAP, car elle ne s'adresse pas seulement \u00e0 la phase de migration, mais garantit, en tant que plateforme centr\u00e9e sur le cycle de vie, la conformit\u00e9 Clean Core durable et la comparaison permanente avec le standard SAP de tous les d\u00e9veloppements sp\u00e9cifiques du client.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Base de donn\u00e9es de connaissances personnalis\u00e9e<\/h2>\n\n\n\n<p>Une caract\u00e9ristique de diff\u00e9renciation particuli\u00e8re est l'extension continue de la base de donn\u00e9es de connaissances individuelle du client sur la base de l'utilisation de l'IA agentique. Cela permet d'augmenter consid\u00e9rablement la pr\u00e9cision des analyses et de soutenir des d\u00e9cisions architecturales mieux fond\u00e9es - un compl\u00e9ment unique, du point de vue de PAC, \u00e0 la rem\u00e9diation du code. Nova Intelligence devient ainsi un levier essentiel pour l'efficacit\u00e9 et la qualit\u00e9 tout au long du cycle de vie du code personnalis\u00e9 SAP.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Analyse du retour sur investissement par PAC<\/h2>\n\n\n\n<p>PAC a r\u00e9alis\u00e9 des analyses de retour sur investissement pour trois sc\u00e9narios d'utilisation diff\u00e9rents de la plateforme Nova Intelligence :<\/p>\n\n\n\n<p><strong>Sc\u00e9nario 1 : nettoyage du code pendant la migration vers S\/4-Hana :<\/strong> Le premier sc\u00e9nario concerne la majorit\u00e9 des clients actuels de SAP en Allemagne, c'est-\u00e0-dire tous ceux qui n'ont pas encore migr\u00e9 vers S\/4 Hana. Typiquement, l'ancien environnement ECC a subi de nombreuses modifications et le code personnalis\u00e9 est peu ou pas document\u00e9. Dans cet environnement, la plateforme Nova Intelligence analyse l'ensemble du code personnalis\u00e9 en termes de d\u00e9pendances et d'intensit\u00e9 d'utilisation. Il s'av\u00e8re g\u00e9n\u00e9ralement qu'une partie importante ne fournit plus de valeur commerciale pertinente ou peut d\u00e9j\u00e0 \u00eatre couverte par des fonctions SAP standard. Sur la base de cette analyse, le code est syst\u00e9matiquement \u00e9limin\u00e9 ou transf\u00e9r\u00e9 dans le standard S\/4-Hana. Ce n'est que l\u00e0 o\u00f9 une diff\u00e9renciation est n\u00e9cessaire que les modifications sont transf\u00e9r\u00e9es dans un code conforme \u00e0 Clean Core.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"665\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web.jpg\" alt=\"\" class=\"wp-image-162601\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-400x266.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-768x511.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-100x67.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-480x319.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-640x426.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-720x479.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-960x638.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-18x12.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie1_web-600x399.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Sc\u00e9nario 1 : nettoyage du code pendant la migration vers S\/4-Hana.<\/figcaption><\/figure>\n\n\n\n<p>Le r\u00e9sultat : un syst\u00e8me S\/4-Hana qui est d'embl\u00e9e l\u00e9ger, proche des standards et capable d'\u00eatre mis \u00e0 niveau - sans perdre les sp\u00e9cificit\u00e9s pertinentes pour l'entreprise. Notre analyse de retour sur investissement mod\u00e9lis\u00e9e pour ce processus montre que Nova Intelligence fournit un retour sur investissement clairement mesurable et significatif pour respectivement 1000, 10.000 et 100.000 objets de code personnalis\u00e9s, en r\u00e9duisant les efforts de transformation, en raccourcissant les temps de modernisation et en r\u00e9duisant consid\u00e9rablement les co\u00fbts de cycle de vie des paysages de code personnalis\u00e9s.<\/p>\n\n\n\n<p><br><strong>Sc\u00e9nario 2 : Modernisation du code dans l'environnement cible S\/4 apr\u00e8s la migration :<\/strong> Le deuxi\u00e8me cas d'application concerne les entreprises qui travaillent d\u00e9j\u00e0 sur SAP S\/4 Hana. Dans beaucoup de ces paysages, le code personnalis\u00e9 de l'\u00e9poque ECC a \u00e9t\u00e9 en grande partie migr\u00e9 techniquement. De plus, d'autres extensions voient le jour apr\u00e8s le go live de S\/4 Hana, afin de combler des lacunes fonctionnelles ou de mettre en \u0153uvre de nouvelles exigences, sans les aligner sur les exigences clean core de SAP ou les aligner sur le standard SAP. La plateforme Nova Intelligence cr\u00e9e une transparence sur l'ensemble du code personnalis\u00e9, ce qui permet d'obtenir une image diff\u00e9renci\u00e9e en rapport avec l'architecture cible du client. La plateforme traduit les objectifs strat\u00e9giques en priorit\u00e9s concr\u00e8tes : Quelles extensions peuvent \u00eatre tol\u00e9r\u00e9es, lesquelles doivent \u00eatre adapt\u00e9es \u00e0 moyen terme, lesquelles repr\u00e9sentent un risque et doivent imp\u00e9rativement \u00eatre red\u00e9velopp\u00e9es en conformit\u00e9 avec Clean Core ?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"695\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web.jpg\" alt=\"\" class=\"wp-image-162603\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-400x278.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-768x534.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-100x70.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-480x334.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-640x445.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-720x500.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-960x667.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-18x12.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie2_web-600x417.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Sc\u00e9nario 2 : Modernisation du code dans l'environnement cible S\/4 apr\u00e8s la migration.<\/figcaption><\/figure>\n\n\n\n<p>Les DSI et les responsables SAP peuvent ainsi g\u00e9rer activement leur stock de code personnalis\u00e9 au lieu de se contenter de r\u00e9agir aux probl\u00e8mes. Au fil du temps, le paysage peut \u00e9voluer de mani\u00e8re cibl\u00e9e vers une image cible plus stable et plus rentable. Dans notre analyse de retour sur investissement mod\u00e9lis\u00e9e, nous avons analys\u00e9 non seulement les conditions g\u00e9n\u00e9rales susmentionn\u00e9es, mais aussi les effets sur l'infrastructure informatique, par exemple en ce qui concerne la capacit\u00e9 des serveurs, la consommation d'\u00e9nergie et les co\u00fbts d'exploitation associ\u00e9s, afin de mettre en \u00e9vidence d'autres \u00e9conomies potentielles. Au final, nous avons calcul\u00e9 un retour sur investissement encore plus \u00e9lev\u00e9 pour respectivement 1000, 10 000 et 100 000 objets de code personnalis\u00e9s. L'analyse prouve que Nova Intelligence r\u00e9alise un retour sur investissement significatif en r\u00e9duisant consid\u00e9rablement les efforts de modernisation et les co\u00fbts du cycle de vie des environnements de code personnalis\u00e9.<\/p>\n\n\n\n<p><strong>Sc\u00e9nario 3 : D\u00e9veloppement continu de l'environnement S\/4-Hana :<\/strong> Id\u00e9alement, l'environnement S\/4-Hana atteint \u00e0 un moment donn\u00e9 un \u00e9tat o\u00f9 le code h\u00e9rit\u00e9 a \u00e9t\u00e9 compl\u00e8tement \u00e9limin\u00e9 ou nettoy\u00e9. Dans cet environnement, les extensions sont g\u00e9n\u00e9ralement formul\u00e9es par les services sp\u00e9cialis\u00e9s et mises en \u0153uvre par les d\u00e9veloppeurs de logiciels dans le cadre d'un processus it\u00e9ratif. Il en r\u00e9sulte de nombreux tours de concertation dans le processus de require-ment ainsi que les fr\u00e9quentes am\u00e9liorations fonctionnelles. Dans ce sc\u00e9nario, la plateforme Nova Intelligence couvre l'ensemble du cycle de vie du processus de d\u00e9veloppement logiciel. L'Agentic AI Platform g\u00e9n\u00e8re directement du code SAP dans les syst\u00e8mes SAP connect\u00e9s (principalement dans les syst\u00e8mes de d\u00e9veloppement SAP), teste ces d\u00e9veloppements et les transf\u00e8re ensuite dans les syst\u00e8mes d'AQ\/de test correspondants via le syst\u00e8me de transport SAP connect\u00e9. Une fois les tests termin\u00e9s, les extensions peuvent ensuite \u00eatre transf\u00e9r\u00e9es dans le syst\u00e8me de production SAP. L'exigence de la plate-forme n'est volontairement pas li\u00e9e \u00e0 un projet, mais plut\u00f4t au cycle de vie. Elle ne s'adresse pas seulement \u00e0 la transformation unique d'un syst\u00e8me, mais \u00e0 toutes les \u00e9tapes de travail qui se produisent pendant des ann\u00e9es lors du d\u00e9veloppement, de l'exploitation, de l'optimisation et de l'\u00e9volution d'un environnement SAP. L'analyse du retour sur investissement de PAC montre que Nova Intelligence g\u00e9n\u00e8re un retour sur investissement significatif pour respectivement 1000, 10 000 et 100 000 objets de code personnalis\u00e9s, en augmentant la productivit\u00e9 des d\u00e9veloppeurs, en r\u00e9duisant les cycles de d\u00e9veloppement et en optimisant durablement les co\u00fbts du cycle de vie \u00e0 long terme des solutions de code personnalis\u00e9. En raison de l'\u00e9conomie de la plateforme, la capacit\u00e9 de traitement \u00e9volue gr\u00e2ce \u00e0 la parall\u00e9lisation des agents. Ainsi, plus il y a d'objets de code personnalis\u00e9 \u00e0 g\u00e9n\u00e9rer, plus le retour sur investissement augmente de mani\u00e8re logarithmique.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"599\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web.jpg\" alt=\"\" class=\"wp-image-162604\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-400x240.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-768x460.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-100x60.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-480x288.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-640x383.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-720x431.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-960x575.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-18x12.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/Folie3_web-600x359.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Sc\u00e9nario 3 : d\u00e9veloppement continu de l'environnement S\/4.<\/figcaption><\/figure>\n\n\n\n<p>Dans l'ensemble, les analyses d\u00e9montrent une corr\u00e9lation significative entre le nombre d'objets de code personnalis\u00e9 \u00e0 moderniser ou \u00e0 d\u00e9velopper et le retour sur investissement obtenu par la plateforme Nova, ce qui est coh\u00e9rent avec son principal moteur de valeur, \u00e0 savoir la mise \u00e0 l'\u00e9chelle des gains d'efficacit\u00e9 dans la transformation et le d\u00e9veloppement de code.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Combinaison des sc\u00e9narios<\/h2>\n\n\n\n<p>Sur cette base, nous avons d\u00e9fini deux cas d'utilisation centraux qui combinent les sc\u00e9narios ci-dessus :<\/p>\n\n\n\n<p><strong>Premi\u00e8rement<\/strong> la combinaison de la modernisation du code personnalis\u00e9 dans le cadre d'une transformation d'ECC vers S\/4 et du red\u00e9veloppement parall\u00e8le du code personnalis\u00e9 avec la plateforme Nova Intelligence.<\/p>\n\n\n\n<p><strong>Deuxi\u00e8mement :<\/strong> la combinaison de la modernisation du code personnalis\u00e9 dans un environnement S\/4 existant, y compris des \u00e9conomies suppl\u00e9mentaires sur les co\u00fbts de mat\u00e9riel, d'\u00e9nergie et d'infrastructure, et le red\u00e9veloppement du code personnalis\u00e9, \u00e9galement soutenu par Nova Intelligence.<\/p>\n\n\n\n<p>Le regroupement de ces sc\u00e9narios dans l'analyse du retour sur investissement est justifi\u00e9 par la m\u00e9thode, \u00e9tant donn\u00e9 que le mod\u00e8le de prix de la plateforme est ind\u00e9pendant de l'utilisation et que les clients peuvent effectuer en parall\u00e8le aussi bien la modernisation que le d\u00e9veloppement sans frais suppl\u00e9mentaires. En supposant respectivement 1000, 10 000 ou 100 000 objets de code personnalis\u00e9 \u00e0 moderniser et 1000, 10 000 ou 100 000 nouveaux objets de code personnalis\u00e9 \u00e0 d\u00e9velopper, le mod\u00e8le de calcul donne pour les deux cas d'application un retour sur investissement d'environ 220 pour cent, 310 pour cent et 1400 pour cent pour respectivement 1000, 10 000 et 100 000 objets de code personnalis\u00e9, ce qui prouve clairement l'effet de levier \u00e9conomique consid\u00e9rable de la plateforme en cas d'augmentation de l'\u00e9chelle des volumes de code personnalis\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e3mag.com\/de\/cc-summit\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1200x675.jpg\" alt=\"\" class=\"wp-image-163272\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1200x675.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-400x225.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-768x432.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-100x56.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-480x270.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-640x360.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-720x405.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-960x540.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1168x657.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1440x810.jpg 1440w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-1536x864.jpg 1536w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-18x10.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080-600x338.jpg 600w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/e3_summit_2026_pop_up_1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-group\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-c6b4b7cd wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group has-background\" style=\"background-color:#f1e9f5;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--60)\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-5a3522f1 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Analyse du retour sur investissement par PAC<\/h2>\n\n\n\n<p><strong>Les analyses de retour sur investissement de PAC reposent sur les hypoth\u00e8ses suivantes :<\/strong><\/p>\n\n\n\n<p><strong>Co\u00fbts de la plate-forme :<\/strong> La plateforme est propos\u00e9e sur la base d'un abonnement annuel \u00e0 la plateforme, auquel s'ajoute une composante Pro-Seat. L'\u00e9chelonnement des performances ne se fait toutefois pas par le biais de comptes d'utilisateurs suppl\u00e9mentaires, mais en premier lieu par l'utilisation parall\u00e8le d'agents IA par utilisateur, qui peuvent traiter des t\u00e2ches au moins dix fois en m\u00eame temps. La capacit\u00e9 de traitement totale augmente ainsi de mani\u00e8re nettement plus efficace. En cons\u00e9quence, le nombre d'utilisateurs n'augmente que mod\u00e9r\u00e9ment, alors que m\u00eame de gros volumes de travail peuvent \u00eatre trait\u00e9s de mani\u00e8re fiable et efficace avec une base d'utilisateurs relativement petite.<\/p>\n\n\n\n<p><strong>Port\u00e9e :<\/strong> Les co\u00fbts de la modernisation ou du nouveau d\u00e9veloppement de 1000, 10.000 et 100.000 objets de code sp\u00e9cifiques au client ont \u00e9t\u00e9 respectivement compar\u00e9s avec et sans la plateforme Nova Intelligence. Dans la pratique, plusieurs objets sont souvent regroup\u00e9s dans le cadre de projets, par exemple pour prendre en charge un flux de travail.<\/p>\n\n\n\n<p><strong>Cat\u00e9gorisation :<\/strong> Chaque objet a \u00e9t\u00e9 class\u00e9 dans l'une des quatre cat\u00e9gories (d\u00e9saffectation, compatible, adaptation, nouveau d\u00e9veloppement).<\/p>\n\n\n\n<p><strong>Profil de complexit\u00e9 : <\/strong>Nous avons d\u00e9fini trois niveaux de complexit\u00e9 : simple (60 pour cent des modifications tombent sous ce seuil), moyen (32 pour cent) et complexe (8 pour cent).<\/p>\n\n\n\n<p><strong>Cadre temporel :<\/strong> L'analyse a pris en compte les co\u00fbts de modernisation, d'exploitation et de maintenance sur cinq ans.<\/p>\n\n\n\n<p><strong>Avantage financier :<\/strong> Les avantages financiers ont \u00e9t\u00e9 calcul\u00e9s en tant que valeur actuelle nette (Net Present Value) de toutes les \u00e9conomies r\u00e9alis\u00e9es.<\/p>\n\n\n\n<p><strong>l'efficacit\u00e9 :<\/strong> D'apr\u00e8s les discussions que nous avons eues avec nos clients, nous pensons que Nova Intelligence augmentera la proportion de codes faciles \u00e0 migrer ou \u00e0 d\u00e9classer, ce qui r\u00e9duira le co\u00fbt total de possession.&nbsp;&nbsp;<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Commentaire PAC<\/h2>\n\n\n\n<p>Le d\u00e9fi de concilier les besoins d'extension individuels avec les principes du Clean Core et de la proximit\u00e9 avec les standards accompagnera les entreprises \u00e0 long terme. Une plateforme moderne qui soutient la modernisation du code personnalis\u00e9 et la comparaison continue avec le standard SAP est donc essentielle. Nova Intelligence offre une solution convaincante \u00e0 cet \u00e9gard, en combinant un savoir-faire SAP approfondi avec une technologie Agentic-AI innovante, cr\u00e9ant ainsi une valeur ajout\u00e9e durable. Nos calculs de retour sur investissement d\u00e9montrent de mani\u00e8re impressionnante la valeur durable de la plateforme tout au long du cycle de vie du d\u00e9veloppement logiciel centr\u00e9 sur SAP. L'approche Cleanfield de la plateforme Nova Intelligence garantit que l'environnement cible S\/4 reste durablement conforme au Clean Core et au standard SAP. Une base essentielle est ainsi pos\u00e9e pour que l'environnement SAP reste ouvert \u00e0 long terme aux innovations futures bas\u00e9es sur l'IA et les agents.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/pdfs\/2605_magazin_online\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125.jpg\" alt=\"\" class=\"wp-image-162017\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/download_banner_D_1000x125-600x75.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<p>Vers l'inscription du partenaire :<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/partners\/pac-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/pac.jpg\" alt=\"\" class=\"wp-image-161555\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/pac.jpg 300w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/pac-100x50.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/pac-18x9.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Pour de nombreuses entreprises, le code personnalis\u00e9 SAP est devenu un facteur de co\u00fbts et un obstacle \u00e0 l'innovation. Il s'est d\u00e9velopp\u00e9 au fil des ann\u00e9es et bloque aujourd'hui la standardisation et le rythme. Dans le cadre de la transformation S\/4-Hana, l'occasion se pr\u00e9sente maintenant de red\u00e9finir le degr\u00e9 de personnalisation.<\/p>","protected":false},"author":2403,"featured_media":162614,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[44439,44440],"tags":[44086,73,517,236],"coauthors":[39721,44442],"class_list":["post-162598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-26-05","category-mag-26-05","tag-clean-core","tag-erp","tag-s4","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/04\/2605_cs_pac-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP Custom Code ist f\u00fcr viele Unternehmen zum Kostentreiber und Innovationshemmnis geworden. \u00dcber Jahre gewachsen, blockiert er heute Standardisierung und Tempo. Im Zuge der S\/4-Hana-Transformation bietet sich jetzt die Chance, den Grad der Individualisierung neu zu bestimmen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/fr\/category\/coverstorys\/coverstory-26-05\/\" rel=\"category tag\">Coverstory 26-05<\/a>, <a href=\"https:\/\/e3mag.com\/fr\/category\/mag-26-05\/\" rel=\"category tag\">MAG 26-05<\/a>","author_info_v2":{"name":"Joachim Hackmann, PAC","url":"https:\/\/e3mag.com\/fr\/author\/joachim-hackmann-pac\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/162598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/users\/2403"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/comments?post=162598"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/162598\/revisions"}],"predecessor-version":[{"id":163280,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/162598\/revisions\/163280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media\/162614"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media?parent=162598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/categories?post=162598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/tags?post=162598"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/coauthors?post=162598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}