{"id":140511,"date":"2024-03-15T07:00:00","date_gmt":"2024-03-15T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=140511"},"modified":"2024-03-13T10:36:00","modified_gmt":"2024-03-13T09:36:00","slug":"conseil-de-lecture-sap-sur-hyperscaler","status":"publish","type":"post","link":"https:\/\/e3mag.com\/fr\/buchtipp-sap-auf-hyperscaler\/","title":{"rendered":"Livre conseill\u00e9 : SAP sur hyperscaler"},"content":{"rendered":"<p>Le cloud est devenu incontournable dans toute entreprise. De nombreuses entreprises sont pass\u00e9es au cloud il y a des ann\u00e9es d\u00e9j\u00e0 avec leurs premi\u00e8res applications ou applications, ou ont reli\u00e9 des applications cloud \u00e0 leurs applications existantes.<\/p>\n\n\n\n<p>L'\u00e9poque o\u00f9 les syst\u00e8mes SAP \u00e9taient install\u00e9s sur site est r\u00e9volue depuis longtemps. De moins en moins d'entreprises ont leur propre centre de donn\u00e9es. Souvent, les syst\u00e8mes sont d\u00e9j\u00e0 entretenus dans des centres de donn\u00e9es centraux ou sont d\u00e9j\u00e0 partiellement install\u00e9s dans un cloud.\u00a0<\/p>\n\n\n\n<p>L'avantage est \u00e9vident : le mat\u00e9riel informatique est rarement achet\u00e9 pour plusieurs ann\u00e9es avant d'\u00eatre amorti. Il est beaucoup plus important de pouvoir r\u00e9agir rapidement et de mani\u00e8re flexible aux exigences de son entreprise et de ses clients et de pouvoir modifier la taille des serveurs en cons\u00e9quence, que ceux-ci soient plus grands ou plus petits. Cela apporte d'une part une grande transparence des co\u00fbts et une influence sur les co\u00fbts d'exploitation actuels, l'\u00e9poque des syst\u00e8mes surdimensionn\u00e9s uniquement au cas o\u00f9 est r\u00e9volue.<\/p>\n\n\n\n\n\n\n\n\n\n\n\n<p>D'autre part, le th\u00e8me de la durabilit\u00e9 devient de plus en plus important, ce qui implique une migration vers le cloud et l'arr\u00eat du propre centre de donn\u00e9es ou des propres serveurs d\u00e9j\u00e0 dans le cadre des installations diesel ou des batteries mises \u00e0 disposition pour le sc\u00e9nario d'urgence en cas d'\u00e9ventuelle panne de courant.&nbsp;<\/p>\n\n\n\n<p>Malheureusement, il est rare de savoir par o\u00f9 commencer sur ce sujet et comment aborder au mieux le th\u00e8me du cloud et de la migration vers le cloud de mani\u00e8re cibl\u00e9e et structur\u00e9e.\u00a0<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rheinwerk-verlag.de\/sap-auf-hyperscaler-clouds\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"895\" height=\"1080\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-1200x1448.png\" alt=\"\" class=\"wp-image-140513\" style=\"width:400px\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover.png 895w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-331x400.png 331w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-768x927.png 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-100x121.png 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-480x579.png 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-640x772.png 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-720x869.png 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-10x12.png 10w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-1200x1448.png 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/2022-08-12-Rheinwerk-Verlag-9239_SAP-auf-Hyperscaler-Clouds_Cover-600x724.png 600w\" sizes=\"auto, (max-width: 895px) 100vw, 895px\" \/><\/a><figcaption class=\"wp-element-caption\">ISBN 978-3-8362-9239-9 <br><a href=\"https:\/\/www.rheinwerk-verlag.de\/sap-auf-hyperscaler-clouds\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.rheinwerk-verlag.de\/sap-auf-hyperscaler-clouds\/<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n<p>Le simple fait d'avoir une vue d'ensemble des diff\u00e9rents mod\u00e8les d'h\u00e9bergement et de ce qui est inclus ou non dans tel ou tel mod\u00e8le d'h\u00e9bergement repr\u00e9sente souvent un premier d\u00e9fi. D'autant plus que le mod\u00e8le d'h\u00e9bergement implique souvent que les responsabilit\u00e9s au sein de l'entreprise doivent \u00e9galement \u00eatre modifi\u00e9es. Cela implique souvent une modification de l'organisation de l'entreprise ainsi que de la gestion des changements, des versions et des tickets, car les responsabilit\u00e9s changent et les chevauchements et la communication entre les fournisseurs jusqu'au client doivent \u00eatre d\u00e9finis et clarifi\u00e9s.<\/p>\n\n\n\n<p>SAP sur des clouds hyperscaler donne un aper\u00e7u des t\u00e2ches les plus importantes lors de l'exploitation de l'infrastructure cloud et de son syst\u00e8me SAP. Diff\u00e9rentes plateformes sont pr\u00e9sent\u00e9es et, \u00e0 l'aide d'un catalogue de crit\u00e8res, l'utilisateur potentiel peut d\u00e9terminer lui-m\u00eame quelle plateforme est la plus adapt\u00e9e ou si un sc\u00e9nario hybride est le meilleur.<\/p>\n\n\n\n<p>Ce livre est une sorte de lampe de poche qui permet d'\u00e9clairer le d\u00e9but du projet, sa r\u00e9alisation et son exploitation ult\u00e9rieure. Il doit aider \u00e0 ne pas n\u00e9gliger les \"points aveugles\" qui peuvent faire \u00e9chouer un projet de migration ou qui peuvent peser \u00e9norm\u00e9ment sur l'exploitation ult\u00e9rieure.<\/p>\n\n\n\n<p>Cela peut arriver rapidement, il suffit qu'un add-in ne soit pas valid\u00e9 par tous les fournisseurs apr\u00e8s la migration ou qu'il manque une liste d'interfaces et qu'apr\u00e8s la migration, tous les syst\u00e8mes environnants ne puissent plus se parler parce que la latence n'a pas \u00e9t\u00e9 prise en compte dans la conception du nouvel environnement.\u00a0<\/p>\n\n\n\n\n\n\n\n<p>Les deux auteurs conseillent depuis des ann\u00e9es tous les segments de client\u00e8le et les branches les plus diverses sur le th\u00e8me du cloud, de la migration et de SAP. Il n'y a rien qui n'ait d\u00e9j\u00e0 \u00e9t\u00e9 fait. Steffi D\u00fcnnebier travaille depuis plus de 20 ans dans l'environnement SAP et a d\u00e9j\u00e0 migr\u00e9 et transform\u00e9 de nombreux syst\u00e8mes avant le cloud.<\/p>\n\n\n\n<p>D'apr\u00e8s leur exp\u00e9rience, on a tendance \u00e0 n\u00e9gliger l'ensemble de la situation et \u00e0 n\u00e9gliger l'exploitation ult\u00e9rieure. Selon son exp\u00e9rience, le d\u00e9fi et le travail ne font que commencer apr\u00e8s une migration r\u00e9ussie vers le cloud. La migration vers le cloud est souvent le premier pas vers un environnement agile, il faut ensuite mettre en place, cr\u00e9er, modifier, \u00e9tablir et vivre les processus d'exploitation et la propre organisation ainsi que la collaboration avec les nouveaux fournisseurs. Il ne faut jamais oublier que les collaborateurs de l'entreprise, les clients, les parties prenantes et la direction doivent toujours \u00eatre impliqu\u00e9s dans ce voyage, car sans le soutien et les connaissances de ses propres rangs, une migration vers le cloud et une transition vers de nouveaux processus d'exploitation et proc\u00e9dures ne seront jamais couronn\u00e9es de succ\u00e8s. <\/p>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-1796892\" data-block-id=\"1796892\"><style>.stk-1796892 .stk--block-align-1796892{align-items:flex-end !important}.stk-1796892{margin-bottom:0px !important}.stk-1796892-column{max-width:500px !important;margin-right:auto !important;margin-left:0px !important}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-1796892 stk-block-content stk-content-align stk-1796892-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-42385e4\" data-v=\"4\" data-block-id=\"42385e4\"><style>.stk-42385e4-inner-blocks{align-items:flex-start !important;justify-content:flex-start !important}.stk-42385e4-container{min-height:0px !important}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-42385e4-container stk-hover-parent\"><div class=\"has-text-align-left stk--column-flex stk-block-content stk-inner-blocks stk-42385e4-inner-blocks\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04b1c25c6d0&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b1c25c6d0\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"500\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Steffi_Duennebier.jpg\" alt=\"\" class=\"wp-image-140517\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Steffi_Duennebier.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Steffi_Duennebier-320x400.jpg 320w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Steffi_Duennebier-100x125.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Steffi_Duennebier-10x12.jpg 10w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><strong>Steffi D\u00fcnnebier,<\/strong><br><em>Architecte d'entreprise g\u00e9rante, Capgemini<\/em><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5cb626e\" data-v=\"4\" data-block-id=\"5cb626e\"><style>.stk-5cb626e{align-self:flex-start !important}.stk-5cb626e-inner-blocks{align-items:flex-start !important;justify-content:flex-start !important}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5cb626e-container stk-hover-parent\"><div class=\"stk--column-flex stk-block-content stk-inner-blocks stk-5cb626e-inner-blocks\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04b1c25d3a8&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b1c25d3a8\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"500\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Uwe-Zabel.jpg\" alt=\"\" class=\"wp-image-140518\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Uwe-Zabel.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Uwe-Zabel-320x400.jpg 320w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Uwe-Zabel-100x125.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/03\/WEB_Uwe-Zabel-10x12.jpg 10w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><strong>Uwe Zabel,<br><\/strong><em>Microsoft Cloud Capability Manager,<\/em> <em>Capgemini<\/em><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>SAP sur des clouds hyperscaler donne un aper\u00e7u des t\u00e2ches les plus importantes lors de l'exploitation de l'infrastructure cloud et de son syst\u00e8me SAP. Diff\u00e9rentes plateformes sont pr\u00e9sent\u00e9es et, \u00e0 l'aide d'un catalogue de crit\u00e8res, l'utilisateur potentiel peut d\u00e9terminer lui-m\u00eame quelle plateforme est la plus adapt\u00e9e ou si un sc\u00e9nario hybride est le meilleur.<\/p>","protected":false},"author":2368,"featured_media":135618,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[43764,43842],"tags":[39,12010],"coauthors":[39720],"class_list":["post-140511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buchtipp","category-mag-24-03","tag-cloud","tag-hosting","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/buchtipps_1000x450-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP auf Hyperscaler-Clouds gibt einen \u00dcberblick \u00fcber die wichtigsten Aufgaben beim Betrieb der Cloud-Infrastruktur und ihres SAP-Systems. Es werden verschiedene Plattformen aufgezeigt und mithilfe eines Kriterienkatalogs kann der potenzielle Anwender selbst herausfinden, welche Plattform am besten passt oder ob ein hybrides Szenario am besten ist.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/fr\/category\/buchtipp\/\" rel=\"category tag\">Buchtipp<\/a>, <a href=\"https:\/\/e3mag.com\/fr\/category\/mag-24-03\/\" rel=\"category tag\">MAG 24-03<\/a>","author_info_v2":{"name":"E3 Magazine","url":"https:\/\/e3mag.com\/fr\/author\/e3_magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/140511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/comments?post=140511"}],"version-history":[{"count":13,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/140511\/revisions"}],"predecessor-version":[{"id":140528,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/140511\/revisions\/140528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media\/135618"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media?parent=140511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/categories?post=140511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/tags?post=140511"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/coauthors?post=140511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}