{"id":131802,"date":"2023-08-24T10:50:33","date_gmt":"2023-08-24T08:50:33","guid":{"rendered":"http:\/\/e3mag.com\/?p=131802"},"modified":"2023-08-24T10:50:48","modified_gmt":"2023-08-24T08:50:48","slug":"pertinence-strategique","status":"publish","type":"post","link":"https:\/\/e3mag.com\/fr\/strategische-relevanz\/","title":{"rendered":"Pertinence strat\u00e9gique"},"content":{"rendered":"<p>D'une part, les logiciels constituent le fondement de la num\u00e9risation des processus commerciaux et donc de la comp\u00e9titivit\u00e9. D'autre part, le personnel informatique qualifi\u00e9 fait de plus en plus d\u00e9faut. Un m\u00e9lange toxique pour lequel les entreprises cherchent d\u00e9sesp\u00e9r\u00e9ment une solution.<\/p>\n\n\n\n<p>Ce n'est pas un hasard si les avantages exceptionnels du Low-Code sont aujourd'hui \u00e0 nouveau reconnus. Les plates-formes Low-Code repr\u00e9sentent une issue prometteuse \u00e0 ce dilemme. Elles permettent<br>permet aux collaborateurs des d\u00e9partements sp\u00e9cialis\u00e9s de d\u00e9velopper eux-m\u00eames des solutions d'automatisation lorsque l'informatique ne peut pas les soutenir en raison de capacit\u00e9s limit\u00e9es. Et qui est mieux plac\u00e9 pour le faire que quelqu'un qui comprend l'entreprise ?<\/p>\n\n\n\n<p>Selon une \u00e9tude r\u00e9cente de CIO, CSO et Computerwoche, environ un tiers des entreprises interrog\u00e9es utilisent d\u00e9j\u00e0 deux ou trois plates-formes Low-Code. Et le march\u00e9 devrait continuer \u00e0 cro\u00eetre. Selon l'\u00e9tude CIO, l'un des principaux domaines d'utilisation des plates-formes Low-Code est le secteur ERP, avec une part de 31%. Il est int\u00e9ressant de noter que si 80 % des responsables informatiques interrog\u00e9s au niveau du conseil d'administration sont satisfaits du r\u00e9sultat de leurs projets Low-Code, seuls 45 % des responsables des domaines sp\u00e9cialis\u00e9s le sont. Les auteurs de l'\u00e9tude interpr\u00e8tent cela comme un signe que les exigences des domaines sp\u00e9cialis\u00e9s sont fondamentalement diff\u00e9rentes de celles des responsables informatiques. Dans le domaine ERP, les projets Low-Code<br>Les plateformes de code pour les entreprises n'atteignent leur plein potentiel que si elles prennent en charge tous les aspects de la gestion d'entreprise dans leur int\u00e9gralit\u00e9. Souvent, l'environnement informatique est fragment\u00e9. La force de la plate-forme Tangro r\u00e9side au contraire dans son \u00e9tendue de prestations globale. Elle peut \u00eatre utilis\u00e9e en tant que plateforme Low-Code pour toutes les applications SAP et, en tant que solution Cloud, elle ne n\u00e9cessite aucune int\u00e9gration ou infrastructure informatique suppl\u00e9mentaire.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><em>La force de la plateforme Tangro<br>r\u00e9side dans son caract\u00e8re transversal<br>Large gamme de prestations.<\/em><\/p>\n\n\n\n<p><em>Patrick Etter,<br>Co-g\u00e9rant,<br>Tangro<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/web-Patrick-Etter_2_cmyk.jpg\" alt=\"\" class=\"wp-image-131804\" style=\"width:246px;height:328px\" width=\"246\" height=\"328\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/web-Patrick-Etter_2_cmyk.jpg 600w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/web-Patrick-Etter_2_cmyk-300x400.jpg 300w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/web-Patrick-Etter_2_cmyk-100x133.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/web-Patrick-Etter_2_cmyk-480x640.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/web-Patrick-Etter_2_cmyk-9x12.jpg 9w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Agilit\u00e9 et collaboration<\/h2>\n\n\n\n<p><br>De plus, la plate-forme Tangro refl\u00e8te des d\u00e9cennies d'exp\u00e9rience en gestion d'entreprise. Ce n'est pas seulement la mise en \u0153uvre technique qui fait la valeur ajout\u00e9e de la plate-forme Tangro, mais surtout la compr\u00e9hension profonde des aspects commerciaux d'une application dans l'environnement ERP. Les modules n\u00e9cessaires pour obtenir les r\u00e9sultats souhait\u00e9s sont examin\u00e9s avec pr\u00e9cision. En outre, l'accent est mis sur le traitement des donn\u00e9es et la mod\u00e9lisation des processus par la combinaison de modules r\u00e9utilisables. Enfin, il est possible de r\u00e9utiliser non seulement des modules individuels, mais aussi des processus entiers dans des applications.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Automatisation efficace des processus<\/h2>\n\n\n\n<p>La puissance de la plate-forme Tangro se traduit par des applications performantes. Par exemple, dans un syst\u00e8me ERP \u00e0 usage interne, qui comprend d\u00e9sormais plus de 200 transactions et qui, au d\u00e9part, n'a \u00e9t\u00e9 d\u00e9velopp\u00e9 que par un seul collaborateur - \u00e9loign\u00e9 de l'informatique. Mais surtout dans la Tangro Inbound Suite, une solution globale de bout en bout pour la num\u00e9risation des processus documentaires dans SAP ERP\/ECC 6.0 et SAP S\/4 Hana. Le d\u00e9veloppement de solutions individuelles, par exemple pour le traitement automatis\u00e9 des confirmations de commande ou pour l'enregistrement des avis de livraison dans ERP et S\/4, n'a pris respectivement que deux et trois semaines.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/2309_E3_Magazin_Online_Coverstory.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg\" alt=\"\" class=\"wp-image-73569\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/partners\/tangro_software\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1.jpg\" alt=\"\" class=\"wp-image-131738\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-400x45.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-960x108.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-600x67.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Von null auf Digital: Warum Low f\u00fcr Unternehmen heute High ist?<br \/>\nDie st\u00e4ndig wachsenden Anforderungen und die zunehmende Anzahl von<br \/>\nAutomatisierungsprojekten setzen viele Unternehmen unter Druck.<\/p>","protected":false},"author":2368,"featured_media":131805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[43473,43474],"tags":[29810,29809,23894,1390],"coauthors":[39720],"class_list":["post-131802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-23-09","category-mag-23-09","tag-low-code","tag-no-code","tag-prozessautomatisierung","tag-s4-hana","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/strategisch-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Von null auf Digital: Warum Low f\u00fcr Unternehmen heute High ist?<br \/>\nDie st\u00e4ndig wachsenden Anforderungen und die zunehmende Anzahl von<br \/>\nAutomatisierungsprojekten setzen viele Unternehmen unter Druck.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/fr\/category\/coverstorys\/coverstory-23-09\/\" rel=\"category tag\">Coverstory 23-09<\/a>, <a href=\"https:\/\/e3mag.com\/fr\/category\/mag-23-09\/\" rel=\"category tag\">MAG 23-09<\/a>","author_info_v2":{"name":"E3 Magazine","url":"https:\/\/e3mag.com\/fr\/author\/e3_magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/131802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/comments?post=131802"}],"version-history":[{"count":3,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/131802\/revisions"}],"predecessor-version":[{"id":131809,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/posts\/131802\/revisions\/131809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media\/131805"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/media?parent=131802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/categories?post=131802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/tags?post=131802"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/fr\/wp-json\/wp\/v2\/coauthors?post=131802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}