{"id":3818,"date":"2016-12-15T09:50:30","date_gmt":"2016-12-15T08:50:30","guid":{"rendered":"http:\/\/e3mag.com\/?p=3818"},"modified":"2019-03-11T15:00:08","modified_gmt":"2019-03-11T14:00:08","slug":"limpieza-digital-en-hamburgo","status":"publish","type":"post","link":"https:\/\/e3mag.com\/es\/digitales-grossreinemachen-in-hamburg\/","title":{"rendered":"Limpieza a fondo digital en Hamburgo"},"content":{"rendered":"<p>Hasta hace unos a\u00f1os, eran sobre todo las empresas de TI, los proveedores de servicios financieros y las compa\u00f1\u00edas de seguros los que confiaban en la autoadministraci\u00f3n electr\u00f3nica de los empleados, pero ahora son cada vez m\u00e1s los grupos industriales y log\u00edsticos que tambi\u00e9n introducen sistemas ESS y MSS. Cuando los empleados y directivos tienen acceso a los datos de personal, muchos procesos que requieren mucho tiempo -como la gesti\u00f3n de las solicitudes de vacaciones o el cambio de direcciones y n\u00fameros de tel\u00e9fono- dejan de ser necesariamente responsabilidad del departamento de RRHH.<\/p>\n<p>El proyecto \"Cambio al registro electr\u00f3nico del tiempo de trabajo\" ya se puso en marcha en 2008 en el servicio municipal de limpieza de Hamburgo, pero su r\u00e1pida implantaci\u00f3n fracas\u00f3 por el veto del comit\u00e9 de personal. \"A menudo nos encontramos con que el personal y los comit\u00e9s de empresa son inicialmente cr\u00edticos con el registro electr\u00f3nico del tiempo\", explica Andreas Blumendorf, Director General de Consodalis, que ahora apoya a SRH con el proyecto. \"Por un lado, temen el control total de los empleados y, por otro, quieren evitar que los empleados permanezcan en sus puestos de trabajo durante periodos innecesariamente largos preocupados por su situaci\u00f3n horaria. Pero el registro electr\u00f3nico del tiempo es m\u00e1s una ventaja que un inconveniente para los empleados: hasta la m\u00e1s m\u00ednima cantidad de horas extraordinarias se registra con precisi\u00f3n, y el valor monetario del tiempo trabajado es mucho m\u00e1s f\u00e1cil de reconocer para cada empleado.\"<\/p>\n<h3>Muchos sistemas, poca transparencia<\/h3>\n<p>El tel\u00f3n de fondo de la modernizaci\u00f3n del registro de tiempos fue la incoherencia de los sistemas de la Stadtreinigung Hamburg: en algunos departamentos, los tiempos de trabajo se registraban mediante tarjetas, y en otros, mediante una soluci\u00f3n inform\u00e1tica no estandarizada. Los tiempos se documentaban en papel. Los pagos especiales, como las dietas de viaje o los complementos por atenci\u00f3n continuada, ten\u00edan que introducirse manualmente en el sistema SAP, al igual que los periodos de vacaciones y las ausencias debidas a viajes de negocios. Aparte de la p\u00e9rdida de tiempo que supon\u00eda este m\u00e9todo de registro, no hab\u00eda forma de comparar los tiempos de trabajo con los acuerdos de servicio de SSR o con la normativa legal en materia de tiempo de trabajo.<\/p>\n<p>Con la nueva soluci\u00f3n normalizada, deber\u00eda ser posible registrar y documentar las horas de trabajo de la forma m\u00e1s sencilla posible y sin \"discontinuidad de medios\", y deber\u00eda eliminarse la introducci\u00f3n manual de las pagas extraordinarias. Del mismo modo, deber\u00edan eliminarse todas las solicitudes en papel: solicitudes de vacaciones, solicitudes de participaci\u00f3n en seminarios, etc. Por \u00faltimo, deber\u00eda ser posible comprobar de forma vinculante el cumplimiento de los requisitos legales en materia de tiempo de trabajo y los acuerdos de servicios de SSR aplicables.<\/p>\n<p>En febrero de 2014, la modernizaci\u00f3n del sistema de registro horario volvi\u00f3 a estar en el orden del d\u00eda. Se eligi\u00f3 a Consodalis como socio estrat\u00e9gico para la implantaci\u00f3n. El proyecto se llev\u00f3 a cabo en varias fases. Comenz\u00f3 con una reuni\u00f3n inicial del proyecto, seguida de talleres con la consultora de Ahrensburg y los distintos departamentos de SSR. En los talleres, los especialistas de Ahrensburg explicaron a los responsables de SRH c\u00f3mo pod\u00edan cumplirse exactamente los requisitos de especificaci\u00f3n utilizando un sistema de gesti\u00f3n del tiempo y soluciones ESS\/MSS basadas en SAP. Los ajustes t\u00e9cnicos se iniciaron en septiembre de 2015. Tres meses despu\u00e9s, en enero de 2016, los sistemas de registro electr\u00f3nico del tiempo y ESS\/MSS entraron en funcionamiento para los 620 empleados asalariados. En junio, el registro electr\u00f3nico del tiempo se ampli\u00f3 a todos los empleados industriales de los centros de reciclaje y se complement\u00f3 con la programaci\u00f3n electr\u00f3nica de la mano de obra. En la fase final de implantaci\u00f3n, todos los dem\u00e1s empleados industriales, como los conductores de camiones de basura, los barrenderos y el equipo de comedor, se integrar\u00e1n en el sistema de registro electr\u00f3nico del tiempo.<\/p>\n<h3>Espectro de utilizaci\u00f3n<\/h3>\n<p>La gama de autoservicios a disposici\u00f3n de empleados y directivos desde principios de a\u00f1o incluye una visi\u00f3n general de la cuenta de tiempo, una funci\u00f3n de creaci\u00f3n de solicitudes de vacaciones y ausencias y un calendario de equipo. Todos los empleados pueden consultar las reservas diarias y las fichas horarias y, posteriormente, introducir en el sistema las fichadas olvidadas. Los jefes tambi\u00e9n pueden generar informes sobre sus empleados en forma de listas (por ejemplo, listas de cumplea\u00f1os, listas de grupos), ver los niveles de cuotas y corregir los tiempos manualmente. Tambi\u00e9n pueden consultar los res\u00famenes de asistencia y ver los recordatorios de citas, por ejemplo, para cumplea\u00f1os o aniversarios de empresa. Por \u00faltimo, SRH en su conjunto tiene ahora la opci\u00f3n de controlar el cumplimiento de la legislaci\u00f3n sobre el tiempo de trabajo y documentar cualquier infracci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>El mayor proveedor de servicios de Hamburgo en el campo de la gesti\u00f3n de residuos y recursos, Stadtreinigung Hamburg (SRH), se est\u00e1 actualizando a un sistema de gesti\u00f3n del tiempo SAP. Tambi\u00e9n se est\u00e1 digitalizando la programaci\u00f3n del personal y se est\u00e1 integrando a todos los empleados en un sistema ESS y MSS.<\/p>","protected":false},"author":38,"featured_media":3819,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[740],"tags":[601,850,437,827],"coauthors":[19920],"class_list":["post-3818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag1612","tag-digitalisierung","tag-hamburg","tag-mitarbeiter","tag-personal","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",400,243,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-768x466.jpg",768,466,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-100x61.jpg",100,61,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-480x291.jpg",480,291,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-640x388.jpg",640,388,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-720x437.jpg",720,437,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-960x583.jpg",960,583,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",18,12,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",1000,607,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",600,364,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49.jpg",600,364,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/Screenshot-2016-12-15-um-09.39.49-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Hamburgs gr\u00f6\u00dfter Dienstleister im Bereich Abfall- und Ressourcenwirtschaft, die Stadtreinigung Hamburg (SRH), r\u00fcstet auf ein SAP-Zeitwirtschaftssystem um. Auch die Personaleinsatzplanung wird digitalisiert, zudem werden alle Mitarbeiter in ein ESS- beziehungsweise MSS-System eingebunden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/es\/category\/mag1612\/\" rel=\"category tag\">MAG 16-12<\/a>","author_info_v2":{"name":"Revista E-3","url":"https:\/\/e3mag.com\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/3818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/comments?post=3818"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/3818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media\/3819"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media?parent=3818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/categories?post=3818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/tags?post=3818"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/coauthors?post=3818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}