{"id":36585,"date":"2018-02-08T10:00:13","date_gmt":"2018-02-08T09:00:13","guid":{"rendered":"http:\/\/e3mag.com\/?p=33110"},"modified":"2022-05-01T09:38:59","modified_gmt":"2022-05-01T07:38:59","slug":"en-la-encrucijada-direccion-del-futuro-vuelta-de-la-agenda-de-la-cfo-2018","status":"publish","type":"post","link":"https:\/\/e3mag.com\/es\/an-der-kreuzung-richtung-zukunft-abbiegen-die-cfo-agenda-2018\/","title":{"rendered":"Girando en la encrucijada hacia el futuro: La Agenda del CFO 2018"},"content":{"rendered":"<p>En muchos lugares, en los departamentos financieros y en la direcci\u00f3n se respira un esp\u00edritu de optimismo y la voluntad de aprovechar positivamente para la propia empresa las oportunidades que ofrece el cambio tecnol\u00f3gico.<\/p>\n<p>El entorno y el estilo de trabajo del Director Financiero cambiar\u00e1n significativamente, lo que permitir\u00e1 y exigir\u00e1 centrarse en el an\u00e1lisis estrat\u00e9gico.<\/p>\n<p>Con las herramientas de an\u00e1lisis predictivo, se pueden simular muchos escenarios en tiempo real, ya no diferenciados cl\u00e1sicamente seg\u00fan \"mejor, probable, peor\", sino directamente en l\u00ednea mediante el cambio de variables.<\/p>\n<p>Los resultados pueden utilizarse para tomar decisiones \"justo a tiempo\" en las reuniones de gesti\u00f3n. Las previsiones ya no se basar\u00e1n solo en la experiencia pasada, sino en an\u00e1lisis de big data.<\/p>\n<p>Las reservas electr\u00f3nicas, incluso entre empresas, cambiar\u00e1n la contabilidad: Muchas tareas de contabilidad y archivo ser\u00e1n superfluas o se automatizar\u00e1n.<\/p>\n<p>El archivo y la gesti\u00f3n de documentos son electr\u00f3nicos, las impresiones y las bandejas de papel desaparecer\u00e1n. Los robots programados trabajan 24 horas al d\u00eda, 7 d\u00edas a la semana, asumiendo tareas sencillas (por ejemplo, rellenar formularios) o procesos recurrentes estandarizados.<\/p>\n<p>Mientras que los engorrosos procesos de reclamaci\u00f3n y seguimiento de las cuentas por cobrar siguen estando muy extendidos hoy en d\u00eda en las PYME, el seguimiento automatizado de las cuentas por cobrar y el pago instant\u00e1neo tendr\u00e1n un impacto positivo en el flujo de caja en el futuro.<\/p>\n<p>Los pagos en tiempo real son la norma; segundos despu\u00e9s de la liberaci\u00f3n, el dinero est\u00e1 en la cuenta del destinatario, incluso por la noche y los fines de semana. Se eliminan los riesgos de pago a lo largo de la cadena de suministro. Para la tesorer\u00eda de las empresas internacionales, esto puede significar trabajo por turnos, porque a pesar de la creciente proporci\u00f3n de pagos en tiempo real, alguien tiene que supervisar los movimientos de pago para poder reaccionar inmediatamente en caso de fallo del sistema, sospecha de fraude u otras fricciones.<\/p>\n<p>Algoritmos de autoaprendizaje se encargan de tareas complejas, como el reconocimiento de textos y las reacciones a los mismos. La financiaci\u00f3n, la colocaci\u00f3n y la negociaci\u00f3n de valores tienen lugar a trav\u00e9s de plataformas blockchain.<\/p>\n<p>Las criptodivisas basadas en blockchain son actualmente el hype, aunque de momento siguen siendo objetos especulativos (el valor de Ripple subi\u00f3 un 36.000% en 2017). Pero tambi\u00e9n hay muchos intentos serios de utilizar esta tecnolog\u00eda, que hacen que la gente sienta curiosidad por los beneficios pr\u00e1cticos que podr\u00edan derivarse de ella.<\/p>\n<p>Las cadenas de suministro se vuelven totalmente transparentes: los clientes tienen la posibilidad de consultar los sistemas de sus proveedores para seguir el estado de las entregas o el progreso de un proyecto conjunto.<\/p>\n<p>Los informes actuales se est\u00e1n sustituyendo por los autoinformes en l\u00ednea, es decir, la recuperaci\u00f3n de datos directamente en el sistema y formas sencillas de generar informes ad hoc, as\u00ed como an\u00e1lisis en tiempo real.<\/p>\n<p>Los requisitos previos para estas innovaciones son un sistema ERP moderno como base para los procesos empresariales digitales (en R\u00f6dl &amp; Partner ser\u00e1 el uso global de SAP S\/4 Hana), as\u00ed como la voluntad de todos los empleados de cuestionar cr\u00edticamente y cambiar los h\u00e1bitos existentes y de continuar su formaci\u00f3n para seguir el ritmo de la tecnolog\u00eda y prepararse para nuevas tareas de an\u00e1lisis e implementaci\u00f3n de mayor valor.<\/p>\n<p>Viajar a lugares lejanos sigue siendo indispensable porque la gente tiene una necesidad leg\u00edtima de reunirse para tratar asuntos importantes (por ejemplo, negocios) y el contacto personal facilita muchas cosas.<\/p>\n<p>Pero los desplazamientos ya no son obligatorios, incluso los procesos de adquisici\u00f3n pueden ser digitales. Las videoconferencias se utilizan desde hace tiempo para todo tipo de reuniones y los drones pueden sustituir a la inspecci\u00f3n f\u00edsica del estado de los centros de producci\u00f3n.<\/p>\n<p>Es un momento emocionante para todos los directores financieros, que no deben verlo como una amenaza, sino como una gran oportunidad para configurar positivamente el futuro de su propia empresa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los nuevos y cambiantes modelos de negocio, las tecnolog\u00edas innovadoras, la colaboraci\u00f3n m\u00e1s all\u00e1 de los l\u00edmites de la empresa, los procesos digitalizados, el big data, la seguridad de los datos y, por \u00faltimo pero no menos importante, un sistema ERP moderno basado en la nube est\u00e1n actualmente en boca de todos.<\/p>","protected":false},"author":1382,"featured_media":36685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[20393,7,20361],"tags":[1114,3413,5959],"coauthors":[21857],"class_list":["post-36585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cfo-kolumne","category-meinung","category-mag-1802","tag-cfo","tag-predictive-analytics","tag-sap-s4-hana","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-80x80.jpg",80,80,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-1030x464.jpg",1030,464,true],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-1168x526.jpg",1168,526,true],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Ver\u00e4nderte und neue Gesch\u00e4ftsmodelle, innovative Technologien, Kollaboration \u00fcber Unternehmensgrenzen, digitalisierte Prozesse, Big Data, Datensicherheit und nicht zuletzt ein modernes, cloudbasiertes ERP-System sind  zurzeit in aller Munde.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/es\/category\/meinung\/cfo-kolumne\/\" rel=\"category tag\">CFO - Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/es\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/es\/category\/mag-1802\/\" rel=\"category tag\">MAG 18-02<\/a>","author_info_v2":{"name":"Bernd Stroppel, R\u00f6dl &amp; Partner","url":"https:\/\/e3mag.com\/es\/author\/bernd-stroppel\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/36585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/users\/1382"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/comments?post=36585"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/36585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media\/36685"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media?parent=36585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/categories?post=36585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/tags?post=36585"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/coauthors?post=36585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}