{"id":163378,"date":"2026-05-13T13:09:50","date_gmt":"2026-05-13T11:09:50","guid":{"rendered":"https:\/\/e3mag.com\/?p=163378"},"modified":"2026-05-13T13:09:52","modified_gmt":"2026-05-13T11:09:52","slug":"empresa-autonoma-frente-a-erp-componible","status":"publish","type":"post","link":"https:\/\/e3mag.com\/es\/autonomous-enterprise-versus-composable-erp\/","title":{"rendered":"Empresa aut\u00f3noma frente a ERP componible"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Plataformas, motores y centros<\/h2>\n\n\n\n<p>SAP ten\u00eda todo lo que un usuario de ERP necesitaba para una aplicaci\u00f3n empresarial moderna: Muchas cosas eran demasiado caras, demasiado complejas y a menudo redundantes, de modo que un problema de ERP pod\u00eda resolverse con diferentes herramientas de SAP. Pero el cliente SAP existente dudaba porque nadie sab\u00eda qu\u00e9 productos ten\u00edan una hoja de ruta verificada y qu\u00e9 productos ser\u00edan sustituidos por adquisiciones. La oferta de SAP era inabarcable y ha crecido a\u00fan m\u00e1s y se ha vuelto a\u00fan m\u00e1s compleja con los \u00faltimos anuncios en torno a Sapphire en Orlando. \u00bfY ahora qu\u00e9? \u00bfQui\u00e9n dar\u00e1 las respuestas a SAP Integration Suite, Hana Knowledge Graph Engine y la cooperaci\u00f3n n8n? \u00bfY qui\u00e9n prevalecer\u00e1 al final: SAP-RPT o Prior Labs?<\/p>\n\n\n\n<p>En Sapphire, Christian Klein, CEO de SAP, baraj\u00f3 de nuevo las cartas del ERP: desde el punto de vista arquitect\u00f3nico, SAP est\u00e1 construyendo la imagen objetivo aut\u00f3noma en varias capas, cuya base es la denominada Business AI Platform, en la que los pilares t\u00e9cnicos de la Business Technology Platform (SAP BTP), la Business Data Cloud (SAP BDC o, como dice la asociaci\u00f3n de usuarios DSAG: Business Data Complexity) y herramientas como Signavio y LeanIX se unen para desarrollar y ofrecer soluciones de IA. El v\u00ednculo esencial entre esta nueva plataforma y las aplicaciones reales ser\u00e1 un \u201eSAP Knowledge Graph\u201c (el antiguo motor gr\u00e1fico de la plataforma de base de datos Hana), cuyo objetivo es hacer que los datos SAP, hist\u00f3ricamente crecidos y a menudo muy complejos, sean legibles y recuperables para los agentes de IA de forma estructurada en primer lugar.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De ECC 6.0 al ERP aut\u00f3nomo<\/h2>\n\n\n\n<p>Seg\u00fan Christian Klein, la nueva y operativa pieza central es la \u201eSAP Autonomous Suite\u201c, en la que SAP promete m\u00e1s de 50 asistentes Joule espec\u00edficos de dominio para \u00e1reas de negocio tradicionales como finanzas, cadena de suministro o compras. En el futuro, estos asistentes actuar\u00e1n como coordinadores digitales y controlar\u00e1n un subgrupo de m\u00e1s de 200 agentes de IA especializados para llevar a cabo procesos completos de principio a fin -como el cierre trimestral en el departamento financiero- de forma en gran medida aut\u00f3noma y reducir el tiempo necesario de semanas a tan solo unos d\u00edas.<\/p>\n\n\n\n<p>Idealmente, el usuario del ERP s\u00f3lo interact\u00faa a trav\u00e9s de la interfaz de usuario de alto nivel \u201eJoule Work\u201c, en la que expresa sus intenciones mediante entradas de lenguaje natural, mientras que la IA revela informaci\u00f3n de forma proactiva y realiza tareas rutinarias autom\u00e1ticamente en segundo plano.<\/p>\n\n\n\n<p>Sin embargo, si se mira entre bastidores de esta visi\u00f3n aut\u00f3noma con distanciamiento period\u00edstico, surge un panorama mucho m\u00e1s sobrio para los clientes actuales de SAP, que la asociaci\u00f3n de usuarios DSAG ya ha analizado. Las aplicaciones b\u00e1sicas de SAP y las conocidas soluciones de software como servicio permanecen pr\u00e1cticamente intactas en la nueva arquitectura; simplemente se reorganizan estrat\u00e9gicamente, se les da el prefijo \u201eaut\u00f3nomo\u201c -como \u201eAutonomous Finance\u201c o \u201eAutonomous Procurement\u201c- y se complementan con diversos agentes de IA.<\/p>\n\n\n\n<p>Por lo tanto, el hecho de que las compras se anuncien como aut\u00f3nomas en el futuro no cambia el hecho de que las conocidas soluciones en la nube, como SAP Ariba o SAP Business Network, seguir\u00e1n operando en la sala de m\u00e1quinas. Seg\u00fan la evaluaci\u00f3n del DSAG, este cambio estrat\u00e9gico no tendr\u00e1, por tanto, ning\u00fan impacto directo en el actual panorama de sistemas de los clientes existentes ni en las conversiones a S\/4 que ya est\u00e1n en marcha, raz\u00f3n por la cual no es necesario detener o reconsiderar los proyectos de transformaci\u00f3n existentes. Por lo tanto, SAP no est\u00e1 reinventando fundamentalmente la rueda del ERP con este movimiento, sino que principalmente est\u00e1 poniendo una nueva capa de IA sobre las soluciones anteriores independientes y resumi\u00e9ndolas en una nueva narrativa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como Tesla, con la Empresa Aut\u00f3noma al choque<\/h2>\n\n\n\n<p>La madurez operativa y el dise\u00f1o comercial de esta promesa de salvaci\u00f3n de un sistema ERP aut\u00f3nomo e independiente deben examinarse de forma especialmente cr\u00edtica. En el momento de los grandiosos anuncios en la feria de clientes Sapphire, faltaban detalles fundamentales sobre la implementaci\u00f3n t\u00e9cnica, las fechas exactas de lanzamiento y, sobre todo, los modelos decisivos de precios y facturaci\u00f3n, lo que pone en peligro masivamente la seguridad de la planificaci\u00f3n financiera de las empresas.<\/p>\n\n\n\n<p>Adem\u00e1s, muchos clientes existentes y expertos en TI han tenido la dolorosa experiencia en el pasado de que el marketing de SAP suele ir muy por delante de la realidad t\u00e9cnica real y de que las anteriores funciones de IA a\u00fan est\u00e1n inmaduras en el duro entorno empresarial cotidiano. Por lo tanto, el DSAG advierte en\u00e9rgicamente que no se debe permitir que las funciones b\u00e1sicas fundamentales que son esenciales para el \u00e9xito del ERP -como la gesti\u00f3n de documentos de extremo a extremo, la administraci\u00f3n central de usuarios fiable o la mejora continua de las interfaces de usuario- pasen a un segundo plano en favor de las costosas inversiones en IA.<\/p>\n\n\n\n<p>Los clientes actuales de SAP tambi\u00e9n tendr\u00e1n que esperar para ver si la traducci\u00f3n de bases de datos complejas de SAP (Hana) por parte del nuevo Knowledge Graph (Hana Engine) funciona realmente sin errores en la pr\u00e1ctica, ya que es precisamente esta falta de conocimiento contextual lo que a menudo ha planteado problemas irresolubles al asistente de IA Joule hasta la fecha. Knowledge Graph - vino viejo en botellas nuevas: La plataforma Hana dispone desde hace a\u00f1os de un motor gr\u00e1fico. Para poder presentar algo concreto en la feria Sapphire de Orlando, se recurri\u00f3 una vez m\u00e1s a la teor\u00eda de grafos de la inform\u00e1tica. En \u00faltima instancia, la suite ERP aut\u00f3noma est\u00e1 demostrando actualmente ser sobre todo una construcci\u00f3n visionaria en la que los clientes deben permanecer vigilantes en cuanto a si la autonom\u00eda prometida justifica realmente el alto precio antes de dejarse deslumbrar ciegamente por las turbias promesas de IA de Walldorf.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"821\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-1200x821.png\" alt=\"\" class=\"wp-image-163385\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-1200x821.png 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-400x274.png 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-768x526.png 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-100x68.png 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-480x328.png 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-640x438.png 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-720x493.png 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-960x657.png 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-1168x799.png 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-1440x985.png 1440w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-18x12.png 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20-600x411.png 600w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/05\/e3nl26kw20.png 1489w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Sapphire 2026 Orlando: Muchas plataformas m\u00e1s el antiguo motor gr\u00e1fico de la base de datos SAP Hana deber\u00edan facilitar las cosas a los actuales clientes de SAP.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Soberan\u00eda digital: aut\u00f3noma frente a componible<\/h2>\n\n\n\n<p>Si la futura direcci\u00f3n del software empresarial (ERP) se observa a trav\u00e9s de una lente cr\u00edtico-anal\u00edtica, surge un conflicto fundamental de direcci\u00f3n entre la \u201eEmpresa Aut\u00f3noma\u201c proclamada recientemente por SAP y el paradigma impulsado por el mercado del \u201eERP Componible\u201c.<\/p>\n\n\n\n<p>El concepto SAP de \u201eempresa aut\u00f3noma\u201c es la \u00faltima narrativa de marketing fuertemente burs\u00e1til de Walldorf, que ya est\u00e1 sustituyendo despiadadamente a la arquitectura North Star presentada hace apenas un a\u00f1o para satisfacer a toda prisa la enorme presi\u00f3n innovadora de los mercados financieros en torno a la inteligencia artificial. Si se examina con ojo cr\u00edtico, esta imagen de objetivo tan pulida a menudo resulta ser puro etiquetado fraudulento para los clientes actuales de SAP, ya que las mismas soluciones en la nube ya establecidas, como Ariba o Business Network, siguen ocultas bajo la nueva capa de az\u00facar de la IA. Por el contrario, la alternativa revolucionaria y liberadora es el ERP componible, un enfoque acu\u00f1ado por analistas como Gartner y l\u00edderes de opini\u00f3n como el profesor August-Wilhelm Scheer, que por fin pone fin a la era de los sistemas r\u00edgidos y monol\u00edticos y, en su lugar, sit\u00faa la m\u00e1xima adaptabilidad empresarial en el centro de las TI. El ERP componible permite a los usuarios liberarse de la amenaza de quedar atrapados en un \u00fanico proveedor y montar de forma flexible su panorama inform\u00e1tico a partir de los mejores bloques modulares de todo el mercado -por ejemplo, el n\u00facleo financiero de SAP combinado con las innovadoras soluciones de RRHH de Workday y los sistemas CRM de Salesforce- a trav\u00e9s de plataformas de integraci\u00f3n como SAP BTP o alternativas independientes como Boomi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Responsabilidad personal de los clientes SAP existentes<\/h2>\n\n\n\n<p>La diferencia decisiva para cada cliente SAP existente radica, por tanto, en la distribuci\u00f3n del poder y la soberan\u00eda digital: Mientras que la \u201eEmpresa Aut\u00f3noma\u201c es el intento transparente de SAP de cimentar el control total sobre los datos y procesos de los clientes a trav\u00e9s de un ecosistema cerrado de IA y empujarlos m\u00e1s profundamente hacia lucrativas dependencias de la nube, Composable ERP requiere y anima a las empresas a asumir una responsabilidad personal radical para dise\u00f1ar su arquitectura m\u00e1s all\u00e1 de las ilusiones de marketing de Walldorf como una red orquestada, abierta e independiente del proveedor de forma autodeterminada y autosuficiente (aut\u00f3noma).<\/p>","protected":false},"excerpt":{"rendered":"<p>Para los clientes actuales de SAP, la cuesti\u00f3n urgente es saber qu\u00e9 se esconde realmente detr\u00e1s de este nuevo y lustroso t\u00e9rmino de suite ERP aut\u00f3noma y si se trata de una aut\u00e9ntica revoluci\u00f3n t\u00e9cnica para los usuarios o simplemente de un timo de etiquetado impulsado por la bolsa.<\/p>","protected":false},"author":2,"featured_media":161236,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[27840],"tags":[44106,44395,73,65,624,517,236],"coauthors":[27825],"class_list":["post-163378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chefredakteur-blog","tag-bdc","tag-btp","tag-erp","tag-hana","tag-ki-joule","tag-s4","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-150x150.jpeg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-400x180.jpeg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-768x346.jpeg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-100x45.jpeg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-480x216.jpeg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-640x288.jpeg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-720x324.jpeg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-960x432.jpeg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-18x8.jpeg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu.jpeg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-600x270.jpeg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-600x450.jpeg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-24x24.jpeg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-48x48.jpeg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-96x96.jpeg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-150x150.jpeg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2026\/02\/Chefredakteur-neu-300x300.jpeg",300,300,true]},"post_excerpt_stackable_v2":"<p>F\u00fcr SAP-Bestandskunden stellt sich die dringende Frage, was sich hinter diesem neuen Hochglanzbegriff einer autonomen ERP-Suite wirklich verbirgt und ob es sich um eine echte technische Revolution f\u00fcr die Anwender oder lediglich um einen b\u00f6rsengetriebenen Etikettenschwindel handelt.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/es\/category\/chefredakteur-blog\/\" rel=\"category tag\">Chefredakteur-Blog<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3 Magazine","url":"https:\/\/e3mag.com\/es\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/163378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/comments?post=163378"}],"version-history":[{"count":3,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/163378\/revisions"}],"predecessor-version":[{"id":163390,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/163378\/revisions\/163390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media\/161236"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media?parent=163378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/categories?post=163378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/tags?post=163378"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/coauthors?post=163378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}