{"id":112495,"date":"2022-04-15T08:30:00","date_gmt":"2022-04-15T06:30:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=112495"},"modified":"2024-01-19T14:47:52","modified_gmt":"2024-01-19T13:47:52","slug":"juntos-hacia-la-neutralidad-climatica","status":"publish","type":"post","link":"https:\/\/e3mag.com\/es\/gemeinsam-zur-klimaneutralitaet\/","title":{"rendered":"Juntos hacia la neutralidad clim\u00e1tica"},"content":{"rendered":"<p>SAP y la consultora de gesti\u00f3n y tecnolog\u00eda BearingPoint han anunciado una cooperaci\u00f3n en el \u00e1mbito de las soluciones para determinar la huella ecol\u00f3gica, especialmente de las emisiones de gases de efecto invernadero. Ambas empresas quieren dise\u00f1ar y desarrollar conjuntamente una soluci\u00f3n orientada al futuro para apoyar a los clientes en su camino hacia la neutralidad clim\u00e1tica.<\/p>\n\n\n\n<p>La medici\u00f3n y gesti\u00f3n de la huella de CO\u2082 desempe\u00f1a un papel importante en la consecuci\u00f3n de emisiones netas cero y forma parte del programa de protecci\u00f3n del clima promovido por SAP. Las empresas se ven cada vez m\u00e1s presionadas para determinar su huella de CO\u2082 no solo a nivel empresarial, sino tambi\u00e9n para productos individuales. Al hacerlo, sin embargo, muchas empresas se enfrentan al reto de recopilar, consolidar y asignar datos. Con la soluci\u00f3n SAP Cloud for Sustainable Enterprises, lanzada recientemente, las soluciones SAP para la sostenibilidad y la larga experiencia de BearingPoint en el c\u00e1lculo de emisiones, las dos empresas est\u00e1n bien equipadas para desarrollar soluciones innovadoras que permitan a los clientes realizar un seguimiento de su huella medioambiental en toda su cadena de valor. <\/p>\n\n\n\n<p><em>\"Al asociarnos SAP y BearingPoint para un desarrollo conjunto, estamos combinando dos grandes fortalezas: BearingPoint tiene una amplia experiencia en ayudar a los clientes a identificar oportunidades para reducir las emisiones y alcanzar los objetivos de sostenibilidad; y SAP tiene capacidad de innovaci\u00f3n, un extenso panorama de sistemas y una amplia gama de clientes. Como socios, juntos redefiniremos los l\u00edmites de lo que es posible para acercar la econom\u00eda al objetivo de la neutralidad de carbono.\"<\/em>afirma Gunther Rothermel, SVP, Responsable de Sostenibilidad de S\/4 Hana, SAP.<\/p>\n\n\n\n<p>Aunque muchas empresas ya registran y analizan sus emisiones de Alcance 1 y Alcance 2, es fundamental tener en cuenta toda la cadena de valor, incluidas las emisiones de Alcance 3. Para ello, las redes deben permitir el intercambio de datos con socios como proveedores, clientes, auditores y autoridades, aunque utilicen sistemas inform\u00e1ticos diferentes. SAP Product Footprint Management se basa en la profunda experiencia de BearingPoint en el c\u00e1lculo de la huella a nivel de empresa y de producto y en el uso de algoritmos. <\/p>\n\n\n\n<p>As\u00ed, la soluci\u00f3n admite la recopilaci\u00f3n de datos, as\u00ed como c\u00e1lculos para medir la huella de CO\u2082 completa y el equilibrio ecol\u00f3gico. La soluci\u00f3n SAP est\u00e1 totalmente integrada en S\/4 Hana y en la arquitectura empresarial inteligente, y tambi\u00e9n puede vincularse a otras fuentes de datos. Esto permite evaluar autom\u00e1ticamente la huella a lo largo de toda la cadena de valor, incluso en entornos de sistemas heterog\u00e9neos.<\/p>\n\n\n\n<p><em>\"La asociaci\u00f3n con BearingPoint acelera la hoja de ruta de soluciones para SAP Product Footprint Management y nos ayudar\u00e1 a convertirnos en uno de los principales proveedores de soluciones para el c\u00e1lculo de la huella ecol\u00f3gica de los productos. Estas soluciones ayudar\u00e1n a nuestros clientes a hacer sus productos y servicios significativamente m\u00e1s sostenibles\".<\/em>afirma Peter Maier, Presidente de Industrias y Asesoramiento al Cliente de SAP.<\/p>","protected":false},"excerpt":{"rendered":"<p>La medici\u00f3n y la gesti\u00f3n de la huella de CO\u2082 desempe\u00f1an un papel importante en la consecuci\u00f3n de las emisiones netas cero. SAP y BearingPoint tambi\u00e9n lo saben.<\/p>","protected":false},"author":38,"featured_media":112496,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,40469,161],"tags":[826,37632,236,39829],"coauthors":[19920],"class_list":["post-112495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-22-03","category-szene","tag-bearingpoint","tag-co2","tag-sap","tag-szene","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1928699927-NicoElNino-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Den CO\u2082-Fu\u00dfabdruck zu messen und zu steuern spielt eine wichtige Rolle beim Erreichen von Netto-null-Emissionen. Das wissen auch SAP und BearingPoint.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/es\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/es\/category\/mag-22-03\/\" rel=\"category tag\">Mag 22-03<\/a>, <a href=\"https:\/\/e3mag.com\/es\/category\/szene\/\" rel=\"category tag\">Szene<\/a>","author_info_v2":{"name":"Revista E-3","url":"https:\/\/e3mag.com\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/112495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/comments?post=112495"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/112495\/revisions"}],"predecessor-version":[{"id":137764,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/posts\/112495\/revisions\/137764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media\/112496"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/media?parent=112495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/categories?post=112495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/tags?post=112495"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/es\/wp-json\/wp\/v2\/coauthors?post=112495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}