{"id":9553,"date":"2016-10-01T00:36:46","date_gmt":"2016-09-30T22:36:46","guid":{"rendered":"http:\/\/e3mag.com\/?p=9553"},"modified":"2022-02-06T00:53:26","modified_gmt":"2022-02-05T23:53:26","slug":"auf-wolke-sieben","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/auf-wolke-sieben\/","title":{"rendered":"HR-Cloud &#8211; Auf Wolke sieben?"},"content":{"rendered":"<p><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2016\/10\/CRex.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Hr-cloud &#8211; auf wolke sieben?\" class=\" wp-image-9567 alignright\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2016\/10\/CRex.jpg\" alt=\"Christine Rex\" width=\"261\" height=\"409\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2016\/10\/CRex.jpg 321w, https:\/\/e3mag.com\/wp-content\/uploads\/2016\/10\/CRex-100x157.jpg 100w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/a>Rund 54 Prozent der Unternehmen in Deutschland setzten 2015 Cloud Computing ein. Ein deutliches Plus im Vergleich zum Vorjahr mit 44 Prozent. Das hat eine Umfrage von Bitkom Research im Auftrag der KPMG ergeben, die in rund 450 Unternehmen durchgef\u00fchrt wurde.<\/p>\n<p>Laut Bitkom Research stehen Personaler den Cloud-L\u00f6sungen oftmals noch reserviert gegen\u00fcber. Wurde jedoch im Unternehmen eine Cloud-Strategie entwickelt, so ist die Einstellung zur Cloud in der Personalabteilung deutlich positiver.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3353817323\"><div id=\"great-4210156436\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>Die HR-Trendstudie 2015 von Kienbaum hat ergeben, dass Cloud-L\u00f6sungen im HR-Bereich einen vergleichsweise hohen Stellenwert einnehmen, der sich zuk\u00fcnftig weiter verst\u00e4rken wird.<\/p>\n<p><strong>Fazit:<\/strong> Es ist ein Trend Richtung HR-Cloud zu erkennen. Wenn das Unternehmen mit gutem Beispiel vorangeht, hat dies einen positiven Einfluss auf die Haltung der Personalabteilung gegen\u00fcber Cloud-L\u00f6sungen.<\/p>\n<h3>Reaktion von SuccessFactors<\/h3>\n<p>Die Unsicherheit von Personalern gegen\u00fcber der HR-Cloud liegt oftmals im Datenschutz begr\u00fcndet.<\/p>\n<p><em>Sind die Daten in der Cloud wirklich sicher?<\/em><\/p>\n<p>SAP SuccessFactors hat darauf bereits reagiert. Die Daten deutscher Kunden werden in einem deutschen Hochsicherheitszentrum gespeichert.<\/p>\n<p>Die SAP Cloud wird jedes Jahr extern hinsichtlich verschiedener Standards getestet, darunter ISO 27001, ISAE-3402 und SSAE-16. Insgesamt investiert SAP j\u00e4hrlich mehr als 500.000 Euro, um die SAP Cloud zu pr\u00fcfen.<\/p>\n<p>Ob der Weg in die HR-Cloud der richtige ist, muss jedes Unternehmen selbst f\u00fcr sich entscheiden.<\/p>\n<p>Dabei sind zun\u00e4chst eine Analyse und Bewertung der Systemlandschaft n\u00f6tig.<\/p>\n<p>Bei HR-Systemen, die in der Cloud laufen, handelt es sich stets um Software-as-a-Service-L\u00f6sungen (SaaS). In diesem Falle wird die Software gemietet und es kann aus verschiedenen Cloud-Umsetzungsmodellen gew\u00e4hlt werden.<\/p>\n<p>In der Public Cloud teilen sich mehrere Kunden eine gemeinsame Infrastruktur. Hingegen bei der Private Cloud mietet ein Kunde die Infrastruktur f\u00fcr sich allein.<\/p>\n<p>Von der Hybrid Cloud profitieren vor allem Unternehmen, die nicht alle HR-Prozesse in die Cloud verlagern m\u00f6chten.<\/p>\n<p>Die Hybrid Cloud ist eine Mischform aus On-Premise und Cloud \u2013 manchmal allerdings auch aus Public und Private Cloud.<\/p>\n<p>In ersterem Fall ist zu \u00fcberlegen, welche HR-Prozesse on premise genutzt und welche besser in die Cloud ausgelagert werden. Die Nutzung der Hybrid Cloud macht besonders dann Sinn, wenn das Unternehmen bereits HR-L\u00f6sungen on premise betreibt.<\/p>\n<p>Auch SAP SuccessFactors bietet diese hybride L\u00f6sung an, sodass Kunden schrittweise und in der passenden Geschwindigkeit in die HR-Cloud gehen k\u00f6nnen.<\/p>\n<h3>HR-Erfolgstreiber<\/h3>\n<p>Es gibt also viele Wege, die in die HR-Cloud f\u00fchren. Wichtig ist es, die M\u00f6glichkeiten ausreichend zu analysieren und passend zur Unternehmensstrategie auszurichten.<\/p>\n<p>Um einen Beitrag zum Unternehmenserfolg zu leisten, muss sich auch die Personalabteilung Gedanken \u00fcber ihre strategische Ausrichtung machen. Wo liegen die HR-Erfolgstreiber?<\/p>\n<p>Wichtig ist die Ausrichtung und Produktivit\u00e4t der Mitarbeiter. Zu pr\u00fcfen ist, ob sich die Mitarbeiter auf die Umsetzung der Unternehmensstrategie fokussieren und entsprechend ihren zugewiesenen Aufgaben handeln.<\/p>\n<p>Es gilt, in die Mitarbeiter zu investieren. Dabei stellt sich die Frage, wie sich ihre aktuellen Leistungen erhalten oder sogar verbessern lassen.<\/p>\n<p>#Au\u00dferdem sind die HR-Prozesse sicherzustellen, um stets die richtige Anzahl an Talenten im Unternehmen zu haben \u2013 nach dem Grundsatz: der richtige Mitarbeiter zur richtigen Zeit im richtigen Job.<\/p>\n<h3>Unterst\u00fctzung durch HR-Cloud<\/h3>\n<p>Wie kann die HR-Cloud diese Erfolgstreiber unterst\u00fctzen?<\/p>\n<p>Allein rein administrative Prozesse wie Core HR, Payroll und Zeitwirtschaft helfen nicht weiter, die Unternehmensergebnisse zu verbessern.<\/p>\n<p>Die strategischen Erfolgsfaktoren werden durch strategische HR-Prozesse unterst\u00fctzt, die sich im Talentmanagement wiederfinden.<\/p>\n<p>Der Weg f\u00fchrt hier in die Cloud. So hat beispielsweise SAP SuccessFactors mit seiner HCM Suite eine benutzerfreundliche L\u00f6sung entwickelt, die Talentmanagement und weitere HR-Anwendungen in einem zentralen System umfasst.<\/p>\n<p>Das HR-Cloud-System ist wesentlich schneller einsatzbereit. Aufw\u00e4ndige Installationen fallen weg.<\/p>\n<p>Das Mieten eines zentralen Cloud-Systems bringt zudem weitaus weniger Personal- und Verwaltungsaufwand sowie geringere Betriebskosten mit sich als eine eigene IT-Infrastruktur.<\/p>\n<h3>Globale Vernetzung<\/h3>\n<p>Gro\u00dfer Vorteil der Cloud: Das HR-System ist online jederzeit abrufbar und stets aktuell. Dies spielt besonders bei global ausgerichteten Unternehmen eine gro\u00dfe Rolle.<\/p>\n<p>Mitarbeiter k\u00f6nnen unabh\u00e4ngig von ihrem Standort global und ohne Extra-In\u00adstallationen zusammenarbeiten. Und eine intuitiv bedienbare, stets abrufbare Software kommt gerade bei der zunehmenden Generation Y gut an, die die Nutzung moderner Systeme aufgrund der sozialen Medien gewohnt ist.<\/p>\n<p>Bei steigenden Mitarbeiterzahlen ist das Cloud-System zudem schnell und einfach skalierbar. Diese Flexibilit\u00e4t ist insbesondere bei schnell wachsenden Unternehmen von Vorteil.<\/p>\n<p>Wichtig sind hier auch flexibel anpassbare L\u00f6sungen, die ganz auf den Bedarf des Unternehmens abgestimmt werden k\u00f6nnen.<\/p>\n<p>Auch in der HR-Cloud lassen sich die Anforderungen kundenindividuell umsetzen. Je nach Unternehmen und Branche weichen die HR-Prozesse teilweise ab, sodass individuelle Funktionalit\u00e4ten au\u00dferhalb des Standardpakets gefragt sein k\u00f6nnen.<\/p>\n<p>SAP hat darauf bereits reagiert. Auf der SAP Hana Cloud Platform (PaaS) bieten SAP-Partnerunternehmen Applikationen zur Erweiterung von SAP SuccessFactors an. Ein Beispiel f\u00fcr eine solche individualisierbare Anwendung ist der Ingentis org.manager [web] for SF.<\/p>\n<p>Die SAP-zertifizierte L\u00f6sung f\u00fcr automatisierte Organigramme und Personalberichte ist auf der SAP Hana Cloud Platform verf\u00fcgbar und bietet flexible Visualisierungsm\u00f6glichkeiten.<\/p>\n<p>Jede hierarchische Struktur kann mit Ingentis org.manager [web] for SF in Echtzeit angezeigt werden \u2013 egal ob es sich dabei um Organisationen, Personen, Stellen oder Hierarchien von HR-F\u00fchrungskr\u00e4ften handelt.<\/p>\n<p>Auch fachliche Berichtslinien lassen sich abbilden.<\/p>\n<h3>Integration in SAP SuccessFactors<\/h3>\n<p>Die SAP SuccessFactors Extension ist direkt in das Men\u00fc von SAP SuccessFactors integriert. Der Nutzer kann sich oder einen Kollegen in SAP SuccessFactors anw\u00e4hlen und anschlie\u00dfend direkt an die passende Stelle im Organigramm springen.<\/p>\n<p>Sowohl den Inhalten als auch dem Design sind keine Grenzen gesetzt. Kennzahlen wie Mitarbeiterzahl, Demografieanalyse, Fehlzeiten oder Budgetvergleich lassen sich direkt im Organigramm anzeigen.<\/p>\n<p>Die L\u00f6sung ist zudem individuell an das Corporate Design anpassbar und verf\u00fcgt \u00fcber umfangreiche Print- und Exportfunktionen.<\/p>\n<h3>Die 4 R als Grundlage von HR-Arbeit<\/h3>\n<p>Warum sind flexible HR-Cloud-Systeme so wichtig?<\/p>\n<p>Oberstes Ziel der HR-Arbeit sind die 4 R. So m\u00fcssen die richtigen Mitarbeiter an das Unternehmen gebunden werden<em> (Right people).<\/em><\/p>\n<p>Es ist sicherzustellen, dass sie produktiv arbeiten <em>(Right way).<\/em> Dar\u00fcber hinaus m\u00fcssen Zielvereinbarungen getroffen werden, die an der Unternehmensstrategie ausgerichtet sind <em>(Right things)<\/em>.<\/p>\n<p>Im letzten Schritt m\u00fcssen L\u00fccken identifiziert und die Weiterentwicklung der Mitarbeiter gef\u00f6rdert werden.<\/p>\n<p>Auch das Thema Nachfolgeplanung sollte angegangen werden <em>(Right development)<\/em>.<\/p>\n<p>Wie k\u00f6nnte das f\u00fcnfte R hei\u00dfen? Das f\u00fcnfte R sollte f\u00fcr \u201e<em>Right HR cloud system\u201c<\/em> stehen. Denn mit dem richtigen HR-Cloud-System, das schlank und flexibel aufgebaut ist, werden die 4 R optimal unterst\u00fctzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welche Wege f\u00fchren in die HR-Cloud und was ist dabei zu beachten? Was bietet SAP SuccessFactors? <\/p>\n","protected":false},"author":123,"featured_media":9563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[704],"tags":[5870,5008,5872,4386,5010,281,5867,5868,117,5828],"coauthors":[24244],"class_list":["post-9553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag1610","tag-hr-prozesse","tag-hybrid-cloud","tag-ingentis","tag-on-premise","tag-public-cloud","tag-saas","tag-sap-cloud","tag-sap-successfactors","tag-sicherheit","tag-talentmanagement","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",400,220,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-768x422.jpg",768,422,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-100x55.jpg",100,55,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-480x264.jpg",480,264,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-640x351.jpg",640,351,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-720x395.jpg",720,395,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-960x527.jpg",960,527,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",18,10,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",1000,549,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",600,329,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199.jpg",600,329,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/02\/shutterstock_125440199-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Welche Wege f\u00fchren in die HR-Cloud und was ist dabei zu beachten? Was bietet SAP SuccessFactors? <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/mag1610\/\" rel=\"category tag\">MAG 16-10<\/a>","author_info_v2":{"name":"Christine Rex, Ingentis","url":"https:\/\/e3mag.com\/de\/author\/christine-rex\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/9553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=9553"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/9553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/9563"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=9553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=9553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=9553"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=9553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}