{"id":95436,"date":"2021-08-30T08:04:00","date_gmt":"2021-08-30T06:04:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=95436"},"modified":"2022-05-01T10:03:31","modified_gmt":"2022-05-01T08:03:31","slug":"kritischer-faktor-einer-fusiondie-moderne-finanzabteilung","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/kritischer-faktor-einer-fusiondie-moderne-finanzabteilung\/","title":{"rendered":"Kritischer Faktor einer Fusion: die moderne Finanzabteilung"},"content":{"rendered":"\n<p>Wachstum ist das A und O in der Marktwirtschaft. Um dieses Ziel zu erreichen, setzen einige Unternehmen auf den Ausbau ihrer Kernkompetenz, andere dagegen auf die Diversifizierung ihres Angebots. Wer die Erweiterung oder Modifizierung seiner Produkte bzw. Dienstleistungen nicht aus eigener Kraft leisten kann, kauft diese in der Regel dazu. <\/p>\n\n\n\n<p>Genau diese Strategie ist einer der Gr\u00fcnde, weshalb es immer mehr Unternehmens\u00fcbernahmen und Fusionen gibt. Selbst w\u00e4hrend der Pandemie blieb das \u00dcbernahmeinteresse hoch, wie Experten aus den Bereichen der Rechtsberatung, des Bankwesens oder des Private Equity berichten. Viele Fachleute teilen die Ansicht, dass Fusionen ein entscheidender Erfolgsfaktor sein k\u00f6nnen. <\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-2048705704\"><div id=\"great-2651863649\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Rick Smith, Gesch\u00e4ftsf\u00fchrer des Insolvenz- und Unternehmenssanierungs-Spezialisten Forbes Burton, beispielsweise glaubt sogar, dass Fusionen eine besonders effektive Strategie sein k\u00f6nnen, die Coro-na-krise zu \u00fcberstehen: \u201e<em>Die Vorteile liegen auf der Hand. Arbeitspl\u00e4tze k\u00f6nnen gesichert werden, das Gesch\u00e4ft wird weitergef\u00fchrt und es ist eine gro\u00dfartige M\u00f6glichkeit f\u00fcr Gesch\u00e4ftsf\u00fchrer sich zur\u00fcckzuziehen, wenn sie sich anderen Dingen widmen wollen.<\/em>\u201c<\/p>\n\n\n\n<p>Eine Firmen\u00fcbernahme ist aber nicht nur der Einkauf von Know-how oder Marktanteilen. Es werden auch eine bestehende Struktur, etablierte Prozesse und eine gewachsene IT-Umgebung \u00fcbernommen. Und gerade hier liegt das Problem, denn sowohl die Strukturen als auch Workflows m\u00fcssen integriert werden. Ein besonderes Augenmerk gilt dabei der Finanzabteilung. Sie ist der Dreh- und Angelpunkt, denn hier laufen alle Unternehmensdaten zusammen. <\/p>\n\n\n\n<p>Doch jedes Unternehmen organisiert seine Buchhaltung etwas anders \u2013 hat unterschiedliche Tools und Prozesse f\u00fcr den Monatsabschluss, die Bilanzen oder das ERP im Einsatz. Wer also eine Fusion zum Erfolg machen will, sollte zuallererst die verschiedenen Buchhaltungs-Ecosysteme konsolidieren; alles andere ist auf lange Sicht zweitrangig. Warum? Weil Manager immer, aber vor allem nach einer Fusion schnell einen genauen \u00dcberblick \u00fcber die konsolidierten Zahlen und Ergebnisse ben\u00f6tigen, um die richtigen Weichen zu stellen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Krux mit den Finanzprozessen<\/h3>\n\n\n\n<p>Viele Fusionen erscheinen in den Nachrichten atemberaubend. Wie selbstverst\u00e4ndlich berichten Unternehmensvertreter von hervorragenden Synergieeffekten, ausgezeichneten Marktchancen und Wachstumsraten. Doch um dorthin zu kommen, bedarf es nicht etwa eines Qu\u00e4ntchens Gl\u00fcck, sondern vor allem eines soliden \u00dcbernahmekonzepts, das idealerweise in der Buchhaltung seinen Ausgangspunkt hat. <\/p>\n\n\n\n<p>Integration, Automatisierung und Digitalisierung sind die Aufgaben, an denen niemand vorbeikommt, denn die Realit\u00e4t zeigt, dass Fusionen erstens oft auch daran kranken, dass die Systeme und Prozesse in den zusammenzuf\u00fchrenden Finanzabteilungen zu unterschiedlich sind. Zweitens d\u00fcrfen die Mitarbeiter und ihre Bed\u00fcrfnisse nicht aus dem Blickfeld geraten. Dabei sind es nicht selten die Mitarbeiter und ihre Einstellung zur \u00dcbernahme, die einen entscheidenden Einfluss auf den Erfolg oder Misserfolg des Unterfangens haben. &nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Herkulesaufgabe: Fusion und manuelle Prozesse<\/h3>\n\n\n\n<p>Doch es kommt eine weitere H\u00fcrde hinzu: die manuellen Prozesse. Auch ohne die Herausforderung durch eine Fusion sind sie schon ein nicht zu untersch\u00e4tzendes Problem. Schwierig sind sie nicht nur, weil wichtiges Wissen in den K\u00f6pfen einzelner Mitarbeiter steckt und manuelle Prozesse fehleranf\u00e4lliger sind. Sie nehmen auch unglaublich viel Zeit in Anspruch, sind vielfach frustrierend und verhindern ein agiles Handeln. <\/p>\n\n\n\n<p>In komprimierter Form findet man all diese Herausforderungen in Finanzabteilungen, deren Strukturen noch auf traditionellen Vorgehensweisen basieren: der Anwendung von Tabellenkalkulationen, dem h\u00e4ndischen Abgleich von Daten und deren manuellen \u00dcbertragungen in andere Systeme. Das alles steht im diametralen Gegensatz zum sogenannten Modern Accounting, einem digitalen und durchg\u00e4ngigen Abschlussprozess, welcher der Finanzabteilung ganz neue M\u00f6glichkeiten er\u00f6ffnet. Denn worum geht es? <\/p>\n\n\n\n<p>Gerade gro\u00dfe Unternehmen, die nicht standardisierte lokale Daten und Zahlen weltweit in einem SSC (Shared Service Center) verarbeiten m\u00fcssen, haben mit manuellen Prozessen Probleme: Sie sind langsam, nicht transparent, unsicher, kaum flexibel und fehleranf\u00e4llig. Insbesondere bei einer Fusion kann das fatale Folgen haben. Ohne tagesaktuelle, valide Zahlen l\u00e4sst sich in den heutigen dynamischen M\u00e4rkten kaum noch sinnvoll navigieren. Ergo: besser heute einen Modern- Accounting-Prozess einf\u00fchren als morgen. &nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/08\/Transformation-zu-CA_A5-pdf-1030x726.jpg\" alt=\"\" class=\"wp-image-95439\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Erfolgreiche Integration und Standardisierung in f\u00fcnf Schritten<\/h3>\n\n\n\n<p>F\u00fcr eine straff geplante und schnelle Inte-gration von Finanzprozessen und Systemen bei einer Fusion oder \u00dcbernahme gibt es f\u00fcnf prinzipielle Erfolgsfaktoren: Erstens, ein vereinheitlichtes System mit durchg\u00e4ngig g\u00fcltigen Prozessen. Zweitens, eine gr\u00f6\u00dftm\u00f6gliche Automatisierung manueller Prozesse. Drittens, die Herstellung durchg\u00e4ngiger Transparenz und Verf\u00fcgbarkeit von Finanzzahlen, um dem Management eine solide Entscheidungsgrundlage zu bieten. <\/p>\n\n\n\n<p>Viertens, die kontinuierliche Verbesserung des Standardprozesses f\u00fcr die Organisations- und Finanzsysteme sowie Business-L\u00f6sungen. Der f\u00fcnfte Aspekt betrifft die Mitarbeiter. Durch die hinzugewonnene Zeit k\u00f6nnen sich die Finanzprofis mehr um Auswertungen und Prognosen k\u00fcmmern, was sie zu wichtigen Partnern des Unternehmensmanagements macht.&nbsp;<\/p>\n\n\n\n<p>F\u00fcr diese f\u00fcnf Schritte ist es von Vorteil, wenn das \u00fcbernehmende Unternehmen bereits eine intelligente Automatisierungsplattform implementiert hat, denn dann sind die Prozesse und Systeme bereits standardisiert und es herrschen Visibilit\u00e4t und Transparenz. Ein weiterer Pluspunkt: Accounting-Plattformen gliedern sich dann nahtlos in ERP-Systeme wie von SAP oder anderen ERP-Anbietern ein. Sie \u00fcbernehmen Aufgaben, die klassisch von den ERP-L\u00f6sungen nicht geleistet werden. Aber was gilt es zu beachten?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u00f6sung f\u00fcr Flexibilit\u00e4t und Kontrolle<\/h3>\n\n\n\n<p>Es ist kein Geheimnis, dass viele F-und-A-L\u00f6sungen Unterst\u00fctzung seitens technischer Berater oder der IT ben\u00f6tigen. Und genau das hindert die Buchhaltung daran, agil und reaktionsschnell zu sein. &nbsp; Aber es geht auch anders: Mit L\u00f6sungen, etwa von BlackLine, k\u00f6nnen die Prozesse und Systeme von den Teams direkt in die Plattform des neuen Unternehmens integriert werden. Dabei kommen Best-Practices-Prinzipien zum Einsatz, Daten werden bereinigt und ineffiziente Arbeitsschritte werden reduziert. <\/p>\n\n\n\n<p>Eine zweckgebundene Automatisierung, etwa durch automatisches Lernen, hilft bei Aufgaben wie beispielsweise dem Abgleich von Transaktionen. Schwellenwerte f\u00fcr Abweichungen und Ausnahmen sind mit nur wenigen Klicks erledigt. Best-Practice-Vorlagen beschleunigen die Standardisierung, schaffen Transparenz, sodass sich Berichtsfelder oder Dashboards on-the-fly \u00e4ndern lassen, ohne dass ein technischer Berater konsultiert werden muss.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Einheitliche Plattform sorgt f\u00fcr Produktivit\u00e4t und Konsistenz<\/h3>\n\n\n\n<p>Zu viele Datensilos, unterschiedliche Benutzererfahrungen und fragmentierte Workflows mindern die Leistung der Buchhaltung. Moderne und auf der Cloud basierende Accounting-L\u00f6sungen sorgen daf\u00fcr, dass alle Finanzdaten und Prozesse zentralisiert, vereinheitlicht und von \u00fcberall zug\u00e4nglich sind. Dieses harmonische Zusammenspiel macht Abschl\u00fcsse, Abstimmungen sowie Journalbuchungen leichter und den Finanzabschluss smarter. <\/p>\n\n\n\n<p>Eine einheitliche Benutzeroberfl\u00e4che bietet Dashboards, die einen Echtzeiteinblick in den Finanzabschluss gew\u00e4hren. Unkompliziert kann dann auf Abweichungen, unvollst\u00e4ndige Aufgaben oder \u00fcberf\u00e4llige Posten reagiert werden. Un\u00fcbersichtliche, nicht zusammenh\u00e4ngende Schnittstellen, mehrere Log-ins oder Tabellenkalkulationen sind Schnee von gestern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vernetzte Plattform<\/h3>\n\n\n\n<p>Daten flie\u00dfen aus verschiedenen Anwendungen, einschlie\u00dflich ERP, Nebenbuchhaltung, Steuern, Treasury, Ausgaben, Gehaltsabrechnung und externer Banksysteme, in der Buchhaltung zusammen. Daher ist eine direkte ERP-agnostische Integration essenziell. <\/p>\n\n\n\n<p>BlackLine beispielsweise ist in der Lage, mit \u00fcber 100 verschiedenen Systemen nahtlos zusammenzuarbeiten. Es unterst\u00fctzt eine Vielzahl von Out-of-the-Box-Konnektoren zu SAP und Systemen anderer Anbieter, um Summen- und Detaildaten zu integrieren, beispielsweise um Journalbuchungen im Hauptbuch zu buchen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Durchg\u00e4ngige Automatisierung reduziert Arbeitsbelastung<\/h3>\n\n\n\n<p>Viele L\u00f6sungen f\u00fcr den Finanzabschluss automatisieren zu wenig. Wichtige Monatsabschlussaufgaben erfolgen erst am Monatsende, wodurch die Buchhaltung ins Hintertreffen ger\u00e4t. Umso wichtiger ist eine h\u00f6chstm\u00f6gliche Automatisierung, denn nur sie sorgt f\u00fcr die erforderliche kontinuierliche Echtzeitverarbeitung und entlastet bei den zahlreichen Monatsabschlussaufgaben. Eine Modern-Accounting-L\u00f6sung, wie die von BlackLine, hilft aber nicht nur den Buchhaltern, sondern auch den Controllern, die so einen besseren \u00dcberblick \u00fcber die Finanzen haben.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Schl\u00fcsselfaktor Modern Accounting<\/h3>\n\n\n\n<p>Die zu \u00fcbernehmenden Unternehmen haben oft komplexe Systeme und Prozesse mit vielen risikoreichen, sehr alten Posten. Aber auf der Grundlage des Modern Accounting entstehen die ben\u00f6tigte Flexibilit\u00e4t und \u00dcbersicht. Das hilft den Unternehmen schon einmal grunds\u00e4tzlich, aber vor allem, wenn es darum geht, Unternehmensstrukturen zusammenzuf\u00fchren. <\/p>\n\n\n\n<p>Wenn die L\u00fccke zwischen den Systemen durch ein \u00fcbergeordnetes Konzept und die entsprechende Technologie, das sogenannte Modern Accounting, geschlossen wird, sind die Unternehmen in der Lage, ihre Workflows und Prozesse auf das n\u00e4chste Level zu heben. Die Ziele sind klar gesteckt: Modern Accounting hilft bei der Bew\u00e4ltigung von F-und-A-Herausforderungen, beim Minimieren von Risiken und optimiert die Kapazit\u00e4ten im Team. Es steht f\u00fcr die Modernisierung des Rechnungswesens und f\u00fcr einen weiteren wichtigen Schritt im Optimierungsprozess: das Continuous Accounting.&nbsp;<\/p>\n\n\n\n<p>Modern Accounting basiert auf vier wesentlichen Prinzipien:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Der Harmonisierung der Daten,<br>Aufgaben und Prozesse<\/li><li>Der Automatisierung von<br>Accounting-Aufgaben<\/li><li>Der Bilanzierung und Kontoanalyse<br>mit Risikoreduzierung<\/li><li>Dem Analysieren der Daten inklusive der Berichterstattung<\/li><\/ul>\n\n\n\n<p>Modern Accounting reduziert die manuellen, Excel-gest\u00fctzten T\u00e4tigkeiten und schafft Sichtbarkeit sowie Transparenz. Das Finanzteam konzentriert sich nur noch auf wertsch\u00f6pfende Arbeit und kann als Gesch\u00e4ftspartner agieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">K\u00f6nigsdisziplin Continuous Accounting<\/h3>\n\n\n\n<p>Das Continuous Accounting ist eine direkte Folge, die aus dem Modern-Accounting-<br>Ansatz hervorgeht. Es l\u00f6st die Probleme einer manuellen, risikobehafteten und vor allem zeitaufw\u00e4ndigen Buchhaltung, indem es auf einen kontinuierlichen Prozess setzt. Es ist das Ziel des Continuous Accounting, Buchungen, Kontenabstimmungen, Analysen und Kontrollen nicht mehr am Ende des Monats, Quartals oder Jahres durchzuf\u00fchren. Vielmehr werden die Buchungen w\u00e4hrend der gesamten Abrechnungsperiode und mit tagesaktuellen Daten vorgenommen \u2013 kontinuierlich. <\/p>\n\n\n\n<p>Transaktionen und Konten werden unmittelbar zu dem Zeitpunkt erfasst und abgeglichen, wann sie tats\u00e4chlich passieren. Daraus ergeben sich gro\u00dfe Vorteile: Abweichungen werden nicht erst am Ende eines Berichtzeitraums entdeckt und k\u00f6nnen ohne Zeitdruck beseitigt werden. Folglich k\u00f6nnen die Spezialisten aus den Finanzabteilungen solide Analysen durchf\u00fchren und Empfehlungen gegen\u00fcber der Gesch\u00e4ftsf\u00fchrung aussprechen \u2013 und zwar in Echtzeit.&nbsp;<\/p>\n\n\n\n<p>M\u00f6glich wird Continuous Accounting mithilfe leistungsf\u00e4higer Softwarel\u00f6sungen, etwa f\u00fcr die Kontenabstimmung, die Abweichungsanalyse oder den Transaktionsabgleich. Dies erleichtert das Schlie\u00dfen der B\u00fccher, verteilt die Arbeit effizienter \u00fcber die gesamte Periode hinweg und erh\u00f6ht sowohl Qualit\u00e4t als auch Transparenz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fazit: Die Zeit ist reif<\/h3>\n\n\n\n<p><br>Ob bei einer Firmen\u00fcbernahme, einer Fusion oder im Zuge einer generellen Modernisierung der Finanzabteilung \u2013 dringend n\u00f6tig ist ein gutes Change-Management. Es braucht einen Verantwortlichen, der sich nicht nur mit den Prozessen einer Ver\u00e4nderung in einer Organisation auskennt, sondern der auch tiefe Einblicke hat, welche M\u00f6glichkeiten heute mit unterschiedlichen Systemen bestehen. <\/p>\n\n\n\n<p>Das grunds\u00e4tzliche Ziel muss eine Transformation sein, bei der unterschiedliche Systeme und Prozesse zentral in eine Einheit \u00fcberf\u00fchrt werden. Im Kontext einer Fusion ist die Integration der Finanzsysteme sogar ein noch kritischerer Erfolgsfaktor als ohnehin schon. Denn eines darf man nicht vergessen: Sp\u00fcrt das Finanzteam des \u00fcbernommenen Unternehmens, dass es ab sofort mit der bestm\u00f6glichen Unterst\u00fctzung rechnen und den f\u00fchrenden L\u00f6sungen arbeiten darf, wird es umso motivierter den Wandel unterst\u00fctzen. <\/p>\n\n\n\n<p>Experten raten deshalb dazu, die Planung der Umstellung in der Finanzabteilung sogar bereits im Rahmen der Due-Dili-gence-Phase zu initiieren. Wer m\u00f6gliche Risiken, Chancen und Ma\u00dfnahmen bereits im Vorfeld analysiert und plant, ist klar im Vorteil und kann die Fr\u00fcchte einer Fusion schneller ernten. Warum also noch warten mit der Einf\u00fchrung von Modern Accounting?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/blackline\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" title=\"Kritischer faktor einer fusion: die moderne finanzabteilung\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline.jpg\" alt=\"https:\/\/e3mag.com\/partners\/blackline\/\" class=\"wp-image-43117\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Wachstum ist das A und O in der Marktwirtschaft. Um dieses Ziel zu erreichen, setzen einige Unternehmen auf den Ausbau ihrer Kernkompetenz, andere dagegen auf die Diversifizierung ihres Angebots. Wer die Erweiterung oder Modifizierung seiner Produkte bzw. Dienstleistungen nicht aus eigener Kraft leisten kann, kauft diese in der Regel dazu. Genau diese Strategie ist einer [&hellip;]<\/p>\n","protected":false},"author":2369,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[39800,39790],"tags":[5699,5238,35885,236],"coauthors":[39528],"class_list":["post-95436","post","type-post","status-publish","format-standard","hentry","category-extra-2109","category-mag-21-09","tag-blackline","tag-change-management","tag-finanzen","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","image-100":"","image-480":"","image-640":"","image-720":"","image-960":"","image-1168":"","image-1440":"","image-1920":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","bricks_large_16x9":"","bricks_large":"","bricks_large_square":"","bricks_medium":"","bricks_medium_square":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>Wachstum ist das A und O in der Marktwirtschaft. Um dieses Ziel zu erreichen, setzen einige Unternehmen auf den Ausbau ihrer Kernkompetenz, andere dagegen auf die Diversifizierung ihres Angebots. Wer die Erweiterung oder Modifizierung seiner Produkte bzw. Dienstleistungen nicht aus eigener Kraft leisten kann, kauft diese in der Regel dazu. Genau diese Strategie ist einer der Gr\u00fcnde, weshalb es immer mehr Unternehmens\u00fcbernahmen und Fusionen gibt. Selbst w\u00e4hrend der Pandemie blieb das \u00dcbernahmeinteresse hoch, wie Experten aus den Bereichen der Rechtsberatung, des Bankwesens oder des Private Equity berichten. Viele Fachleute teilen die Ansicht, dass Fusionen ein entscheidender Erfolgsfaktor sein k\u00f6nnen. Rick&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/extra-2109\/\" rel=\"category tag\">Extra 2109<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-21-09\/\" rel=\"category tag\">MAG 21-09<\/a>","author_info_v2":{"name":"Robert Kathmann, BlackLine","url":"https:\/\/e3mag.com\/de\/author\/robert-kathmann-blackline\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/95436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2369"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=95436"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/95436\/revisions"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=95436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=95436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=95436"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=95436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}