{"id":73953,"date":"2021-06-24T08:00:00","date_gmt":"2021-06-24T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=73953"},"modified":"2025-08-23T13:32:48","modified_gmt":"2025-08-23T11:32:48","slug":"rollenbasierte-arbeitsprozesse-und-bestandsplanung","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/rollenbasierte-arbeitsprozesse-und-bestandsplanung\/","title":{"rendered":"Rollenbasierte Arbeitsprozesse und Bestandsplanung"},"content":{"rendered":"\n<p>Es ist unerl\u00e4sslich, die Logistik zu vereinheitlichen und zu zentralisieren. SAP-Bestandskunde Karl Mayer, ein internationaler Hersteller von Textilmaschinen, hat sein bisheriges System um eine SAP-basierte L\u00f6sung erweitert, um die von SAP gesteuerten Prozesse zu optimieren. Die Rule Workbench (RWB) und das Role Administration Cockpit (RAC) aus dem Hause GIB sorgen seitdem f\u00fcr verbesserte Best\u00e4nde und reduzieren operative Bearbeitungszeiten durch rollenbasierte Arbeitsprozesse. Das Maschinenbau-unternehmen hat sich seit seiner Gr\u00fcndung 1937 zu einer internationalen Unternehmensgruppe entwickelt. Als innovativer Marktf\u00fchrer im Textilmaschinenbau bietet der Hersteller L\u00f6sungen f\u00fcr die beiden wichtigsten Maschenbildungsverfahren, Wirken und Stricken, sowie f\u00fcr die Bereiche Technische Textilien, Kettvorbereitung Weberei und Digitalisierung. Heute hat das Unternehmen Niederlassungen in den USA, England, Indien, Italien, Hongkong, Japan, China, Bangladesch und in der Schweiz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Globale Logistik<\/h3>\n\n\n\n<p>Das internationale Wachstum war eine Herausforderung f\u00fcr die logistischen Prozesse. Es gab unternehmensweit keine allge\u00admeinen Regeln, wie ein Sicherheitsbestand zu berechnen ist. Die Sicherheitsbest\u00e4nde wurden nicht in regelm\u00e4\u00dfigen Abst\u00e4nden gepr\u00fcft, sondern nur, wenn eine offene Bestell\u00adanforderung vorlag. Zus\u00e4tzlich organisierten die Disponenten den Tagesablauf nicht nach einheitlichen Vorgaben.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-846094276\"><div id=\"great-4042028443\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>\u201eMit dieser Bestandsplanung bestand ein hohes Risiko zu geringer oder zu hoher Lagerbest\u00e4nde und damit auch das Risiko einer verz\u00f6gerten Produktion\u201c, erinnert sich Sonja Meyrose, Fachgruppenleiterin Materialwirtschaft bei Karl Mayer. \u201eUns wurde klar, dass wir eine einheitliche L\u00f6sung im Unternehmen brauchen, um den Tagesablauf der Disponenten besser zu strukturieren und so das Arbeiten effizienter zu machen. Die neu gewonnenen Zeitressourcen k\u00f6nnen dann zum Beispiel darauf verwendet werden, die Sicherheitsbest\u00e4nde professioneller zu planen, ebenfalls mit einer Software\u201c, so Meyrose zur Ausgangssituation.<\/p>\n\n\n\n<p>Da man bereits seit einigen Jahren erfolgreich mit den Modulen GIB Operations und GIB Controlling arbeitete, wurde auf den gleichen Entwickler gesetzt. SAP-Partner GIB hat sich auf die Optimierung logistischer Prozesse spezialisiert und die Module Rule Workbench (RWB) sowie Role Administration Cockpit (RAC) sollten als erg\u00e4nzende L\u00f6sung die Prozesse in der Logistikabteilung optimieren.<\/p>\n\n\n\n<p>Durch die Kompatibilit\u00e4t mit den bereits vorhandenen L\u00f6sungen sparte Karl Mayer bei der Implementierung Zeit. Lediglich sechs Monate vergingen vom Projektstart bis zum Go-live an den Standorten. Bis auf ein paar wenige Anpassungen verlief die Umsetzung reibungslos. Heute arbeiten rund 100 Anwender mit GIB Operations, Controlling und RAC, und das an s\u00e4mtlichen Standorten weltweit. Die Anwender waren von der Anwenderfreundlichkeit der Module positiv \u00fcberrascht. Die Benutzung ist ann\u00e4hernd selbsterkl\u00e4rend, sodass die Schulungsdauer f\u00fcr den T\u00e4tigkeitsnavigator rund einen halben Tag betrug. Operations ist etwas intensiver, erfordert ein bis zwei Tage Einweisung, sodass Mitarbeiter auch diese L\u00f6sung nutzen k\u00f6nnen. Ausl\u00e4ndische Standorte wurden entweder vor Ort oder per Videokonferenz geschult.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rollenbasiertes Cockpit<\/h3>\n\n\n\n<p>Die Einf\u00fchrung hat positive Effekte f\u00fcr die Arbeitsabl\u00e4ufe erzeugt. Besonders durch das Role-Administration-Cockpit f\u00e4llt Suchen und Navigieren im SAP-System weg und es erm\u00f6glicht, Aufgaben in Rekordzeit abzuwickeln. Das RAC blendet ungenutzte Funktionen aus und erleichtert so die Navigation. Einmalig m\u00fcssen regelm\u00e4\u00dfig wiederkehrende Aufgaben wie mit einem elektronischen Organizer geplant werden, damit der User in der personalisierten Maske alle To-dos sieht, die mit einem Doppelklick aufgerufen werden k\u00f6nnen. <\/p>\n\n\n\n<p>Ein gro\u00dfer Gewinn f\u00fcr das Tagesgesch\u00e4ft, findet Mey\u00adrose: \u201eDie Schaffung einheitlicher Standards in der Disposition bringt viel Transparenz, eine gewisse Austauschbarkeit bei Krankheit oder Urlaub und vor allem erleichtert sie das t\u00e4gliche Doing, da jedem Disponenten klar vor Augen gef\u00fchrt wird, welche T\u00e4tigkeiten zu erledigen sind.\u201c Die Bestandsplanung hat sich deutlich verbessert, bez\u00fcglich der Fehlteildarstellung, die komplett von Excel in GIB \u00fcberf\u00fchrt wurde. Die einheitliche Nutzung der Module an allen Standorten hat die Transparenz in der Disposition gesteigert, weil sich die Disponenten konzernweit einen \u00dcberblick \u00fcber Best\u00e4nde verschaffen und diese so auch besser optimieren k\u00f6nnen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e3mag.com\/partners\/gib-sales-development-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB.jpg\" alt=\"https:\/\/e3mag.com\/partners\/gib-sales-development-gmbh\/ \u200e\" class=\"wp-image-15616\" title=\"Rollenbasierte arbeitsprozesse und bestandsplanung\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-GIB-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/08\/2105_gib_E_web.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">PDF auf Englisch <\/a><\/h2>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Unternehmen mit mehreren Produktionsstandorten sind durch die globalisierten Logistikprozesse mehr gefordert. Die Bestandsplanung und die Unsicherheiten bei Angebot und Nachfrage stellen hohe Anforderungen an das SCM.<\/p>\n","protected":false},"author":2251,"featured_media":73443,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[4,39280],"tags":[4431,20968,7631],"coauthors":[38614,38928],"class_list":["post-73953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-21-05","tag-gib","tag-logistikprozesse","tag-scm","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/shutterstock-1813934876-VideoFlow-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Unternehmen mit mehreren Produktionsstandorten sind durch die globalisierten Logistikprozesse mehr gefordert. Die Bestandsplanung und die Unsicherheiten bei Angebot und Nachfrage stellen hohe Anforderungen an das SCM.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/management\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-21-05\/\" rel=\"category tag\">MAG 21-05<\/a>","author_info_v2":{"name":"GIB","url":"https:\/\/e3mag.com\/de\/author\/gib\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/73953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2251"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=73953"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/73953\/revisions"}],"predecessor-version":[{"id":154314,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/73953\/revisions\/154314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/73443"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=73953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=73953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=73953"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=73953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}