{"id":71615,"date":"2021-03-23T08:00:00","date_gmt":"2021-03-23T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=71615"},"modified":"2021-03-03T10:38:22","modified_gmt":"2021-03-03T09:38:22","slug":"konferenzstart-2021-in-berlin","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/konferenzstart-2021-in-berlin\/","title":{"rendered":"Konferenzstart 2021 in Berlin"},"content":{"rendered":"\n<p>Ein durchdachtes Smart-Networking-Konzept erm\u00f6glicht unter Ber\u00fccksichtigung der n\u00f6tigen Hygienema\u00dfnahmen den Austausch und die Vernetzung der Mitglieder untereinander. Als eine der ersten dieser Konferenzen wird die Disruptive Technologies &amp; Innovation Minds \u2013 kurz DTIM \u2013 als Hybrid-Event am 29. und 30. April live vor Ort in Berlin und online stattfinden. Das gr\u00f6\u00dfte deutschsprachige Industrie-Event zum Thema Innovation und Innovationsstrategien feiert au\u00dferdem sein Zehn-Jahr-Jubil\u00e4um! <\/p>\n\n\n\n<p>Von Innovationsmanagern \u00fcber marktf\u00fchrende Business-Development-Spezialisten zu den j\u00fcngsten Vision\u00e4ren unter den L\u00f6sungsanbietern f\u00fcr Innovations- und Technologiemanagement \u2013 wo auch immer Sie im Innovations-\u00d6kosystem stehen, das DTIM-Branchentreffen bietet Ihnen aufschlussreiche Inhalte und Gespr\u00e4che mit den Kontakten, die Sie weiterbringen. Neben hochkar\u00e4tigen Sprechern erwartet Sie vor allem ein breites Spektrum interaktiver Formate, sowohl vor Ort als auch online. <\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-2051962651\"><div id=\"great-3354459801\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Diskutieren Sie den Umgang mit Innovationsdruck, die Herausforderungen und Chancen digitaler Technologien und die komplexen Auswirkungen von Disruption. Seien Sie dabei und diskutieren Sie mit einflussreichen Innovationsspezialisten und New-Business-<br>Experten in Berlin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach einer langen Durststrecke f\u00fcr Live-Veranstaltungen wird<br \/>\nWe.Conect Global Leaders im Fr\u00fchling dieses Jahres wieder die ersten Konferenzen vor Ort in Berlin durchf\u00fchren. <\/p>\n","protected":false},"author":38,"featured_media":71618,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,38632],"tags":[],"coauthors":[19920],"class_list":["post-71615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-21-02","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2021\/02\/shutterstock1746605735-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Nach einer langen Durststrecke f\u00fcr Live-Veranstaltungen wird<br \/>\nWe.Conect Global Leaders im Fr\u00fchling dieses Jahres wieder die ersten Konferenzen vor Ort in Berlin durchf\u00fchren. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-21-02\/\" rel=\"category tag\">MAG 21-02<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/71615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=71615"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/71615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/71618"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=71615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=71615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=71615"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=71615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}