{"id":70653,"date":"2021-02-24T14:30:00","date_gmt":"2021-02-24T13:30:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=70653"},"modified":"2021-01-28T15:37:52","modified_gmt":"2021-01-28T14:37:52","slug":"idc-futurescape-wie-auf-die-folgen-von-corona-reagieren","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/idc-futurescape-wie-auf-die-folgen-von-corona-reagieren\/","title":{"rendered":"IDC FutureScape &#8211; Wie auf die Folgen von Corona reagieren?"},"content":{"rendered":"\n<p>Die Prognosen stehen im neuen IDC-FutureScape-Bericht, den Rick Villars, IDC Group Vice President Worldwide Research, in einer Live-Webkonferenz pr\u00e4sentierte. Die diesj\u00e4hrigen Vorhersagen sind von den heftigen Auswirkungen der Coronapandemie gepr\u00e4gt, die das globale Wirtschaftssystem in den n\u00e4chsten zw\u00f6lf bis 24 Monaten (und auch danach) dramatisch ver\u00e4ndern wird. <\/p>\n\n\n\n<p>Die Folgen von Corona sind omnipr\u00e4sent und beeinflussen auch die externen Faktoren, die den Wandel vorantreiben. Doch trotz der St\u00f6rungen durch die globale Pandemie im Jahr 2020 ist die Weltwirtschaft nach wie vor auf dem Weg zu ihrem \u201edigitalen Ziel\u201c, da die meisten Produkte und Dienstleistungen auf einem digitalen Liefermodell basieren oder eine digitale Erweiterung ben\u00f6tigen, um wettbewerbsf\u00e4hig zu bleiben. Diese Ver\u00e4nderung f\u00fchrt dazu, dass 65 Prozent des globalen BIP bis 2020 digital erwirtschaftet werden, was 6,8 Billionen US-Dollar an IT-Ausgaben von 2020 bis 2023 nach sich zieht.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3761999142\"><div id=\"great-2318111362\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Um diese Ver\u00e4nderungsphase erfolgreich zu meistern, m\u00fcssen sich CIOs und digital ambitionierte Vorst\u00e4nde in den n\u00e4chsten f\u00fcnf Jahren auf drei Bereiche konzentrieren. Sie m\u00fcssen kurzfristig alle Schnellsch\u00fcsse und M\u00e4ngel in der IT beheben, die w\u00e4hrend der anf\u00e4nglichen Krisenreaktion entstanden sind. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars.jpg\" alt=\"\" class=\"wp-image-70656\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-150x150.jpg 150w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-768x768.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-100x100.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-480x480.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-640x640.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-720x720.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-24x24.jpg 24w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-48x48.jpg 48w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-96x96.jpg 96w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/Rick-Villars-300x300.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Sie m\u00fcssen ermitteln, wo die Krise und die Reaktionen darauf die IT-Transformation in ihren Unternehmen beschleunigt haben, und an diesen Fortschritten festhalten. Und am wichtigsten: Sie m\u00fcssen nach M\u00f6glichkeiten suchen, neue Technologien einzuf\u00fchren, um die branchenweiten Umbr\u00fcche zu nutzen und mit erweiterten F\u00e4higkeiten das Gesch\u00e4ft in der \u201eneuen Normalit\u00e4t\u201d auszubauen.<\/p>\n\n\n\n<p><br>Ein detaillierter Blick in die Top Ten der weltweiten Prognosen der IT-Branche von IDC zeigt, dass sich der Wandel zur Zentralisierung in der Cloud beschleunigt. Bis Ende 2021 werden 80 Prozent der Unternehmen aufgrund der j\u00fcngst gemachten Erfahrungen einen Mechanismus einf\u00fchren, um doppelt so schnell wie vor der Pandemie auf cloudzentrierte Infrastrukturen und Anwendungen umzustellen. <\/p>\n\n\n\n<p>CIOs m\u00fcssen den \u00dcbergang zu einem cloudzentrierten IT-Modell beschleunigen, um wettbewerbsf\u00e4hig zu bleiben und das Unternehmen digital robuster aufzustellen.<br>Bis 2023 werden sich 75 Prozent der 2000 weltweit gr\u00f6\u00dften Unternehmen au\u00dferdem dazu verpflichten, ihre Arbeitnehmer technisch so auszustatten, dass sie von vornherein (und nicht erst gezwungen durch \u00e4u\u00dfere Umst\u00e4nde) r\u00e4umlich getrennt in Echtzeit zusammenarbeiten k\u00f6nnen. Das wird zu besser informierten, zusammenarbeitenden und produktiveren Mitarbeitern f\u00fchren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IDC hat ihre weltweiten Prognosen f\u00fcr die IT-Industrie f\u00fcr 2021 und Folgejahre ver\u00f6ffentlicht und erkl\u00e4rt, wie Unternehmen auf die Folgen der Covid-19-Pandemie reagieren m\u00fcssen.<\/p>\n","protected":false},"author":38,"featured_media":70654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,38469],"tags":[37753,69],"coauthors":[19920],"class_list":["post-70653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-20-12","tag-corona","tag-idc","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/12\/shutterstock_1658501806-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>IDC hat ihre weltweiten Prognosen f\u00fcr die IT-Industrie f\u00fcr 2021 und Folgejahre ver\u00f6ffentlicht und erkl\u00e4rt, wie Unternehmen auf die Folgen der Covid-19-Pandemie reagieren m\u00fcssen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-20-12\/\" rel=\"category tag\">MAG 20-12<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/70653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=70653"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/70653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/70654"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=70653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=70653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=70653"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=70653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}