{"id":70094,"date":"2021-01-13T08:00:00","date_gmt":"2021-01-13T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=70094"},"modified":"2020-12-03T11:24:00","modified_gmt":"2020-12-03T10:24:00","slug":"woran-innovationen-im-unternehmen-scheitern","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/woran-innovationen-im-unternehmen-scheitern\/","title":{"rendered":"Woran Innovationen im Unternehmen scheitern"},"content":{"rendered":"\n<p>Dies geht aus der neuen Studie von Capgemini \u201eScaling Innovation \u2013 What\u2019s the Big Idea?\u201c hervor, was erkl\u00e4rt, warum die meisten Innovationen nicht erfolgreich ausgerollt werden.<\/p>\n\n\n\n<p>Olivier Herv\u00e9, Leiter des Beratungsbereichs Strategie bei Capgemini Invent, fasst die Ergebnisse folgenderma\u00dfen zusammen: <\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3347292145\"><div id=\"great-851133429\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p><em>\u201eDie Skalierung von Innovationen muss als eigene Disziplin innerhalb der Innovationsreise behandelt werden, weil sie grundlegend anders ist. Sie hat ihre eigenen Herausforderungen und ist typischerweise in einem Gesch\u00e4ftsbereich eines Unternehmens angesiedelt, der von der Ideenfindung v\u00f6llig getrennt ist, Skalierung erfordert auch eine andere Denkweise und andere F\u00e4higkeiten. <\/em><\/p>\n\n\n\n<p><em>Indem sie Skalierung als eine spezifische und einzigartige Disziplin behandeln, die richtige Governance einf\u00fchren und eine Kultur aufbauen, die bereit ist, harte Entscheidungen zur Skalierung von Innovationen zu treffen, k\u00f6nnen Unternehmen dies mit einer Geschwindigkeit und der Gewissheit erreichen, bei der Konkurrenten nur schwer mithalten k\u00f6nnen.\u201c<\/em><\/p>\n\n\n\n<p>Innovation und die erfolgreiche Skalierung derselben sind zwei verschiedene Funktionen, die oft unterschiedliche Einstellungen und F\u00e4higkeiten erfordern. Nur wenige Unternehmen unterscheiden jedoch zwischen dem Front-End der Innovationserzeugung und dem Back-End der Innovationsskalierung. Sie denken nicht an die Skalierung selbst \u2013 eine Disziplin, die sich in ihrem Zweck, ihren Anforderungen und Herausforderungen klar unterscheidet. <\/p>\n\n\n\n<p>Obwohl die Skalierung in der nachgelagerten Phase des Innovationsprozesses erfolgt, ist sie oft zu gering und kommt zu sp\u00e4t. Durch die Betrachtung der Skalierung von Innovationen als eigenst\u00e4ndige Diszi\u00adplin k\u00f6nnen Unternehmen sicherstellen, dass sie bereits zu Beginn der Ideenfindungsphase Teams einsetzen, die sich st\u00e4rker auf die Durchf\u00fchrbarkeit und Machbarkeit von Innovationen konzentrieren.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"626\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve.jpg\" alt=\"\" class=\"wp-image-70095\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve-768x601.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve-100x78.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve-480x376.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve-640x501.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/Olivier-Herve-720x563.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Die Unf\u00e4higkeit vieler Unternehmen, Innovationen im gro\u00dfen Stil umzusetzen, hindert sie daran, das Potenzial von Zukunftstechnologien zu nutzen \u2013 obwohl sie mehr denn je darauf angewiesen sind.<\/p>\n","protected":false},"author":38,"featured_media":70096,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,38353],"tags":[1015,11834],"coauthors":[19920],"class_list":["post-70094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-20-11","tag-capgemini","tag-innovationen","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/11\/shutterstock_1346114726-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die Unf\u00e4higkeit vieler Unternehmen, Innovationen im gro\u00dfen Stil umzusetzen, hindert sie daran, das Potenzial von Zukunftstechnologien zu nutzen \u2013 obwohl sie mehr denn je darauf angewiesen sind.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-20-11\/\" rel=\"category tag\">MAG 20-11<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/70094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=70094"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/70094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/70096"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=70094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=70094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=70094"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=70094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}