{"id":69373,"date":"2020-10-08T12:00:00","date_gmt":"2020-10-08T10:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=69373"},"modified":"2025-06-24T14:40:36","modified_gmt":"2025-06-24T12:40:36","slug":"loeschen-im-auftrag-von-mensch-und-natur","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/loeschen-im-auftrag-von-mensch-und-natur\/","title":{"rendered":"L\u00f6schen im Auftrag von Mensch und Natur"},"content":{"rendered":"\n<p>Sieht man Bilder von den neuen gigantischen Rechenzentren, die auf der ganzen Welt entstehen, verschl\u00e4gt es einem leicht den Atem: mehrere Tausend Quadratmeter geballte Energie, die die qualmenden Fabriken der ersten und zweiten industriellen Revolution fast lieblich aussehen lassen. Und wozu? Um unsere digitale Welt 24\/7 anzufeuern und die gesamte Datenproduktion in Clouds zu lagern. Cloud, das klingt leicht und luftig \u2013 doch das sind die massiven Farmen bei Weitem nicht. Weltweit m\u00fcssen Milliarden Server gek\u00fchlt und Rechner mit Strom versorgt werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speichern auf Teufel komm raus<\/h3>\n\n\n\n<p>Noch sch\u00e4men sich die wenigsten, wenn sie flei\u00dfig Dateien und Dokumente mehrfach duplizieren und vor allem niemals etwas l\u00f6schen. Doch stellen immer mehr Umweltsch\u00fctzer fest: \u201eKlickscham\u201c ist die neue \u201eFlugscham\u201c. Und das alles, weil nicht gel\u00f6scht wird. Aber warum f\u00e4llt es vielen so schwer, sich von ihren Dokumenten zu trennen? Weil wir verlernt haben, wie das geht. <\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1290138299\"><div id=\"great-1452925017\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>War es fr\u00fcher noch notwendig, sich auf das Wesentliche zu beschr\u00e4nken, weil Speichermedien in ihren Ausma\u00dfen begrenzt und Speicherplatz teuer war, hat sich das Blatt in den vergangenen Jahren gewendet. Nachrichten, Dokumente, Akten und Fotos verschwinden \u2013 weil es so einfach ist \u2013 in der Cloud, teilweise auf Nimmerwiedersehen. Das f\u00fchrt vor allem f\u00fcr Unternehmen neben der Umweltfrage noch zu weiteren Problemen.<\/p>\n\n\n\n<p>Jede einzelne Datei ben\u00f6tigt Speicherplatz, was Kosten in den Unternehmen verursacht, aber obendrein \u2013 und das kann langfristig noch viel entscheidender sein: Dokumentenmassen f\u00fchren dazu, dass in der t\u00e4glichen Arbeit das Relevante im Nebel des Irrelevanten kaum mehr zu sehen ist.<\/p>\n\n\n\n<p>An dieser Frage forscht auch die Universit\u00e4t Bamberg unter dem Motto \u201eDare2Del\u201c. Einer der Grundpfeiler ihrer Forschung ist das Wissen, dass digitale Daten, die \u00fcberfl\u00fcssig geworden sind, die Suche nach Informationen erschweren, Entscheidungen verz\u00f6gern und von anstehenden Aufgaben ablenken. <\/p>\n\n\n\n<p>Professorin und Projektleiterin Uta Schmid schlussfolgert: Sinnvoll zu l\u00f6schen erh\u00f6he die Arbeitsleistung. Doch auch wenn das L\u00f6schen ins Bewusstsein r\u00fcckt, die Forscher wissen, die wenigsten Menschen m\u00f6chten sich w\u00e4hrend ihrer Arbeit Gedanken um die Archivierung machen. Aufheben oder l\u00f6schen? Dies sollte m\u00f6glichst unauff\u00e4llig im Hintergrund passieren \u2013 zuverl\u00e4ssig, intelligent und nat\u00fcrlich nachhaltig.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Autonome Archivierung<\/h3>\n\n\n\n<p>Steffen Holzmann, Green-IT-Experte bei der Deutschen Umwelthilfe, r\u00e4t: alte E-Mails l\u00f6schen. Sich von nicht ben\u00f6tigten Newslettern abmelden. Aber das gen\u00fcgt im Unternehmensumfeld nat\u00fcrlich nicht. Vor allem die t\u00e4glich erstellten Dokumente sind eine Herausforderung in Sachen Gigabyte-Gigantismus. <\/p>\n\n\n\n<p>Wenn wir mit dem Thema Archivierung umwelt- und leistungsbewusst umgehen wollen und die manuellen \u00dcberlegungen der Mitarbeitenden minimieren wollen, m\u00fcssen wir auf intelligente Software z\u00e4hlen. KGS nennt diese Archivierungsl\u00f6sung \u201eTia\u201c \u2013 The Intelligent Archive. Das Ziel: eine autonome Archivierung, die Muster selbst erkennt und \u201ePredictive Archiving Services\u201c bietet.<\/p>\n\n\n\n<p>So macht das intelligente Archiv L\u00f6schvorschl\u00e4ge, reorganisiert \u00fcbervolle Archive, entlastet teure Speicherpl\u00e4tze und nutzt g\u00fcnstigen Speicher sinnvoll aus. Machine Learning hei\u00dft das Zauberwort: Das System lernt und unterscheidet. Ein rechtlich relevantes Dokument wird anders \u201egelagert\u201c als eine Alltagsnotiz.<\/p>\n\n\n\n<p>Ein Dokument, das keine Aufbewahrungsfrist enth\u00e4lt, jahrelang nicht auf den Bildschirm geholt wurde, doppelt oder dreifach verf\u00fcgbar ist, wird als zu l\u00f6schender Datenm\u00fcll angezeigt \u2013 oder f\u00fcr die ganz geheilten Datenmessies: direkt automatisch entsorgt. Ja, es rebelliert das Sammlerherz in uns. Doch Mensch und Natur brauchen dringend Luft zum Atmen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e3mag.com\/partners\/kgs-software-gmbh-co-kg\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" title=\"L\u00f6schen im auftrag von mensch und natur\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS.jpg\" alt=\"https:\/\/e3mag.com\/partners\/kgs-software-gmbh-co-kg\/\" class=\"wp-image-11369\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-KGS-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In Zeiten von Nachhaltigkeit und Green IT steht es schlecht um Datenmessies und Sicherheitsfreaks. Wer wahllos alles in der Cloud speichert, l\u00e4uft nicht nur Gefahr, den \u00dcberblick zu verlieren, sondern auch, als Umwelts\u00fcnder beschimpft zu werden. <\/p>\n","protected":false},"author":2178,"featured_media":22917,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[14087,7,38075],"tags":[39,606],"coauthors":[38317],"class_list":["post-69373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cloud-computing-kolumne","category-meinung","category-mag-2009","tag-cloud","tag-daten","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",400,172,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-768x331.jpg",768,331,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-100x43.jpg",100,43,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-480x207.jpg",480,207,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-640x276.jpg",640,276,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-720x310.jpg",720,310,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-960x414.jpg",960,414,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",1000,431,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o.jpg",600,259,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2017\/05\/Cloud-Computing-Kolumne-o-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>In Zeiten von Nachhaltigkeit und Green IT steht es schlecht um Datenmessies und Sicherheitsfreaks. Wer wahllos alles in der Cloud speichert, l\u00e4uft nicht nur Gefahr, den \u00dcberblick zu verlieren, sondern auch, als Umwelts\u00fcnder beschimpft zu werden. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/cloud-computing-kolumne\/\" rel=\"category tag\">Cloud Computing Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-2009\/\" rel=\"category tag\">MAG 20-09<\/a>","author_info_v2":{"name":"Winfried Althaus, KGS Software","url":"https:\/\/e3mag.com\/de\/author\/winfried-althaus\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/69373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2178"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=69373"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/69373\/revisions"}],"predecessor-version":[{"id":151866,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/69373\/revisions\/151866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/22917"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=69373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=69373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=69373"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=69373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}