{"id":68422,"date":"2020-08-27T11:55:42","date_gmt":"2020-08-27T09:55:42","guid":{"rendered":"http:\/\/e3mag.com\/?p=68422"},"modified":"2020-09-10T16:05:00","modified_gmt":"2020-09-10T14:05:00","slug":"mehr-als-die-summe-seiner-teile","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/mehr-als-die-summe-seiner-teile\/","title":{"rendered":"Mehr als die Summe seiner Teile"},"content":{"rendered":"\n<p>Sie identifizieren zielsicher die Anforderungen der Kunden und erf\u00fcllen sie mit innovativen Produkten und Services. Dabei nutzen sie die Chancen, die sich ihnen bieten, ohne die Risiken aus dem Auge zu verlieren.<\/p>\n\n\n\n<p>Die Idee, dass Intelligenz auch f\u00fcr Unternehmen als Organisation ein entscheidender Faktor ist, hat der amerikanische Wissenschaftler James Brian Quinn in seinem 1992 erschienenen Buch \u201eIntelligent Enterprise: A Knowledge and Service \u00adBased Paradigm for Industry\u201c formuliert.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3058700328\"><div id=\"great-698709314\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Innovativen Technologien weist er dabei eine entscheidende Rolle zu. Insofern wundert es nicht, dass SAP seit ein paar Jahren das \u201eIntelligent Enterprise\u201c in den Mittelpunkt der Kommunikation r\u00fcckt \u2013 auch wenn nicht ganz klar ist, ob sich der Softwareanbieter explizit auf Quinn bezieht. Fakt ist jedenfalls: SAP sieht offenbar Potenziale, die Unternehmen bislang trotz des Einsatzes etlicher IT-Tools noch nicht nutzen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Intelligenz auf Ebene der Organisation<\/h3>\n\n\n\n<p>Wobei die Frage berechtigt ist, ob zwischen einem \u201eIntelligent Enterprise\u201c und einem herk\u00f6mmlichen Unternehmen tats\u00e4chlich ein grunds\u00e4tzlicher Unterschied besteht. Oder ob der Begriff lediglich eine Selbstverst\u00e4ndlichkeit pointiert zum Ausdruck bringt. Wir sind \u00fcberzeugt, dass mit dem Einsatz innovativer Technologien tats\u00e4chlich ein Paradigmenwechsel verbunden sein kann: <\/p>\n\n\n\n<p>Bislang wurde IT vor allem dazu genutzt, Menschen bei ihren kognitiven Aufgaben zu unterst\u00fctzen. IT lieferte beispielsweise Kennzahlen. Menschen trafen auf dieser Basis Entscheidungen. In einem \u201eIntelligent Enterprise\u201c handelt die IT \u2013 oder besser die Technologie \u2013 deutlich autonomer. In der Lage ist sie dazu, weil eine ganze Reihe von einzelnen Komponenten in einer komplexen Architektur miteinander verzahnt sind. Das Ganze wird so zu wesentlich mehr als nur der Summe seiner Teile!<\/p>\n\n\n\n<p>SAP veranschaulicht diesen Gedanken mithilfe eines Endlosbands, das drei Bereiche umschlie\u00dft: \u201eIntelligence\u201c in der Mitte wird auf der linken Seite flankiert von \u201eExperience\u201c, auf der rechten von \u201eOperations\u201c. Im Intelligence-Bereich flie\u00dfen die Experience-Daten und die operativen Daten zusammen. Durch die Analyse der so konsolidierten Datenbasis \u2013 auch in Echtzeit \u2013 lassen sich Erkenntnisse dazu gewinnen, was passiert ist und weshalb es passiert ist. Hinzu kommt, dass Technologien diese Erkenntnisse nutzen, um autonom Entscheidungen zu treffen, Prozesse mit Experience- und Operations-Bezug anzusto\u00dfen und dezidierte Aktivit\u00e4ten auszul\u00f6sen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die neue Offenheit in der SAP-Welt<\/h3>\n\n\n\n<p>Damit sich Szenarien \u00fcber die drei Bereiche hinweg realisieren lassen, soll ein \u201eIntelligent Enterprise\u201c ganz unterschiedliche Technologien kombinieren. Dabei k\u00f6nnen explizit auch L\u00f6sungen zum Einsatz kommen, die nicht von SAP stammen. Ohne diese Offenheit geht es heute nicht mehr \u2013 das ist auch SAP klar. Entstehen soll auf diese Weise aber keine Systemlandschaft, die sich aus etlichen nicht aufeinander abgestimmten Einzell\u00f6sungen zusammensetzt, wie es in der Vergangenheit fast die Regel war. <\/p>\n\n\n\n<p>Stattdessen sollen die Auswahl und Verbindung der Komponenten einem holistischen Plan folgen, der sich \u00fcber das gesamte Unternehmen erstreckt. Das erfordert zun\u00e4chst einen kulturellen Wandel in den Unternehmen. Denn bis heute verstehen sich viele Fachbereiche als eigenst\u00e4ndige Einheiten und verteidigen hartn\u00e4ckig ihre fest verankerten Rechte. Inklusive des Rechts auf freie IT-Wahl. Sollen sie das aufgeben, bedarf es der \u00dcberzeugungs\u00adarbeit durch die Unternehmensf\u00fchrung und des Beweises, dass die neue Ausrichtung funktioniert.<\/p>\n\n\n\n<p>Neben dem Kulturwandel ist ein solides technologisches Fundament unverzichtbar, das alle grundlegenden Funktionen bereitstellt und \u00fcber das die Integration aller weiteren Technologien erfolgen kann. Genau das soll die SAP Business Technology Platform leisten. Versammelt sind hier Applikationen f\u00fcr das Datenbank- und Datenmanagement, Analysel\u00f6sungen, Tools f\u00fcr die Anwendungsentwicklung und -integration sowie intelligente Technologien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Transformation zum Intelligent Enterprise<\/h3>\n\n\n\n<p>Die Transformation zu einem \u201eIntelligent Enterprise\u201c verl\u00e4uft f\u00fcr jedes Unternehmen nach einer individuell ausgestalteten Roadmap \u2013 ausgehend vom jeweiligen Gesch\u00e4ftsmodell, den Produkten und Services, der Organisation, den Prozessen und der vorhandenen Technologie. Dennoch sind die Schritte, die ber\u00fccksichtigt werden sollten, immer \u00e4hnlich:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Holistischer Plan:<\/strong> Jedes Unternehmen sollte sich unbedingt klarmachen, aus welchem Grund es sich zum \u201eIntelligent Enterprise\u201c weiterentwickeln m\u00f6chte und was das konkret bedeutet: Was soll den Kunden k\u00fcnftig auf welche Weise angeboten werden? Wie sollen sich Gesch\u00e4ftsmodell, Produkte und Services wandeln? Und was bedeutet das f\u00fcr die Organisation und die Prozesse? Antworten auf diese Fragen skizzieren eine Vision f\u00fcr die Zukunft, aus der sich ein holistischer Plan ableiten l\u00e4sst.<br><\/li><li><strong>Soll-Architektur: <\/strong>Auf Basis des holistischen Plans l\u00e4sst sich eine Soll-Architektur entwerfen, mit der sich alle angestrebten Szenarien realisieren lassen. Der Abgleich dieser Soll-Architektur mit der Ist-Architektur zeigt auf, welche Schritte unternommen werden m\u00fcssen, um die L\u00fccken zu schlie\u00dfen.<br><\/li><li><strong>Priorisierung von Szenarien und Technologien: <\/strong>Die gesamte Transformation in einem gro\u00dfen Wurf zu erledigen ist weder machbar noch sinnvoll. Stattdessen sollten einzelne Projekte identifiziert, priorisiert und dann sukzessive durchgef\u00fchrt werden. Ma\u00dfstab f\u00fcr die Priorisierung kann der Nutzen eines Projekts sein \u2013 optimal ist, wenn sich gerade zu Beginn der Transformation der Mehrwert rasch einstellt. <br><br>Als Ma\u00dfstab kann aber auch das technologische Gap dienen: Manchmal gen\u00fcgt schon die Erweiterung der Architektur um kleine Anwendungen, um einen Effekt zu erzielen. Oder man nutzt eine App im MVP-Ansatz (Minimum Viable Product), um rasch Erfahrungen bei der produktiven Nutzung zu sammeln und in die z\u00fcgige Weiterentwicklung einflie\u00dfen zu lassen.<br><\/li><li><strong>Auswahl der Technologie: <\/strong>Auch wenn klar ist, welche Art von Technologie eingef\u00fchrt werden soll, besteht in vielen F\u00e4llen noch eine gewisse Auswahl. Die Entscheidung f\u00fcr eine konkrete L\u00f6sung sollte im Sinne eines Best-of-Breed-Ansatzes zum einen davon geleitet werden, wie gut sie die gestellten Anforderungen erf\u00fcllt. Zum anderen lohnt sich aber immer auch der Blick auf das gro\u00dfe Ganze. Denn eine Anwendung, die zwar f\u00fcr ein einzelnes Szenario perfekt geeignet ist, l\u00e4sst sich unter Umst\u00e4nden nur mit M\u00fche in die Gesamtarchitektur einbinden.<br><\/li><li><strong>Umsetzung:<\/strong> Auch wenn Unternehmen bei der Priorisierung und der Auswahl von Use Cases und Technologien maximale Flexibilit\u00e4t haben, spricht vieles f\u00fcr SAP S\/4 Hana als Kern eines \u201eIntelligent Enterprise\u201c. Insofern sollte die Einf\u00fchrung strategisch vorbereitet werden \u2013 das umfasst die Entscheidung f\u00fcr eine Deployment-Variante und einen Transformationsweg. Allerdings: Die Entwicklung zu einem \u201eIntelligent Enterprise\u201c kann auch schon vor der Einf\u00fchrung von SAP S\/4 Hana beginnen. Dabei sollte aber stets die Rolle der innovativen ERP-Suite bedacht werden.<br><\/li><li><strong>Iteration:<\/strong> Die Auflistung der f\u00fcnf vorgenannten Schritte unterstellt einen linearen Ablauf. Das trifft im Wesentlichen auch zu, darf aber nicht zu starr ausgelegt werden. So ergeben sich zum Beispiel aus der Auseinandersetzung mit den Technologien h\u00e4ufig Impulse f\u00fcr Gesch\u00e4ftsmodell, Produkte und Services. Hinzu kommt, dass in kurzen zeitlichen Abst\u00e4nden neue Technologien verf\u00fcgbar sind, mit denen zum Zeitpunkt der initialen Planung noch gar nicht gerechnet wurde. <br><br>Das bedeutet letztlich auch: Die Transformation zu einem \u201eIntelligent Enterprise\u201c ist niemals abgeschlossen, weil Innovationen immer neue M\u00f6glichkeiten er\u00f6ffnen.<br>Bei der Transformation zu einem \u201eIntelligent Enterprise\u201c unterst\u00fctzt Nagarro Allgeier ES Unternehmen ganzheitlich \u2013 zu s\u00e4mtlichen Business- und Technologie-Aspekten. Immer mit dem Blick darauf, was sich mit IT in der Wirklichkeit machen l\u00e4sst!<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e3mag.com\/partners\/allgeier-enterprise-services\/\"><img decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/Allgeier-ES-Special-1030x132.jpg\" alt=\"\" class=\"wp-image-68424\"\/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-ugb-button ugb-button-wrapper ugb-1473ae4 ugb-button--design-fullwidth ugb-main-block\" id=\"\"><style>.ugb-1473ae4 .ugb-button1{background-color:#a61510}.ugb-1473ae4 .ugb-button1 .ugb-button--inner,.ugb-1473ae4 .ugb-button1 svg:not(.ugb-custom-icon){color:#ffffff !important}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-button-container\"><a class=\"ugb-button1 ugb-button ugb-button--size-normal\" href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/09\/2009_nagarro_allgeier_web.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"\"><span class=\"ugb-button--inner\"><strong>Special downloaden<\/strong><\/span><\/a><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Erfolg eines Unternehmens h\u00e4ngt seit eh und je ganz erheblich von der Klugheit, dem Einfallsreichtum und der Kreativit\u00e4t der beteiligten Menschen ab. Mithilfe dieser Intelligenz erkennen sie, wo ein Bedarf nicht gedeckt ist, und finden effektive L\u00f6sungen. <\/p>\n","protected":false},"author":1075,"featured_media":68426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[38130,38083,38075],"tags":[23829,369],"coauthors":[23129],"class_list":["post-68422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dsag","category-e-3-special-2009","category-mag-2009","tag-intelligent-enterprise","tag-it","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1060926155_cmyk-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Der Erfolg eines Unternehmens h\u00e4ngt seit eh und je ganz erheblich von der Klugheit, dem Einfallsreichtum und der Kreativit\u00e4t der beteiligten Menschen ab. Mithilfe dieser Intelligenz erkennen sie, wo ein Bedarf nicht gedeckt ist, und finden effektive L\u00f6sungen. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/e-3-special-2009\/dsag\/\" rel=\"category tag\">DSAG<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/e-3-special-2009\/\" rel=\"category tag\">E-3 Special 2009<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-2009\/\" rel=\"category tag\">MAG 20-09<\/a>","author_info_v2":{"name":"Michael Brecht, Allgeier","url":"https:\/\/e3mag.com\/de\/author\/michael-brecht\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/68422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1075"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=68422"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/68422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/68426"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=68422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=68422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=68422"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=68422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}