{"id":68393,"date":"2020-08-27T11:57:08","date_gmt":"2020-08-27T09:57:08","guid":{"rendered":"http:\/\/e3mag.com\/?p=68393"},"modified":"2020-09-03T10:22:09","modified_gmt":"2020-09-03T08:22:09","slug":"s-4-hana-nimmt-auch-jenseits-des-atlantiks-fahrt-auf","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/s-4-hana-nimmt-auch-jenseits-des-atlantiks-fahrt-auf\/","title":{"rendered":"S\/4 Hana nimmt auch jenseits des Atlantiks Fahrt auf"},"content":{"rendered":"\n<p>Laut dieser implementiert die Mehrheit der DSAG-Mitglieder (70 Prozent) und der ASUG-Mitglieder (55 Prozent) S\/4 Hana bereits oder plant, dies in Zukunft zu tun (siehe Grafik). Zw\u00f6lf Prozent (DSAG) bzw. 16 Prozent (ASUG) sind bereits live. <\/p>\n\n\n\n<p>Gr\u00fcnde, warum noch kein S\/4-Hana-Projekt umgesetzt wurde, sind bei den ASUG-Mitgliedern die Kosten, der fehlende Business Case und laufende SAP-ECC-Projekte. Unter den DSAG-Mitgliedern dominieren die fehlende Notwendigkeit f\u00fcr einen Umstieg, die Unsicherheit bez\u00fcglich der Funktionalit\u00e4ten und an dritter Stelle steht der fehlende Business Case.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-796264052\"><div id=\"great-1803925171\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Die am weitesten verbreitete L\u00f6sung bei den Mitgliedern beider SAP-Anwendergruppen ist nach wie vor SAP ECC mit 84 Prozent bei der DSAG und 78 Prozent bei der ASUG. Aber S\/4 ist \u00fcberall auf dem Vormarsch. Einen festen Platz in der Planung hat S\/4 bei 69 Prozent der DSAG-Mitglieder und bei 57 Prozent der ASUG-Mitglieder. Interessant ist auch das Ergebnis zu SAP Fiori.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"456\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk.jpg\" alt=\"\" class=\"wp-image-68394\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk-768x350.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk-100x46.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk-480x219.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk-640x292.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk-720x328.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/04_s4hana-einfuehrung_cmyk-960x438.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Auf die Frage, wie weit ihr Unternehmen im Hinblick auf die Einf\u00fchrung von S\/4 Hana sei, gaben die meisten an, dass sie sich noch in der Planung befinden. Sechs Prozent der Mitglieder in beiden Anwendergruppen planen keine Einf\u00fchrung von S\/4 Hana. \u00dcberraschend: Vier Prozent der ASUG-Mitglieder haben noch nie von S\/4 Hana geh\u00f6rt. Quelle: DSAG e. V.<\/figcaption><\/figure>\n\n\n\n<p>Rund die H\u00e4lfte der ASUG-Mitglieder (57 Prozent) und DSAG-Mitglieder (47 Prozent) nutzt die Benutzeroberfl\u00e4che bereits. Weitere 44 Prozent der DSAG-Mitglieder k\u00f6nnen sich den Einsatz zuk\u00fcnftig vorstellen, im Vergleich zu 22 Prozent der ASUG-Mitglieder.<\/p>\n\n\n\n<p>Die gr\u00f6\u00dften Differenzen ergaben sich beim Vergleich der Zuk\u00e4ufe Concur, SuccessFactors und Ariba. W\u00e4hrend die ASUG-Mitglieder bereits zu 58 Prozent auf Concur setzen, tun das von den DSAG-Mitgliedern nur 17 Prozent. Bei SuccessFactors sind es 46 Prozent der ASUG und 23 Prozent der DSAG. Und Ariba nutzen bereits 32 Prozent der ASUG-Mitglieder, aber nur elf Prozent der DSAG-Mitglieder. <\/p>\n\n\n\n<p>Dieses Ergebnis \u00fcberrascht nicht, da die genannten L\u00f6sungen alle in den USA entwickelt wurden, bevor SAP sie \u00fcbernahm. Interessant in diesem Zusammenhang jedoch: Nur zw\u00f6lf Prozent der ASUG-Mitglieder, die SuccessFactors noch nicht im Einsatz haben, wollen sich mit der L\u00f6sung in Zukunft besch\u00e4ftigen, mehr als doppelt so viele sind es in der DSAG (30 Prozent).<\/p>\n\n\n\n<p>Bei der Frage, wie SAP nach einem Einf\u00fchrungsprojekt eingesch\u00e4tzt wird, ergibt sich ein recht einheitliches Bild. Bei 13 Prozent der ASUG-Mitglieder hat sich die Wahrnehmung von SAP durch S\/4 Hana stark verbessert, bei den DSAG-Mitgliedern sind es 14 Prozent. Bei der Frage, wie SAP das Kundenerlebnis verbessern kann, stehen bei den ASUG-Mitgliedern die Support-Best\u00e4ndigkeit und -Verf\u00fcgbarkeit gefolgt von vertiefter Ausbildung und dem Wunsch nach mehr Schulungsmaterialien und einem anwenderfreundlichen Erlebnis auf den ersten Pl\u00e4tzen. <\/p>\n\n\n\n<p>Bei den DSAG-Mitgliedern sind vorrangig ein besseres Produkterlebnis, Integration sowie Informations- und Kommunikationsstrategien von SAP gefragt. Die Befragten aus beiden Lagern w\u00fcnschen sich zudem weniger Anpassungsaufwand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die amerikanische SAP-Anwendergruppe ASUG und die Deutschsprachige SAP-Anwendergruppe e. V. (DSAG) haben erstmals eine gemeinsame Umfrage unter ihren Mitgliedern \u00fcber SAP im Kontext von S\/4 Hana durchgef\u00fchrt. <\/p>\n","protected":false},"author":2155,"featured_media":68396,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[38130,38083,38075],"tags":[8100,273,65,517],"coauthors":[38132],"class_list":["post-68393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dsag","category-e-3-special-2009","category-mag-2009","tag-asug","tag-dsag","tag-hana","tag-s4","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/08\/shutterstock_1254279517-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die amerikanische SAP-Anwendergruppe ASUG und die Deutschsprachige SAP-Anwendergruppe e. V. (DSAG) haben erstmals eine gemeinsame Umfrage unter ihren Mitgliedern \u00fcber SAP im Kontext von S\/4 Hana durchgef\u00fchrt. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/e-3-special-2009\/dsag\/\" rel=\"category tag\">DSAG<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/e-3-special-2009\/\" rel=\"category tag\">E-3 Special 2009<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-2009\/\" rel=\"category tag\">MAG 20-09<\/a>","author_info_v2":{"name":"DSAG e.V.","url":"https:\/\/e3mag.com\/de\/author\/dsag-e-v\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/68393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2155"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=68393"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/68393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/68396"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=68393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=68393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=68393"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=68393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}