{"id":66934,"date":"2020-08-18T08:00:00","date_gmt":"2020-08-18T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=66934"},"modified":"2025-01-22T13:58:20","modified_gmt":"2025-01-22T12:58:20","slug":"historische-erp-daten-vereinfachen-automatisieren-und-geld-sparen","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/historische-erp-daten-vereinfachen-automatisieren-und-geld-sparen\/","title":{"rendered":"Historische ERP-Daten: vereinfachen, automatisieren und Geld sparen"},"content":{"rendered":"\n<p>Die digitale Transformation verlangt in den verschiedensten M\u00e4rkten und Branchen nach intelligenten Antworten, die trotz der Unsicherheit, unter der Unternehmenslenker heute Entscheidungen treffen m\u00fcssen, zu langfristig tragf\u00e4higen L\u00f6sungen f\u00fchren. Dies gilt umso mehr, als im Nachgang der Coronakrise mit tiefgreifenden Umstrukturierungen in vielen Unternehmen zu rechnen ist. Zu- und Verk\u00e4ufe, Fusionen, Aufspaltungen, Zusammenlegung und Aufl\u00f6sung von Gesch\u00e4ftsbereichen etc. werden auf der Tagesordnung der Manager stehen, um die Folgen der Krise erfolgreich zu meistern. <\/p>\n\n\n\n<p>Hinzu kommt: Die Unternehmen m\u00fcssen Geld sparen, und zwar kurzfristig. IT-Projekte, die das erm\u00f6glichen, m\u00fcssen jedoch im Einklang mit den langfristigen Strategien und Ma\u00dfnahmen stehen. Der wahre Unternehmenswert spielt sowohl kurzfristig wie langfristig eine entscheidende Rolle. Je h\u00f6her er liegt, umso st\u00e4rker die Verhandlungsposition und umso gr\u00f6\u00dfer die Handlungsm\u00f6glichkeiten. Zu einem wesentlichen Teil liegt dieser Wert in den Daten und Dokumenten der Unternehmen. Kein Wunder also, dass namhafte Analystenh\u00e4user immer st\u00e4rker die Bedeutung von Informationen betonen, um Unternehmen agiler zu machen und damit ihren Wert zu steigern.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1362459945\"><div id=\"great-1695868374\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Dabei verstehen sie unter Informationen insbesondere sogenannte X- und O-Daten, also Transaktionsdaten aus dem operativen Betrieb (O-Daten) und alle Daten rund um die Nutzererfahrung (X-Daten, wobei X f\u00fcr Experience steht). Betrachtet man die erfolgreichen datengest\u00fctzten Gesch\u00e4ftsmodelle von Onlineanbietern, so ist die Konzentration auf X- und O-Daten nur folgerichtig. Internetanbieter sind jedoch im Vergleich zu Unternehmen klassischer Branchen wie Maschinen- und Anlagenbau, Automobil oder Textilindustrie immer noch jugendliche Newcomer. Das erkl\u00e4rt gewiss zu einem Gutteil, warum X- und O-Daten aktuell eine so prominente Stellung einnehmen. Das Wissen jedoch, wie man Fahrzeuge effizient und mit gleichbleibend hoher Qualit\u00e4t baut, ist \u00e4lter als das Design eines Elektroautos und der entsprechenden Steuerungssoftware. <\/p>\n\n\n\n<p>Der menschliche K\u00f6rper, seine Gr\u00f6\u00dfe und Ma\u00dfe unterliegen nicht derselben Ver\u00e4nderbarkeit wie der Zuschauergeschmack bei Serien und Filmen. Deshalb geh\u00f6ren Schnittmuster etwa aus den 1950er-Jahren immer noch zum wertvollen geistigen Eigentum eines Textilunternehmens. Maschinen und Anlagen haben einen Lebenszyklus von mehreren Jahrzehnten, sodass nicht nur Baupl\u00e4ne, sondern auch Wartungsberichte \u00fcber diesen Zeitraum wertvolle Erkenntnisse bereithalten. Diese k\u00f6nnen einen gro\u00dfen Dienst bei der Entwicklung k\u00fcnftiger Produkte leisten, auch wenn der Softwareanteil daran in Zukunft ungleich gr\u00f6\u00dfer sein wird. Schlie\u00dflich verf\u00fcgen auch Branchen wie Banken und Versicherungen oder der Gesundheitssektor, die zurzeit ganz besonders von der Digitalisierung herausgefordert werden, \u00fcber einen immensen Schatz in ihren historischen Daten, die sie schon aus rechtlichen Gr\u00fcnden f\u00fcr viele Jahrzehnte aufbewahren m\u00fcssen.<\/p>\n\n\n\n<p>Diesen Schatz zu heben d\u00fcrfte wertvolle Antworten auf die digitalen Herausforderungen von heute liefern. Es ist also der Gesamt\u00adbestand an Informationen, der aktuellen ebenso wie der historischen, der den wahren Wert eines Unternehmens ausmacht und ihn mehrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Digital trifft auf real<\/h3>\n\n\n\n<p>Hier die Lehren aus den noch jungen Onlinegesch\u00e4ftsmodellen, dort das Erfahrungswissen aus jahrzehntelanger Gesch\u00e4ftst\u00e4tigkeit. Hier der Fokus auf kurzfristige Ver\u00e4nderungen, dort der langfristige Wert \u00fcber viele Jahrzehnte erworbenen geistigen Eigentums. Was wie ein Gegensatz aussieht und bis vor wenigen Jahren wohl auch einer war, geht im Zuge der digitalen Transformation in ein Miteinander \u00fcber. Neben den bew\u00e4hrten Baupl\u00e4nen tragen in Zukunft immer mehr Daten aus den Maschinen und Anlagen zur Wertsch\u00f6pfung bei. <\/p>\n\n\n\n<p>Analysen, die auf Ver\u00e4nderungen im Konsumentengeschmack hindeuten, erlauben Textilunternehmen, sich schneller und zielgruppengenauer an neue Trends anzupassen und diese sogar zu steuern. Automobilbauer k\u00f6nnen mit ihrem bew\u00e4hrten Prozess- und Produktionswissen wieder zum Innovationsmotor werden, wenn sie die M\u00f6glichkeiten der Digitalisierung voll aussch\u00f6pfen. <\/p>\n\n\n\n<p>Das Wissen aus einer teilweise mehrere Generationen umfassenden Kundenhistorie kann Banken und Versicherungen den notwendigen Vorsprung beim Design personalisierter digitaler Angebote verschaffen. Die digitale Transformation bewirkt allerorten, dass digital auf real und Historie auf Zeitgeist triff. <\/p>\n\n\n\n<p>Das intelligente Unternehmen der Zukunft konzentriert sich deshalb nicht nur auf die X- und O-Daten, sondern auch auf die historischen, die H-Daten. F\u00fcr die IT-Abteilungen der Unternehmen ist dieses Zusammenf\u00fchren von X-, O- und H-Daten und ihre gemeinsame Nutzbarmachung eine Herausforderung. Sie alle sind, insbesondere jedoch die H-Daten, auf viele verschiedene und zum Teil sehr alte Systeme verteilt. Und allein ihre Menge steht einer h\u00f6heren Agilit\u00e4t der Unternehmen im Weg. Typischerweise macht der Anteil der Unternehmensinformationen, die schon aus rechtlichen Gr\u00fcnden nicht mehr ver\u00e4ndert werden d\u00fcrfen, in den Live-Systemen 80 bis 95 Prozent des Gesamtvolumens aus.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer.jpg\" alt=\"Historische erp-daten: vereinfachen, automatisieren und geld sparen\" class=\"wp-image-66935\" title=\"Historische erp-daten: vereinfachen, automatisieren und geld sparen\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-150x150.jpg 150w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-768x768.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-100x100.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-480x480.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-640x640.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-720x720.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-24x24.jpg 24w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-48x48.jpg 48w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-96x96.jpg 96w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/Thomas-Failer-300x300.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Separieren, automatisieren, sparen<\/h3>\n\n\n\n<p>Damit die Historie aus einer IT-Altlast zu einer Quelle h\u00f6herer Wertsch\u00f6pfung wird, gilt es, die X- und O-Daten von den H-Daten zu trennen und den Lebenszyklus der historischen Informationen separat auf einer eigenen Plattform zu managen. Dieser Ansatz hat zahlreiche Vorteile: Bereits kurzfristig stellen sich deutliche Kosten\u00adersparnisse ein, weil die Legacy-Systeme nach der Trennung und Auslagerung der Informationen komplett stillgelegt werden k\u00f6nnen. Dadurch lassen sich die Betriebskosten im Vergleich zum Weiterbetrieb der Altsysteme in der Regel um 80 Prozent senken. Idealerweise sind daf\u00fcr keine Vorabinvestitionen notwendig, wenn sich die Plattform und ihre Funktionalit\u00e4ten wie im Cloud-Zeitalter \u00fcblich als Service abonnieren lassen.<\/p>\n\n\n\n<p>Zudem erlaubt diese \u00dcbernahme von Altinformationen \u2013 inklusive des Gesch\u00e4ftskontexts, in dem sie einmal entstanden sind \u2013, den Anteil der Daten und Dokumente, die in den operativen Systemen \u00fcbernommen werden m\u00fcssen, drastisch zu reduzieren. Im Kontext einer Transformation auf SAP S\/4 Hana zum Beispiel l\u00e4sst sich so der Aufwand bei der Datenmigration im Allgemeinen halbieren. Dar\u00fcber hinaus aber geht dieser kurzfristige Effekt in langfristige Vorteile \u00fcber: Zum einen lassen sich historische Informationen regelm\u00e4\u00dfig auf eine separate Plattform f\u00fcr Informationsmanagement \u00fcberspielen. Nicht nur aus Systemen, die stillgelegt werden sollen, sondern auch aus den operativen L\u00f6sungen. Diese bleiben dadurch auf Dauer schlank und agil \u2013 und erfordern keine kontinuierliche Ressourcenerweiterung. <\/p>\n\n\n\n<p>Die Gesamtbetriebskosten (TCO) einer neuen S\/4-Umgebung um 25 Prozent zu senken ist vor diesem Hintergrund kein frommer Wunsch, sondern eine realistische Sch\u00e4tzung. Zum anderen wirkt sich dieser Ansatz auch in anderen Szenarien auf Dauer positiv aus. Unternehmen k\u00f6nnen ihre heterogenen System- und Applikationslandschaften, ja sogar ganze IT-Standorte harmonisieren und konsolidieren. <\/p>\n\n\n\n<p>Haben sie Tochterfirmen oder Gesch\u00e4ftsbereiche verkauft, k\u00f6nnen sie deren Daten schnell und vollst\u00e4ndig selektieren und in einem modernen Format an den K\u00e4ufer \u00fcbergeben. Au\u00dferdem erh\u00f6hen die Unternehmen mit diesem Ansatz den Schutz ihres geistigen Eigentums und mindern oder beseitigen rechtliche Risiken. Die Anforderungen aktueller und neuer gesetzlicher Vorschriften wie der EU-DSGVO oder anderer Regularien, die ein l\u00fcckenloses Managen des Lebenszyklus auch der historischen Informationen verlangen, lassen sich dank eines integrierten Retention Management erf\u00fcllen.<\/p>\n\n\n\n<p>Zudem bleiben die historischen Informationen und ihr Gesch\u00e4ftskontext trotz der Aufbewahrung auf einer separaten Plattform zu 100 Prozent im Zugriff. Fachanwender haben dadurch eine vollst\u00e4ndige Sicht zum Beispiel auf Kunden und Lieferanten. Unternehmen k\u00f6nnen jederzeit gegen\u00fcber der internen Revision oder bei externen Pr\u00fcfungen ihrer Nachweis- und Auskunftspflicht gen\u00fcgen. Schlie\u00dflich bildet eine solche Plattform die Voraussetzung f\u00fcr Big-Data-Szenarien jeder Art. Denn mit ihrer Hilfe lassen sich Altdaten vor der revisionssicheren Auslagerung und Speicherung bereinigen und optimieren. <\/p>\n\n\n\n<p>Dubletten lassen sich l\u00f6schen und unvollst\u00e4ndige Datens\u00e4tze durch Informationen aus anderen Quellen erg\u00e4nzen und anreichern. Das ist entscheidend, damit die Verhei\u00dfungen datengest\u00fctzter Gesch\u00e4ftsprozesse und -modelle wahr werden. Entscheidungen, die auf der Basis von Datenanalysen fallen, sind nur so gut wie die Qualit\u00e4t der Daten selbst. Das gilt umso mehr in Szenarien, in denen Massendaten anfallen. Und diese werden in Zukunft Standard sein.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Einfachheit statt Komplexit\u00e4t<\/h3>\n\n\n\n<p>Automatisierung ist der Schl\u00fcssel, die Komplexit\u00e4t zu senken: Komplexit\u00e4t, die durch die Heterogenit\u00e4t der Applikations- und Systemlandschaft entsteht. Komplexit\u00e4t, die das Resultat zu gro\u00dfer Informationsmengen in den operativen L\u00f6sungen ist. <\/p>\n\n\n\n<p>Komplexit\u00e4t, die aufgrund mangelhafter Datenqualit\u00e4t aufw\u00e4ndige Nachbesserungen erforderlich macht. Komplexit\u00e4t, die sich in Migrations- und Transformationsprojekten nur durch zus\u00e4tzliche personelle und finanzielle Ressourcen beherrschen l\u00e4sst.<\/p>\n\n\n\n<p>Die Spezialisierung auf das Management des Lebenszyklus von historischen Informationen und die richtigen Verbindungen einer daf\u00fcr geeigneten Plattform zu den operativen Systemen schaffen die Voraussetzung f\u00fcr diese Automatisierung. <\/p>\n\n\n\n<p>Gleichzeitig ist sie der Schl\u00fcssel, der das Tor zur Schatzkammer der Unternehmen \u00f6ffnet \u2013 zu den aktuellen wie den historischen Informationen \u2013 und unabh\u00e4ngig von ihrer Branchenzugeh\u00f6rigkeit die damit verbundenen Kosten massiv senkt. Denn in den Informationen liegt der gegenw\u00e4rtige wie der k\u00fcnftige Wert eines Unternehmens \u2013 eine Erkenntnis, die ihre Ursache nicht in der gegenw\u00e4rtigen Krise hat, zu deren Bew\u00e4ltigung aber einen entscheidenden Beitrag leisten kann.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e3mag.com\/partners\/data-migration-services\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration.jpg\" alt=\"https:\/\/e3mag.com\/partners\/data-migration-services-ag\/\" class=\"wp-image-54460\" title=\"Historische erp-daten: vereinfachen, automatisieren und geld sparen\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/08\/Data-Migration-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Der Wert eines Unternehmens bemisst sich am Gesamtbestand seiner Informationen \u2013 inklusive der historischen. Damit er sichtbarer wird, braucht es Vereinfachung und Automatisierung. Mit beidem l\u00e4sst sich viel Geld sparen, nicht morgen, sondern heute.<\/p>\n","protected":false},"author":1289,"featured_media":66936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[5,37729],"tags":[601,73,65,369,517],"coauthors":[22002],"class_list":["post-66934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-management","category-mag-2006","tag-digitalisierung","tag-erp","tag-hana","tag-it","tag-s4","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2020\/06\/shutterstock_1663089904_cmyk-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Der Wert eines Unternehmens bemisst sich am Gesamtbestand seiner Informationen \u2013 inklusive der historischen. Damit er sichtbarer wird, braucht es Vereinfachung und Automatisierung. Mit beidem l\u00e4sst sich viel Geld sparen, nicht morgen, sondern heute.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/it-management\/\" rel=\"category tag\">IT-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-2006\/\" rel=\"category tag\">MAG 20-06<\/a>","author_info_v2":{"name":"Thomas Failer, Data Migration International","url":"https:\/\/e3mag.com\/de\/author\/thomas-failer\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/66934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1289"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=66934"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/66934\/revisions"}],"predecessor-version":[{"id":148320,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/66934\/revisions\/148320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/66936"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=66934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=66934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=66934"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=66934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}