{"id":65711,"date":"2020-04-02T08:00:52","date_gmt":"2020-04-02T06:00:52","guid":{"rendered":"http:\/\/e3mag.com\/?p=65711"},"modified":"2020-03-30T10:46:53","modified_gmt":"2020-03-30T08:46:53","slug":"sap-lizenzen-immer-ein-grund-zum-streiten","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/sap-lizenzen-immer-ein-grund-zum-streiten\/","title":{"rendered":"SAP-Lizenzen \u2013 immer ein Grund zum Streiten?"},"content":{"rendered":"\r\n<p>Manche Lizenzunklarheiten lichten sich sp\u00e4testens mit S\/4 Hana. Zwar erst, wenn man sich f\u00fcr das \u201eS\/4 Hana Only\u201c-Lizenzmodell entscheidet, aber immerhin. Nur was bedeutet dieses \u201eOnly\u201c?<\/p>\r\n\r\n\r\n\r\n<p>Im Zuge der Meinungsverschiedenheiten zwischen SAP und diversen Datenbankherstellern hat sich SAP speziell mit dem Thema der R\u00fcckverg\u00fctung von Datenbanknutzungen au\u00dferhalb des vorgesehenen Standards auseinandersetzen m\u00fcssen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-50622930\"><div id=\"great-2167193712\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\r\n\r\n\r\n\r\n<p>Speziell hierbei ist das Thema der Third-Party-Lizenzen entstanden. Bei diesem Thema ist SAP \u2013 auch dank DSAG \u2013 in den vergangenen Monaten stark zur\u00fcckgerudert.<\/p>\r\n\r\n\r\n\r\n<p>Sollte man sich aber dazu entschlie\u00dfen, nur noch die Hana-Datenbank einzusetzen und sich dabei einem Vertragswechsel zu unterziehen, dann wird dieses Thema nahezu obsolet. Eine juristische Grundlage ist noch schwer einzuordnen, aber SAP setzt dieses Thema bei den meisten Kunden gerne aus.<\/p>\r\n\r\n\r\n\r\n<p>Nat\u00fcrlich nur nahezu. Denn ein gro\u00dfes Thema bleiben die neuen Digital-Access-Lizenzen. Diese endlich greifbaren Richtlinien der indirekten Nutzung sind auch vor allem dem Bem\u00fchen der DSAG zu verdanken.<\/p>\r\n\r\n\r\n\r\n<p>Nun lassen sich die Definitionen der indirekten Nutzung viel genauer festlegen. Derzeit sind zw\u00f6lf Bewegungsdaten (z. B. FI-Buchungszeilen, Auftragszeilen, Bestellzeilen etc.) festgelegt worden, deren Ursprung \u2013 sofern diese nicht von lizenzierten SAP-Usern erstellt worden sind \u2013 durch Digital-Access-Lizenzierung abzudecken ist.<\/p>\r\n\r\n\r\n\r\n<p>Aber Achtung: Auch hier liegt der Teufel im Detail. So sind aktuelle Lizenzmodelle wie beispielsweise \u201eSales Order Process\u201c nicht mit der neuen Lizenz\u00adart Digital Access mischbar. Hier empfiehlt es sich, ein beratendes Gespr\u00e4ch mit dem SAP-Partner zu vereinbaren, um die richtige Entscheidung zu treffen.<\/p>\r\n\r\n\r\n\r\n<p>Eine weitere Vereinfachung bei den Lizenzen stellt die Zuordnung der Gesch\u00e4ftsprozesse zu den Kategorien wie beispielsweise \u201eProfessional Use\u201c oder \u201eFunctional Use\u201c dar. Die fr\u00fchere Einordnung von Professional User und Limited User hat oftmals bei Vermessungen zu Problemen gef\u00fchrt.<\/p>\r\n\r\n\r\n\r\n<p>Jetzt ist aber ganz klar definiert, welcher Businessprozess mit welchem User darstellbar ist. Aber auch hier kommt man erst in den Genuss, wenn man sich einem Vertragswechsel unterzieht.<\/p>\r\n\r\n\r\n\r\n<p>Und genau bei dem Vertragswechsel steckt die Gefahr. Denn mit diesem Wechsel verzichtet man auf die bisherigen Lizenzanspr\u00fcche und somit auch teilweise auf Nutzungsvereinbarungen von Funktionen, die im neuen Lizenzmodell nicht mehr m\u00f6glich sind.<\/p>\r\n\r\n\r\n\r\n<p>Nur kennen viele der jungen Key Account Manager bei SAP diese Bedingungen nicht mehr \u2013 und dort beginnen auch gerne die Streitigkeiten zwischen Kunde und SAP. Deswegen ist immer zuerst ein Blick in die bestehende Vertragsgestaltung mit dem Abgleich der genutzten Funktionalit\u00e4ten dringend angeraten.<\/p>\r\n\r\n\r\n\r\n<p>Speziell Themen wir SRM und CRM k\u00f6nnen einem Vertragswechsel im Wege stehen. Hier ist es immer ratsam, die genaue Roadmap f\u00fcr die n\u00e4chsten Jahre auszuarbeiten \u2013 und einhergehend mit dem Wechsel von L\u00f6sungen auch die Lizenzverhandlungen zu verbinden.<\/p>\r\n\r\n\r\n\r\n<p>Solange man sich noch auf alten Vertr\u00e4gen bewegt, ist es schlussendlich auch in vielen Belangen immer ein Dialog, den man hier f\u00fchren kann. Mit SAP, mit seinem Partner und auch gerne mit der DSAG. Dann lassen sich immer L\u00f6sungen ohne Barrikaden finden.<\/p>\r\n\r\n\r\n\r\n<p>Ein noch komplexer Bereich bleibt das Thema Cloud. Hierbei im Vorfeld eine Einsch\u00e4tzung von Kosten \u00fcber geplante Szenarien zu bekommen ist auch f\u00fcr die SAP-Partnerwelt noch schwierig. Denn das Zusammenspiel zwischen Cloud-L\u00f6sungen, der SAP Cloud Platform und der SAP Cloud Integration rundet erst das richtige Preisspektrum ab.<\/p>\r\n\r\n\r\n\r\n<p>Besonders achtsam sollte man bei der Einbindung von Third-Party-Szenarien in das Cloud-Konzept sein. Denn hier gilt es wiederum genau zu hinterfragen, bei welchen Szenarien bis ins ERP hinein das Thema \u201eDigital Access\u201c wichtig wird. Hier bleibt leider nur der Schritt \u00fcber die SAP oder einen SAP-Partner.<\/p>\r\n\r\n\r\n\r\n<p>Deswegen empfiehlt es sich hier nicht zwingend, einen Blick auf die Preisliste zu werfen und sich entmutigen zu lassen. Definieren Sie Anforderungen und gehen Sie offen auf SAP und Partner zu.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>In den vergangenen Jahren hat SAP viele neue Begriffe in den undurchsichtigen Nebel der Lizenzierung geworfen. Sowohl bei der Cloud als auch im Bereich von On-prem. Warum steigen viele Kunden auf die Barrikaden und wo lichtet sich dieser Nebel?<\/p>\n","protected":false},"author":2038,"featured_media":2453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,11,37393],"tags":[39,273,65,269,21219],"coauthors":[37463],"class_list":["post-65711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-lizenz-kolumne","category-mag-2003","tag-cloud","tag-dsag","tag-hana","tag-lizenzen","tag-s-4","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",400,173,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-768x332.jpg",768,332,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-100x43.jpg",100,43,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-480x207.jpg",480,207,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-640x276.jpg",640,276,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-720x311.jpg",720,311,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-960x415.jpg",960,415,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",600,259,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/Lizenzen-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>In den vergangenen Jahren hat SAP viele neue Begriffe in den undurchsichtigen Nebel der Lizenzierung geworfen. Sowohl bei der Cloud als auch im Bereich von On-prem. Warum steigen viele Kunden auf die Barrikaden und wo lichtet sich dieser Nebel?<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/lizenz-kolumne\/\" rel=\"category tag\">Lizenz-Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-2003\/\" rel=\"category tag\">MAG 20-03<\/a>","author_info_v2":{"name":"Otto Kitzm\u00fcller, Informatics","url":"https:\/\/e3mag.com\/de\/author\/otto-kitzmueller\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/65711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2038"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=65711"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/65711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/2453"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=65711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=65711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=65711"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=65711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}