{"id":64412,"date":"2020-02-27T09:56:00","date_gmt":"2020-02-27T08:56:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=64412"},"modified":"2025-09-29T14:18:32","modified_gmt":"2025-09-29T12:18:32","slug":"allen-unkenrufen-trotz","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/allen-unkenrufen-trotz\/","title":{"rendered":"Allen Unkenrufen zum Trotz"},"content":{"rendered":"\n<p>Wird nicht gleich zu Beginn des \u201eRequirements to Deploy\u201c-Prozesses das Backlog klar definiert und priorisiert, steigt bereits das Projektrisiko: Fehlende Transparenz f\u00fchrt zu Verz\u00f6gerungen und Mehraufwand. Ein effizientes Change-Management verlangt klare Planung und Kontrolle, damit keine Nachbesserungen anfallen. Darauf hat SAP mit der vorkonfigurierten Best-Practice-L\u00f6sung Focused Build reagiert und die bestehende SolMan-L\u00f6sung agiler, benutzerfreundlicher und nicht zuletzt \u2013 durch volle Integration \u2013 transparent gemacht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SAP ALM, Focused Build und mehr<\/h2>\n\n\n\n<p>Zur Planung von Projekten sind die SAP-ALM-Methodologien ein klarer Vorteil: Sie bauen zum einen auf den W\u00fcnschen der Anwenderunternehmen auf \u2013 mit dem SAP-Customer-Connect-Programm sind in den vergangenen Jahren Kundenw\u00fcnsche direkt in das Produkt geflossen \u2013 und zum anderen k\u00f6nnen auch Best Practices verwendet werden, die auf der Projekterfahrung vieler SAP-Implementierungsprojekte aufbauen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1354300057\"><div id=\"great-4125179214\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Im Bereich Run und Operations hat SAP die Diagnostik-, \u00dcberwachungs- und Analysefunktionen mit Focused Run auf das n\u00e4chste Level gehoben: Focused Run warnt nicht nur fr\u00fchzeitig vor Problemen, sondern erweitert die System\u00fcberwachung so, dass maschinelles Lernen, Pattern Matching, Cluster-Analyse und verschiedene Visualisierungen ebenso genutzt werden k\u00f6nnen. All die wertvollen Erfahrungen aus den On-prem-Produkten m\u00fcnden letztendlich in dem j\u00fcngsten Produkt SAP Cloud ALM. Seit 2018 hat SAP das Portfolio um Cloud ALM erg\u00e4nzt und kann cloudzentrische Projekte von der Planung bis hin zur Implementierung optimal unterst\u00fctzen.<\/p>\n\n\n\n<p>Erweiterungen im Funktionsumfang sind in der Pipeline, sodass bis 2022 auch Operations-Funktionen in Cloud ALM zu finden sein werden. Ziel ist es also, dass auch Kunden mit wenigen On-prem-L\u00f6sungen eine optimale ALM-L\u00f6sung erhalten.<\/p>\n\n\n\n<p>Die St\u00e4rke der Produkte liegt darin, dass die L\u00f6sungen integriert sind. Einzelne Bereiche sind nicht in abgeschotteten Silos, sondern in Value Chains gegliedert, was ein Zusammenspiel ihrer Vorteile m\u00f6glich macht. So sind die L\u00f6sungen weit mehr als nur Monitoring-Tools: Die Produkte unterst\u00fctzen ganze Szenarien wie \u201eRequirements to Deploy\u201c oder \u201eDetect and Correct\u201c.<\/p>\n\n\n\n<p>Wo bei nicht integrierten L\u00f6sungen die Probleme bereits programmiert sind, da keine aktuelle Dokumentation der Unternehmensprozesse existiert oder weil zusammenh\u00e4ngende \u00c4nderungen nicht integrativ getestet werden (k\u00f6nnen), minimieren die ALM-L\u00f6sungen von SAP, sofern richtig implementiert und genutzt, die Risiken und den Zeitaufwand sowie die Kosten.<\/p>\n\n\n\n<p>Gleichzeitig werden sowohl Unternehmensprozesse als auch Ver\u00e4nderungen im System nachvollziehbar, was Audits unproblematisch und die Systemlandschaft endlich transparent macht. Die volle Transparenz wird zus\u00e4tzlich durch Focused Insights untermauert, mit dem auf einfache und schnelle Art und Weise komplexe Zusammenh\u00e4nge in Dashboards dargestellt werden k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SolMan u.a. helfen Kunden, erfolgreich zu sein<\/h2>\n\n\n\n<p>Mit Focused Build wird jedes Release mit allen Entwicklungen und Ver\u00e4nderungen in der SAP-Systemlandschaft durchg\u00e4ngig von Anfang bis Ende geplant. Damit entsteht ein enorm leistungsf\u00e4higes ALM-Tool. W\u00e4hrend mit dem \u201eManagement by Office\u201c Excel-Tabellen herumgereicht werden und die Suche nach Dokumentationen und Abh\u00e4ngigkeiten epische Formen annimmt, zeigt und verwaltet Focused Build alle Prozessschritte aktuell, transparent und \u00fcbersichtlich.<\/p>\n\n\n\n<p>Die Test\u00adszenarien sind optimal integriert und unterst\u00fctzt. Tests sind automatisch wiederholbar und werden mithilfe von Dashboards in Echtzeit gesteuert. Und da SAP-Projekte effizienter werden m\u00fcssen, damit die SAP-Anwenderunternehmen die anstehenden gro\u00dfen, aber auch die vielen kleinen Changes innerhalb einer komplexen L\u00f6sungslandschaft gut bew\u00e4ltigen k\u00f6nnen, tragen all diese Tatsachen zum Erfolg bei. Ein professionelles ALM mit dem Solu\u00adtion Manager und Focused Build stellt die Weichen, sodass ein Projekt zuverl\u00e4ssig und \u00adkosteneffektiv abgeschlossen werden kann.<\/p>\n\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/09\/2002_blue_works_E_web.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">PDF auf Englisch<\/a><\/h2>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Mit dem SolMan mit Focused Build und Focused Insights, Cloud ALM und Focused Run bietet SAP das derzeit beste ALM-Produktportfolio f\u00fcr die unterschiedlichsten Bed\u00fcrfnisse.<\/p>\n","protected":false},"author":1536,"featured_media":4955,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,37274,23],"tags":[13335,30757,36985,286],"coauthors":[23529],"class_list":["post-64412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-mag-2002","category-solman","tag-alm","tag-cloud-alm","tag-on-prem","tag-solman","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",400,172,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-768x331.jpg",768,331,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-100x43.jpg",100,43,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-480x207.jpg",480,207,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-640x276.jpg",640,276,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-720x310.jpg",720,310,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-960x414.jpg",960,414,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",1000,431,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan.jpg",600,259,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/SolMan-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Mit dem SolMan mit Focused Build und Focused Insights, Cloud ALM und Focused Run bietet SAP das derzeit beste ALM-Produktportfolio f\u00fcr die unterschiedlichsten Bed\u00fcrfnisse.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-2002\/\" rel=\"category tag\">MAG 20-02<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/solman\/\" rel=\"category tag\">SolMan Kolumne<\/a>","author_info_v2":{"name":"Stefan Thomann, Blueworks","url":"https:\/\/e3mag.com\/de\/author\/stefan-thomann-autor\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/64412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1536"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=64412"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/64412\/revisions"}],"predecessor-version":[{"id":155846,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/64412\/revisions\/155846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/4955"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=64412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=64412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=64412"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=64412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}