{"id":62823,"date":"2019-11-05T08:00:24","date_gmt":"2019-11-05T07:00:24","guid":{"rendered":"http:\/\/e3mag.com\/?p=62823"},"modified":"2024-01-19T14:49:44","modified_gmt":"2024-01-19T13:49:44","slug":"it-sicherheit-und-datenschutz","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/it-sicherheit-und-datenschutz\/","title":{"rendered":"IT-Sicherheit und Datenschutz"},"content":{"rendered":"<p>IT-Sicherheit und Cybersecurity werden mit der digitalen Transformation immer wichtiger \u2013 gesellschaftlich, wirtschaftlich und politisch. Diese Entwicklung zeigt sich deutlich am Interesse an der it-sa.<\/p>\n<p><em>\u201ePraktisch alle namhaften Anbieter aus der IT-Sicherheitsbranche sowie gro\u00dfe internationale Konzerne mit ihrer Cyber-Sicherheitssparte haben sich angemeldet\u201c<\/em><\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-2356823988\"><div id=\"great-4250530742\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/e3mag.com\/de\/event\/e3-roundtable-it-plattformen-sap-btp-sap-bdc-etc\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26_08_26_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>freut sich Frank Venjakob, Executive Director it-sa.<\/p>\n<p>Der Fokus liegt auf konkreten Anwenderszenarien \u2013 von der Industrie 4.0 \u00fcber Fintech, kritische Infrastrukturen, \u00f6ffentliche Verwaltung bis zum Gesundheitswesen. Interessierte erhalten deshalb in diesem Jahr noch einmal mehr branchenspezifische Angebote und Formate im Rahmenprogramm.<\/p>\n<p>Das Vortragsprogramm der offenen Foren bildet mit \u00fcber 300 Beitr\u00e4gen einen Querschnitt aktueller IT-Sicherheitsfragen ab. Zu den H\u00f6hepunkten z\u00e4hlen Expertendiskussionen und Fachvortr\u00e4ge beispielsweise zur IT-Sicherheit in Krankenh\u00e4usern und dem Finanzsektor, zur Standardisierung f\u00fcr die Blockchain oder Sicherheitsfragen beim Smart Metering.<\/p>\n<p>Die wachsende Relevanz sicherer IT-Infrastrukturen zeigt auch die Entwicklung der it-sa, der weltweit ausstellerst\u00e4rksten Messe zum Thema. Das Thema Cybersecurity besch\u00e4ftigt nicht nur die Wirtschaft, sondern eben auch die Regierungsstellen.<\/p>\n<p>Im vergangenen Jahr hat die Bundesregierung die Gr\u00fcndung einer Agentur f\u00fcr Innovation in der Cybersicherheit beschlossen. Mit der Region Leipzig\/Halle ist jetzt der k\u00fcnftige Standort der Agentur bekannt.<\/p>\n<p>Dazu erkl\u00e4rt Bitkom-Pr\u00e4sident Achim Berg:<\/p>\n<p><em>\u201eDie Agentur f\u00fcr Innovation in der Cybersicherheit muss und kann wichtige Beitr\u00e4ge nicht nur f\u00fcr ein Mehr an Cybersicherheit, sondern ebenso f\u00fcr einen Zugewinn an digitaler Souver\u00e4nit\u00e4t in Deutschland leisten. <\/em><\/p>\n<p><em>Wir begr\u00fc\u00dfen es, dass die Bundesregierung inzwischen eine Standortentscheidung getroffen hat. Jetzt gilt es, mehr Tempo aufzunehmen und die Pl\u00e4ne schnell in die Tat umzusetzen. <\/em><\/p>\n<p><em>Als Rechtsform bietet sich eine GmbH an. Die Agentur bekommt damit schnellere und schlankere Prozesse, agiert freier und kann attraktivere Angebote an die umworbenen Spezialisten f\u00fcr IT-Sicherheit machen. <\/em><\/p>\n<p><em>Entscheidend ist, dass die neue Cyberagentur wie angek\u00fcndigt auch risikoreiche Projekte f\u00f6rdert und sich nicht im Beh\u00f6rden-Klein- Klein verliert. Der Weg von der Forschung in die Praxis ist lang genug. Je eher die Cyberagentur ihre Arbeit aufnimmt, desto besser f\u00fcr Deutschlands Cybersicherheit.\u201c <\/em><\/p>\n<p>Onliner in Deutschland sind besorgt \u00fcber die Sicherheitslage im Internet. Neun von zehn Internetnutzern (89 Prozent) sehen eine wachsende Bedrohung durch Internetkriminalit\u00e4t. Das ist das Ergebnis einer repr\u00e4sentativen Umfrage im Auftrag des Digitalverbands Bitkom unter mehr als 1000 Internetnutzern in Deutschland.<\/p>\n<p><em>\u201eViele Nutzer haben inzwischen ein gr\u00f6\u00dferes Bewusstsein f\u00fcr Gefahren im Internet\u201c<\/em><\/p>\n<p>sagt Susanne Dehmel, Mitglied der Bitkom-Gesch\u00e4ftsleitung.<\/p>\n<p><em>\u201eDie Polizei verzeichnet jedes Jahr mehr Cyberdelikte. Internetkriminelle gehen immer trickreicher vor und gleichzeitig nimmt die Zahl der vernetzten Ger\u00e4te st\u00e4ndig zu.\u201c<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ob Wirtschaft, Verwaltung oder Politik \u2013 Cybersicherheit ist im Zuge der Digitalisierung eine dr\u00e4ngende Herausforderung, der sich Staats- und Unternehmenslenker stellen m\u00fcssen. Die digitale Vernetzung macht Wirtschaft, Staat und Gesellschaft angreifbar, wie zahlreiche Beispiele zeigen.<\/p>\n","protected":false},"author":38,"featured_media":62824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[161,2,36593],"tags":[35,7792,6124],"coauthors":[19920],"class_list":["post-62823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-szene","category-sap-nachrichten","category-mag-1910","tag-bitkom","tag-digitalen-transformation","tag-it-sa","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/10\/shutterstock_760170937-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Ob Wirtschaft, Verwaltung oder Politik \u2013 Cybersicherheit ist im Zuge der Digitalisierung eine dr\u00e4ngende Herausforderung, der sich Staats- und Unternehmenslenker stellen m\u00fcssen. Die digitale Vernetzung macht Wirtschaft, Staat und Gesellschaft angreifbar, wie zahlreiche Beispiele zeigen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/szene\/\" rel=\"category tag\">Szene<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-1910\/\" rel=\"category tag\">MAG 19-10<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/62823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=62823"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/62823\/revisions"}],"predecessor-version":[{"id":137950,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/62823\/revisions\/137950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/62824"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=62823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=62823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=62823"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=62823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}