{"id":61451,"date":"2015-11-03T13:33:04","date_gmt":"2015-11-03T12:33:04","guid":{"rendered":"http:\/\/e3mag.com\/?p=61451"},"modified":"2024-01-19T14:54:24","modified_gmt":"2024-01-19T13:54:24","slug":"frachtkosten-im-blick","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/frachtkosten-im-blick\/","title":{"rendered":"Frachtkosten im Blick"},"content":{"rendered":"<p>Pro Jahr fallen in der Firmenzentrale in Ditzingen ca. 17.500 Papierrechnungen von Logistikdienstleistern f\u00fcr durchgef\u00fchrte Frachten an. Diese beinhalten 210.000 Positionen f\u00fcr Ersatz-, Service- und Kleinteile sowie 16.000 Positionen f\u00fcr Maschinenversand. 90 Prozent aller Frachten wickelt Trumpf \u00fcber f\u00fcnf Dienstleister ab, mit denen bestimmte Konditionen vereinbart sind.<\/p>\n<p>Erh\u00e4lt Trumpf die Rechnungen der Dienstleister, m\u00fcssen diese auf Abweichungen von den vereinbarten Konditionen \u00fcberpr\u00fcft werden. Ein enormer Aufwand, denn die Rechnungen umfassen teilweise bis zu 200 Seiten.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3857848364\"><div id=\"great-3693018337\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/e3mag.com\/de\/podcast-erp-architekturen-mit-suse\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"e3pc_banner_2609_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"800\" height=\"100\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>Dieser Prozess der Frachtkostenpr\u00fcfung sollte nun vereinfacht und mit einer wesentlich h\u00f6heren Pr\u00fcfqualit\u00e4t verbunden werden. Die elektronischen Eingangsrechnungen der Dienstleister sollten automatisch gepr\u00fcft und innerhalb einer definierten Toleranzgrenze vom System gebucht werden.<\/p>\n<p>Positionen mit Abweichungen au\u00dferhalb des Schwellwertes hingegen sollten markiert und im Folgeschritt manuell vom Versand gepr\u00fcft werden. Zugleich sollte die neue L\u00f6sung von den Mitarbeitern leicht pflegbar und ohne gro\u00dfen Aufwand international ausrollbar sein.<\/p>\n<p>Die nachfolgenden Ausschreibung konnte f\u00fcr Serkem mit einer direkt in SAP implementierten Frachtkostenl\u00f6sung f\u00fcr sich entschieden. Alle Anforderungen von Trumpf werden benutzerfreundlich in SAP abgebildet.<\/p>\n<p>Ein Frachtkostenmonitor \u2013 das Herzst\u00fcck der L\u00f6sung \u2013 erm\u00f6glicht dabei die \u00fcbersichtliche \u00dcberwachung und Steuerung aller Vorg\u00e4nge.<\/p>\n<h3>Automatisierte Frachtkostenpr\u00fcfung in SAP<\/h3>\n<p>Zu jeder Auslieferung legt das SAP-System einen Transport sowie einen Frachtkostenbeleg an. Im Frachtkostenbeleg werden die Soll-Frachtkosten anhand der Konditionen vorausberechnet, die zu jedem Dienstleister in SAP hinterlegt sind.<\/p>\n<p>Als Basis der Berechnung k\u00f6nnen wahlweise Bruttogewicht, Volumengewicht oder Lademeter eingestellt werden. Die Konditionen lassen sich dabei von den Mitarbeitern bequem per Excel-Tabelle pflegen und einfach im SAP-System aktualisieren.<\/p>\n<p>Pro Spediteur sind bis zu 20 Konditionsarten mit einer beliebigen Anzahl an Auspr\u00e4gungen hinterleg- und pflegbar. Jede Konditionsvereinbarung hat ihren individuellen G\u00fcltigkeitszeitraum.<\/p>\n<p>Zuschl\u00e4ge f\u00fcr Entfernung, Gewicht, Gefahrgut, Incoterms etc. werden so bei der Soll-Kostenberechnung ber\u00fccksichtigt. Anhand der Versandbedingungen wird zus\u00e4tzlich die sp\u00e4teste Zustellzeit ermittelt und sp\u00e4ter mit der Zeit aus der Lieferempfangsbest\u00e4tigung abgeglichen, beispielsweise bei Express bis 10 Uhr.<\/p>\n<h3>Rechnungen konvertieren<\/h3>\n<p>Die elektronischen Rechnungen und Abliefernachweise der einzelnen Dienstleister werden als Einzelrechnung in verschiedenen Formaten an einen Datenkonvertierer geliefert und dort in ein einheitliches SAP-IDOC-Format konvertiert. Anschlie\u00dfend werden die konvertierten Rechnungen an das Modul PI des Trumpf-SAP \u00fcbertragen und in den Frachtpr\u00fcfungsmonitor eingelesen.<\/p>\n<p>Im Frachtkostenmonitor werden die einzelnen Positionen auf Abweichungen zu den vorausberechneten Frachtkosten und Lieferzeiten gepr\u00fcft: den zuvor ermittelten Soll-Werten werden nun auf Positionsebene die Ist-Werte der Eingangsrechnungen gegen\u00fcbergestellt.<\/p>\n<p>Liegt die Abweichung unter dem vorab eingestellten Schwellwert, wird die Rechnungsposition automatisch im SAP-System gebucht und ist damit integriert in der Finanzbuchhaltung zur Zahlung frei.<\/p>\n<p>Wird der Schwellwert \u00fcberschritten \u2013 z. B. Express bis 10 Uhr bestellt, Anlieferung nach 10 Uhr oder \u00dcberschreitung der Soll-Kosten um mehr als drei Prozent \u2013, erh\u00e4lt die Versandabteilung eine Benachrichtigung vom System. Die Position wird in der \u00dcbersicht gekennzeichnet und vom Versand manuell gepr\u00fcft.<\/p>\n<p>Besonders wichtig war Trumpf die Kontrolle der Zustellzeiten. Anhand der Versandbedingungen wird jetzt die sp\u00e4teste Zustellzeit ermittelt und mit der tats\u00e4chlichen Zustellzeit abgeglichen.<\/p>\n<p>Trumpf zahlt so zuk\u00fcnftig nur noch dann Zuschl\u00e4ge f\u00fcr Express-Versand, wenn die Zustellung rechtzeitig erfolgt. Durch den Einsatz des komplett in SAP umgesetzten Monitors sparte Trumpf bereits im ersten Jahr \u00fcber 250.000 Euro ein. Gleichzeitig wird \u00fcber den Monitor von Serkem die Liefertreue der Dienstleister ausgewertet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Werkzeugmaschinenhersteller Trumpf wollte die Genauigkeit der Frachtkostenpr\u00fcfung erh\u00f6hen und den manuellen Aufwand minimieren. Eine direkt in SAP implementierte Frachtkostenl\u00f6sung verarbeitet in Zukunft die Eingangsrechnungen der Logistikdienstleister verst\u00e4rkt automatisiert.<\/p>\n","protected":false},"author":38,"featured_media":61274,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[161,2,1583],"tags":[5786],"coauthors":[19920],"class_list":["post-61451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-szene","category-sap-nachrichten","category-1583","tag-automatisiert","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",400,155,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-768x297.jpg",768,297,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-100x39.jpg",100,39,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-480x186.jpg",480,186,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-640x248.jpg",640,248,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-720x279.jpg",720,279,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-960x372.jpg",960,372,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",600,232,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",600,232,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Werkzeugmaschinenhersteller Trumpf wollte die Genauigkeit der Frachtkostenpr\u00fcfung erh\u00f6hen und den manuellen Aufwand minimieren. Eine direkt in SAP implementierte Frachtkostenl\u00f6sung verarbeitet in Zukunft die Eingangsrechnungen der Logistikdienstleister verst\u00e4rkt automatisiert.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/szene\/\" rel=\"category tag\">Szene<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/1511\/\" rel=\"category tag\">MAG 15-11<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/61451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=61451"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/61451\/revisions"}],"predecessor-version":[{"id":138467,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/61451\/revisions\/138467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/61274"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=61451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=61451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=61451"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=61451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}