{"id":61434,"date":"2015-11-03T11:20:07","date_gmt":"2015-11-03T10:20:07","guid":{"rendered":"http:\/\/e3mag.com\/?p=61434"},"modified":"2019-07-24T11:30:59","modified_gmt":"2019-07-24T09:30:59","slug":"future-ready-cloud-portfolio","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/future-ready-cloud-portfolio\/","title":{"rendered":"Future-ready-Cloud-Portfolio"},"content":{"rendered":"<p>Cloud Computing hat sich in Deutschland lange Zeit schwergetan. In den ersten Jahren nach dem inoffiziellen Start der Cloud im Jahre 2006 wurde das neue \u2013 durchaus revolution\u00e4re \u2013 IT-Konzept zwar breit diskutiert und gepr\u00fcft, aber an konkrete Umsetzungen wollten sich nur wenige wagen.<\/p>\n<p>Vor allem der deutsche Mittelstand, R\u00fcckgrat der Volkswirtschaft, blieb beim Thema Cloud Computing lange Zeit \u00fcberaus zur\u00fcckhaltend, auch dann noch, als in der neuen Dekade auch hiesige Gro\u00dfunternehmen verst\u00e4rkt darangingen, Cloud-L\u00f6sungen zu implementieren.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1695591793\"><div id=\"great-2657366405\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=iFPzKOVI4rg\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26_07_22_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>Vielen war die Vorstellung unheimlich, die eigenen Daten \u2013 sozusagen die digitale Transsubstantiation des Know-hows \u2013 aus der Hand zu geben, sie nicht im eigenen Haus unter der eigenen Kontrolle zu wissen, also auf die M\u00f6glichkeit zu verzichten, notfalls rasch und ohne R\u00fccksprache mit dem CIO einen Stecker ziehen und sich damit von den F\u00e4hrnissen der Welt einfach abkoppeln zu k\u00f6nnen.<\/p>\n<p>Da die geldwerten Vorteile der Cloud durch Skalierbarkeit und Flexibilit\u00e4t auf Dauer aber keinen Betriebswirt unbeeindruckt lie\u00dfen, begannen sich etwa ab 2011 Unternehmen trotzdem auf breiter Front, also auch im vorsichtigen Mittelstand, f\u00fcr die Cloud-Idee zu erw\u00e4rmen.<\/p>\n<p>Die gro\u00dfe Cloud-Krise mit der Snowden-Aff\u00e4re stoppte 2013 diese Entwicklung. Jetzt waren auf einmal alle Einw\u00e4nde und Bedenken ins Recht gesetzt, und eigentlich war alles noch schlimmer als je bef\u00fcrchtet.<\/p>\n<p>Wer bisher grunds\u00e4tzlich nichts Digitales aus der Hand gegeben hatte, der hatte, so schien es jetzt, aufs richtige Pferd gesetzt. So war es kein Wunder, dass schon vom \u201eEnde der Cloud\u201c gemunkelt wurde.<\/p>\n<p>Heute, mehr als zwei Jahre sp\u00e4ter, haben sich die Wogen zwar wieder gegl\u00e4ttet und eine differenzierte Betrachtung hat die Oberhand gewonnen, aber es ist trotzdem nichts mehr wie vor 2013.<\/p>\n<p>Kaum jemand h\u00e4lt die Einw\u00e4nde und Bedenken f\u00fcr grunds\u00e4tzlich erledigt. Im Gegenteil: Sie sind heute fester Bestandteil jeder vern\u00fcnftigen Cloud-Strategie. Niemand leugnet ernsthaft die Risiken des Cloud Computing.<\/p>\n<p>Die Sicherheit von Daten, Anwendungen und Systemen ist ein Top-Thema, wo immer die Cloud diskutiert wird. So ist die heute \u00fcbliche Differenzierung des Cloud-Konzepts in die Modelle Public \u2013 eigentlich war 2006 nur das die Idee gewesen \u2013, Private und Hybrid auch eine Folge dieses etwas beschwerlichen Weges.<\/p>\n<p>Insofern lassen sich die zur\u00fcckliegenden neun Jahre Cloud Computing als Reifungs- und Lernprozess verstehen, der \u00fcber Klippen und R\u00fcckschl\u00e4ge zu einem vorl\u00e4ufigen Ergebnis gef\u00fchrt hat, das klar besser, effizienter und vor allem sicherer ist als das, was 2006 ins Spiel gebracht worden war.<\/p>\n<p>Damit ist Cloud Computing zu einer Erfolgsgeschichte geworden, deren Fortsetzung gerade hierzulande eine solide und sichere Basis findet.<\/p>\n<h3>Hybrid geht vor<\/h3>\n<p>Kein Wunder, dass Cloud Computing heute auch in Deutschland, nicht nur bei Fans, sondern auch im Zust\u00e4ndigkeitsbereich vorsichtiger Ingenieure und Betriebswirte etabliert ist.<\/p>\n<p>Fast die H\u00e4lfte der deutschen Unternehmen nutzt bereits Cloud Computing, und ein weiteres Viertel hat entsprechende Pl\u00e4ne in der Schublade. Der lange und oft schwierige Weg zur Cloud hat aber auch dazu gef\u00fchrt, dass gerade Unternehmen in Europa und besonders in Deutschland diese Vorteile heute sehr differenziert wahrnehmen.<\/p>\n<p>Dogmatische Positionen \u2013 nur Cloud versus niemals Cloud \u2013 wird man hier nur sehr selten finden. Anders als in den USA, wo die Public Cloud im Vordergrund steht, wird hier das Modell der Hybrid Cloud, also die Kombination von Public Cloud und Private Cloud, klar bevorzugt:<\/p>\n<p>Neun von zehn Unternehmen bevorzugen das hybride Modell f\u00fcr k\u00fcnftige IT-Umgebungen, weil sie zwar die Vorteile des Cloud-Konzepts nutzen, aber doch nicht alles nach au\u00dfen geben wollen.<\/p>\n<p>Bei Test- und Entwicklungsumgebungen werden die Kosten- und Flexibilit\u00e4tsvorteile der Public Cloud gern in Anspruch genommen \u2013 gerade auch im Umfeld von SAP-Anwendungen. Sobald es aber in die Pre-Produktion oder in die Produktion geht, erwarten die Unternehmen mehr Sicherheit und Kontrolle.<\/p>\n<p>Der Hybrid-Ansatz l\u00e4sst sich auch unter fachlich-inhaltlichen Aspekten sehen: So werden gerade in Deutschland ERP-Systeme h\u00e4ufig konservativ betrieben, also bevorzugt on-premise; eine ganze SAP-Umgebung in die Public Cloud beispielsweise zu Amazon S3 zu geben, haben bisher nur wenige gewagt.<\/p>\n<p>Ein Grund daf\u00fcr ist, dass man die betreffenden Daten als zu wichtig betrachtet, ein anderer, dass die Automatisierung der eigenen SAP-Welt noch gar nicht so weit ist; hier stehen viele Anwender noch am Anfang.<\/p>\n<p>In anderen Bereichen sind Unternehmen weiter. Zum Beispiel ist bei E-Mail-Anwendungen oder bei MS Office 365 die Akzeptanz der Cloud deutlich h\u00f6her. Generell werden Commodity-Anwendungen tendenziell eher in die (Public) Cloud verlagert, weil sich hier Kostenvorteile in der Regel ohne Pferdefu\u00df realisieren lassen.<\/p>\n<p>Bei SAP-Systemen ist eine Off-Premise Private Cloud, wie sie durch Managed Service Provider angeboten wird, der bevorzugte Weg; wobei Dell in Deutschland auf bew\u00e4hrte Partner zur\u00fcckgreift.<\/p>\n<p>Ein weiterer wichtiger Aspekt ist die hohe Standardisierung, die die Grundlage f\u00fcr die Kostenvorteile der Public Cloud ist \u2013 diese stellen sich ja nur ein, weil Provider vielen Kunden die gleichen Ressourcen auf gleiche Weise zur Verf\u00fcgung stellen k\u00f6nnen.<\/p>\n<p>Das beschr\u00e4nkt jedoch die Differenzierungsm\u00f6glichkeiten der Anwender im Markt. Auch deswegen lassen Anwender oft zentrale Aufgaben und Assets m\u00f6glichst nahe am Unternehmen, sei es in einem klassischen On-Premise-Modell mit der IT im eigenen Haus, die dann trotzdem Cloud-Technologie nutzen kann, oder off-premise bei einem Service Provider, dann aber in einer dedizierten Umgebung, die ihre Ressourcen exklusiv bereitstellt.<\/p>\n<p>Letztlich geht es darum, einen \u201egoldenen\u201c Mittelweg zwischen Flexibilit\u00e4t, Effizienz und Sicherheit zu finden, und dieser m\u00fcndet direkt in die Hybrid Cloud.<\/p>\n<p>Mittlerweile gibt es auch einen starken Trend zur Public Cloud Repatriation: Viele Unternehmen, die Public Cloud ausprobiert haben, sehen, dass sie ihre Anforderungen an Sicherheit und Individualisierung so nicht erf\u00fcllen k\u00f6nnen.<\/p>\n<p>Anders als zu Beginn der Cloud-\u00c4ra gibt es heute auch kleinere Service Provider, die im Markt besser anpassbare L\u00f6sungen als die gro\u00dfen Private Clouds zur Verf\u00fcgung stellen, sodass die Anwender Alternativen haben.<\/p>\n<p>Dabei erhalten sich aber die meisten Unternehmen die gewonnenen Erfahrungen und nutzen die Public Cloud weiterhin als zus\u00e4tzliche Ressource, z. B. f\u00fcr Lastspitzen \u2013 womit sie sich letzten Endes ebenfalls in einer Hybrid-Cloud-Umgebung wiederfinden.<\/p>\n<p>Gerade wegen der Vielfalt von Modellen und Ans\u00e4tzen, die unterschiedliche Anforderungen aufgreifen k\u00f6nnen, erweist sich Cloud Computing als Markt, der deutlich mehr w\u00e4chst als die \u00fcbrige IT.<\/p>\n<p>Dell begleitet die Reise der Anwender zur Cloud und im Weiteren mit der Cloud schon von Anfang an. Heute bietet das Unternehmen ein breites Portfolio von L\u00f6sungen, die unterschiedliche Cloud-Modelle, -Architekturen und -Ans\u00e4tze f\u00fcr Workloads aller Gr\u00f6\u00dfen abdecken. Dabei stellt Dell jeweils Hardware, Software und die passenden Dienstleistungen, also Komplettl\u00f6sungen, zur Verf\u00fcgung.<\/p>\n<ul>\n<li>Dell unterst\u00fctzt die Realisierung lokaler Private Clouds durch hyperconverged Server, Software Defined Datacenter und Software. Die Infrastruktur- und Automatisierungsl\u00f6sungen erlauben es Anwendern, ihre Cloud-Umgebung mit den eigenen Assets effizient zu betreiben.\n<p>IT- oder SAP-Fachanwender k\u00f6nnen beispielsweise Test- oder Entwicklungssysteme selbst buchen oder neue Ressourcen schnell bereitstellen beziehungsweise in Anspruch nehmen.<\/li>\n<li>Anwender, die zwar eine Private Cloud brauchen, aber diese nicht selbst betreiben wollen, k\u00f6nnen auf Service Provider zur\u00fcckgreifen. Dell arbeitet hier mit Partnern zusammen, die eine Infrastruktur zur Verf\u00fcgung stellen und diese auch hosten; sie bieten daf\u00fcr auch spezielles SAP-Know-how sowie Managed Services. Dabei baut Dell solche Cloud-Umgebungen auch zusammen mit den Providern auf und unterst\u00fctzt diese beim Bereitstellen ihrer Services.<\/li>\n<li>Mit dem Dell Cloud Manager k\u00f6nnen Anwender Dienste in verschiedenen Clouds, eigenen wie fremden, steuern und \u00fcberwachen.<\/li>\n<li>L\u00f6sungen wie Shareplex und Boomi unterst\u00fctzen Anwender bei der Integration und Migration von Anwendungen in die Cloud, zum Beispiel von Salesforce oder einer Reisekosten-Abrechnung.<\/li>\n<li>Da das Thema Sicherheit in jeder Cloud-Umgebung von zentraler Bedeutung ist, bietet Dell ein umfangreiches Cloud-Security-Portfolio. Es umfasst zum einen Managed Security, also Sicherheits-Dienstleistungen wie ein proaktives Monitoring, das Unternehmen auf m\u00f6gliche Gef\u00e4hrdungen hinweist.\n<p>Zum anderen bietet Dell Software-Produkte, mit denen Anwender ihre Cloud-Sicherheit selbst verbessern k\u00f6nnen, beispielsweise den Dell One Identity Manager f\u00fcr ein l\u00fcckenloses Access- und Identity-Management.<\/li>\n<\/ul>\n<p>Die \u00fcberwiegende Mehrzahl der Unternehmen wird in Zukunft auf die Hybrid Cloud setzen, weil sie nur so differenzierte Anforderungen erf\u00fcllen k\u00f6nnen. Damit w\u00e4hlen sie ein Modell, das anspruchsvoller ist als ein simples, aber wenig zukunftsf\u00e4higes \u201eAlles Cloud\u201c oder ein \u201eNiemals Cloud\u201c.<\/p>\n<p>Umso wichtiger ist es, auf dem Weg in diese Cloud einen Partner zu haben, der wie Dell nicht nur \u00fcber ein leistungsf\u00e4higes Cloud-Portfolio verf\u00fcgt, sondern auch \u00fcber Know-how und Erfahrung im Cloud Computing.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber etliche Schwierigkeiten hinweg hat sich Cloud Computing mittlerweile auch in Deutschland etabliert. Mehr und mehr erweist sich die Hybrid Cloud als Modell der Zukunft. Dell kann daf\u00fcr ein breites Portfolio an Infrastruktur, Software und Dienstleistungen zur Verf\u00fcgung stellen.    <\/p>\n","protected":false},"author":1843,"featured_media":61274,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[22146,1583],"tags":[145,39,621,5010],"coauthors":[34277,34314],"class_list":["post-61434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-1511","category-1583","tag-automatisierung","tag-cloud","tag-cloud-computing","tag-public-cloud","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",400,155,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-768x297.jpg",768,297,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-100x39.jpg",100,39,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-480x186.jpg",480,186,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-640x248.jpg",640,248,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-720x279.jpg",720,279,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-960x372.jpg",960,372,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",600,232,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015.jpg",600,232,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2019\/07\/2015-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>\u00dcber etliche Schwierigkeiten hinweg hat sich Cloud Computing mittlerweile auch in Deutschland etabliert. Mehr und mehr erweist sich die Hybrid Cloud als Modell der Zukunft. Dell kann daf\u00fcr ein breites Portfolio an Infrastruktur, Software und Dienstleistungen zur Verf\u00fcgung stellen.    <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-1511\/\" rel=\"category tag\">Coverstory 15-11<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/1511\/\" rel=\"category tag\">MAG 15-11<\/a>","author_info_v2":{"name":"Dr. Roland Kunz, Dell","url":"https:\/\/e3mag.com\/de\/author\/roland-kunz\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/61434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1843"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=61434"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/61434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/61274"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=61434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=61434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=61434"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=61434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}