{"id":6127,"date":"2015-07-23T00:00:00","date_gmt":"2015-07-22T22:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=6127"},"modified":"2019-08-30T14:11:37","modified_gmt":"2019-08-30T12:11:37","slug":"chief-digital-officer","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/chief-digital-officer\/","title":{"rendered":"Chief Digital Officer"},"content":{"rendered":"<p>Die Sache war mir von Beginn an suspekt: SAP braucht einen CDO? Und SAP findet niemand Besseren als den eigenen CMO (Chief Marketing Officer). Dem Mann sei es verg\u00f6nnt: Bei uns w\u00e4re eine Karriere vom CMO zum CDO nicht m\u00f6glich.<\/p>\n<p>Umso interessierter las ich das Interview des SAP CDO Jonathan Becher auf handelsblatt.com \u2013 warum finde ich solche Interviews nie im E-3 Magazin?<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3346674809\"><div id=\"great-109777582\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>Der SAP CDO hat ambitionierte Ziele: Er meint, dass Papier und Vertriebsbeauftragte einer alten, analogen Welt angeh\u00f6ren. Wenn ich das Interview richtig interpretiere, dann will CDO Becher die SAP-Verk\u00e4ufer abschaffen und die Bestandskunden sollen die Pflegegeb\u00fchr mittels Kreditkarte zahlen.<\/p>\n<p>Das passt ins allgemeine Walldorf-Bild: Dort werden schon wieder Mitarbeiter freigesetzt \u2013 nicht pl\u00f6tzlich und spektakul\u00e4r, sondern mit langen \u00dcbergangszeiten. Bis zu drei Jahre d\u00fcrfen sich ausgew\u00e4hlte Mitarbeiter mit vollen Bez\u00fcgen in Fr\u00fchrente begeben.<\/p>\n<p>Besonders stolz ist Jonathan Becher auf sein Bezahlsystem mit Kreditkarte f\u00fcr SAP-Cloud-Services. Wo lebt dieser Mann? Laut eigenen Angaben in Palo Alto, USA. Wo er jedoch intellektuell verortet ist, kann nicht wirklich festgestellt werden.<\/p>\n<p>Jedenfalls ist die Bezahlung mittels Kreditkarte keine echte Cloud-Computing-Innovation \u2013 vielleicht in Walldorf?<\/p>\n<p>Am besten hat mir diese Aussage gefallen:<\/p>\n<p><em>\u201eIch leite sozusagen ein Orchester aus Experten, die ein unbekanntes St\u00fcck namens Digitalisierung zusammen erarbeiten m\u00fcssen. Meine Aufgabe ist es, Misst\u00f6ne zu verhindern.\u201c<\/em><\/p>\n<p>Digital Transformation ist kein unbekanntes St\u00fcck, sondern Realit\u00e4t f\u00fcr jeden SAP-CIO. Warum haben wir in Hana investiert, weil uns die Digital Transformation bewusst ist. Auch das mit den Misst\u00f6nen scheint ihm nicht wirklich zu gelingen: Die Stimmung in Walldorf ist katastrophal.<\/p>\n<p>Wie packen Sie 600 Millionen Tonnen Fracht in eine Box, in die nur 216 Millionen passen? Diese Frage las ich unl\u00e4ngst auf Spiegel Online, darunter war ein SAP-Logo \u2013 es war also ein Werbebanner.<\/p>\n<p>Ich hatte Gl\u00fcck: Wenige Tage sp\u00e4ter hatten wir in St. Leon-Rot ein Executive Meeting und allen anwesenden SAP-Kollegen stellte ich diese Frage \u2013 keiner wusste eine Antwort, aber jeder schimpfte auf das SAP-Marketing, beheimatet im fernen New York City.<\/p>\n<p>Einer meiner SAP-Golfpartner nahm mich dann zur Seite und meinte: Hana soll es richten, aber sei froh, dass du nicht in Orlando auf der Sapphire warst, die war dieses Jahr voll mit solchen intelligenten Fragen.<\/p>\n<p>Ich mache mir Sorgen um SAP: Mit Managern wie CDO Becher und einem Marketing, das auf billige Effekte aus ist, auf der einen Seite; Entlassungen, schlechten Zahlen f\u00fcr ECC 6.0 on Hana, Anlaufschwierigkeiten bei S\/4, einem ungeduldigen Aufsichtsratsvorsitzenden und extrem hohen Umsatzvorgaben auf der anderen Seite; so kenne ich die Walldorfer nicht.<\/p>\n<p>An unserem SAP-Stammtisch gibt es nur noch ein Thema: Lizenzvermessung und die Versuche der SAP, noch mehr Lizenzen zu verkaufen. Die Preisliste aus dem ersten Quartal zielt deutlich darauf ab, mit gewandelten Vertr\u00e4gen noch mehr Geld aus den Bestandskunden herauszupressen.<\/p>\n<p>Hier scheint SAP jedes Mittel recht zu sein. Die Analysten von Gartner sind mitunter wahre Propheten! Bereits im Herbst 2013 verfassten sie eine Note, in der auf die Wertigkeit von SAP-Altvertr\u00e4gen hingewiesen wurde.<\/p>\n<p>Niemals hatten Analysten mehr recht als diesmal. Als besonders perfide betrachten die CIOs an unserem Stammtisch das beim SAP-Kunden Daimler entwickelte Lizenzvermessungs-Toolset. I<\/p>\n<p>ch habe davon durch meinen CCC-Leiter erfahren, der am DSAG-Webinar Lizenzvermessungstool Mitte M\u00e4rz teilgenommen hat. Der Hebel, um die Auster aufzubrechen, ist raffiniert: SAP gibt vor, dem Bestandskunden bei der Rechteverwaltung und Zuordnung seiner Anwender unterst\u00fctzen zu wollen \u2013 nicht ohne das neue Werkzeug in den Himmel zu loben und daf\u00fcr auch Lizenzgeb\u00fchren zu verlangen, obwohl das St\u00fcckchen Software noch nicht einmal SolMan-kompatibel ist.<\/p>\n<p>Das SAPsche Lizenzvermessungswerkzeug wird als Verwaltungsinstrument und Berechtigungswerkzeug f\u00fcr Anwender und SAP-Module angepriesen. In Wirklichkeit ist es ein Schn\u00fcffelprogramm, um SAP mitzuteilen, wer welche Module verwendet, welche Berechtigungskonzepte und Rollen existieren und ob das alles mit der Lizenzgebarung und Vermessung \u00fcbereinstimmt.<\/p>\n<p>Man kann davon ausgehen, dass sp\u00e4testens drei Monate nach dem Customizing des Lizenzvermessungstools der SAP-VB mit einer Lizenzrechnung vor der T\u00fcr steht.<\/p>\n<p>Mein Corporate-CCC-Leiter hat mir den Link zum DSAG-Webinar organisiert, nach dem Einloggen findet sich die Aufzeichnung plus zwei \u201ehilfreiche\u201c PDFs: CDP \u2013 Corporate License Measurement, die Unterlagen zum DSAG-Webinar von Eckhard Lehrer, SAP Custom Development Sales (M\u00e4rz, 2015) und Automating SAP License Measurement, ebenfalls von Eckhard Lehrer (etwas \u00e4lter aus Mai 2013, Confidential).<\/p>\n<p>Soweit ich es verstanden habe: f\u00fcr jeden CCC-Leiter sowie Justiziar und Syndikus eine Pflichtlekt\u00fcre. Mit dieser \u201eSommerlekt\u00fcre\u201c verabschiede ich mich bis zum September und w\u00fcnsche erholsame Ferientage.<\/p>\n<p><a href=\"mailto:noname@pe3.greatsolution.dev\">noname@pe3.greatsolution.dev<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haben wir auch! Wir haben weltweit sogar mehrere Chief Digital Officers (CDO), die sich aber um Digital Use und Business Cases sorgen und nicht darum, ob einer unserer Lieferanten oder Kunden mit einer Kreditkartentransaktion abgerechnet wird. Bei SAP ist wieder einmal alles anders.<\/p>\n","protected":false},"author":9,"featured_media":2461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[12,7,1553],"tags":[4135,621,601,12217,517,353],"coauthors":[21816],"class_list":["post-6127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noname","category-meinung","category-1553","tag-cdo","tag-cloud-computing","tag-digitalisierung","tag-lizenzgebuehren","tag-s4","tag-sapphire","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",400,172,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-768x331.jpg",768,331,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-100x43.jpg",100,43,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-480x207.jpg",480,207,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-640x276.jpg",640,276,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-720x310.jpg",720,310,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-960x414.jpg",960,414,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName.jpg",600,259,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/NoName-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Haben wir auch! Wir haben weltweit sogar mehrere Chief Digital Officers (CDO), die sich aber um Digital Use und Business Cases sorgen und nicht darum, ob einer unserer Lieferanten oder Kunden mit einer Kreditkartentransaktion abgerechnet wird. Bei SAP ist wieder einmal alles anders.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/noname\/\" rel=\"category tag\">No\/Name-Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/1507\/\" rel=\"category tag\">MAG 15-07<\/a>","author_info_v2":{"name":"no-name","url":"https:\/\/e3mag.com\/de\/author\/no-name\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/6127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=6127"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/6127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/2461"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=6127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=6127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=6127"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=6127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}