{"id":55362,"date":"2019-01-16T08:00:56","date_gmt":"2019-01-16T07:00:56","guid":{"rendered":"http:\/\/e3mag.com\/?p=55362"},"modified":"2022-05-01T10:33:52","modified_gmt":"2022-05-01T08:33:52","slug":"e-helden-mit-hana-auswaehlen","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/e-helden-mit-hana-auswaehlen\/","title":{"rendered":"E-Helden mit Hana ausw\u00e4hlen"},"content":{"rendered":"<p>SAP hatte zusammen mit ESL bereits f\u00fcr das E-Sports-Turnier \u201eESL One Hamburg 2018\u201c im Oktober die Analyse von Spieldaten f\u00fcr den Live-Broadcasts vorangetrieben und entwickelt.<\/p>\n<p>Durch verschiedene Datenauswertungen konnte den Zuschauern und Kommentatoren innovative Anhaltspunkte gegeben, um die Komplexit\u00e4t des Spiels Dota 2 und die Entscheidungen der Pro-Gamer besser zu verstehen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3332162523\"><div id=\"great-4162686132\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<p>Bei Dota 2 handelt es sich um eine Multiplayer Online Battle Arena, eine Form eines Echtzeit-Strategiespiels. Bei der Kooperation steht die Heldenauswahl von Dota 2 im Fokus.<\/p>\n<p>Durch eine Auswertung der Spieldaten vergangener Profispiele k\u00f6nnen Einsch\u00e4tzungen und Statistiken unmittelbar im Live-Broadcast eingeblendet werden. Zuschauer und Kommentatoren erhalten dadurch direkten Einblick und k\u00f6nnen gewisse Auswahlkriterien so besser nachvollziehen.<\/p>\n<p>Mithilfe von Hana werden gro\u00dfe Mengen an Spieldaten verarbeitet und \u00fcber die SAP Cloud Platform in ma\u00dfgeschneiderten Anaslysen zur Verf\u00fcgung gestellt.<\/p>\n<p><em>\u201eGemeinsam mit SAP sind wir in der Lage, das Zuschauererlebnis sowie den Live-Broadcast noch weiter zu verbessern\u201c<\/em><\/p>\n<p>so Bernhard Mogk, SVP Global Sales &amp; Business Development bei der ESL.<\/p>\n<p><em>\u201eNach unserem erfolgreichen E-Sports-Einstieg Anfang des Jahres ist die Event-Partnerschaft mit der ESL f\u00fcr uns ein wichtiger und logischer Schritt\u201c<\/em><\/p>\n<p>sagt Lars Lamad\u00e9, verantwortlich f\u00fcr Sponsorships in Europa und Asien bei SAP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAP hat eine Kooperation mit ESL, dem weltweit gr\u00f6\u00dften E-Sport-Unternehmen, vereinbart.<\/p>\n","protected":false},"author":38,"featured_media":55363,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[6,26129],"tags":[],"coauthors":[19920],"class_list":["post-55362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaft","category-mag-1811","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/10\/shutterstock_420304099-REDAKTIONELL-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP hat eine Kooperation mit ESL, dem weltweit gr\u00f6\u00dften E-Sport-Unternehmen, vereinbart.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/wirtschaft\/\" rel=\"category tag\">Wirtschaft<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-1811\/\" rel=\"category tag\">MAG 18-11<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/55362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=55362"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/55362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/55363"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=55362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=55362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=55362"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=55362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}