{"id":36606,"date":"2018-02-22T09:57:48","date_gmt":"2018-02-22T08:57:48","guid":{"rendered":"http:\/\/e3mag.com\/?p=33903"},"modified":"2019-03-11T10:57:41","modified_gmt":"2019-03-11T09:57:41","slug":"was-bringts-dem-sap-bestandskunden","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/was-bringts-dem-sap-bestandskunden\/","title":{"rendered":"Was bringt\u2019s dem SAP-Bestandskunden?"},"content":{"rendered":"<p>F\u00fcr die Beantwortung der grundlegenden Fragen rund um Blockchain bleibt kaum Zeit, denn die IT- und Business-Welt dreht sich immer schneller. Wie k\u00f6nnen es Unternehmen dennoch schaffen, in k\u00fcrzester Zeit valide Entscheidungen zu treffen und Megatrends nicht zu verpassen?<\/p>\n<p>Als Antwort auf diese Frage hat Camelot Innovative Technologies (Came\u00adlot ITLab) das Produkt- und Serviceportfolio Digital Experience\u00b2 entwickelt. Steffen Joswig, Gesch\u00e4ftsf\u00fchrer der Camelot ITLab, erkl\u00e4rt im Interview, was es damit auf sich hat.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-312353046\"><div id=\"great-3960197319\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n<h3>Herr Joswig, was war die Motivation f\u00fcr Camelot Digital Experience\u00b2?<\/h3>\n<p><strong>Steffen Joswig:<\/strong> Unternehmen sind h\u00e4ufig \u00fcberfordert angesichts der Vielfalt an technologischen M\u00f6glichkeiten und der Schnelligkeit, mit der neue Megatrends entstehen.<\/p>\n<p>Sie stehen einer F\u00fclle an bereits existierenden digitalen Business Cases gegen\u00fcber, schaffen es aber nicht, diese auf ihr eigenes Unternehmen zu \u00fcbertragen. Die Problematik l\u00e4sst sich mit digitalen Beraterkonzepten in Form von Powerpoint-Folien allein nicht l\u00f6sen.<\/p>\n<p>Unternehmen m\u00fcssen neue Technologien und deren digitalen Return on Investment tats\u00e4chlich erleben k\u00f6nnen, um \u00fcber den Einsatz einer Technologie sinnvoll entscheiden zu k\u00f6nnen \u2013 und das in m\u00f6glichst kurzer Zeit. Dazu haben wir Digital Expe\u00adrience2 entwickelt.<\/p>\n<h3>Worum geht es bei Digital Experience\u00b2?<\/h3>\n<p><strong>Joswig:<\/strong> Wie der Name schon andeutet, geht es um das Erleben von technologischen Megatrends wie zum Beispiel Blockchain. Im Fokus steht die beschleunigte und individuell erlebbare digitale Wertgenerierung von innovativen Kundenanwendungen.<\/p>\n<p>Digital Experience\u00b2 ist ein Gesamtpaket aus verschiedenen vorgefertigten Softwarebauk\u00e4sten mit leicht konfigurierbaren Templates und darauf abgestimmten Methoden f\u00fcr die Entwicklung digitaler Innovationen.<\/p>\n<p>Erprobte innovationsf\u00f6rdernde Teamans\u00e4tze und agile, schnelle Entwicklungsmethoden erlauben konkrete Resultate in Form eines Wirksamkeitsnachweises in weniger als vier Wochen \u2013 ein Kundenangebot, das bez\u00fcglich Umfang und Geschwindigkeit bis dato einmalig ist.<\/p>\n<figure id=\"attachment_33905\" aria-describedby=\"caption-attachment-33905\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/02\/Camelot-Interview-1803.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33905\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/02\/Camelot-Interview-1803.jpg\" alt=\"Camelot Interview 1803\" width=\"1000\" height=\"667\" \/><\/a><figcaption id=\"caption-attachment-33905\" class=\"wp-caption-text\">Steffen Joswig ist Gesch\u00e4ftsf\u00fchrer der Camelot ITLab.<\/figcaption><\/figure>\n<h3>Sie sprachen von Softwarebauk\u00e4sten und konfigurierbaren Templates. Wie kann man sich das vorstellen? Und welche Rolle spielen SAP-L\u00f6sungen in dem Kontext?<\/h3>\n<p><strong>Joswig:<\/strong> Das Herzst\u00fcck von Digital Expe\u00adrience\u00b2 ist die sogenannte Digital Workbench, in der die verschiedenen Softwarebauk\u00e4sten und Templates zusammengefasst sind. Diese wiederum basieren auf neuen Technologien wie Blockchain, k\u00fcnstliche Intelligenz, Digital Voice, IoT Connectivity und Cloud Technology.<\/p>\n<p>Zu der Digital Workbench geh\u00f6ren insbesondere die Twinification Bridge, ein Camelot-IoT-Service und Connectivity-Template f\u00fcr die Generierung von \u201edigitalen Zwillingen\u201c, die Camelot Hypertrust Platform, ein blockchainbasiertes Modell f\u00fcr die Entwicklung verteilter Anwendungen, sowie der sogenannte AI Composer zum schnellen Entwickeln von KI- und Digital-Voice-Anwendungen.<\/p>\n<p>Die Digital Workbench basiert weitestgehend auf dem Basistechnologie-Portfolio von SAP Leonardo, der neuen Plattform der SAP SE f\u00fcr digitale Innovation, und wird in Zukunft hieraus weiterentwickelt.<\/p>\n<h3>Wie funktioniert Digital Experience\u00b2 in der Praxis?<\/h3>\n<p><strong>Joswig:<\/strong> Digital Experience\u00b2 umfasst ein klar umrissenes dreistufiges Vorgehen: In der ersten Phase \u201eIdeate and Innovate\u201c werden mithilfe von Design-Thinking-Methoden gemeinsam mit dem Kunden Ideen f\u00fcr innovative digitale Anwendungsf\u00e4lle kreiert.<\/p>\n<p>In Phase zwei \u201eCompose and Construct\u201c entwickeln eigene Centers of Digital Innovation der Camelot ITLab mithilfe der Digital Workbench konkrete Applikationen. Hierbei kommen moderne agile Methoden zum Einsatz, die eine Applikationsentwicklung in kurzen Sprints erm\u00f6glichen.<\/p>\n<p>Die Phase drei \u201eDiscover and Drive\u201c schlie\u00dflich umfasst das \u201eTouch &amp; Zoom\u201c-Erleben und Validieren der Applikation und ihres Wertbeitrags durch den Kunden. Abschlie\u00dfend wird ein erster Aktionsplan f\u00fcr die kundenspezifische Umsetzung erarbeitet.<\/p>\n<h3>Wie profitieren Kunden konkret?<\/h3>\n<p><strong>Joswig:<\/strong> Die Hauptvorteile f\u00fcr Kunden sind: Sie erhalten konkrete, unternehmensspezifische Use Cases f\u00fcr digitale Technologien innerhalb von nur vier Wochen.<\/p>\n<p>Durch ein physisches Erleben technologischer Megatrends und ihres digitalen Return on Investment sind sie in der Lage, valide Entscheidungen zu treffen. Und nicht zuletzt: das gute Gef\u00fchl, endlich Klarheit im Dschungel der digitalen M\u00f6glichkeiten zu haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim Thema Blockchain, aber auch in Bezug auf andere technologische Megatrends stellt sich f\u00fcr Unternehmen die Frage: Ist die Technologie \u00fcberhaupt relevant f\u00fcr mein Unternehmen? In welchen Bereichen macht der Einsatz am meisten Sinn und welchen Mehrwert bringt mir das?<\/p>\n","protected":false},"author":38,"featured_media":4944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[20708,20719],"tags":[625,886,20742,370,624,626],"coauthors":[19920],"class_list":["post-36606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-1803","category-mag-1803","tag-ai","tag-blockchain","tag-camelot","tag-iot","tag-ki-joule","tag-kuenstliche-intelligenz","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",400,274,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-768x526.jpg",768,526,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-100x69.jpg",100,69,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-480x329.jpg",480,329,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-640x438.jpg",640,438,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-720x493.jpg",720,493,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-960x658.jpg",960,658,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",18,12,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",985,675,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",600,411,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",600,411,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/12\/E3-Interview-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Beim Thema Blockchain, aber auch in Bezug auf andere technologische Megatrends stellt sich f\u00fcr Unternehmen die Frage: Ist die Technologie \u00fcberhaupt relevant f\u00fcr mein Unternehmen? In welchen Bereichen macht der Einsatz am meisten Sinn und welchen Mehrwert bringt mir das?<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-1803\/\" rel=\"category tag\">Coverstory 18-03<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-1803\/\" rel=\"category tag\">MAG 18-03<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/36606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=36606"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/36606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/4944"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=36606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=36606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=36606"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=36606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}