{"id":154716,"date":"2025-09-17T07:30:00","date_gmt":"2025-09-17T05:30:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=154716"},"modified":"2025-09-15T15:52:03","modified_gmt":"2025-09-15T13:52:03","slug":"ki-ist-kein-luxus","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/ki-ist-kein-luxus\/","title":{"rendered":"KI ist kein Luxus"},"content":{"rendered":"\n<p>Eine wesentliche Erkenntnis hat unser Lenkungsausschuss f\u00fcr KI aber bereits manifestiert: Ohne k\u00fcnstliche Intelligenz wird es in Zukunft nicht gehen! Die vor vielen Jahren gestartete digitale Transformation kam zeitweise aufgrund fehlender IT-Werkzeuge ins Stocken. KI kann diesen Deadlock l\u00f6sen. Somit ist KI auch anders zu bewerten als Cloud Computing. W\u00e4hrend KI-Technik ein singul\u00e4res Ph\u00e4nomen ist, ein Paradigmenwechsel und Kristallisationspunkt, bleibt Cloud Computing ein weiteres Betriebsmodell unter vielen anderen IT-Architekturen.<\/p>\n\n\n\n<p>SAP hat die gesamte Energie und den Fokus auf Cloud gesetzt. Aufgrund der Erfolge der Hyperscaler und der wachsenden Konkurrenz durch Cloud-only-\u00adCompanys war dieser Schritt zwingend notwendig, aber nicht vision\u00e4r. Die Herausforderungen der Wissensgesellschaft und Informatik liegen woanders. Nat\u00fcrlich braucht ERP nach Virtualisierung weitere Betriebsmodelle. Cloud ist f\u00fcr viele Anwendungen eine hervorragende Infrastruktur und mit dem Skalierungseffekt der Hyperscaler l\u00e4sst sich viel Geld verdienen. Aber, und diesen Umstand hat SAP nicht ber\u00fccksichtigt, Cloud ist keine nachhaltige L\u00f6sung, keine Innovation und kein Ausweg aus einer Deindustrialisierung. Cloud ist ein hinreichend akzeptables Betriebsmodell f\u00fcr eine Vielzahl von ERP-Anwendungen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-790696966\"><div id=\"great-3064846266\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>KI hingegen ist kein Luxus, sondern eine Zukunftsstrategie mit dem Versprechen auf Innovation. Der Ort der n\u00e4chsten ERP-Generation mag beliebig sein \u2013 On-prem oder Cloud \u2013, aber die Basis wird k\u00fcnstliche Intelligenz sein. Large-Language-Modelle, Reinforcement Learning und KI-Agenten werden die Richtung vorgeben. Aufgrund der Arbeit unserer Praktikanten im hauseigenen KI-Labor wird ein Compos\u00adable ERP immer wahrscheinlicher. Die M\u00f6glichkeiten f\u00fcr ein Best-of-Breed-ERP auf einer konsolidierten IT-Plattform bietet uns die KI.<\/p>\n\n\n\n<p>Dieses Zukunftsszenario hat viele Auswirkungen: Es ist nicht nur eine klassische ERP-Herausforderung mit den bekannten Parametern Betriebswirtschaft, Organisation, Technik und Lizenzrecht, sondern auch eine umfassende gesellschaftliche Evolution. KI-Agenten auf IT-Plattformen mit m\u00e4chtigen LLMs erbringen 80 Prozent der Leistung von Berufseinsteigern und Junior-Beratern. In einem Text aus dem englischen \u201eThe Economist\u201c hei\u00dft es, dass viele Berater wie AI-Bots klingen. Die KI wird viele IT-Berater und SAP-Systemh\u00e4user kr\u00e4ftig durchsch\u00fctteln. Der Bedarf an Hilfs- und Einstiegskr\u00e4ften wird dramatisch sinken. Gebraucht werden nur noch hochbegabte Spezialisten.<\/p>\n\n\n\n<p>Meine SAP-Stammtischschwestern und -br\u00fcder begannen nat\u00fcrlich umgehend eine Diskussion \u00fcber die gesellschaftliche Herausforderung der Nach\u00adwuchs\u00adausbildung. Werden keine Berufseinsteiger, Lehrlinge und Praktikanten mehr gef\u00f6rdert und ausgebildet, dann wird es mit hoher Wahrscheinlichkeit sp\u00e4ter auch keine Fachkr\u00e4fte und Spezialisten geben. Damit stellt sich die Frage, ob KI ein Luxus ist, aus einer ganz neuen und \u00fcberraschenden Perspektive. KI ver\u00e4ndert den Arbeitsmarkt und verbaut uns eine gesellschaftliche Zukunft?<\/p>\n\n\n\n<p>An unserem Stammtisch besch\u00e4ftigt uns die Frage, wie SAP damit umgeht, ebenso intensiv, denn wir erkennen keine Zeichen, dass SAP von dem Fokus Cloud Computing abl\u00e4sst und ein wenig mehr Energie auf das Thema KI verlegt. Nat\u00fcrlich r\u00fchmt sich unser ERP-Konzern eines umfassenden Einsatzes von KI-Technik, aber die eigene Wertsch\u00f6pfung und das Innovationspotenzial von SAP sind gering. SAP hat einst das Internet verschlafen, nun ist sich SAP der Herausforderung nat\u00fcrlich bewusst, man findet aber dennoch keine Antwort auf KI. SAP ist gegen\u00fcber vielen KI-Innovationen sprach- und ideenlos. Dieses SAP\u2019sche KI-Defizit ist f\u00fcr uns Bestandskunden eine gro\u00dfe Gefahr, weil wir dann zuk\u00fcnftige LLMs, KI-Agenten und Reinforcement Learning von anderen IT-Konzernen beziehen m\u00fcssen.<\/p>\n\n\n\n<p>Nat\u00fcrlich scheut SAP die KI wie der Teufel das Weihwasser, weil KI das Gesch\u00e4ftsmodell von SAP korrumpieren wird. Mit Reinforcement Learning l\u00e4sst sich ein perfektes Controlling errichten. LLMs steuern die Produktion und Logistik. KI-Agenten orchestrieren die digitale Aufbau- und Ablauforganisation. Das Composable ERP wird damit Realit\u00e4t und SAP wird um den Platz in der ERP-Szene k\u00e4mpfen m\u00fcssen.<\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Mit unseren Praktikanten experimentieren wir in unterschiedlicher Zusammensetzung seit etwa drei Jahren mit k\u00fcnstlicher Intelligenz.<br \/>\nEin Diskurs wurde er\u00f6ffnet, aber eine Richtungsentscheidung gibt es noch nicht.<\/p>\n","protected":false},"author":9,"featured_media":135869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[44257,12],"tags":[],"coauthors":[21816],"class_list":["post-154716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-25-09","category-noname","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Mit unseren Praktikanten experimentieren wir in unterschiedlicher Zusammensetzung seit etwa drei Jahren mit k\u00fcnstlicher Intelligenz.<br \/>\nEin Diskurs wurde er\u00f6ffnet, aber eine Richtungsentscheidung gibt es noch nicht.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/mag-25-09\/\" rel=\"category tag\">MAG 25-09<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/noname\/\" rel=\"category tag\">No\/Name-Kolumne<\/a>","author_info_v2":{"name":"no-name","url":"https:\/\/e3mag.com\/de\/author\/no-name\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/154716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=154716"}],"version-history":[{"count":16,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/154716\/revisions"}],"predecessor-version":[{"id":155470,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/154716\/revisions\/155470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/135869"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=154716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=154716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=154716"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=154716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}