{"id":151128,"date":"2025-05-20T21:06:22","date_gmt":"2025-05-20T19:06:22","guid":{"rendered":"http:\/\/e3mag.com\/?p=151128"},"modified":"2025-07-28T10:03:05","modified_gmt":"2025-07-28T08:03:05","slug":"unabhaengigkeit-vom-backend-erp","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/unabhaengigkeit-vom-backend-erp\/","title":{"rendered":"Unabh\u00e4ngigkeit vom Backend-ERP"},"content":{"rendered":"\n<p>Das Angebot Business Technology Platform gliedert sich in f\u00fcnf zentrale Bereiche: Application &amp; Development, Automation, Integration, Data &amp; Analytics sowie k\u00fcnstliche Intelligenz (AI). Unternehmen haben dabei die M\u00f6glichkeit, flexibel und bedarfsgerecht auf einzelne Services aus diesen Bereichen zuzugreifen und sie individuell zu kombinieren. Die angebotenen Services stehen in unterschiedlichen Preismodellen zur Verf\u00fcgung \u2013 etwa im Abonnement oder nach dem Pay-as-you-Go-Prinzip.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wartungsarm durch Clean Core<\/h2>\n\n\n\n<p>Die Services der BTP erm\u00f6glichen es Unternehmen, individuelle Anwendungen zu entwickeln oder ganze Gesch\u00e4ftsprozesse im sogenannten Side-by-Side-Ansatz auszulagern. Im Zentrum steht dabei das Konzept des \u201eClean Core\u201c: Durch die Entkopplung von Erweiterungen und Individualentwicklungen vom zentralen SAP-ERP-System wird dieses deutlich wartungs\u00e4rmer und l\u00e4sst sich k\u00fcnftig einfacher auf neue Softwareversionen oder -stacks aktualisieren. Die Umsetzung und der effiziente Betrieb von L\u00f6sungen auf der SAP BTP setzen bestimmte Rahmenbedingungen voraus. So sollte die Anwendung m\u00f6glichst lose mit dem SAP-Standard gekoppelt sein, idealerweise unabh\u00e4ngig von SAP-Daten funktionieren oder Daten aus anderen Cloud-L\u00f6sungen beziehen. Auch der Verzicht auf die Nutzung eines SAP-Benutzers f\u00fcr den Zugriff sowie die Notwendigkeit, Daten extern bereitzustellen, sprechen f\u00fcr eine Umsetzung auf der Plattform.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-101856002\"><div id=\"great-2692022734\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Im klassischen SAP-System der ECC Business Suite waren Unternehmen auf die Entwicklung in Abap beschr\u00e4nkt und konnten ausschlie\u00dflich die Funktionen nutzen, die SAP selbst bereitstellte. Zwar erweiterten einige Partner oder kleinere Softwareanbieter das Angebot durch eigene Abap-Tools und Zusatzl\u00f6sungen, doch blieb alles strikt an den SAP NetWeaver und die Abap-Welt gebunden. Mit der Einf\u00fchrung der BTP \u00f6ffnet sich nun ein deutlich gr\u00f6\u00dferer Handlungsspielraum: Entwicklerinnen und Entwickler haben Zugang zu einer Vielzahl moderner Programmiersprachen, erweiterten Funktionalit\u00e4ten und neuen Integrationsm\u00f6glichkeiten. Damit entstehen v\u00f6llig neue Perspektiven f\u00fcr Innovationen und ma\u00dfgeschneiderte Gesch\u00e4ftsprozesse. Mit den neuen M\u00f6glichkeiten gehen auch v\u00f6llig neue Herausforderungen einher.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PaaS erfordert Umdenken&nbsp;<\/h2>\n\n\n\n<p>Die Nutzung von Platform-as-a-Service-Strukturen und der modulare Einsatz unterschiedlichster Services und Laufzeitumgebungen fordern von SAP-Partnern, Kunden und Anwendern ein Umdenken. W\u00e4hrend in klassischen SAP-Systemen Funktionen wie Transportmanagement, Berechtigungsverwaltung oder Quellcode-Versionierung fest integriert und einfach mitgenutzt werden konnten, m\u00fcssen diese Aspekte auf der BTP nun eigenst\u00e4ndig organisiert und verwaltet werden. Auch die Auswahl der passenden Laufzeitumgebung \u2013 sei es Cloud Foundry, Abap, Kyma oder eine Kombination aus allem \u2013 verlangt technisches Know-how und strategische Entscheidungen. Erschwerend kommt hinzu, dass sich auch die Lizenzmodelle deutlich differenzierter pr\u00e4sentieren: Neben Pay-as-you-Go und Subscriptions existiert das Credit-basierte BTP Enterprise Agreement, bei dem zus\u00e4tzlich volumenabh\u00e4ngige Kosten einzelner Services ber\u00fccksichtigt werden m\u00fcssen. Dieser komplexe Mix aus Technologien, Betriebsmodellen und Abrechnungsstrukturen erfordert eine sorgf\u00e4ltige Planung und ein gezieltes Orches-trieren der eingesetzten Komponenten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BTP Operations<\/h2>\n\n\n\n<p>Es empfiehlt sich, eine zus\u00e4tzliche Schicht bei der BTP in den Fokus zu nehmen. Wir nennen sie \u201eBTP Operations\u201c. Der Plattformbetrieb wird von der SAP und den Hyperscalern \u00fcbernommen, die Anwendungen meist von der internen IT, Partnern oder den Entwicklern verwaltet. Aber genau die Schicht dazwischen wird in der Regel vergessen oder untersch\u00e4tzt. Doch gerade hier stellen sich zentrale Fragen: Wer \u00fcbernimmt die Verantwortung f\u00fcr das Management der eingesetzten Services? Wer beh\u00e4lt Kosten und Nutzung im Blick? Wer organisiert die Nutzer im Identity Service oder definiert die Berechtigungen in Subaccounts und einzelnen Services? Auch das Deployment neuer Services sowie die strukturierte Organisation der Subaccounts bed\u00fcrfen klarer Zust\u00e4ndigkeiten und Prozesse. Unternehmen sollten sich diesen Fragestellungen fr\u00fchzeitig widmen \u2013 idealerweise gemeinsam mit einem erfahrenen Partner, der beim Aufbau entsprechender Betriebsmodelle unterst\u00fctzt oder diese Leistungen sogar direkt \u00fcbernimmt. So lassen sich Best Practices aus anderen Projekten nutzen und ein reibungsloser, effizienter BTP-Betrieb sicherstellen.<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/pdfs\/2506-cover\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg\" alt=\"\" class=\"wp-image-73569\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<p>Zum Partnereintrag:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/e3mag.com\/de\/partners\/nagarro\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"298\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg.png\" alt=\"\" class=\"wp-image-149036\" style=\"width:300px\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg.png 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-400x99.png 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-768x191.png 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-100x25.png 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-480x119.png 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-640x159.png 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-720x179.png 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-960x238.png 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-1168x290.png 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-18x4.png 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/02\/Nagarro_logo_new.svg-600x149.png 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Die SAP Business Technology Platform (BTP) soll als strategisches PaaS-Angebot Unternehmen dabei unterst\u00fctzen, schneller zu entwickeln, effizienter zu arbeiten. Doch wie genau gelingt es, interne wie externe Anforderungen unter einen Hut zu bringen?<\/p>\n","protected":false},"author":5683,"featured_media":151112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[44171,44173],"tags":[39870,44086,555,43640,509,43815,38878,236],"coauthors":[44177],"class_list":["post-151128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-25-06","category-mag-25-06","tag-btp-bdc","tag-clean-core","tag-ecc","tag-grow","tag-paas","tag-rise","tag-rise-with-sap","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/05\/2506cs_romberger_nagarro-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die SAP Business Technology Platform (BTP) soll als strategisches PaaS-Angebot Unternehmen dabei unterst\u00fctzen, schneller zu entwickeln, effizienter zu arbeiten. Doch wie genau gelingt es, interne wie externe Anforderungen unter einen Hut zu bringen?<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-25-06\/\" rel=\"category tag\">Coverstory 25-06<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-25-06\/\" rel=\"category tag\">MAG 25-06<\/a>","author_info_v2":{"name":"Florian Romberger, Nagarro","url":"https:\/\/e3mag.com\/de\/author\/florian-romberger\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/151128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/5683"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=151128"}],"version-history":[{"count":4,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/151128\/revisions"}],"predecessor-version":[{"id":152840,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/151128\/revisions\/152840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/151112"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=151128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=151128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=151128"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=151128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}