{"id":150758,"date":"2025-05-12T07:00:00","date_gmt":"2025-05-12T05:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=150758"},"modified":"2025-04-28T11:11:30","modified_gmt":"2025-04-28T09:11:30","slug":"gestalten-nicht-verwalten-oder","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/gestalten-nicht-verwalten-oder\/","title":{"rendered":"Gestalten, nicht verwalten, oder?"},"content":{"rendered":"\n<p>Ausgangspunkt der Diskussion meiner Stammtischschwestern und -br\u00fcder waren zwei Kommentare \u00fcber das Gehalt von SAP-Chef Christian Klein auf dem Webportal handelsblatt.com. Zur Klarstellung: F\u00fcr einen Dax-Konzern ist sein Gehalt astronomisch hoch. Im Vergleich zum Ausland und im Besonderen zu den USA ist es ein bescheidenes Auskommen. Ich denke, dass er auch noch mehr verdienen k\u00f6nnte, wenn sein SAP-Gehalt inklusive Bonus- und Aktienprogramm als \u201eSchmerzensgeld\u201c verbucht wird \u2013 denn wer will in diesen Zeiten noch bei SAP arbeiten? Aber das ist eine andere Geschichte.<\/p>\n\n\n\n<p>Ein Aspekt beim Diskurs auf handelsblatt.com war das Verh\u00e4ltnis zwischen Gehalt und sichtbarer Leistung: Gestaltet nun Christian Klein die SAP-Entwicklung oder verwaltet er lediglich die Assets? Diese Frage besch\u00e4ftigt uns Bestandskunden nat\u00fcrlich ganz besonders, weil letztendlich davon auch die Zukunft unseres ERP abh\u00e4ngig ist. Sind wir Kunden eines Innovators oder befindet sich unser ERP-Lieferant im Innovator\u2019s Dilemma, siehe Clayton M. Christensen (1952 bis 2020)?<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-528113649\"><div id=\"great-3105784107\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Es gibt zum Gehalt von SAP-Chef Klein zwei Kommentare auf handelsblatt.com: einen Pro- und einen Contra-Kommentar. Wesentlich emotionaler wurde der Pro-Text am SAP-Stammtisch diskutiert, weil fast alle Stammtischschwestern und -br\u00fcder zwar frei von einer Neiddebatte sind, sich aber dennoch nicht der Argumentation des Handelsblatt-Autors anschlie\u00dfen wollen. Dieser rechtfertigt das Gehalt von Christian Klein mit seiner innovativen und perspektivischen Unternehmensf\u00fchrung. Im Detail wird im Pro-Kommentar das Cloud Computing hervorgehoben \u2013 was aus unserer Sicht genau die gr\u00f6\u00dfte SAP-Baustelle ist und Ursache f\u00fcr das Rise- und Grow-Desaster.<\/p>\n\n\n\n<p>Auf die Cloud-Roadmap wurde SAP von Ex-CEO Bill McDermott gef\u00fchrt. Sein Zugang zu dieser Technik war nat\u00fcrlich rein kaufm\u00e4nnisch: Er kaufte ein Cloud-Unternehmen nach dem anderen, bis die Kasse des damaligen SAP-CFO Luka Mucic leer war. Aufr\u00e4umen, konsolidieren und orchestrieren musste dann sein Nachfolger Christian Klein. Aus dem Cloud-Kon\u00adglomerat formte Klein eine hinreichend konsistente ERP-Landschaft. Freiwillig hat er diesen Job nicht gemacht. Aus dem Hintergrund musste er tatkr\u00e4ftig durch Hasso Plattner und Gerd Oswald motiviert werden. Aber das Ergebnis kann sich sehen lassen, auch wenn es weniger innovativ und weitsichtig als technisch und pragmatisch ist.<\/p>\n\n\n\n<p>Der Pro-Kommentar betont aber letztendlich die Klein-Vision des Cloud Computing und versucht, mit dieser SAP-Cloud-Roadmap das hohe Gehalt zu rechtfertigen. Dem ist aber in keiner Weise so, sagt \u00fcbereinstimmend mein SAP-Stammtisch: Nachdem die Hyperscaler bereits die Marschrichtung und Preise vorgegeben haben, andere IT-Anbieter wie Oracle und IBM bereits in Richtung Cloud aufgebrochen sind, hatte SAP keine andere Chance, als diesem Pfad ebenfalls zu folgen. Der Aufbruch war holprig und inkonsistent. Mittlerweile hat SAP viel Cloud-Lehrgeld bezahlt und die Services ergeben Sinn, wenn auch noch immer zu einem weit \u00fcberh\u00f6hten Preis \u2013 im Vergleich zu den erw\u00e4hnten Hyperscalern.<\/p>\n\n\n\n<p>Es gibt Stammtischschwestern und -br\u00fcder, die die selektiven Cloud-Services von SAP erfolgreich nutzen. Niemand von uns w\u00fcrde aber auf die Idee kommen, es als Geniestreich von Christian Klein zu definieren. Der SAP-Chef verwaltet das Erbe von Professor Hasso Plattner gewissenhaft und akkurat, aber letztendlich folgt er den IT-Megatrends wie Cloud und KI in sicherem Abstand. Eigene und innovative Wege beschreitet SAP schon lange nicht mehr. Informatikrevolutionen wie ein dreistufiges Client\/Server-Modell oder In-memory Computing liegen weit \u00fcber zehn Jahre zur\u00fcck.<\/p>\n\n\n\n<p>Was andere IT-Konzerne am Wegesrand liegen lassen, das greift SAP erfreut auf: Aus Graph- und Vektordatenbanken entsteht aktuell ein Semantic Layer f\u00fcr die SAP Business Data Cloud, aus der Nutzung unterschiedlicher LLMs werden an die 300 KI-Funktionen f\u00fcr ECC 6.0 und S\/4 auf Basis der Business Technology Platform (SAP BTP) geformt. Unter Christian Klein bewegt sich SAP z\u00fcgig vorw\u00e4rts und daf\u00fcr ist mein Stammtisch auch dankbar, aber noch mehr freuen w\u00fcrden wir uns, wenn mehr innovativ und vorausschauend gestaltet und weniger lizenzlastig verwaltet w\u00fcrde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am SAP-Stammtisch ist eine veritable Diskussion im Gang, ob SAP aktiv und dynamisch gestaltet oder das Erbe von Professor Hasso Plattner nur<br \/>\nnoch gewissenhaft verwaltet. Ich bin der Meinung, SAP ruht in sich.<\/p>\n","protected":false},"author":9,"featured_media":135869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,44120,12],"tags":[27970,43815],"coauthors":[21816],"class_list":["post-150758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-mag-25-05","category-noname","tag-hyperscaler","tag-rise","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/12\/No-Name_1000x450-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Am SAP-Stammtisch ist eine veritable Diskussion im Gang, ob SAP aktiv und dynamisch gestaltet oder das Erbe von Professor Hasso Plattner nur<br \/>\nnoch gewissenhaft verwaltet. Ich bin der Meinung, SAP ruht in sich.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-25-05\/\" rel=\"category tag\">MAG 25-05<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/noname\/\" rel=\"category tag\">No\/Name-Kolumne<\/a>","author_info_v2":{"name":"no-name","url":"https:\/\/e3mag.com\/de\/author\/no-name\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/150758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=150758"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/150758\/revisions"}],"predecessor-version":[{"id":150760,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/150758\/revisions\/150760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/135869"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=150758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=150758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=150758"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=150758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}