{"id":150557,"date":"2025-04-24T09:03:00","date_gmt":"2025-04-24T07:03:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=150557"},"modified":"2025-04-24T09:08:02","modified_gmt":"2025-04-24T07:08:02","slug":"von-sap-ecc-zu-s-4-hana","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/von-sap-ecc-zu-s-4-hana\/","title":{"rendered":"Von SAP ECC zu S\/4 Hana"},"content":{"rendered":"\n<p>Eine S\/4-Conversion ist ein komplexes Unterfangen, das die Anpassung von Prozessen und Datenstrukturen beinhaltet. Viele SAP-Bestandskunden betreiben seit Jahren stark individualisierte ERP-Systeme, deren \u00dcberf\u00fchrung nach S\/4 mitunter aufw\u00e4ndig ist. Altsysteme mit gro\u00ad\u00dfen Datenmengen, fehlende Kompatibilit\u00e4t zu neuen Plattformen, Unsicherheiten bei der Sicherheit und regulatorische Anfor\u00adderungen bremsen den versprochenen Fort\u00adschritt aus. Allein die schiere Menge an Code-Anpassungen (Z-Programme) ist f\u00fcr viele Unternehmen eine gro\u00dfe Herausforderung. Sp\u00e4testens mit dem Auslaufen des Supports f\u00fcr ECC 6.0 wird die Zeit f\u00fcr IT- und Fachabteilungen immer knapper f\u00fcr den Umstieg auf S\/4. In der Praxis erweist sich der Innovationsschub oft als hochkomplexer Kraftakt. Diese Komplexit\u00e4t wird oft untersch\u00e4tzt und zieht Projekte unerwartet in die L\u00e4nge, was zur Steigerung von Kosten f\u00fchrt. Dazu kommt, dass die zur Verf\u00fcgung stehenden Geldmittel r\u00fcckl\u00e4ufig sind. Das hat auch die aktuelle Investi\u00adtionsumfrage der DSAG festgestellt. Darin gibt ein Viertel der befragten Unternehmen an, dass sie mit sinkendem Budget auskommen m\u00fcssen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lizenzierung unter S\/4<\/h2>\n\n\n\n<p>Weitere Unsicherheiten ergeben sich durch ver\u00e4nderte Lizenzmodelle. Dabei fehlt es h\u00e4ufig an Know-how innerhalb der Unternehmen. Die Umstellung auf S\/4 und die Nutzung von KI erfordern tiefgreifendes Spezialwissen. Der Weg zu S\/4 stellt somit viele SAP-Bestandskunden vor eine echte Zerrei\u00dfprobe. In der Gemengelage dieser Unsicherheiten gewinnt ein Modell besonders an Bedeutung: Die Hybrid Cloud als Kombination aus On-prem-, Private- und Public-Cloud-Umgebungen erlaubt Unternehmen maximale Flexibilit\u00e4t. Workloads k\u00f6nnen je nach Sensibilit\u00e4t verteilt werden. Standardprozesse werden in die Public Cloud verschoben, w\u00e4hrend unternehmenskritische Daten in der Private Managed Cloud bleiben. So k\u00f6nnen IT-Verantwortliche den steigenden Anforderungen an Datenschutz und Compliance begegnen. Die aktuelle DSAG-Investitionsumfrage zeigt, dass SAP-Kunden unterschiedliche S\/4-Deployment-Modelle nutzen. Dieses Resultat unterstreicht die Notwendigkeit des flexiblen Ansatzes. Die Hybrid Cloud erm\u00f6glicht zudem einen sanften \u00dcbergang in die Cloud-Welt. Die starke Nutzung der SAP Business Suite (DSAG-Investitionsumfrage: 51 Prozent) deutet darauf hin, dass viele Unternehmen auf eine langsame Transformation setzen \u2013 ohne ihre bisherigen Investitionen ad hoc aufzugeben.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3979169538\"><div id=\"great-2404777007\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/e3mag.com\/de\/event\/e3-roundtable-it-plattformen-sap-btp-sap-bdc-etc\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26_08_26_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">BTP als Br\u00fccke<\/h2>\n\n\n\n<p>Die SAP Business Technology Platform (BTP) fungiert dabei als technologische Br\u00fccke: 40 Prozent der Befragten planen mittlere bis hohe Investitionen in die Plattform, um Innovationen wie KI oder IoT parallel zum bestehenden ERP-System zu nutzen. Auch bei der Integration spezialisierter Dritt\u00adanbieterl\u00f6sungen \u2013 etwa f\u00fcr CRM oder HCM \u2013 punktet das Hybrid-Modell. Dar\u00fcber hinaus minimiert es Risiken: Unternehmen k\u00f6nnen sich in eigenem Tempo mit neuen Technologien vertraut machen, ohne sofort vollst\u00e4ndig in die Public Cloud wechseln zu m\u00fcssen. Die Hybrid Cloud bietet somit Wahlfreiheit und Planungssicherheit f\u00fcr On-premises-Kunden, die ihre digitale Transformation strategisch und kontrolliert gestalten wollen. Der erste Schritt f\u00fchrt \u00fcber eine detaillierte Bestandsaufnahme. Tools wie SAP Signavio und LeanIX helfen, Gesch\u00e4ftsprozesse und IT-Architekturen transparent zu machen und Optimierungspotenziale zu identifizieren. Hier kommt die Kombination aus Suse und Fsas Technologies ins Spiel.<\/p>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-4022567\" data-block-id=\"4022567\"><style>.stk-4022567 .stk-img-figcaption{text-align:center !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch stk--has-lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-150567\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-scaled.jpg\" width=\"2560\" height=\"607\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-scaled.jpg 1920w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-400x95.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-1200x284.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-768x182.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-100x24.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-480x114.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-640x152.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-720x171.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-960x228.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-1168x277.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-1440x341.jpg 1440w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-1536x364.jpg 1536w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-18x4.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Fsas_SAP-hybrid-Cloud-Fujitsu-FSAS-SUSE-slides_cmyk-600x142.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/span><figcaption class=\"stk-img-figcaption\">SAP Activate Transformation Model: Die Technologieplattform ist ein Dreh- und Angelpunkt f\u00fcr das Unternehmen und seine F\u00e4higkeiten.<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">SystemInspection<\/h2>\n\n\n\n<p>Fsas Technologies erg\u00e4nzt diesen Einstieg mit der SystemInspection, einem technischen Deep Dive in bestehende SAP-Systeme \u2013 ein wichtiger Baustein, um Risiken fr\u00fchzeitig zu erkennen und den Transformationspfad sauber aufzusetzen. Dabei handelt es sich um einen umfassenden Check-up f\u00fcr bestehende SAP-Landschaften, der von Fsas Technologies angeboten wird. Dieser Service wird mit einer Fahrzeugwartung verglichen, bei der potenzielle Schwachstellen, Performance-Engp\u00e4sse und zuk\u00fcnftige Engstellen identifiziert werden, bevor sie den Gesch\u00e4ftsbetrieb negativ beeinflussen k\u00f6nnen. Die SystemInspection erstellt ein vollst\u00e4ndiges Inventar der gesamten SAP-Landschaft, einschlie\u00dflich Systeme, Anwendungen, Datenbanken, Server und virtueller Maschinen. <\/p>\n\n\n\n<p>Der n\u00e4chste Schritt ist die Wahl der richtigen Betriebsplattform. Neben On-premises r\u00fccken Pri\u00advate- und Hybrid-Cloud-Modelle in den Fokus \u2013 nicht zuletzt wegen wachsender Anforderungen an Flexibilit\u00e4t, Performance und Datenschutz. Mit Primeflex for SAP Landscapes und Flexframe bietet Fsas Technologies speziell auf SAP-Workloads zugeschnittene Infrastrukturen, wie eine anwendungsbezogene private Cloud-Umgebung, die eine skalierbare und kosteneffiziente Migration erm\u00f6glichen \u2013 auch im Zusammenspiel mit Hyperscalern, ohne die Kon\u00adtrolle \u00fcber die eigenen Daten zu verlieren. Unterst\u00fctzt wird dies durch das Fsas Management Tool, das eine durchg\u00e4ngige Steuerung der hybriden SAP-Landschaft erlaubt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sichere, offene Architekturen<\/h2>\n\n\n\n<p>Eine Herausforderung bleibt die Integration von Public-Cloud-Diensten. Um Vendor Lock-in zu vermeiden und Datensouver\u00e4nit\u00e4t zu sichern, setzen Fsas Technologies und Suse auf offene Architekturen. Diese erm\u00f6glichen nicht nur die Anbindung verschiedener Cloud-Services, sondern sorgen auch daf\u00fcr, dass regulatorische Anforderungen eingehalten werden k\u00f6nnen. KI wird auch f\u00fcr viele SAP-Bestandskunden zu einem Schl\u00fcsselfaktor, um die zuk\u00fcnftige Wettbewerbsf\u00e4higkeit sicherzustellen. Viele Unternehmen wollen KI nutzen, um Prozesse intelligenter zu gestalten und Daten besser auszuwerten \u2013 allerdings auf sichere und kontrollierte Weise. <\/p>\n\n\n\n<p>Die M\u00f6glichkeit, KI-Modelle lokal zu betreiben und mit unternehmensinternen Daten zu trainieren, ohne diese externen Plattformen preiszugeben, gewinnt daher an Bedeutung. Fsas Technologies und Suse bieten hierf\u00fcr passende Infrastrukturen, die Sicherheit und Innovationskraft vereinen. Auch SAP geht mit SAP Joule den Weg in Richtung generativer KI und bietet Nutzern intelligente Assistenzfunktionen direkt in den SAP-Anwendungen. Suse und Fsas Technologies unterst\u00fctzen gemeinsam Unternehmen dabei, ihre eigenen KI-Modelle unter Verwendung vorhandener Daten in SAP- und Nicht-SAP-Umgebungen zu erstellen. Fsas Technologies unterst\u00fctzt diese Strategie durch sichere, leistungsf\u00e4hige Plattformen, auf denen KI lokal oder hybrid betrieben werden kann \u2013 datensouver\u00e4n, flexibel und individuell anpassbar. <\/p>\n\n\n\n<p>M\u00f6glichen Herausforderungen einer S\/4-Migration kann das Konzept der \u201eSafe Transformation\u201c von Fsas Technologies begegnen. Es handelt es um einen strukturierten, sicheren und Com\u00adpliance-konformen Ansatz, der verhindern soll, dass Gesch\u00e4ftsprozesse gef\u00e4hrdet oder gesetzliche Vorgaben verletzt werden. Im Mittelpunkt steht eine gesch\u00fctzte Transformationsumgebung \u2013 eine \u201eSafe Zone\u201c \u2013, in der bestehende Systeme analysiert, bewertet und schrittweise in die neue Architektur \u00fcberf\u00fchrt werden. Dabei kommen bew\u00e4hrte Methoden und Best-Practice-Modelle zum Einsatz, die technische und organisatorische Aspekte abdecken. So lassen sich Kompatibilit\u00e4tsprobleme fr\u00fchzeitig erkennen, Risiken minimieren und eine sichere Datenmigration gew\u00e4hrleisten. Ein Erfolgsfaktor ist die konsequente Orientierung an Datensicherheit und regulatorischer Compliance. Der Schutz sensibler Informationen, die DSGVO-Einhaltung und branchenspezifische Vorgaben sind integraler Bestandteil der Transformationsplanung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Technology Blueprint<\/h2>\n\n\n\n<p>Einen fundierten Fahrplan, um die Reise zu S\/4 erfolgreich zu gestalten, bietet auch der Suse Technology Blueprint mit einer realen Option f\u00fcr Hybrid-Cloud-Szenarien. Im Zentrum des Konzepts stehen vier entscheidende Prinzipien: Sicherheit, Automatisierung, Hochverf\u00fcgbarkeit und flexible Virtualisierung. Suse Linux Enterprise Server (SLES) for SAP Applications bildet dabei die Sicherheitsbasis. Mit einer vom Bundesamt f\u00fcr Sicherheit in der Informationstechnik (BSI) zertifizierten Suse-Linux-Plattform erf\u00fcllt das System h\u00f6chste Sicherheitsstandards (EAL 4+) und erm\u00f6glicht es Unternehmen, regulatorischen Anforderungen wie Nis 2 nachkommen zu k\u00f6nnen. Features wie Live-Patching sorgen daf\u00fcr, dass Sicherheits\u00adupdates ohne Systemneustart eingespielt werden k\u00f6nnen, w\u00e4hrend der Suse-Multi-Linux-Manager als zentrale Instanz f\u00fcr Richtlinienmanagement und Compliance-\u00adKontrolle fungiert. Gleichzeitig setzt Suse stark auf Automatisierung \u2013 ein zen\u00adtraler Hebel, um Komplexit\u00e4t zu reduzieren und Ressourcen zu schonen. Mit Open-Source-Tools wie Terraform, Salt und An\u00adsible lassen sich Infrastrukturprovisionierung, Systemdeployment und Anwendungsbereitstellung automatisiert abbilden \u2013 sowohl on-prem als auch in der Cloud. <\/p>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-adb81da\" data-block-id=\"adb81da\"><style>.stk-adb81da .stk-img-figcaption{text-align:center !important;}.stk-adb81da .stk-img-wrapper{width:50% !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch stk--has-lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-150559\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1.jpeg\" width=\"2243\" height=\"1037\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1.jpeg 1920w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-400x185.jpeg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-1200x555.jpeg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-768x355.jpeg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-100x46.jpeg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-480x222.jpeg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-640x296.jpeg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-720x333.jpeg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-960x444.jpeg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-1168x540.jpeg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-1440x666.jpeg 1440w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-1536x710.jpeg 1536w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-18x8.jpeg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/Folie1-600x277.jpeg 600w\" sizes=\"auto, (max-width: 2243px) 100vw, 2243px\" \/><\/span><figcaption class=\"stk-img-figcaption\">Suse Rancher for SAP Applications.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Das sorgt f\u00fcr Tempo bei der S\/4-Einf\u00fchrung und verschlankt den laufenden Betrieb. F\u00fcr den unterbrechungsfreien Betrieb gesch\u00e4ftskritischer Anwendungen sorgt die High Availability Extension. Basierend auf Pacemaker gew\u00e4hrleistet sie Unternehmen, die Hana in hybriden Umgebungen produktiv betreiben, ein automatisches Fail\u00adover bei System\u00adausf\u00e4llen. Auch bei der Virtualisierung setzt Suse auf Flexibilit\u00e4t: KVM ist eine leistungsstarke Alternative zu kostspieligen VM\u00adware-L\u00f6sungen. Ausf\u00fchrliche Best-Practice-Guides unterst\u00fctzen bei der Umsetzung in produktiven S\/4-Szenarien. Der Blueprint tr\u00e4gt der zunehmenden Bedeutung hybrider IT-Architekturen Rechnung. Mit der SAP Edge Integration Cell, realisiert auf Basis von con\u00adtainerbasierten Technologien wie Suse Rancher for SAP Applications, k\u00f6nnen Unter\u00adnehmen sensible Daten lokal verarbeiten und gleichzeitig die Skalierbarkeit der Cloud nutzen. So lassen sich Cloud-Innovationen und lokale Datenhoheit in Einklang bringen. Insgesamt stellt der Suse Technology Blueprint einen sicheren, effizienten und flexiblen Weg zu S\/4 dar. In einer Zeit, in der Unternehmen nach technologischer Souver\u00e4nit\u00e4t und Zukunftsf\u00e4higkeit streben, bieten Suse und Fsas Technologies erprobte und praxistaugliche Antworten auf die Herausforderungen der SAP-Transformation.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.fsastech.com\/de-de\/\" target=\"_blank\" rel=\"noreferrer noopener\">fsastech.com<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/pdfs\/2505-cover\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg\" alt=\"\" class=\"wp-image-73569\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-810163f\" data-block-id=\"810163f\"><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<p>Zum Partnereintrag:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/e3mag.com\/de\/partners\/suse-linux-gmbh\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"172\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo.jpg\" alt=\"\" class=\"wp-image-142008\" style=\"width:350px\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo.jpg 722w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-400x95.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-100x24.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-480x114.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-640x152.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-720x172.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-18x4.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/suse-logo-600x143.jpg 600w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Der S\/4-Umstieg ist mehr als ein rein technischer Releasewechsel. Er ist vielmehr eine Conversion. Das erfordert eine umfassende Analyse der Gesch\u00e4ftsstrategie und organisatorische Anpassungen.<\/p>\n","protected":false},"author":5665,"featured_media":150563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[44139,44120],"tags":[],"coauthors":[44140,25625],"class_list":["post-150557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-25-05","category-mag-25-05","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/04\/shutterstock_2459345281_-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Der S\/4-Umstieg ist mehr als ein rein technischer Releasewechsel. Er ist vielmehr eine Conversion. Das erfordert eine umfassende Analyse der Gesch\u00e4ftsstrategie und organisatorische Anpassungen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-25-05\/\" rel=\"category tag\">Coverstory 25-05<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-25-05\/\" rel=\"category tag\">MAG 25-05<\/a>","author_info_v2":{"name":"Hussein Keilani, Fsas Technologies","url":"https:\/\/e3mag.com\/de\/author\/hussein-keilani\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/150557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/5665"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=150557"}],"version-history":[{"count":4,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/150557\/revisions"}],"predecessor-version":[{"id":150606,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/150557\/revisions\/150606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/150563"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=150557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=150557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=150557"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=150557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}