{"id":147985,"date":"2025-01-13T07:00:00","date_gmt":"2025-01-13T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=147985"},"modified":"2025-01-07T10:20:34","modified_gmt":"2025-01-07T09:20:34","slug":"studie-zu-ki-integration-in-dax-40-unternehmen-zwei-drittel-der-ki-loesungen-bei-den-glorreichen-sieben","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/studie-zu-ki-integration-in-dax-40-unternehmen-zwei-drittel-der-ki-loesungen-bei-den-glorreichen-sieben\/","title":{"rendered":"Studie zu KI-Integration in DAX-40-Unternehmen: Zwei Drittel der KI-L\u00f6sungen bei den glorreichen sieben"},"content":{"rendered":"\n<p>Prof. Julian Kawohl und Maximilian Otte von der Hochschule f\u00fcr Technik und Wirtschaft (HTW Berlin) haben die Integration von KI-Technologien in den DAX-40-Unternehmen analysiert. Das Ergebnis: 32 der 40 Unternehmen bieten bereits KI-\u00adL\u00f6sungen an, wobei insgesamt 263 verschiedene KI-L\u00f6sungen identifiziert wurden, die sich \u00fcber sieben von zehn definierten Lebensbereichen erstrecken. Allerdings werden 63 Prozent aller L\u00f6sungen von lediglich sieben Unternehmen bereitgestellt.<\/p>\n\n\n\n<p>Die Analyse zeigt, dass 81 Prozent der KI-L\u00f6sungen in den Bereichen Work und Mobility angesiedelt sind, w\u00e4hrend in den Bereichen Spirituality, Socialize und Recreation keine KI-L\u00f6sungen gefunden wurden. Eine detaillierte Branchenanalyse offenbart gro\u00dfe Unterschiede in verschiedenen Branchen. \u201eUnsere Forschung zeigt, dass besonders die Mobilit\u00e4tsbranche mit einer Integrationsrate von 57 Prozent die h\u00f6chste Durchdringung von KI aufweist\u201c, stellt Prof. Julian Kawohl, Inhaber der Professur f\u00fcr Strategisches Management an der HTW Berlin, fest. <\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3248993874\"><div id=\"great-1155680971\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Im Gegensatz dazu verzeichnen die Branchen Chemie, Finanzen, Immobilien und Logistik die geringste KI-Durchdringung. Computer Vision (25 Prozent) und Prozessoptimierung (19 Prozent) sind die am h\u00e4ufigsten genutzten KI-Arten. \u201eBemerkenswert ist die Konzentration von KI-L\u00f6sungen auf wenige Unternehmen: Sieben Unternehmen stellen 63 Prozent aller identifizierten KI-L\u00f6sungen bereit\u201c, erl\u00e4utert Prof. Kawohl. Diese sind: SAP, Telekom, Porsche, Mercedes-Benz, BMW, VW und Continental.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.htw-berlin.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">htw-berlin.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HTW Berlin hat die Integration von KI-Technologien in den DAX-40-Unternehmen analysiert.<\/p>\n","protected":false},"author":2368,"featured_media":147989,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,44051],"tags":[],"coauthors":[39720],"class_list":["post-147985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-24-12","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2025\/01\/shutterstock_1811960044-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>HTW Berlin hat die Integration von KI-Technologien in den DAX-40-Unternehmen analysiert.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-24-12\/\" rel=\"category tag\">MAG 24-12<\/a>","author_info_v2":{"name":"E3-Magazin","url":"https:\/\/e3mag.com\/de\/author\/e3_magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/147985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=147985"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/147985\/revisions"}],"predecessor-version":[{"id":147986,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/147985\/revisions\/147986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/147989"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=147985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=147985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=147985"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=147985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}