{"id":145549,"date":"2024-09-16T07:00:00","date_gmt":"2024-09-16T05:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=145549"},"modified":"2024-09-18T11:32:19","modified_gmt":"2024-09-18T09:32:19","slug":"sap-ist-auf-allzeithoch-und-draengt-in-die-cloud","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/sap-ist-auf-allzeithoch-und-draengt-in-die-cloud\/","title":{"rendered":"SAP ist auf Allzeithoch und dr\u00e4ngt in die Cloud"},"content":{"rendered":"\n<p>Die Dynamik, mit der die SAP ihre Konzern- und Produktpolitik betreibt, beeindruckt. On-\u00adprem-Angebote wurden drastisch verteuert \u2013 auch, um SAP-Kunden in die Cloud zu dr\u00e4ngen. Mit dem Private-Cloud-Komplettpaket Rise with SAP und mit Grow with SAP f\u00fcr Public Cloud bietet SAP eine neue Form der Cloud-Transforma\u00adtion an. Das Subskriptionsmodell bringt Kunden in eine Dauerabh\u00e4ngigkeit und generiert SAP best\u00e4ndig profi\u00adtable Ums\u00e4tze. Das flexiblere Lizenzmodell stellt Cloud- gegen\u00fcber On-prem-Kunden deutlich besser. Dabei sind die Vertragsmodelle wie auch die Transformation selbst hochkomplex und bieten viele Risiken und Nebenwirkungen \u2013 bis hin zum notwendigen IT-Umbau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cloud nur mit Mehrpreis<\/h2>\n\n\n\n<p>Die Ank\u00fcndigung, Innovationen wie die Nutzung k\u00fcnstlicher Intelligenz und Nachhaltigkeitsreporting nur noch in den SAP-eigenen Cloud-Angeboten gegen Mehrpreis zur Verf\u00fcgung zu stellen, d\u00fcpierte und verunsicherte Kunden wie Partner. Die Folge: noch mehr Druck, den Wechsel in die SAP-Cloud anzugehen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3845314255\"><div id=\"great-3597532056\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Offenbar sind bisher weniger zu S\/4 migriert als geplant. Die Cloud-Angebote wurden nicht im erw\u00fcnschten Umfang angenommen. Bereits get\u00e4tigte Investitionen in On-prem-Software wurden nicht angerechnet, bis Anfang 2024 der n\u00e4chste Schachzug in Form eines neuen Bonus- und Rabattprogramms folgte: Mit \u201eRise with SAP Migra\u00adtion and Modernization\u201c sollen Kunden eingeladen werden, eine Cloud-first-Gesch\u00e4ftsstrategie auf SAP-Basis zu entwickeln.<\/p>\n\n\n\n<p>Und SAP verst\u00e4rkt weiter den Druck: Bereits seit September vergangenen Jahres erhalten viele Kunden \u00fcber die Standardrabatte hinaus nicht mehr die in der Vergangenheit regelm\u00e4\u00dfig gew\u00e4hrten zus\u00e4tzlichen Rabatte. SAP will mit dieser De-facto-Verteuerung Bestandskunden den Erwerb ben\u00f6tigter On-prem-Lizenzen zus\u00e4tzlich verg\u00e4llen und zum Umstieg auf Rise-Cloud-L\u00f6sungen bewegen \u2013 und damit den Profit erh\u00f6hen. Neukunden wurde der Erwerb von On-prem-Lizenzen mit Hinweis auf die Cloud-Angebote bereits mehrfach verwehrt.<\/p>\n\n\n\n<p>Inzwischen hat SAP das Rise-Umstiegsprogramm durch Verl\u00e4ngerung des Eilzuschlags noch attraktiver gestaltet: Bei Abschluss eines entsprechenden Vertrags bis Ende September 2024 gibt es zus\u00e4tzlich zu den 45 Prozent f\u00fcr ECC-Kunden (max. 3 Millionen Euro) bzw. 60 Prozent f\u00fcr S\/4-Kunden (max. 6 Millionen Euro) Migration Credit als Gutschriften, weitere 25 Prozent Turbo-Uplift \u2013 was im Einzelfall sehr viel Geld sein kann! Dazu kommen oft noch hohe Subventionen der Hyperscaler. \u00dcber 5200 Kunden haben nach aktuellen Angaben von SAP bereits Private-Cloud-SAP-\u00adVertr\u00e4ge abgeschlossen.<\/p>\n\n\n\n<p>Wenn Sie noch nicht in fortgeschrittenen Gespr\u00e4chen mit SAP sind, ist ein Vertragsabschluss bis September 2024 kaum realistisch. Wir empfehlen Ihnen dennoch unbedingt, sich kurzfristig mit Rise oder Grow auseinanderzusetzen, um m\u00f6gliche wirtschaftliche und strategische Nachteile f\u00fcr Ihr Unternehmen zu vermeiden \u2013 zumal das Programm bis Ende 2024 begrenzt ist.<\/p>\n\n\n\n<p>Der SAP-CEO Christian Klein betreibt seit mehr als einem Jahr auch die Umgestaltung des Unternehmens, hin zu mehr Public Cloud, zu KI \u2013 und zum Abbau von 10.000 \u201eAltjobs\u201c. Prim\u00e4r, um den B\u00f6rsenwert von SAP signifikant zu erh\u00f6hen und um seinen Job zu retten. Denn die Unzufriedenheit der Besch\u00e4ftigten von SAP steigt: Fast die H\u00e4lfte traut Klein laut aktueller Befragung nicht mehr zu, SAP in die Zukunft zu f\u00fchren. Daf\u00fcr gibt es mehrere Gr\u00fcnde: Der Vorstandschef f\u00fchrt autorit\u00e4r, beordert die Belegschaft zur\u00fcck ins B\u00fcro und will ein Bewertungssystem einsetzen, um Low Performer zu identifizieren. SAP steckt in der Transformation. All das kannten die erfolgsverw\u00f6hnten SAPler bislang so nicht.<\/p>\n\n\n\n<p>10.000 langj\u00e4hrig SAP-erfahrene (und vermutlich kritische) Mitarbeiter freizusetzen zugunsten g\u00fcnstigerer, unerfahrener und loyaler Mitarbeiter \u2013 wie wird das SAP ver\u00e4ndern? Wo es doch bereits heute f\u00fcr Kunden schwierig ist, qualifizierten Support und Weiterentwicklung der Software zu erhalten, da erfahrene Ressourcen fehlen.<\/p>\n\n\n\n<p>Ab 2025 rechnet SAP mit rund 200 Millionen Euro weniger Kosten als bisher geplant. Dadurch soll auch das Ergebnis vor Zinsen und Steuern (Ebit) ent\u00adsprechend steigen: SAP plant nun mit 10,2 Milliarden Euro, bislang waren es 10 Milliarden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Grow und Public Cloud<\/h2>\n\n\n\n<p>Die Produktstrategie von Christian Klein ist klar: In aktuellen Pr\u00e4senta\u00adtionen wird immer mit Grow with SAP die Public Cloud als Ziel gesetzt, Rise with SAP als \u00dcbergang, sofern Grow (noch) nicht m\u00f6glich ist. Und dazu KI. Die B\u00f6rse hat dies alles und auch die euphorischen Quartalsergebnisse des zweiten Quartals honoriert (das ope\u00adrative Ergebnis stieg um 33 Prozent auf 1,94 Milliarden Euro). Analysten hatten lediglich mit einem Anstieg um 24 Prozent gerechnet: Der B\u00f6rsenkurs ist in den vergangenen zw\u00f6lf Monaten um fast 60 Prozent auf nahezu 200 Euro pro Aktie gestiegen.<\/p>\n\n\n\n<p>SAP-Cloud oder passendere Alternativen? Pr\u00fcfen Sie zeitnah! Vor dem neuen Programm gab es beim Abschluss von Cloud-Vertr\u00e4gen nie Anrechnungen f\u00fcr get\u00e4tigte On-prem-Lizenzk\u00e4ufe \u2013 daher ver\u00e4ndert dies das Momentum nun noch mal deutlich zugunsten von Rise with SAP. Die SAP-SAM-Experten von HiSolutions haben in den vergangenen Jahren viele Unternehmen beim Wechsel in die SAP-Cloud begleitet. Andererseits erwies sich bei einer mindestens ebenso gro\u00dfen Zahl von Kunden die SAP-Cloud als nicht wirtschaftlich oder unpassend. Daraufhin wurden gemeinsam zukunftsf\u00e4hige Alternativen gesucht, gefunden, bewertet und auf den Weg gebracht.<\/p>\n\n\n\n<p>Dies ist hochkomplex. Es ber\u00fchrt die elementaren Grundlagen der IT und jedes Unternehmens. Es geht um Millionen. Viele Unternehmen haben f\u00fcr diese einmalige Transaktion nicht die erforderliche Erfahrung und Expertise und sollten daher auch Rat und Unterst\u00fctzung von seri\u00f6sen und erfahrenen SAP-Lizenz- und -Vertragsberatern einholen.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.hisolutions.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">hisolutions.com<\/a><\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>SAP strukturiert weiter massiv um: F\u00fcr die SAP Business Suite ist der Nachfolger<br \/>\nS\/4 Hana l\u00e4ngst da. Das Ende der Mainstream-Wartung naht, die Migration scheint unausweichlich. Und mit der Fokussierung auf die Cloud stellt sich SAP selbst neu auf.<\/p>\n","protected":false},"author":2626,"featured_media":139823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,11,43996],"tags":[73],"coauthors":[41869],"class_list":["post-145549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-lizenz-kolumne","category-mag-24-09","tag-erp","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP strukturiert weiter massiv um: F\u00fcr die SAP Business Suite ist der Nachfolger<br \/>\nS\/4 Hana l\u00e4ngst da. Das Ende der Mainstream-Wartung naht, die Migration scheint unausweichlich. Und mit der Fokussierung auf die Cloud stellt sich SAP selbst neu auf.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/lizenz-kolumne\/\" rel=\"category tag\">Lizenz-Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-24-09\/\" rel=\"category tag\">MAG 24-09<\/a>","author_info_v2":{"name":"Lorenz M\u00fcller, HiSolutions","url":"https:\/\/e3mag.com\/de\/author\/lorenz-mueller\/"},"comments_num_v2":"1 comment","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/145549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2626"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=145549"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/145549\/revisions"}],"predecessor-version":[{"id":145934,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/145549\/revisions\/145934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/139823"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=145549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=145549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=145549"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=145549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}