{"id":142013,"date":"2024-04-29T14:00:52","date_gmt":"2024-04-29T12:00:52","guid":{"rendered":"http:\/\/e3mag.com\/?p=142013"},"modified":"2024-05-07T15:15:29","modified_gmt":"2024-05-07T13:15:29","slug":"fue-abschaetzung-fuer-neue-rise-with-sap-vertraege","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/fue-abschaetzung-fuer-neue-rise-with-sap-vertraege\/","title":{"rendered":"FUE: Absch\u00e4tzung f\u00fcr neue Rise-with-SAP-Vertr\u00e4ge"},"content":{"rendered":"\n<p>Bei Rise with SAP werden die SAP-Lizenzen nicht mehr erworben, sondern gemietet (Subscription). Die Kunden erwerben also nicht mehr ein Nutzungsrecht auf Lebenszeit, sondern nach der Vertragslaufzeit erl\u00f6scht das Nutzungsrecht schlagartig, oder Sie m\u00fcssen einer Vertragsverl\u00e4ngerung zu gegebenenfalls ge\u00e4nderten Konditionen abschlie\u00dfen.<\/p>\n\n\n\n<p>Schaut man sich die Struktur der zuk\u00fcnftigen Kosten (Miete pro Jahr) an, so f\u00e4llt auf, dass nach wie vor die User-Lizenzen die gr\u00f6\u00dfte Einzelposition darstellen. Allerdings mietet man nicht mehr einzelne User-Lizenztypen, sondern sogenannte Full Use Equivalents (FUEs). Das ist auf den ersten Blick eine Erleichterung, da man vor der Nutzung nicht die genaue Anzahl der einzelnen User-Lizenz-Typen sch\u00e4tzen muss. Auf den zweiten Blick muss man aber immer noch absch\u00e4tzen, wie viele FUEs man in Zukunft pro Jahr nutzen wird. Das ist genauso schwierig wie fr\u00fcher bei R\/3 (ECC) oder S\/4 (On-prem).<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-481139001\"><div id=\"great-1653044573\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">User-Lizenztypen<\/h2>\n\n\n\n<p>In der Cloud gibt es vier User-Lizenztypen, die unterschiedliche L\u00f6sungsfunktionen zugewiesen sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>SAP S\/4 Hana f\u00fcr Advanced Use: Der Benutzer, dem diese User-Lizenz zugeordnet worden ist, darf, wie damals der Professional User, alle L\u00f6sungsfunktionen nutzen.<\/li>\n\n\n\n<li>SAP S\/4 Hana f\u00fcr Core Use: Ist vor allem f\u00fcr Sales- und Service-Organisationen interessant. Benutzer, dem diese User-Lizenz zugeordnet worden ist, darf die L\u00f6sungsfunktionen eingeschr\u00e4nkt nutzen. Vor allem darf er keine L\u00f6sungsfunktionen aus dem Bereich Finance nutzen.<\/li>\n\n\n\n<li>SAP S\/4 Hana f\u00fcr Self-Service-Use: Diese User-Lizenz ist die eingeschr\u00e4nkteste. Allerdings erlaubt sie den lesenden Zugriff und mit ihr d\u00fcrfen Genehmigungen erteilt werden. Besonders f\u00fcr das produzierende Gewerbe ist dieser User-Lizenztyp interessant.<\/li>\n\n\n\n<li>SAP S\/4 Hana f\u00fcr Developer-Use: Der Benutzer, dem diese User-Lizenz zugeordnet worden ist, darf die Entwicklerwerkzeuge nutzen.<\/li>\n<\/ul>\n\n\n\n<p>Die Grafik zeigt, wie FUEs berechnet werden. Wie man sehen kann, kommt es nach wie vor darauf an, die SAP-Core-Nutzung jedes einzelnen Benutzers zu klassifizieren. Es stellt sich die Frage, wie man an die ausreichende Anzahl von FUEs kommt, um seine zuk\u00fcnftige Rise-with-SAP-\u00adCloud-Umgebung zu betreiben.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-55f21f3\" data-block-id=\"55f21f3\"><style>.stk-55f21f3 .stk-img-wrapper img{transform:scale(1) !important}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch stk--has-lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-142018\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk.jpg\" width=\"974\" height=\"404\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk.jpg 974w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-400x166.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-768x319.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-100x41.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-480x199.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-640x265.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-720x299.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-960x398.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-18x7.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/04\/WEB-E3-Artikel-Mai-2024-FUE-Abschaetzung-final_grafik_cmyk-600x249.jpg 600w\" sizes=\"auto, (max-width: 974px) 100vw, 974px\" \/><\/span><\/figure><\/div>\n\n\n\n<p>SAP S\/4 Hana Cloud Licensing. Licensing user access to digital core via full usage equivalents. (Quelle: SAP)<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-eaa1bee\" data-block-id=\"eaa1bee\"><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<p><strong>Guido Schneider, SLC365<\/strong>: Was h\u00e4ltst du, Myrja, von der Idee, seinen bisherigen User-Lizenz-Bestand eins zu eins \u00fcber eine Tabelle umzusetzen? Also zum Beispiel eine Professional-User-Lizenz f\u00fcr ein FUE?<\/p>\n\n\n\n<p><strong>Myrja Schumacher, Honico<\/strong>: Wer zu viel Geld hat, kann das so machen. Vor der Migration sollte man sich von jedweder Shelfware l\u00f6sen. Eine m\u00f6gliche \u00dcberlizenzierung w\u00fcrde man in der Cloud fortf\u00fchren. Wer in ECC noch nutzungsbasiert vermessen wurde, k\u00f6nnte in Zukunft bei S\/4 Hana nach Berechtigungen vermessen werden; wer sich damit nicht schon vorher besch\u00e4ftigt, k\u00f6nnte gegebenenfalls in gro\u00dfe Compliance-Konflikte kommen.<\/p>\n\n\n\n<p><strong>Gudio Schneider<\/strong>: Das sehe ich auch so, das ist keine gute Idee. Man sollte beim Wechsel in die Cloud die Chance nutzen, nicht mehr ben\u00f6tigte Lizenzen nicht in die neue Landschaft zu \u00fcbernehmen. Nun bietet die SAP einen kostenlosen Service an, um den Bedarf und damit die Anzahl der FUEs zu ermitteln. Was h\u00e4ltst du denn vom \u201eS\/4 Hana Trusted Authorization Review\u201c, also dem Star-Service der SAP, und w\u00fcrdest du diesen empfehlen?<\/p>\n\n\n\n<p><strong>Myrja Schumacher<\/strong>: SAP hat mit dem Star-Service erstmals ein eigenes Lizenzregelwerk auf Basis von Berechtigungsobjekten in Form einer Excel publiziert. Dieses k\u00f6nnte in Zukunft die Basis eines SAP-Remote-Audits bilden. Ist aber in vielerlei Hinsicht, nennen wir es vorsichtig, \u201eunscharf\u201c. Ein SAP_ALL-User wird f\u00e4lschlicherweise als \u201eFunctional Use\u201c klassifiziert, weil das Star-Regelwerk keine Unter-Profile kennt. Wenn der Aufruf \u00fcber Engine-\u00adFunktionalit\u00e4t stattfindet, klassifiziert SAP h\u00e4ufig eine Use-Lizenz. Das ist inkonsistent zur SAP-Preisliste: Erst wenn tats\u00e4chlich au\u00dferhalb einer Engine Core-Funktionalit\u00e4t genutzt wird, ist eine User-Lizenz notwendig. Aus diesen Gr\u00fcnden sollte man nicht zu 100 Prozent auf den Star-Service vertrauen. S\/4 Hana Trusted Authorization Review (Star) berechnet sowohl zu teure als auch zu g\u00fcnstige User-Lizenztypen.<\/p>\n\n\n\n<p><strong>Gudio Schneider<\/strong>: Gibt es auch eine M\u00f6glichkeit, diese S\/4-Hana-Trusted-Authorization-Review-Klassifizierung ohne die SAP durchzuf\u00fchren? Und, wenn ja, was w\u00e4ren die Vorteile?<\/p>\n\n\n\n<p><strong>Myrja Schumacher<\/strong>: Diese M\u00f6glichkeit gibt es. Man kann den Star-Service auch ohne die Unterst\u00fctzung der SAP \u00fcber den Hinweis (me.sap.com\/notes\/3113382) nutzen. Das Ergebnis ist die Klassifizierung der Rollen, allerdings mit allen Nachteilen wie oben beschrieben. Dann muss man das Systemvermessungsprogramm (Transaktion USMM) starten, die entsprechenden Preislisten ausw\u00e4hlen und die entsprechenden Lizenzmaterialien manuell zuordnen. Die USMM ermittelt den ben\u00f6tigten Lizenztyp anhand der vorhandenen Rollen-Klassifizierungen. Voraussetzung daf\u00fcr ist, dass im User-Stamm kein Lizenztyp eingetragen ist (SU01). In der LAW werden die einzelnen Account-Lizenzen konsolidiert. Anschlie\u00dfend erfolgt die manuelle Ermittlung des FUE-Bedarfs entsprechend den Gewichtungsfaktoren, siehe oben.<\/p>\n\n\n\n<p><strong>Gudio Schneider<\/strong>: In meinem E3-Artikel (Nutzungs- versus berechtigungsbasierte User-Lizenzvergabe, Februar 2024, Seite 18) ist zu lesen, dass ich der berechtigungsbasierten User-Lizenzvergabe kritisch gegen\u00fcberstehe. Daran \u00e4ndert auch die Umrechnung in FUEs nichts. Demnach sollte man f\u00fcr die Bestimmung der FUE-Anzahl ein Tool verwenden, welches auf Grundlage der tats\u00e4chlichen Nutzung unter ECC den zuk\u00fcnftigen L\u00f6sungsfunktionen in S\/4 automatisiert zuweist und somit den Lizenzbedarf simuliert. Mit diesem Ergebnis schaut man dann in die SAP-Preis- und -Konditionenliste (PKL) und schaut nach der n\u00e4chsth\u00f6heren Rabattstufe. In vielen F\u00e4llen macht es kaufm\u00e4nnisch Sinn, die Anzahl der FUEs der n\u00e4chsth\u00f6heren Rabattstufe zu mieten, da dies auf der einen Seite kosteng\u00fcnstiger ist und auf der anderen Seite zuk\u00fcnftige Nutzungs\u00e4nderungen mit abfangen kann. Was h\u00e4ltst du von dieser Methode?<\/p>\n\n\n\n<p><strong>Myrja Schumacher:<\/strong> Ich stehe mittlerweile der berechtigungsbasierten Vermessung nicht mehr ganz so ablehnend gegen\u00fcber. In ECC hat berechtigungsbasierte Vermessung nichts zu suchen, da bin ich v\u00f6llig deiner Meinung. Ich stimme dir zu, dass ich bisher noch in keinem Vertrag eindeutig gelesen habe, dass in S\/4 auf Basis der Berechtigungen zu lizenzieren sei. Es besteht allerdings die Gefahr, dass SAP seine Vermessungstools mehr und mehr auf Basis der vorhandenen Berechtigungen ausrichtet. Um darauf vorbereitet zu sein, macht es Sinn, das bestehende Berechtigungskonzept aus Lizenzsicht zu untersuchen. Welches Berechtigungsobjekt wird \u00fcberhaupt genutzt, was macht diese Rolle zu einem Advanced-Use-Typ? Oft ist es nur ein einziges Berechtigungsobjekt, das die Rolle verteuert, herauszufinden, ob dieses Objekt \u00fcberhaupt genutzt wurde und von wem, das ist die Kunst! <\/p>\n\n\n\n<p>Mit einem Tool kann die Nutzung der Berechtigungsobjekte innerhalb der Rollen gemonitort und die Rollen entsprechend angepasst werden. Dies k\u00f6nnte sich auch auf die Nutzungsart der Rollen auswirken, indem beispielsweise eine Rolle von \u201eAdvanced\u201c auf \u201eCore\u201c herabgestuft wird, was dann den FUE-Verbrauch verringert. SAM-Tools k\u00f6nnen unterschiedliche Szenarien f\u00fcr den SAP-\u00adBestandskunden simulieren und dann automatisiert die besten Ergebnisse zur\u00fcckschreiben. Ein Tool, wie Dynamic License Control von Honico, ist auch in der Lage, automatisiert Inkonsistenzen zwischen der Engine-Nutzung und der User-Klassifizierung aufzul\u00f6sen. Auch reichen Transaktionen f\u00fcr die Zukunft nicht mehr aus, Fiori-Applikationen werden mehr und mehr genutzt, diese muss man tracken, das geht nat\u00fcrlich auch mit einem SAM-Tool am besten. Wenn man all das f\u00fcr sich analysiert hat und auch wei\u00df, wo das Unternehmen in der Zukunft hinsteuert, dann ist der Einsatz der n\u00e4chsth\u00f6heren Preisstufe oft sinnvoll, siehe oben.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>Guido Schneider<\/strong>: Vielen Dank, Myrja, f\u00fcr deine Einsch\u00e4tzung und Erkl\u00e4rung. Neben der Optimierung der Star-Ergebnisse durch ein Tool sehe ich auch noch die M\u00f6glichkeit, die FUE-Bestimmung nutzungsbasiert durchzuf\u00fchren. Meiner Meinung nach haben die SAP-Kunden nach wie vor die Wahl, auf welcher Basis sie die FUE-Absch\u00e4tzung machen wollen.<\/p>\n\n\n\n\n\n\n\n<p><a href=\"https:\/\/slc365.com\/\" data-type=\"link\" data-id=\"https:\/\/slc365.com\/\" target=\"_blank\" rel=\"noopener\">slc365.com<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.honico.com\/\" target=\"_blank\" rel=\"noopener\">honico.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-7c28f60\" data-block-id=\"7c28f60\"><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<p>Zum Partner-Eintrag:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/e3mag.com\/de\/partners\/honico-systems-gmbh\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"214\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/01\/Logo-Honico.png\" alt=\"\" class=\"wp-image-138902\" style=\"width:350px\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2024\/01\/Logo-Honico.png 600w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/01\/Logo-Honico-400x143.png 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/01\/Logo-Honico-100x36.png 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/01\/Logo-Honico-480x171.png 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2024\/01\/Logo-Honico-18x6.png 18w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Beim Wechsel von einem ECC-Vertrag zu einem SAP-Rise-Vertrag \u00e4ndert sich die Metrik f\u00fcr die<br \/>\nSAP-User. SAP-Bestandskunden stehen vor der Herausforderung, die Anzahl des Full Use Equivalent, FUE, vor dem Abschluss des neuen Rise-Vertrages zu sch\u00e4tzen.<\/p>\n","protected":false},"author":5474,"featured_media":139823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,11,43945],"tags":[],"coauthors":[43697,38539],"class_list":["post-142013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-lizenz-kolumne","category-mag-24-05","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2024\/02\/Lizenzen-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Beim Wechsel von einem ECC-Vertrag zu einem SAP-Rise-Vertrag \u00e4ndert sich die Metrik f\u00fcr die<br \/>\nSAP-User. SAP-Bestandskunden stehen vor der Herausforderung, die Anzahl des Full Use Equivalent, FUE, vor dem Abschluss des neuen Rise-Vertrages zu sch\u00e4tzen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/lizenz-kolumne\/\" rel=\"category tag\">Lizenz-Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-24-05\/\" rel=\"category tag\">MAG 24-05<\/a>","author_info_v2":{"name":"Myrja Schumacher, HONICO","url":"https:\/\/e3mag.com\/de\/author\/myrja-schumacher\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/142013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/5474"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=142013"}],"version-history":[{"count":8,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/142013\/revisions"}],"predecessor-version":[{"id":142325,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/142013\/revisions\/142325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/139823"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=142013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=142013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=142013"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=142013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}