{"id":134315,"date":"2023-11-13T08:00:00","date_gmt":"2023-11-13T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=134315"},"modified":"2023-12-12T09:50:04","modified_gmt":"2023-12-12T08:50:04","slug":"vorprojekte-adieu","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/vorprojekte-adieu\/","title":{"rendered":"Vorprojekte Adieu!"},"content":{"rendered":"\n<p>SAP-Bestandskunden haben nur noch vier Jahre Zeit, um ihre bisherige SAP-System- und -Applikationslandschaft ohne zus\u00e4tzliche Wartungsgeb\u00fchren auf die neue Generation S\/4 zu transformieren. Und dennoch z\u00f6gern sie. Ein zentraler Grund daf\u00fcr ist \u2013 das zeigen Gespr\u00e4che mit SAP-Nutzern immer wieder \u2013 gar nicht nur die Transformation selbst, sondern der bef\u00fcrchtete Zusatzaufwand durch vorbereitende Projekte. Dazu z\u00e4hlen insbesondere:<\/p>\n\n\n\n<p>Archivierung: Viele SAP-Bestandskunden sitzen auf Bergen von Altdaten. Da die Hana-Datenbank im immer noch teuren Arbeitsspeicher l\u00e4uft, wollen sie den Datenbestand vor der Transformation m\u00f6glichst stark senken.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-249906438\"><div id=\"great-941996447\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>New GL: Viele Unternehmen meinen, Zeit zu sparen, wenn sie zuerst das neue General Ledger (GL) einf\u00fchren. Schlie\u00dflich gibt es das neue SAP-Hauptbuch schon seit ECC 6.0. Andererseits ist es ein Muss in der S\/4-Welt.<\/p>\n\n\n\n<p>Hana: Wieder andere implementieren SAP Hana, bevor sie sich den Anwendungen widmen. Sie erhoffen sich durch die Aufspaltung der Transformation in ein Daten- und ein Anwendungsprojekt ein weniger komplexes Gesamtprojekt, machen sich jedoch keine Illusionen dar\u00fcber, dass es sich hier um ein rein technisches Projekt handelt, das f\u00fcr sich genommen wenig oder keinen gesch\u00e4ftlichen Nutzen hat.<\/p>\n\n\n\n<p>Neues Gesch\u00e4ftsobjekt, GP: Die Hana-Datenbank erfordert generell eine andere Datenstruktur. Hinzu kommt: Das neue Business-Objekt (BO) Gesch\u00e4ftspartner (GP) vereinigt die bisherigen BOs Kunde und Lieferant. Viele SAP-Bestandskunden halten es deshalb f\u00fcr notwendig, die Struktur ihrer bisherigen Kunden- und Lieferantendaten schon vor ihrer Migration an GP anzupassen.<\/p>\n\n\n\n<p>Datenbereinigung: Viele SAP-Bestandskunden wollen v\u00f6llig zu Recht die Transformation nutzen, um ihren Datenbestand von Fehlern und Dubletten zu bereinigen. Schlie\u00dflich ist der Umstieg auf S\/4 ein zentraler Bestandteil ihrer Zukunftsstrategie, f\u00fcr die gilt: Ohne Datenqualit\u00e4t keine Digitalisierung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Blinder Fleck: Altdaten<\/h2>\n\n\n\n<p>Nur um einem Missverst\u00e4ndnis vorzubeugen: Die \u00dcberlegungen, die den jeweiligen Vorprojekten zugrunde liegen, sind v\u00f6llig gerechtfertigt. Und doch verm\u00f6gen sie ein zentrales Problem nicht zu l\u00f6sen: das, was nach der abgeschlossenen Transformation mit den Legacy-Daten und -Systemen geschehen soll. Das ist der blinde Fleck, der nicht zuletzt deshalb viel zu selten wahrgenommen wird, weil die Projektteams, die mit der Transformation betraut sind, sich nicht daf\u00fcr interessieren (m\u00fcssen).<\/p>\n\n\n\n<p>Es scheint fast so, als h\u00e4tten sich viele SAP-Bestandskunden damit abgefunden, ihre Altsysteme nach dem Umstieg auf die S\/4-Welt weiter zu betreiben und ihre Altdaten, deren Struktur aus gesetzlichen Gr\u00fcnden teilweise f\u00fcr Jahrzehnte nicht ver\u00e4ndert werden darf, in Archiven zu lagern. Letzteres bedeutet aber, dass auch die Legacy-Systeme so lange weiterlaufen m\u00fcssen, weil sich die archivierten Daten nur mit ihnen aufrufen und anzeigen lassen.<\/p>\n\n\n\n<p>Abgesehen von dem langfristigen Mehraufwand birgt diese Vorgehensweise erhebliche Risiken hinsichtlich IT- und Rechtssicherheit. Die weiterlaufenden Altsysteme fallen in der Regel aus der Wartung, wichtige Sicherheits-Patches werden nicht mehr eingespielt und Cyberkriminelle freuen sich. Hinzu kommen st\u00e4ndig neue Anforderungen vom Gesetzgeber.<\/p>\n\n\n\n<p>Vorschriften der europ\u00e4ischen Datenschutz-Grundverordnung oder des neuen Schweizer Datenschutzgesetzes wie zum Beispiel die M\u00f6glichkeit, gezielt auf der Ebene des einzelnen Datensatzes zu l\u00f6schen, lassen sich in zahlreichen Altsystemen gar nicht mehr oder nur unter viel Aufwand implementieren.<\/p>\n\n\n\n<p>Au\u00dferdem ist in diesem Szenario SAP-Nutzern der unmittelbare Zugriff auf Legacy-Daten weitgehend oder ganz verwehrt. Das stellt ein nicht zu vernachl\u00e4ssigendes Risiko f\u00fcr die Produktivit\u00e4t und Qualit\u00e4tssicherung in den Unternehmen dar. Aus diesem Grund aber s\u00e4mtliche Altdaten zu transformieren und nach S\/4 zu migrieren, ergibt wirtschaftlich keinen Sinn.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Transformation ohne Legacy<\/h2>\n\n\n\n<p>Allen Vorprojekten gemeinsam sind der gro\u00dfe blinde Fleck und die damit verbundenen wirtschaftlichen, sicherheitsrelevanten und rechtlichen Risiken. SAP-Bestandskunden sollten deshalb dar\u00fcber nachdenken, einen radikal neuen Ansatz zu w\u00e4hlen, der nicht nur die Probleme l\u00f6st, sondern auch die vermeintlich notwendigen Projekte \u00fcberfl\u00fcssig macht und deren Risiken beseitigt.<\/p>\n\n\n\n<p>Dieser Ansatz besteht darin, den kompletten Lebenszyklus von Legacy-Daten bis zu ihrer endg\u00fcltigen und rechtssicheren L\u00f6schung separat, das hei\u00dft losgel\u00f6st von den Altsystemen und -applikationen, zu managen und mit dem Lebenszyklusmanagement der Ziel-Anwendungen und -Systeme einer S\/4-Hana-Landschaft zu synchronisieren.<\/p>\n\n\n\n<p>N\u00f6tig ist daf\u00fcr eine Plattform, auf der sich s\u00e4mtliche Altdaten von SAP- und Non-SAP-Systemen rechtssicher aufbewahren und l\u00f6schen lassen, die aber gleichzeitig alle M\u00f6glichkeiten zur Weiterbearbeitung dieser Daten wie ihre Reduktion, Selektion, Optimierung und Transformation \u00fcber das Migration Cockpit und den Application Layer bietet. Diese Plattform ist mit S\/4 integriert, um Legacy-Daten on the fly und automatisch an die neuen Datenstrukturen wie zum Beispiel die des Business-Objekts GP anzupassen und in SAP Fiori anzuzeigen. Dies geschieht, als ob sie in S\/4 erzeugt worden w\u00e4ren. M\u00f6glich wird diese Funktionalit\u00e4t, weil s\u00e4mtliche Metadaten zur abzul\u00f6senden SAP- und Non-SAP-Landschaft auf Knopfdruck in einem Transformations-Cockpit erfasst und gespeichert werden.<\/p>\n\n\n\n<p>Zus\u00e4tzlich wird jeder Projektschritt dokumentiert und die Plattform wei\u00df, welches Altsystem die Unternehmen stilllegen und entsorgen k\u00f6nnen. Auf Knopfdruck und im Turbo-Verfahren lassen sich s\u00e4mtliche Legacy-Daten aus den ADK-Archiven \u00fcber den Application Layer extrahieren und damit ihre Information zum Lebenszyklus von Daten und Systemen f\u00fcr andere L\u00f6sungen im Bereich Application Lifecycle Management (ALM) bereitstellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eine Plattform f\u00fcr alles<\/h2>\n\n\n\n<p>Keine Vorprojekte, kein Legacy-Problem und kein Tool-Wirrwarr muss der SAP-Bestandskunde f\u00fcrchten. Eine solche Plattform versetzt SAP-Bestandskunden in die Lage, gleich drei Fliegen mit einer Klappe zu schlagen: Erstens analysiert und managt die Plattform den kompletten Lebenszyklus s\u00e4mtlicher Legacy-Daten und bietet, zweitens, alle erforderlichen Funktionalit\u00e4ten f\u00fcr die rechtssichere Aufbewahrung und Analyse sowie selektive Transformation und Migration dieser Daten und l\u00f6st, drittens, das Problem der Altanwendungen und -systeme bei der Transformation ein f\u00fcr alle Mal und macht aus jedem Brownfield- ein Greenfield-Projekt.<\/p>\n\n\n\n<p>Der SAP-Bestandskunde ersetzt nicht den Readiness-Check der SAP, der sich auf Prozesse und Standards bezieht, sondern erg\u00e4nzt ihn als Kern einer unternehmensweiten und intelligenten Data Fabric. Dadurch beseitigt die DMI-L\u00f6sung als \u201eeine Plattform f\u00fcr alles\u201c die Komplexit\u00e4t des ansonsten f\u00fcr die Datenebene typischen Tool-Wirrwarrs. Die Plattform, die den blinden Fleck der S\/4-Transformation auf Knopfdruck ausleuchten und die Vorprojekte auf dem Weg dorthin \u00fcberfl\u00fcssig machen kann, hat einen Namen: JiVS IMP.<\/p>\n\n\n\n<p><a href=\"https:\/\/jivs.com\/\" target=\"_blank\" rel=\"noopener\">jivs.<\/a><a href=\"https:\/\/jivs.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\/4-Transformation ohne Vorprojekte?\u00a0Viele SAP-Bestandskunden scheuen die Transformation auf SAP S\/4 Hana wegen der vermeintlich notwendigen Vorprojekte. Diese erweisen sich jedoch als \u00fcberfl\u00fcssig \u2013 mit dem richtigen Ansatz,<br \/>\num den Lebenszyklus von Apps, Daten und Systemen zu managen.<\/p>\n","protected":false},"author":1289,"featured_media":134319,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[4,2,43645],"tags":[65,871],"coauthors":[22002],"class_list":["post-134315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-sap-nachrichten","category-mag-23-11","tag-hana","tag-plattform","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-400x160.jpg",400,160,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-768x307.jpg",768,307,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-100x40.jpg",100,40,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-480x192.jpg",480,192,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-640x256.jpg",640,256,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-720x288.jpg",720,288,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-960x384.jpg",960,384,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-18x7.jpg",18,7,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1.jpg",1000,400,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-600x240.jpg",600,240,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-600x400.jpg",600,400,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/WEB_Loesung_shutterstock_2285316367-1-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>S\/4-Transformation ohne Vorprojekte?\u00a0Viele SAP-Bestandskunden scheuen die Transformation auf SAP S\/4 Hana wegen der vermeintlich notwendigen Vorprojekte. Diese erweisen sich jedoch als \u00fcberfl\u00fcssig \u2013 mit dem richtigen Ansatz,<br \/>\num den Lebenszyklus von Apps, Daten und Systemen zu managen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/management\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-11\/\" rel=\"category tag\">MAG 23-11<\/a>","author_info_v2":{"name":"Thomas Failer, Data Migration International","url":"https:\/\/e3mag.com\/de\/author\/thomas-failer\/"},"comments_num_v2":"2 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/134315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1289"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=134315"}],"version-history":[{"count":5,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/134315\/revisions"}],"predecessor-version":[{"id":135979,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/134315\/revisions\/135979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/134319"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=134315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=134315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=134315"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=134315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}