{"id":133228,"date":"2023-10-20T10:00:00","date_gmt":"2023-10-20T08:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=133228"},"modified":"2023-12-12T15:16:05","modified_gmt":"2023-12-12T14:16:05","slug":"sap-community-short-facts-oktober","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/sap-community-short-facts-oktober\/","title":{"rendered":"SAP-Community Short Facts Oktober"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>SAP plant \u00dcbernahme von LeanIX<\/strong><\/h2>\n\n\n\n<p>SAP hat eine Vereinbarung zur \u00dcbernahme von LeanIX geschlossen, einem Unternehmen im Bereich Enterprise Architecture Management (EAM). Die geplante Akquisition hilft SAP dabei, ihr Portfolio f\u00fcr Gesch\u00e4ftstransformationen zu erweitern. LeanIX, ein nicht b\u00f6rsennotiertes Unternehmen, ist seit zehn Jahren&nbsp;ein strategischer Partner von SAP und Signavio. Viele CIOs nutzen die Angebote von LeanIX im Rahmen ihrer digitalen Transformation mit Rise. LeanIX erg\u00e4nzt die vorhandenen Transformations-F\u00e4higkeiten von Signavio und bietet SAP-Kunden einen vollst\u00e4ndigen \u00dcberblick \u00fcber ihre IT-Landschaften. LeanIX hat vor Kurzem einen KI-Assistenten auf den Markt gebracht, der Unternehmen dabei unterst\u00fctzt, die Potenziale generativer KI f\u00fcr das Management von IT-Landschaften zu heben. Dies erh\u00f6ht den Automatisierungsgrad beim Steuern von IT-Landschaften und legt den Grundstein f\u00fcr intelligente Empfehlungen bei der Transformation von IT-Landschaften der Zukunft.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-cc038cb\" data-block-id=\"cc038cb\"><style>.stk-cc038cb .stk--block-align-cc038cb{align-items:center !important}.stk-cc038cb-column{justify-content:flex-end !important}<\/style><div class=\"stk-row stk-inner-blocks stk--block-align-cc038cb stk-block-content stk-content-align stk-cc038cb-column stk--flex\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-a701718\" data-v=\"4\" data-block-id=\"a701718\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-a701718-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-a701718-inner-blocks\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/WEB_ChristianKlein-600x450-2.jpg\" alt=\"\" class=\"wp-image-133231\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/WEB_ChristianKlein-600x450-2.jpg 600w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/WEB_ChristianKlein-600x450-2-400x300.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/WEB_ChristianKlein-600x450-2-100x75.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/WEB_ChristianKlein-600x450-2-480x360.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/WEB_ChristianKlein-600x450-2-16x12.jpg 16w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-d6d1e89\" data-v=\"4\" data-block-id=\"d6d1e89\"><style>.stk-d6d1e89-inner-blocks{align-items:flex-start !important}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-d6d1e89-container stk--no-background stk--no-padding\"><div class=\"stk--column-flex stk-block-content stk-inner-blocks stk-d6d1e89-inner-blocks\">\n<p>&#8220;<em>Gemeinsam mit LeanIX wollen wir eine einzigartige Transformations-Suite anbieten, um unseren Kunden eine ganzheitliche Unterst\u00fctzung in ihren Gesch\u00e4ftstransforma-tionen zu erm\u00f6glichen.<\/em>&#8220;<\/p>\n\n\n\n<p><strong>Christian Klein,<\/strong><br>CEO,<br>SAP<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p><a href=\"https:\/\/www.sap.com\/austria\/index.html?url_id=auto_hp_redirect_austria\" data-type=\"link\" data-id=\"https:\/\/www.sap.com\/austria\/index.html?url_id=auto_hp_redirect_austria\" target=\"_blank\" rel=\"noopener\">sap<\/a><a href=\"https:\/\/www.sap.com\/austria\/index.html?url_id=auto_hp_redirect_austria\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/www.sap.com\/austria\/index.html?url_id=auto_hp_redirect_austria\" rel=\"noreferrer noopener\">.<\/a><a href=\"https:\/\/www.sap.com\/austria\/index.html?url_id=auto_hp_redirect_austria\" data-type=\"link\" data-id=\"https:\/\/www.sap.com\/austria\/index.html?url_id=auto_hp_redirect_austria\" target=\"_blank\" rel=\"noopener\">com<\/a><\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1570271089\"><div id=\"great-479544662\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-034cb9b\" data-block-id=\"034cb9b\"><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>KI-Tools verst\u00e4rken die Bedeutung von Datenkompetenz<\/strong><\/h2>\n\n\n\n<p>Die fortlaufende Weiterentwicklung von k\u00fcnstlicher Intelligenz wird derzeit hei\u00df diskutiert. Ob als generative KI f\u00fcr Textproduktion, Bilderstellung oder in der Datenanalyse, letztlich beruhen KI-Tools und die Mechanismen dahinter immer auf Daten. Wer die F\u00e4higkeiten hat, Daten und deren Ergebnisse richtig zu interpretieren und zu nutzen, war schon in den vergangenen Jahren einen Schritt voraus. Die Bedeutung von Datenkompetenz d\u00fcrfte sich in Zukunft weiter verst\u00e4rken \u2013 auch angetrieben durch den KI-Boom. Aktuell kommt dem Thema Datenkompetenz weder in der Schule noch in der beruflichen Weiterbildung eine tragende Rolle zu. Bei den unz\u00e4hligen M\u00f6glichkeiten, die generative KI aktuell bietet, ist jedoch \u00e4u\u00dferst wichtig zu wissen, wie sich gef\u00e4lschte Informationen und Daten erkennen und sich deren Ausbreitung eind\u00e4mmen l\u00e4sst. Wissensl\u00fccken m\u00fcssen Bildungseinrichtungen und Unternehmen gleicherma\u00dfen schlie\u00dfen, um Menschen mit den notwendigen Kenntnissen auszustatten. Datenkompetenz wird beruflich und gesellschaftlich unverzichtbar sein und Lernen am Arbeitsplatz sollte zu einem bewussten und kontinuierlichen Prozess werden, um den Bedarf an Kr\u00e4ften f\u00fcr die datengesteuerte Arbeitswelt auch zuk\u00fcnftig decken zu k\u00f6nnen.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.qlik.com\/us\/\" data-type=\"link\" data-id=\"https:\/\/www.qlik.com\/us\/\" target=\"_blank\" rel=\"noopener\">qlik.com<\/a><\/p>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-9b53a68\" data-block-id=\"9b53a68\"><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Esker stellt neues Gremium f\u00fcr Cybersicherheit vor<\/strong><\/h2>\n\n\n\n<p>Esker, Anbieter von KI-gesteuerten Prozessautomatisierungsl\u00f6sungen f\u00fcr die Bereiche Finanzen, Beschaffung und Kundenservice, gab bekannt, dass das Unternehmen ein Aufsichtsratsgremium f\u00fcr Cybersicherheit gegr\u00fcndet hat. Das neue Gremium setzt sich aus den Esker-Aufsichtsratsmitgliedern Steve Vandenberg, Global Black Belt f\u00fcr Microsoft-Sicherheitsl\u00f6sungen, sowie der erfahrenen IT-Expertin Nicole Pelletier&#8211;Perez zusammen und schl\u00e4gt eine Br\u00fccke zwischen Chief Information Security Officer (CISO) und Aufsichtsrat. Das Gremium sorgt f\u00fcr eine effektive Kommunikation zwischen dem Esker-Aufsichtsrat und den IT-Managern des Unternehmens, die wiederum den Aufsichtsrat bei der Entscheidung \u00fcber Priorit\u00e4ten und Investitionen in die IT-Infrastruktur unterst\u00fctzen, um eine robuste Cybersicherheitsabwehr sicherzustellen.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.esker.de\/\" data-type=\"link\" data-id=\"https:\/\/www.esker.de\/\" target=\"_blank\" rel=\"noopener\">esker.de<\/a><\/p>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-bc34af6\" data-block-id=\"bc34af6\"><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>SAP-integrierte Business&nbsp;Solutions von xSuite <\/strong><\/h2>\n\n\n\n<p>Die neue Version 5.2.10 der xSuite Business Solutions bindet Microsoft Power BI an und unterst\u00fctzt vollumf\u00e4nglich Lean Services f\u00fcr die vereinfachte Verbuchung von Dienstleistungen in S\/4 Hana. Die xSuite Business Solutions umfassen Workflowl\u00f6sungen f\u00fcr die Beschaffung, die Verarbeitung eingehender Auftragsbest\u00e4tigungen, Lieferscheine, Rechnungen und Auftr\u00e4ge. \u00dcber die neue API-Schnittstelle zu Microsoft Power BI in neuem Release werden nun Daten aus xSuite&#8211;Rechnungsworkflows einfach an den Business-Intelligence&#8211;Werkzeugkasten von Microsoft \u00fcbergeben. Power BI ist eine Sammlung von Softwarediensten, Apps und Connectors, die nicht verbundene Datenquellen in koh\u00e4rente, visuell \u00fcberzeugende und interaktive Erkenntnisse umwandelt. Gerade im Finanzsektor w\u00fcnschen sich Verantwortliche eine schnelle Bereitstellung von KPIs zur Messung von Durchlaufzeiten, Ermittlung von Toplieferanten, involvierten Besch\u00e4ftigten etc. Qualit\u00e4t und Effizienz von Prozessen lassen sich so besser monitoren und Potenziale zu deren Optimierung aufdecken.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.xsuite.com\/\" data-type=\"link\" data-id=\"https:\/\/www.xsuite.com\/\" target=\"_blank\" rel=\"noopener\">xsuite.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keine monatlichen SAP-Meldungen sollen au\u00dfer Acht gelassen werden.<br \/>\nDie Short Facts widmen sich den kleineren Neuigkeiten sowie den<br \/>\nscheinbar mehr oder weniger wichtigen Statements der Community.<br \/>\nHier ist der Platz f\u00fcr SAP-spezifische Pressemitteilungen, die sonst gerne \u00fcbersehen werden. Firmen und Personen sind nicht indexiert. <\/p>\n","protected":false},"author":2368,"featured_media":133229,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,43596],"tags":[43631,236],"coauthors":[39720],"class_list":["post-133228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-23-10","tag-community","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-150x150.jpeg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-400x180.jpeg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-768x346.jpeg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-100x45.jpeg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-480x216.jpeg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-640x288.jpeg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-720x324.jpeg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-960x432.jpeg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-18x8.jpeg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF.jpeg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-600x270.jpeg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-600x450.jpeg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-24x24.jpeg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-48x48.jpeg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-96x96.jpeg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-150x150.jpeg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/CSF-300x300.jpeg",300,300,true]},"post_excerpt_stackable_v2":"<p>Keine monatlichen SAP-Meldungen sollen au\u00dfer Acht gelassen werden.<br \/>\nDie Short Facts widmen sich den kleineren Neuigkeiten sowie den<br \/>\nscheinbar mehr oder weniger wichtigen Statements der Community.<br \/>\nHier ist der Platz f\u00fcr SAP-spezifische Pressemitteilungen, die sonst gerne \u00fcbersehen werden. Firmen und Personen sind nicht indexiert. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-10\/\" rel=\"category tag\">MAG 23-10<\/a>","author_info_v2":{"name":"E3-Magazin","url":"https:\/\/e3mag.com\/de\/author\/e3_magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/133228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=133228"}],"version-history":[{"count":4,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/133228\/revisions"}],"predecessor-version":[{"id":133311,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/133228\/revisions\/133311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/133229"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=133228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=133228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=133228"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=133228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}