{"id":132866,"date":"2023-10-04T10:00:00","date_gmt":"2023-10-04T08:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=132866"},"modified":"2023-12-12T15:03:23","modified_gmt":"2023-12-12T14:03:23","slug":"sap-modernisierung","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/sap-modernisierung\/","title":{"rendered":"SAP-Modernisierung"},"content":{"rendered":"\n<p>Echtzeit-Transparenz f\u00fcr alle Beteiligten, Anpassungsf\u00e4higkeit und Kollaboration w\u00e4hrend der gesamten Projektlaufzeit bilden das Fundament f\u00fcr eine aktuell im deutschsprachigen Raum entstehende \u00d6kosystem-Toolchain f\u00fcr S\/4- und Rise-Modernisierungen.<\/p>\n\n\n\n<p>Open-Source-L\u00f6sungen und Linux werden immer mehr zum Standard in den meisten Unternehmen. Das gilt auch f\u00fcr SAP-Modernisierungsstrategien auf dem Weg zum intelligenten, integrierten Unternehmen. Offenbar eignen sich nicht nur die Open-Source-Technologien daf\u00fcr besonders, auch die Open-Source-Prinzipien wie Transparenz, Anpassungsf\u00e4higkeit und Kollaboration sind entscheidend, um selbst hochkomplexe Projekte in rasantem Tempo und in hoher Skalierung umzusetzen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1707411729\"><div id=\"great-482750909\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Beispiel: Linux-Distribution<\/h2>\n\n\n\n<p><br>Werfen wir zur Veranschaulichung einen Blick auf die Entstehungsweise einer typischen Linux-Distribution. Sie besteht aus Tausenden unterschiedlichsten Open-Source-Komponenten in verschiedenen Reifegraden. Erst die Einigung auf offene Schnittstellen, \u00dcbergabepunkte, miteinander agierende Services, das Teilen von Daten und eine strukturierte Orchestrierung aller Module, \u00fcbergreifende Tests sowie agile, automatisierte Go-live-Prozesse ergibt eine stabile, zertifizierte Gesamtl\u00f6sung, die auch h\u00f6chsten Anforderungen f\u00fcr den Produktiveinsatz gerecht wird.<\/p>\n\n\n\n<p>Wie lassen sich diese Open-Source-Prinzipien nun f\u00fcr die erfolgreiche SAP-Modernisierung nutzen \u2013 gerade angesichts der \u00e4hnlich hohen Komplexit\u00e4t? Die Antwort auf die Frage liegt eine Ebene h\u00f6her: in einer integrierten \u00d6kosystem-Toolchain, die sich ebenfalls das Teilen und die Kollaboration zum Ziel setzt.&nbsp;<\/p>\n\n\n\n<p>Zum einen liefert eine durchgehende Technologie-Plattform f\u00fcr alle Aspekte der Modernisierung auf Open-Source-Basis das Fundament f\u00fcr die Adressierung von Themen wie Prozessanpassungen, Change Management, Schnittstellen, API-Management, Legacy Code, Eigenentwicklungen, Data Lakes, Historisierung, Hybrid-Cloud-Szenarien oder Non-SAP-Integration.<\/p>\n\n\n\n<p>Zum anderen ergeben sich aus dieser einheitlichen Technologie-Grundlage so viele Synergien, dass Fachbereiche, IT-Abteilungen, Partnerunternehmen und viele weitere Stakeholder, die bislang v\u00f6llig isoliert gearbeitet haben, miteinander reden und planen k\u00f6nnen. Das zentrale Charakteristikum einer integrierten \u00d6kosystem-Toolchain ist also das Teilen von Informationen, Fakten und Erkenntnissen in einem konkreten Modernisierungsprojekt. Analyseergebnisse und Projektparameter werden unter-einander ausgetauscht, Resultate und Quick Wins von allen genutzt, Zielplattform-Vorgaben automatisiert an den n\u00e4chsten Stakeholder \u00fcbergeben.&nbsp;<\/p>\n\n\n\n<p>Bereits die Transparenzanalyse der gewachsenen und oft stark kundenspezifisch angepassten SAP-Landschaft unterst\u00fctzt die Toolchain in hohem Ma\u00dfe. Moderne Analysewerkzeuge k\u00f6nnen relevante Informationen heute in Minuten anstatt in Monaten zur Verf\u00fcgung stellen. Dar\u00fcber hinaus besteht \u00fcber den Projektfortschritt w\u00e4hrend der gesamten Modernisierung f\u00fcr alle Beteiligten eine vollst\u00e4ndige Transparenz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Open Source Quick Wins<\/h2>\n\n\n\n<p><br>Die Vorteile eines SAP-Modernisierungsprozesses, der auf Open-Source-Prinzipien und -Methoden fu\u00dft, sind weitreichend. Durch das parallele Arbeiten sind f\u00fcr Unternehmen nach einer Analysephase mit der Ermittlung des Innovationspotenzials Quick Wins schneller realisierbar \u2013 und zwar ohne lange Projektvorlaufzeiten.<\/p>\n\n\n\n<p>Die integrierte Open-Source-basierte \u00d6kosystem-Toolchain rund um SAP w\u00e4chst \u2013 und das aus gutem Grund. Schlie\u00dflich k\u00f6nnen damit SAP-Modernisierungen und -Migrationen deutlich vereinfacht und beschleunigt werden. SAP-Partner sollten diesen Trend nicht ignorieren, um weiterhin an der Spitze der Innovation zu stehen.<\/p>\n\n\n\n<p><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/10\/2309_red_hat_e_high.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel als PDF (Englisch)<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/en\/partners\/redhat\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/06\/RedHatCI-Banner.jpg\" alt=\"\" class=\"wp-image-75062\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Was bringen Open-Source-Methoden? SAP-Modernisierungen und -Migrationen sind komplex. Eine andere Herangehensweise, die auf Open-Source-Prinzipien basiert, kann viele Probleme und Stolpersteine von Anfang an vermeiden.<\/p>\n","protected":false},"author":1906,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,5,24,43474],"tags":[43612],"coauthors":[36603],"class_list":["post-132866","post","type-post","status-publish","format-standard","hentry","category-meinung","category-it-management","category-linux","category-mag-23-09","tag-sap-modernisierung","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","image-100":"","image-480":"","image-640":"","image-720":"","image-960":"","image-1168":"","image-1440":"","image-1920":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","bricks_large_16x9":"","bricks_large":"","bricks_large_square":"","bricks_medium":"","bricks_medium_square":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>Was bringen Open-Source-Methoden? SAP-Modernisierungen und -Migrationen sind komplex. Eine andere Herangehensweise, die auf Open-Source-Prinzipien basiert, kann viele Probleme und Stolpersteine von Anfang an vermeiden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/it-management\/\" rel=\"category tag\">IT-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/linux\/\" rel=\"category tag\">Linux Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-09\/\" rel=\"category tag\">MAG 23-09<\/a>","author_info_v2":{"name":"Peter K\u00f6rner, Red Hat","url":"https:\/\/e3mag.com\/de\/author\/peter-koerner-red-hat\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/132866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1906"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=132866"}],"version-history":[{"count":5,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/132866\/revisions"}],"predecessor-version":[{"id":132969,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/132866\/revisions\/132969"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=132866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=132866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=132866"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=132866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}