{"id":132767,"date":"2023-10-02T08:00:00","date_gmt":"2023-10-02T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=132767"},"modified":"2023-09-29T11:36:46","modified_gmt":"2023-09-29T09:36:46","slug":"greenfield-conversion","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/greenfield-conversion\/","title":{"rendered":"Greenfield Conversion"},"content":{"rendered":"\n<p>Das Familienunternehmen Dehner ist eine europaweit t\u00e4tige Unternehmensgruppe mit Sitz im bayerischen Rain am Lech. 1947 als Zwei-Personen-Betrieb gegr\u00fcndet, ist Dehner heute der f\u00fchrende Cross-Channel-H\u00e4ndler der \u201egr\u00fcnen Branche\u201c mit \u00fcber 5700 Besch\u00e4ftigten. Auch in Zukunft will Dehner dynamisch wachsen und die eigene Position als f\u00fchrender Anbieter kontinuierlich erweitern. Daf\u00fcr baut das Unternehmen seine digitalen Angebote konsequent aus und ben\u00f6tigt dazu die passende technologische Plattform zur Abbildung seiner Gesch\u00e4ftsprozesse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">S\/4 Private Cloud<\/h2>\n\n\n\n<p><br>F\u00fcr die Eroberung neuer M\u00e4rkte braucht es kontinuierliche Innovation und eine zukunftsf\u00e4hige Systemlandschaft. Deshalb hat Dehner im Sp\u00e4tsommer 2021 das gr\u00f6\u00dfte Ver\u00e4nderungsprojekt innerhalb der Unternehmensgruppe gestartet: die Migration seiner zentralen SAP-Systeme im Greenfield-Ansatz auf die neue Produktgeneration S\/4 Hana in der Cloud. Cloud ist allerdings nicht gleich Cloud. Bei welchem Provider die SAP-Systeme betrieben werden, hat nicht unwesentlichen Einfluss darauf, wie diese zur Steigerung des Gesch\u00e4ftserfolges beitragen. Die Form des Hostings kann ein Baustein zum Erfolg beim effizienten Einsatz von S\/4 werden. Nachteile entstehen, wenn parallel laufende Entwicklungsprojekte ausgebremst werden, weil Systemupgrades zu lange dauern oder die Reaktionszeiten der Services nicht den Erwartungen entsprechen. Dehner hat sich f\u00fcr den Microsoft-Azure-Betrieb entschieden, um schneller und effizienter die Projektziele zu erreichen. Mit diesem Anspruch wurde die Migration aus der SAP Hana Enterprise Cloud (HEC) aufgesetzt. Die S\/4-Systeme von Dehner liefen von Beginn an auf Azure-Hardware, das hei\u00dft in der Public-Cloud-Infrastruktur von Microsoft. Die Migrationsarbeit bestand darin, die komplexe SAP-Landschaft aus der HEC auszul\u00f6sen und in die von FIS-ASP verwalteten Azure-Bereiche zu \u00fcberf\u00fchren.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1292937663\"><div id=\"great-1256497200\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>\u201eAuch f\u00fcr den Betrieb beim Hyperscaler ist ein koh\u00e4rentes Serviceverst\u00e4ndnis wichtig f\u00fcr die Zusammenarbeit und den Projekterfolg. Zuverl\u00e4ssigkeit und Umsetzungstempo bleiben entscheidend. Administration und pragmatische Arbeitsweise ben\u00f6tigen Balance. FIS-ASP als ausgewiesener Experte im Bereich Managed Services f\u00fcr SAP on Azure ist bekannt f\u00fcr hohe Servicequalit\u00e4t\u201c, so Achim Sperlich, IT-Architekt und verantwortlich f\u00fcr das Hosting-Projekt bei Dehner.<\/p>\n\n\n\n<p>Ein gemeinsames Projektteam aus Fachleuten wurde gebildet, um eine saubere und schnelle Durchf\u00fchrung der Cloud-Migration zu gew\u00e4hrleisten. Dabei konnte bei der Detailplanung des Migrationsprojekts die parallel laufende S\/4-Einf\u00fchrung im Dehner-Garten-Center ber\u00fccksichtigt werden. Mit Best Practices von Microsoft, SAP und FIS-ASP erfolgte die Migration reibungslos und im geplanten Zeitfenster zwischen September und Dezember 2022.<\/p>\n\n\n\n<p>Ganz konkret bedeutet Service f\u00fcr Dehner: Wer im Migrationsprojekt Ansprechpartner f\u00fcr den Kunden ist, bleibt es auch sp\u00e4ter im Betrieb. Die IT-Abteilung hat bekannte Kontaktpersonen bei ihrem Provider und diese reagieren bei Anfragen innerhalb kurzer Zeit. So laufen zum Beispiel S\/4-Upgrades im Vergleich mit dem Service zuvor doppelt so schnell.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cloud und Cloud-Backup<\/h2>\n\n\n\n<p><br>Zum Azure-Cloud- und SAP-Anwendungs-Know-how gesellt sich bei FIS-ASP eine ausgewiesene Microsoft-365-Expertise, auf die wir im Bedarfsfall zur\u00fcckgreifen k\u00f6nnen\u201c, so Markus Freitag, IT-Leiter bei Dehner. \u201eHinzu kommt die M\u00f6glichkeit einer Kombination unserer Systeme mit den hochverf\u00fcgbaren eigenen Rechenzentren der FIS-ASP.\u201c Der Gartenspezialist kann wie geplant zus\u00e4tzliche Server abschalten und in diesem Zuge eigene Hardware an FIS-ASP auslagern. Er betreibt seine virtuellen Maschinen dann als Co-Location in Grafenrheinfeld, w\u00e4hrend diese im Hybridbetrieb mit den SAP-Systemen on Azure verbunden sind. (pmf)<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/partners\/fis-asp\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP.jpg\" alt=\"https:\/\/e3mag.com\/partners\/fis-asp\/\" class=\"wp-image-11365\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FIS-ASP-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Beim Hosting von S\/4-Systemen in der Cloud kommt es auf den Servicegrad des Providers an.<br \/>\nMit FIS-ASP erreicht die Dehner-Unternehmensgruppe ein neues Niveau. Dehner hat sich f\u00fcr den Microsoft-Azure-Betrieb entschieden, um schnell und effizient die Ziele zu erreichen.<\/p>\n","protected":false},"author":2368,"featured_media":132768,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[4,43474],"tags":[43604,43605,65],"coauthors":[39720],"class_list":["post-132767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-23-09","tag-dehner","tag-fis-asp-2","tag-hana","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/09\/WEB_Greenfield-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Beim Hosting von S\/4-Systemen in der Cloud kommt es auf den Servicegrad des Providers an.<br \/>\nMit FIS-ASP erreicht die Dehner-Unternehmensgruppe ein neues Niveau. Dehner hat sich f\u00fcr den Microsoft-Azure-Betrieb entschieden, um schnell und effizient die Ziele zu erreichen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/management\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-09\/\" rel=\"category tag\">MAG 23-09<\/a>","author_info_v2":{"name":"E3-Magazin","url":"https:\/\/e3mag.com\/de\/author\/e3_magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/132767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=132767"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/132767\/revisions"}],"predecessor-version":[{"id":132770,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/132767\/revisions\/132770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/132768"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=132767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=132767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=132767"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=132767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}