{"id":131810,"date":"2023-08-24T10:59:22","date_gmt":"2023-08-24T08:59:22","guid":{"rendered":"http:\/\/e3mag.com\/?p=131810"},"modified":"2023-08-24T13:01:08","modified_gmt":"2023-08-24T11:01:08","slug":"proof-of-concept","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/proof-of-concept\/","title":{"rendered":"Kommentar: Proof of Concept"},"content":{"rendered":"\n<p>Was traditionell eine zeitraubende und fehleranf\u00e4llige T\u00e4tigkeit f\u00fcr Mitarbeiter ist, kann heute intelligente Software \u00fcbernehmen. Die L\u00f6sungen Tangro OC (Order Confirmation) und DA (Despatch Advice) verarbeiten Auftragsbest\u00e4tigungen bzw. Lieferavise automatisch \u2013 mit ganzheitlichem Leistungsumfang f\u00fcr die Texterkennung, Interpretation, Validierung und Buchung der Beleginhalte in SAP. Dank der Tangro-Low-Code-Plattform konnten diese L\u00f6sungen als ma\u00dfgeschneiderte Software f\u00fcr den jeweils spezifischen Verarbeitungsprozess in nur wenigen Wochen entwickelt werden.&nbsp;<\/p>\n\n\n\n<p>Lassen Sie uns einen genaueren Blick auf die Lieferavis-Verarbeitung werfen und betrachten wir im Detail, welche erheblichen Effizienzverbesserungen eine passende L\u00f6sung f\u00fcr die Verarbeitung dieser Gesch\u00e4ftsbelege im Einkauf mit sich bringt. Tangro DA erkennt alle relevanten Kopf- und Positionsdaten des Gesch\u00e4ftsbelegs und pr\u00fcft diese gegen die zugrunde liegenden Bestelldaten in SAP. Sind die Inhalte korrekt, kann der Beleg mit einem Klick unmittelbar in SAP gebucht werden. Optional ist auch eine vollautomatische Verarbeitung im Hintergrund m\u00f6glich.&nbsp;<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-297969738\"><div id=\"great-3785756407\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Gibt es Kl\u00e4rungsbedarf, dann laufen die Workflows elektronisch gesteuert ab. Die passenden Ansprechpartner schl\u00e4gt die L\u00f6sung automatisch vor. Bleiben R\u00fcckmeldungen aus, greift eine systemseitige Erinnerungsfunktion.<\/p>\n\n\n\n<p>Manuelles Abtippen entf\u00e4llt komplett, Erfassungsfehler sind kein Thema mehr. M\u00fchsames \u00dcberpr\u00fcfen und l\u00e4stiges Nachfassen geh\u00f6ren ebenfalls der Vergangenheit an. Der Einkauf hat jederzeit den vollst\u00e4ndigen \u00dcberblick \u00fcber aktuelle Wareneing\u00e4nge.<\/p>\n\n\n\n<p>Alle verarbeiteten Lieferavise werden im Eingangsbuch mit dem aktuellen Belegstatus aufgelistet. Sind Erg\u00e4nzungen oder Korrekturen erforderlich, dann erleichtert die zentrale Maske die Nachbearbeitung. Unstimmigkeiten und Termin- oder Mengenabweichungen sind hier durch visuelle Warnkennzeichen sofort zu sehen. Die Mitarbeiter erkennen auf einen Blick, welche Inhalte \u00fcberpr\u00fcft werden m\u00fcssen und wo ggf. Daten anzupassen sind.&nbsp;<\/p>\n\n\n\n<p>Da Tangro-L\u00f6sungen grunds\u00e4tzlich in SAP ERP\/ECC 6.0 bzw. S\/4 Hana eingebettet sind, kann der Bearbeiter dabei jederzeit direkt auf die SAP-Stamm- und -Bewegungsdaten zugreifen. Mit einem Doppelklick auf die Bestellnummer oder den Lieferanten erfolgt ein direkter Absprung in die jeweilige SAP-Transaktion.&nbsp;<\/p>\n\n\n\n<p>Durch die elektronische Archivierung sind die Belege \u00fcber SAP-Indexdaten zudem jederzeit recherchier- und einsehbar. Nachfragen lassen sich damit schnell beantworten und Recherchen mit wenig Aufwand erledigen.&nbsp;<\/p>\n\n\n\n<p>Dank einer Oberfl\u00e4che, die wie die gewohnte SAP-Umgebung aussieht, ist keine langwierige Einarbeitung n\u00f6tig. Die Mitarbeiter sind schnell mit der L\u00f6sung vertraut.<\/p>\n\n\n\n<p>Mit Tangro DA k\u00f6nnen Mitarbeiter sich ganz auf ihre Kernaufgaben konzentrieren, w\u00e4hrend die Softwarel\u00f6sung die Belegverarbeitung \u00fcbernimmt.<\/p>\n\n\n\n<p><a href=\"\/\/www.tangro.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">tangro.de<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/2309_E3_Magazin_Online_Coverstory.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg\" alt=\"\" class=\"wp-image-73569\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/de\/partners\/tangro_software\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1.jpg\" alt=\"\" class=\"wp-image-131738\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-400x45.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-960x108.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/ci-banner-1-600x67.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen in der digitalen Welt: Wo Softwarel\u00f6sungen eingehende Gesch\u00e4ftsbelege wie Auftragsbest\u00e4\u00adtigungen oder Lieferavise automatisch erfassen, w\u00e4hrend wir uns anderen Aufga\u00adben widmen k\u00f6nnen.<\/p>\n","protected":false},"author":76,"featured_media":131811,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[43473,43474],"tags":[1390],"coauthors":[21846],"class_list":["post-131810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-23-09","category-mag-23-09","tag-s4-hana","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/08\/proof-of-concept-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Willkommen in der digitalen Welt: Wo Softwarel\u00f6sungen eingehende Gesch\u00e4ftsbelege wie Auftragsbest\u00e4\u00adtigungen oder Lieferavise automatisch erfassen, w\u00e4hrend wir uns anderen Aufga\u00adben widmen k\u00f6nnen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-23-09\/\" rel=\"category tag\">Coverstory 23-09<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-09\/\" rel=\"category tag\">MAG 23-09<\/a>","author_info_v2":{"name":"Gesine Liskien, Tangro","url":"https:\/\/e3mag.com\/de\/author\/gesine-liskien\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/131810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=131810"}],"version-history":[{"count":2,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/131810\/revisions"}],"predecessor-version":[{"id":131827,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/131810\/revisions\/131827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/131811"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=131810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=131810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=131810"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=131810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}