{"id":129670,"date":"2023-06-30T09:00:00","date_gmt":"2023-06-30T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=129670"},"modified":"2023-06-14T09:47:13","modified_gmt":"2023-06-14T07:47:13","slug":"erp-transformation-ist-nicht-nur-it-upgrade","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/erp-transformation-ist-nicht-nur-it-upgrade\/","title":{"rendered":"ERP-Transformation ist nicht nur IT-Upgrade"},"content":{"rendered":"\n<p>Ziel ist es, optimierte Prozesse sowie mehr Transparenz und Agilit\u00e4t zu erreichen. Aufgrund der Komplexit\u00e4t dieser Systeme ist die digitale Transformation, beispielsweise auf SAP S\/4HANA, allerdings selten trivial. Und dennoch wird die digitale Transformation zu oft als reines IT-Projekt behandelt, obwohl es neben dem Wechsel der technischen Plattform viel mehr auch um die Optimierung der Kernprozesse und deren Automatisierung geht. Daher sind erfolgreiche Transformationen zumeist solche, bei denen der Transformationsprozess durch die Fachbereiche, beispielsweise das Finance und Accounting (F&amp;A), ma\u00dfgeblich mitbestimmt wird. Denn nur die Finanzexperten haben die F\u00e4higkeit, die Probleme und Chancen ihrer Abteilung zu identifizieren und durch bessere oder ganz neue Prozesse ma\u00dfgeblich zu verbessern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Rollen des CFO und des F&amp;A bei der digitalen Transformation<\/h3>\n\n\n\n<p>Unternehmen und damit vornehmlich der CFO stehen vor vier Herausforderungen, um aus der digitalen Transformation ein erfolgreiches Projekt zu machen. Nicht selten ist die Entt\u00e4uschung gro\u00df und die Frage zwischen Kosten und Nutzen steht sperrig im Raum. An erster Stelle steht die Definition des sogenannten North Star. Wo soll die Reise hingehen? Dann kommt der verf\u00fcgbare Zeitrahmen, der realistisch und gegebenenfalls mit ausreichend Puffer ausgestattet sein muss. Ein weiterer Aspekt ist die Budgetplanung, die nicht nur die Kosten der hausinternen Ressourcen und der neuen Plattform, sondern auch die von externen Spezialisten und zus\u00e4tzlicher Software f\u00fcr die Automatisierung umfassen muss. Die dritte Herausforderung ist die Planung, welche die eigentliche Optimierung bestehender Prozesse einschlie\u00dft. An vierter Stelle steht die Datenintegration, sprich die \u00dcberpr\u00fcfung der Daten und ihre fehlerfreie \u00dcbertragung in die neuen Prozesse. Und zuletzt der wohl wichtigste Aspekt, das Change Management, um alle Beteiligten an Bord zu haben.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-2090521289\"><div id=\"great-1675765801\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>F\u00fcr den CFO und die Finanzabteilung ist bei einer Transformation der Aspekt der h\u00f6chstm\u00f6glichen Automatisierung von entscheidender Bedeutung. Manuelle Prozesse, wie der Datenabgleich von unterschiedlichen Tabellen aus diversen Quellen, m\u00fcssen so weit wie m\u00f6glich eliminiert werden. Denn genau diese traditionellen Prozesse hindern den CFO und sein Team daran, wichtige Aufgaben zu erf\u00fcllen. Durch die Automatisierung wird ein Gro\u00dfteil der Fehlerquellen beseitigt, die Geschwindigkeit wird gesteigert und die Transparenz und Agilit\u00e4t ma\u00dfgeblich erh\u00f6ht. Die Folge: Der CFO und sein Finanzteam haben die Zeit und M\u00f6glichkeit, das Management durch bessere, schnellere und valide Finanzanalysen und Szenarien mit Echtzeitdaten zu unterst\u00fctzen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Transformation: schrittweise oder in einem Rutsch<\/h3>\n\n\n\n<p>Besonders wichtig bei der Transformation eines ERP und insbesondere der Finanzfunktion ist die h\u00f6chstm\u00f6gliche Automatisierung der Standardprozesse. Das Financial Close Management, die Automatisierung der Debitorenbuchhaltung und das Intercompany Financial Management von BlackLine beispielsweise erg\u00e4nzt und erweitert ERP-Systeme um einen virtuellen Subledger, innerhalb dessen es manuelle Prozesse eliminiert, die normalerweise au\u00dferhalb des ERP-Systems in Tabellenkalkulationen durchgef\u00fchrt werden.<\/p>\n\n\n\n<p>F\u00fcr die Prozessoptimierung und Abfolge der Transformation gibt es unterschiedliche Ans\u00e4tze. L\u00f6sungen wie von BlackLine sind in der Lage, sowohl Altsysteme als auch das transformierte ERP, etwa in den von SAP S\/4HANA vor- und nachgelagerten Prozessen, zu einem hohen Grad zu automatisieren. Eine M\u00f6glichkeit besteht darin, bereits in einem sehr fr\u00fchen Stadium das Altsystem mit maximaler Automation zu optimieren. Das hat den Vorteil, die Transformationsteams massiv zu entlasten. Denn damit wird sichergestellt, dass die existierende Grundlage, bestm\u00f6glich f\u00fcr die Transformation vorbereitet ist wie zum Beispiel das Clearing von Open Items. Eine weitere Option ist die Prozessoptimierung und Automatisierung w\u00e4hrend der Transformation selbst. Die besten Resultate allerdings bietet die Kombination beider Ans\u00e4tze.<\/p>\n\n\n\n<p>Unabh\u00e4ngig von der Wahl des Ansatzes sorgt die digitale Transformation des ERP und der Finanzfunktion f\u00fcr eine weitreichende Wertsch\u00f6pfung im Finance und Accounting. Durch die Integration, Orchestrierung und Automatisierung von End-to-End-Buchhaltungsprozessen werden schneller vollst\u00e4ndige und genaue Ergebnisse erzielt. L\u00f6sungen wie von BlackLine k\u00f6nnen schnell und mit minimaler IT-Unterst\u00fctzung in unterschiedlichen Stadien implementiert werden und erlauben den Unternehmen mehr Kontrolle, reduzieren die Risiken und sorgen daf\u00fcr, den Nutzen einer umfassenden ERP-Umstellung bereits zu einem sehr fr\u00fchen Zeitpunkt zu erzielen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/blackline\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline.jpg\" alt=\"https:\/\/e3mag.com\/partners\/blackline\/\" class=\"wp-image-43117\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2018\/05\/CI-Banner-Blackline-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Prozesse wie Lieferketten, Lagerhaltung, Betrieb, Handel, Berichterstattung, Fertigung, Personalwesen und vor allem die Finanzen laufen im zentralen ERP wie Nervenstr\u00e4nge in einem Gehirn zusammen. Ergo sind Unternehmen bestrebt, dieses Kerninstrument zu pflegen, auf aktuellem Stand zu halten und wenn n\u00f6tig auf ein neues Level zu transformieren. <\/p>\n","protected":false},"author":1975,"featured_media":129675,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[42339],"tags":[5699,1114,600,73,1390],"coauthors":[37083],"class_list":["post-129670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-online-advertorial","tag-blackline","tag-cfo","tag-digitale-transformation","tag-erp","tag-s4-hana","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/06\/2023-07-blackline_titelbild_1000x450px-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Prozesse wie Lieferketten, Lagerhaltung, Betrieb, Handel, Berichterstattung, Fertigung, Personalwesen und vor allem die Finanzen laufen im zentralen ERP wie Nervenstr\u00e4nge in einem Gehirn zusammen. Ergo sind Unternehmen bestrebt, dieses Kerninstrument zu pflegen, auf aktuellem Stand zu halten und wenn n\u00f6tig auf ein neues Level zu transformieren. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/online-advertorial\/\" rel=\"category tag\">Online-Advertorial<\/a>","author_info_v2":{"name":"Ralph Weiss, Blackline","url":"https:\/\/e3mag.com\/de\/author\/ralph-weiss-blackline\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/129670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/1975"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=129670"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/129670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/129675"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=129670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=129670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=129670"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=129670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}