{"id":126508,"date":"2023-04-27T10:00:00","date_gmt":"2023-04-27T08:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=126508"},"modified":"2023-05-14T12:47:31","modified_gmt":"2023-05-14T10:47:31","slug":"sap-basis-2023-und-steampunk","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/sap-basis-2023-und-steampunk\/","title":{"rendered":"SAP-Basis 2023 und Steampunk"},"content":{"rendered":"\n<p>Nun steht mit der BTP, Business Technology Platform, ein verifiziertes Framework zur Verf\u00fcgung und mit dem SolMan-Nachfolger ALM, Application Lifecycle Management, ein hinreichend gutes IT-Werkzeug.<br><br>Sag mir, woher du kommst, und ich sag dir, wer du bist. SAP-Vorstandsmitglied J\u00fcrgen M\u00fcller ist der Steampunk-Master. Er lie\u00df die alteingesessene SAP-Programmiersprache Abap runderneuern und in die Business Technology Platform (BTP) einbetten. Dieses Projekt hatte bei SAP den Codenamen \u201eSteampunk\u201c, er wurde in der Community kolportiert und von dieser begeistert aufgenommen. Embedded Abap ist Steampunk und auf dem SAP Competence Center Summit 2023 in Salzburg wird es eine der ersten \u00f6ffentlichen Keynotes zum Thema Steampunk von einem SAP-Partner geben. Am Donnerstag, 1. Juni, ist in Salzburg <a href=\"https:\/\/e3mag.com\/summit-cc\/#programm\" target=\"_blank\" rel=\"noreferrer noopener\">Steampunk-Party<\/a>!<\/p>\n\n\n\n<p>\u201eF\u00fcr erfahrene SAP-Verantwortliche steht fest: Nur eine gut funktionierende Infrastruktur befl\u00fcgelt die wichtigen SAP-Anwendungen. Und je mehr und umfangreicher smarte Tools eingesetzt werden, IT-Infrastrukturaufgaben beziehungsweise Aktionen einfach, hochautomatisiert und schnell zu unterst\u00fctzen, desto mehr kann die SAP-Basis sich auf wichtige anwendungsbezogene Aufgaben oder T\u00e4tigkeiten konzentrieren\u201c, erkl\u00e4rte Hans Haselbeck, CEO beim SAP-Partner <a href=\"https:\/\/e3mag.com\/partners\/empirius-gmbh\/\" target=\"_blank\" rel=\"noreferrer noopener\">Empirius<\/a> und Aussteller am SAP <a href=\"https:\/\/e3mag.com\/summit-cc\/\" target=\"_blank\" rel=\"noreferrer noopener\">Competence Center Summit<\/a> in Salzburg. \u201eObendrein ergeben sich damit f\u00fcr SAP-Verantwortliche Nutzenvorteile. L\u00e4uft die SAP-Infrastruktur optimal, laufen auch die Anwendungen optimal. Verbunden sind mit Automatisierungsl\u00f6sungen nachweislich Zeit- und damit Kosteneinsparungen. Auch helfen Automatisierungsl\u00f6sungen, Personalprobleme im SAP-Basis-Umfeld besser zu managen.\u201c<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-4163447330\"><div id=\"great-1138598228\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/e3mag.com\/de\/podcast-erp-architekturen-mit-suse\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"e3pc_banner_2609_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/08\/e3pc_banner_2609_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"800\" height=\"100\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"640\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck.jpg\" alt=\"Hans Haselbeck, Empirius\" class=\"wp-image-126512\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-400x320.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-768x614.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-100x80.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-480x384.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-640x512.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-720x576.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/Empirius_Hans-Haselbeck-600x480.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:16px\"><br>&#8220;<em>F\u00fcr SAP-Verantwortliche steht fest: Nur eine gut funktionierende Infrastruktur befl\u00fcgelt die wichtigen SAP-Anwendungen.<\/em>&#8220;<\/p>\n\n\n\n<p style=\"font-size:16px\"><em><br><\/em>Hans Haselbeck,<br>CEO der Empirius, M\u00fcnchen<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Die SAP-Bestandskunden brauchen f\u00fcr S\/4 Hana nicht nur ein adaptiertes Basiskonzept, sondern auch neue IT-Werkzeuge. Empirius ist einer der Lieferanten f\u00fcr erfolgreiche Automation und damit auch eine Antwort auf den Personalmangel in den IT-Abteilungen. \u201eNach wie vor nutzen viele SAP-Kunden die Business Suite 7 mit Any-DBs, viele S\/4 mit der Hana-Datenbank in eigenen Rechenzentren oder \u00fcber SAP-Serviceprovider. Und alle SAP-Kunden befassen sich mit den Betriebsthemen Cloud, Hybrid-Cloud und On-premises. Schon fr\u00fch richtete Empirius die L\u00f6sungen darauf aus, sowohl SAP-Systemkopien beim Klassiker mit Any-DBs als auch beim S\/4-Einsatz mit Hana nutzen zu k\u00f6nnen.\u201c Weitere IT-Werkzeuge pr\u00e4sentiert Empirius in Salzburg.<\/p>\n\n\n\n<p>Die neue Basis ist die BTP. Diese Plattform liegt in der Verantwortung von SAP-Steampunk-Master J\u00fcrgen M\u00fcller. BTP gilt als zentrales Element der SAP-Strategie und fand somit auch Eingang in den j\u00e4hrlichen DSAG-Investitionsreport. Bei den SAP-Cloud-L\u00f6sungen gaben 24 Prozent der DSAG-Mitglieder an, hohe und mittlere Investitionen in die SAP Business Technology Platform (BTP) zu t\u00e4tigen. Investitionen meint in diesem Fall die Steigerung von Ausgaben in Cloud-L\u00f6sungen inklusive Subskriptionen. An zweiter Stelle im Ranking der SAP-Cloud-L\u00f6sungen folgte SAP SuccessFactors mit hohen und mittleren Investitionen bei 17 Prozent der Befragten. An dritter Stelle steht SAP Customer Experience mit neun Prozent.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Business Technology Platform<\/h3>\n\n\n\n<p>\u201eSAP positioniert die BTP als zentrales Element ihrer Strategie. Vor diesem Hintergrund ist es verst\u00e4ndlich, dass die Umfrageteilnehmer diese SAP-Cloud-L\u00f6sung in Erw\u00e4gung ziehen\u201c, so DSAG-Vorstandsvorsitzender Jens Hungershausen. Aus DSAG-Sicht sei es positiv zu bewerten, dass nun erste Migrationsservices entwickelt werden, die z. B. bei der Umstellung bestehender Integrationsarchitekturen auf die Integration Suite der BTP unterst\u00fctzen. Die Kosten f\u00fcr Entwicklung, Qualit\u00e4tssicherung und Nutzung der Services ohne produktiven Bezug seien aber zu hoch \u2013 genauso wie die Kosten f\u00fcr den generellen Betrieb. Hierzu steht die DSAG im Austausch mit SAP.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800.jpg\" alt=\"Jens Hungershausen\" class=\"wp-image-121031\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800-400x267.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800-768x512.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800-100x67.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800-480x320.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800-640x426.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/02\/jenshungershausen_800-720x480.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:16px\"><br>&#8220;<em>SAP positioniert die BTP als zentrales Element ihrer Strategie. Es ist es verst\u00e4ndlich, dass SAP-Cloud-L\u00f6sungen gefragt sind.<\/em>&#8220;<\/p>\n\n\n\n<p style=\"font-size:16px\"><br>Jens Hungershausen,<br>Vorstandsvorsitzender, DSAG<br><\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Bei der Business Technology Platform liegt in Bezug auf die Relevanz f\u00fcr Investitionen der Bereich Daten und Analysen (z. B. SAP Hana Cloud, SAP Analytics Cloud) mit 38 Prozent hohen und mittleren Investitionen vor der Anwendungsentwicklung und -automatisierung sowie der Integration mit jeweils 17 Prozent f\u00fcr hohe und mittlere Investitionen. K\u00fcnstliche Intelligenz bildet mit drei Prozent f\u00fcr hohe und mittlere Investitionen das Schlusslicht. <br><br>\u201eDie Bedeutung von Daten und Analysen bewegt sich auf Vorjahresniveau und unterstreicht den Stellenwert von agilem Handeln in schnelllebigen Zeiten. Echtzeitanalysen, Prognosen und konkrete Planungen spielen eine gro\u00dfe Rolle\u201c, so Jens Hungershausen. In diesen Kontext passt das von SAP angek\u00fcndigte Angebot \u201eSAP Datasphere\u201c, das Gesch\u00e4ftskunden die Verarbeitung und Analyse gesch\u00e4ftskritischer Informationen erleichtern soll. Es adressiert die seit Langem bestehende Forderung der DSAG nach der Zusammenf\u00fchrung von SAP- und Non-SAP-Daten.<\/p>\n\n\n\n<p>\u201eSAP-Kunden generieren 87 Prozent des gesamten weltweiten Handels. SAP-Daten geh\u00f6ren f\u00fcr Unternehmen somit zum wertvollsten Gut und sind in den wichtigsten Bereichen pr\u00e4sent \u2013 von der Fertigung bis hin zu Logistikketten, Finanzwesen, Personalmanagement und vielen anderen Bereichen\u201c, sagt J\u00fcrgen M\u00fcller, Chief Technology Officer und Mitglied des Vorstands der SAP. \u201eWir wollen unseren Kunden helfen, hier einen Schritt weiterzugehen und SAP-Daten sowie Daten aus Anwendungen und Plattformen anderer Unternehmen einfach und sicher zu integrieren. Sie erhalten dadurch vollkommen neue Einblicke und Informationen und k\u00f6nnen ihre Digitalisierung weiter voranbringen.\u201c<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"569\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller.jpg\" alt=\"J\u00fcrgen M\u00fcller, SAP\" class=\"wp-image-126516\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-400x285.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-768x546.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-100x71.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-480x341.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-640x455.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-720x512.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/sap_juergen_mueller-600x427.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:16px\">&#8220;<em>SAP-Daten geh\u00f6ren f\u00fcr<br>Unternehmen somit zum wertvollsten Gut und sind in den wichtigsten Bereichen pr\u00e4sent.<\/em>&#8220;<\/p>\n\n\n\n<p style=\"font-size:16px\"><br>J\u00fcrgen M\u00fcller,<br>CTO und Mitglied des SAP-Vorstands, SAP<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">SAP Datasphere<\/h3>\n\n\n\n<p>Datasphere ist ab sofort verf\u00fcgbar und bildet die n\u00e4chste Generation der L\u00f6sung SAP Data Warehouse Cloud. Datenspezialisten sind damit in der Lage, skalierbaren Zugriff auf gesch\u00e4ftskritische Daten zu erm\u00f6glichen. Die L\u00f6sung bietet einen durchg\u00e4ngigen Service f\u00fcr Datenintegration, Datenkatalogisierung, semantische Modellierung, Data Warehousing, Data Federation und Datenvirtualisierung. Dadurch k\u00f6nnen Datenexperten gesch\u00e4ftskritische Daten unter Beibehaltung von Gesch\u00e4ftskontext und Logik in der Datenlandschaft ihres Unternehmens verteilen. Datasphere basiert auf der BTP, die unter anderem leistungsstarke Sicherheitsfunktionen f\u00fcr Unternehmen \u2013 beispielsweise Datenbanksicherheit, Verschl\u00fcsselung und Governance \u2013 bietet.<\/p>\n\n\n\n<p>Der Bedarf an Basisfunktionen f\u00fcr das Daten- und Prozessmanagement ist gro\u00df. Vor rund eineinhalb Jahren erweiterte Empirius den L\u00f6sungsfokus und brachte ein smartes und einfach zu bedienendes SAP-Systemmanagement-Framework mit der Bezeichnung EPOS auf den Markt; eine zentrale Managementsoftware f\u00fcr den SAP-Infrastrukturbereich, mit der Aktionen auf einzelnen oder allen SAP-Systemen durchgef\u00fchrt werden k\u00f6nnen. SAP-Bestandskunde Leonhard Kurz Stiftung sieht den EPOS-Einsatz als Ausgangspunkt f\u00fcr weitere Automatisierungsinitiativen bei Abl\u00e4ufen im SAP-Basis-Umfeld. Eine Art Automatisierungsbooster f\u00fcr die SAP-Basis. Die Motivation nach der Systemeinf\u00fchrung sowie den gemachten Erfahrungen mit der SAP-Basis-Systemmanagement-Automatisierungsl\u00f6sung EPOS ist gro\u00df.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"467\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert.jpg\" alt=\"\" class=\"wp-image-126517\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert.jpg 1100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-400x170.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-768x326.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-100x42.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-480x204.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-640x272.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-720x306.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-960x408.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/SAP_Grigoleit_Business_Data-komprimiert-600x255.jpg 600w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><figcaption class=\"wp-element-caption\">SAP Business and Data Transformation Solutions. Digitize Transition, Manage Decisions and Gain End-to-End Visibility.<\/figcaption><\/figure>\n\n\n\n<p>\u201eZu den Kompetenzfeldern von Empirius z\u00e4hlen Automatisierung, Anonymisierung, Workflow Automation. Und im Bereich Dienstleistungen: Migrationen, Releasewechsel, Betriebsplanung und -unterst\u00fctzung, Architekturplanung oder Managed Cloud Services\u201c, erkl\u00e4rte Hans Haselbeck im E-3 Interview. \u201eMit dem SAP-Systemmanagement-Framework EPOS, Empirius Planning and Operations Suite, hat das Unternehmen den L\u00f6sungsradius in puncto Automatisierungssoftware deutlich erweitert. Hierbei geht es nicht nur um ein Aufgaben- und L\u00f6sungsfeld, sondern um ein Managementtool mit Automatisierungsfunktionalit\u00e4t, das wesentliche Komponenten einer SAP-Systemumgebung ber\u00fccksichtigt, wie etwa Server, Datenbanken oder SAP-Komponenten: und zwar hinsichtlich Verwaltung, Steuerung oder Management und Kontrolle mit Monitoring. Dementsprechend beinhaltet EPOS Info-Apps und Automation-Apps wie etwa SAP-Kernel-Updates oder System Maintenance und k\u00fcnftig SAP-Systemkopien.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">(Embedded) Steampunk<\/h3>\n\n\n\n<p>Eine besondere Herausforderung an der SAP-Basis ist die \u00dcbertragung des Z-Namensraums, also der Abap-Modifikationen, in die neue S\/4-BTP-Welt. Die Resonanz auf Steampunk war in den DSAG-Arbeitskreisen anl\u00e4sslich der Technologietage in Mannheim sehr positiv. Gro\u00dfteils waren es aber SAP-ERP-Bestandskunden, die ihr halbes Berufsleben mit Abap verbracht haben. Wie schaut die Zukunft aus? Soll ein Neukunde f\u00fcr die Private oder Public Cloud auch noch Abap mit Ausblick auf Steampunk lernen? Dazu antwortet Karl Kessler, VP Product Management Abap Platform bei SAP, im E-3-Exklusivinterview: \u201eAbap ist nach wie vor relevant und wird es auch in Zukunft sein. <br><br>F\u00fcr SAP-S\/4-Hana-Kunden, sowohl Bestandskunden als auch Neukunden, bietet SAP das moderne Abap-Cloud-Entwicklungsmodell an. Abap Cloud erlaubt es, upgradestabile und cloudf\u00e4hige L\u00f6sungen und Erweiterungen zu bauen. Je nach Szenario k\u00f6nnen Kunden oder Partner ihre Abap-Cloud-Erweiterung direkt auf dem S\/4-Hana-Stack oder auf der SAP Business Technology Platform bauen. Innerhalb der Community spricht man hier auch von Embedded Steampunk bzw. Steampunk. Das Entwicklungsmodell Abap Cloud ist auf der BTP und in allen SAP-S\/4-Hana-Editionen, also Public Cloud, Private Cloud und On-premises, in der neuesten Version verf\u00fcgbar.\u201c<\/p>\n\n\n\n<p>Abap-Modifikationen an SAP-Objekten im SAP-Namensraum haben bei zur\u00fcckliegenden Releasewechseln immer wieder zu Problemen gef\u00fchrt. Wie schaut die S\/4-Zukunft aus? Das Abap-Cloud-Entwicklungsmodell erlaubt keine Modifikationen an SAP-Objekten und stellt den SAP-Bestandskunden stattdessen freigegebene stabile APIs und Extension Points zur Verf\u00fcgung. Das f\u00fchrt zur Upgrade-Stabilit\u00e4t der Abap-Cloud-Erweiterungen. Diese Abap-Cloud-Regeln gelten unabh\u00e4ngig davon, ob die Abap-Cloud-Erweiterungen direkt auf dem S\/4-Stack (Embedded Steampunk) oder Side-by-Side auf der BTP laufen. Und Karl Kessler pr\u00e4zisiert, dass im BTP-Abap-Environment, Steampunk, die Abap Cloud verpflichtend ist, denn die klassische Abap-Entwicklung wird hier nicht unterst\u00fctzt. Von der BTP-Erweiterung aus ruft der Anwender freigegebene Remote-S\/4-Hana-APIs auf, um auf das System zuzugreifen.<\/p>\n\n\n\n<p>Eine weitere M\u00f6glichkeit, Erweiterungen mit dem Standard zu koppeln, besteht darin, auf Business Events zu reagieren, die im S\/4-System ausgel\u00f6st werden.&nbsp; Damit k\u00f6nnen Kunden eine eventgetriebene Architektur realisieren. F\u00fcr Abap-Erweiterungen, die direkt auf dem S\/4-Stack laufen (Embedded Steampunk), wird zwischen verschiedenen Editionen unterschieden. Zum einen die Public Cloud, wo nur Abap Cloud verwendet werden kann und keine Modifikationen m\u00f6glich sind. Auf der anderen Seite die Private Cloud und On-premises, wo Abap Cloud empfohlen ist und klassische Abap-Erweiterungstechniken sowie Modifikationen weiterhin m\u00f6glich sind.<\/p>\n\n\n\n<p>Unmittelbar daraus ergibt sich f\u00fcr die SAP-Bestandskunden nun die Frage: Sind Abap-Modifikationen mit Steampunk somit eine Gefahr f\u00fcr den SAP-Anspruch \u201eClean Core f\u00fcr SAP S\/4 Hana\u201c? Karl Kessler antwortet: \u201eWie vorher schon kurz erw\u00e4hnt, erlaubt Abap Cloud keine Modifikationen. Abap Cloud ist in der Public Cloud das einzig verf\u00fcgbare Abap-Entwicklungsmodell. In der Private Cloud und On-premises k\u00f6nnen Kunden ihren klassischen Abap-Code schrittweise in Richtung Abap Cloud transformieren und haben damit zusammen mit der SAP BTP einen planbaren und gangbaren Weg zu einem Clean Core.\u201c<\/p>\n\n\n\n<p>Steampunk bzw. das zugrunde liegende Modell Abap Cloud spricht vor allem professionelle Entwicklerinnen und Entwickler an. Mit Abap Cloud k\u00f6nnen Kunden mit den Abap Development Tools f\u00fcr Eclipse im Entwicklungsteam eine neue L\u00f6sung entwickeln und professionelle Debugging-, Refactoring-, Code-Analyse- und Test-Tools nutzen. Neben den SAP-Bestandskunden k\u00f6nnen SAP-Partner Steampunk und Abap Cloud f\u00fcr ihre Add-on-L\u00f6sungen nutzen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2305_E-3_Magazin_Online_Coverstory.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg\" alt=\"\" class=\"wp-image-73569\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>SAP bekommt mit S\/4 nicht nur die Datenbank Hana, sondern auch ein neues Basiskonzept. Es hat lange, f\u00fcr manche SAP-Bestandskunden zu lange, gedauert, bis sich die SAP-Verantwortlichen auf ein Konzept zur Konsolidierung des Z-Namensraums und der zugekauften Applikationen einigten. <\/p>\n","protected":false},"author":2,"featured_media":126656,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[42540,42541],"tags":[453,14545,42543,41850,16983,42082],"coauthors":[27825],"class_list":["post-126508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-23-05","category-mag-23-05","tag-abap","tag-empirius","tag-mag-23-05","tag-sap-basis","tag-sap-daten","tag-steampunk","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-1168x526.jpg",1168,526,true],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final.jpg",1200,540,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-600x540.jpg",600,540,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/shutterstock_1936233259_Kiselev_Andrey_Valerevich-final-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP bekommt mit S\/4 nicht nur die Datenbank Hana, sondern auch ein neues Basiskonzept. Es hat lange, f\u00fcr manche SAP-Bestandskunden zu lange, gedauert, bis sich die SAP-Verantwortlichen auf ein Konzept zur Konsolidierung des Z-Namensraums und der zugekauften Applikationen einigten. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-23-05\/\" rel=\"category tag\">Coverstory 23-05<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-05\/\" rel=\"category tag\">Mag 23-05<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e3mag.com\/de\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/126508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=126508"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/126508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/126656"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=126508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=126508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=126508"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=126508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}