{"id":122007,"date":"2023-04-19T08:00:00","date_gmt":"2023-04-19T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=122007"},"modified":"2023-04-19T09:50:01","modified_gmt":"2023-04-19T07:50:01","slug":"warum-ist-automatisierte-duale-wartung-fuer-sap-unverzichtbar","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/warum-ist-automatisierte-duale-wartung-fuer-sap-unverzichtbar\/","title":{"rendered":"Warum ist automatisierte, duale Wartung f\u00fcr SAP unverzichtbar?"},"content":{"rendered":"\n<p>Gestern bestellt, heute umgesetzt und am liebsten morgen in der Produktion. Je schneller ich meinem Unternehmen durch Innovationen entscheidende Impulse gebe, desto wettbewerbsf\u00e4higer werde ich. Die automatisierte, duale Wartung in SAP ist dabei ein entscheidender Faktor. Sie kommt vor allem bei gro\u00dfen Transformationsprojekten wie einer S\/4-Migration zum Tragen.<\/p>\n\n\n\n<p>Der Umgang mit parallelen SAP-Landschaften, wie sie beispielsweise bei einer S\/4-Migration auftreten, ist schwierig und komplex. Um Gesch\u00e4ftsunterbrechungen zu vermeiden, m\u00fcssen parallele Systeme synchron gehalten werden. Dies erfordert, dass relevante \u00c4nderungen zweimal (oder mehr, je nach Anzahl der Landschaften) in beiden Systemen durchgef\u00fchrt werden, was als \u201edoppelte Wartung\u201c bezeichnet wird. Vereinfacht ausgedr\u00fcckt ist die doppelte Wartung in SAP, auch bekannt als Merge\/Retrofit oder Parallelentwicklung, eine Landschaft mit mehreren Entwicklungssystemen, die in mehrere Produktionsumgebungen integriert sind.&nbsp;<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3181268269\"><div id=\"great-114635878\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>F\u00fcr SAP-Systeme gibt es drei Arten der doppelten Wartung: kontinuierliche Wartung mit einer permanenten Wartungslandschaft und einer Projektlandschaft; duale Wartung f\u00fcr einen bestimmten Zeitraum w\u00e4hrend eines Upgrades oder einer ERP-Implementierung; und duale Wartung \u00fcber einen l\u00e4ngeren Zeitraum w\u00e4hrend einer Brownfield- oder Hybrid-Transformation zu S\/4 Hana.<\/p>\n\n\n\n<p>Normalerweise befinden sich diese Systeme alle auf einer Plattform, wie zum Beispiel ECC, aber es gibt auch Szenarien, in denen sie sich auf verschiedenen Plattformen befinden k\u00f6nnen, wie zum Beispiel bei der Migration von ECC zu S\/4. In diesem Fall m\u00fcssen die Altsysteme w\u00e4hrend der Migration weiterlaufen, wahrscheinlich \u00fcber Jahre hinweg, w\u00e4hrend die neuen S\/4-Systeme aufgebaut werden. Viele langj\u00e4hrige SAP-Anwender wissen nur zu gut, wie frustrierend, riskant, zeit- und ressourcenaufw\u00e4ndig es ist, \u00c4nderungen zwischen Systemen manuell zu verwalten. Warum brauchen Sie eine automatisierte doppelte Wartung in SAP?<\/p>\n\n\n\n<p>Es gibt drei Hauptgr\u00fcnde, warum automatisierte doppelte Wartung f\u00fcr SAP-Unternehmen unerl\u00e4sslich ist. Die manuelle Wartung mehrerer Landschaften ist sehr zeitaufw\u00e4ndig und f\u00fchrt zu Verz\u00f6gerungen bei der Bereitstellung gesch\u00e4ftskritischer \u00c4nderungen. Wenn Unternehmen auf manuelle Methoden zur\u00fcckgreifen, werden sie unter anderem durch die Notwendigkeit von Change Freezes erheblich behindert. Viele Unternehmen haben weder die Zeit noch die Ressourcen, um mehrere Systeme manuell synchron zu halten. Sie sind gezwungen, regelm\u00e4\u00dfige Aktualisierungen zu unterbrechen, bis spezielle Nacharbeiten abgeschlossen sind. Dies ist f\u00fcr die Unternehmen von Nachteil und h\u00e4lt sie davon ab, die von den Fachabteilungen geforderten \u00c4nderungen vorzunehmen.<\/p>\n\n\n\n<p>Umstellungsprobleme, die h\u00e4ufig durch eine unzuverl\u00e4ssige und nicht automatisierte Synchronisierung der Bereitstellung verursacht werden, sollten ebenfalls vermieden werden. Wenn Ihr Unternehmen mit einer neuen Konfiguration oder verschiedenen benutzerdefinierten L\u00f6sungen gearbeitet hat, kann es bei der Umstellung auf das neue System zu Problemen kommen, wenn diese Transporte nicht synchronisiert sind.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus kann eine fehlende Synchronisierung zu Verz\u00f6gerungen bei Projekten f\u00fchren, w\u00e4hrend diese identifiziert und behoben werden. Im Extremfall, wenn zu viele \u00c4nderungen \u00fcbersehen wurden, kann der Neustart des Entwicklungssystems eine Neuausrichtung des Projekts erforderlich machen. Dies muss zus\u00e4tzlich vermieden werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Automatisierung als Befreiungsschlag<\/h3>\n\n\n\n<p>Die Automatisierung der doppelten Wartung ist ein wesentlicher Vorteil. Sie tr\u00e4gt dazu bei, Risiken, Projektverz\u00f6gerungen und erh\u00f6hte Kosten zu vermeiden, insbesondere bei gr\u00f6\u00dferen Projekten wie der Migration auf S\/4 Hana. Automatisierte doppelte Wartung ist daher unverzichtbar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/basis_technologies\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu.jpg\" alt=\"Basis Technologies \" class=\"wp-image-126123\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-400x45.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-960x108.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/04\/2023-04-ci-banner-basis-neu-600x67.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dass ich Innovationen im Unternehmen umsetze, ist keine Frage. Es geht vielmehr um den Zeitpunkt der Umsetzung. Der Druck auf die SAP-Teams, die Anforderungen der Fachbereiche m\u00f6glichst schnell umzusetzen, ist enorm.<\/p>\n","protected":false},"author":2046,"featured_media":50414,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[24421,42179],"tags":[145,451,8443,517,40844],"coauthors":[37545],"class_list":["post-122007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-devops-kolumne","category-mag-23-03","tag-automatisierung","tag-devops","tag-kolumne","tag-s4","tag-s-4-transformation-2","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2018\/07\/DevOps-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Dass ich Innovationen im Unternehmen umsetze, ist keine Frage. Es geht vielmehr um den Zeitpunkt der Umsetzung. Der Druck auf die SAP-Teams, die Anforderungen der Fachbereiche m\u00f6glichst schnell umzusetzen, ist enorm.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/devops-kolumne\/\" rel=\"category tag\">DevOps Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-23-03\/\" rel=\"category tag\">Mag 23-03<\/a>","author_info_v2":{"name":"David Lees, Basis Technologies","url":"https:\/\/e3mag.com\/de\/author\/david-lees\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/122007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2046"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=122007"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/122007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/50414"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=122007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=122007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=122007"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=122007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}