{"id":120890,"date":"2023-01-27T08:00:00","date_gmt":"2023-01-27T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=120890"},"modified":"2024-01-19T12:47:37","modified_gmt":"2024-01-19T11:47:37","slug":"composable-und-hybrid","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/composable-und-hybrid\/","title":{"rendered":"Composable und hybrid"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Wie die S\/4-Migration zum Erfolg wird<\/h2>\n\n\n\n<p>Der Support f\u00fcr die SAP Business Suite endet bereits im Jahr 2027 und alle Optionen, f\u00fcr eine erweiterte Wartung zus\u00e4tzlich zu bezahlen, laufen im Jahr 2030 aus. Angesichts der Komplexit\u00e4t der Migration sind diese Fristen knapp. Zieht man dazu den Fachkr\u00e4ftemangel in Betracht, wird klar, dass ein Abwarten von Entscheidungen eine \u00e4u\u00dferst riskante Strategie ist.<\/p>\n\n\n\n<p>Die Schaffung eines neuen gesch\u00e4ftlichen Vorteils, man k\u00f6nnte es auch Business Transformation nennen, erfordert aber etwas mehr. Denn wenn man nur modernisiert, ist dies \u00e4quivalent zur Wartung. Folgende zwei Best Practices zeigen strategische Vorteile auf, die sich aus der S\/4-Hana-Migration ergeben: Composable ERP und Cloud-Migration\/Hybrid-IT. Neue Services von Fujitsu helfen, eine schnelle und zuverl\u00e4ssige Nutzung dieser Vorteile aufzuzeigen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3621776465\"><div id=\"great-1034151361\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=iFPzKOVI4rg\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26_07_22_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_07_22_1200x150-1-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Composable ERP<\/h3>\n\n\n\n<p>Ein strategischer Vorteil der Migration ist die M\u00f6glichkeit, ein Unternehmen so zu vernetzen, dass es adaptiver wird. Nach einer Analyse von Gartner haben viele Hersteller mehrere Systeme im Einsatz \u2013 SAP, Salesforce, Oracle, ServiceNow, AWS und Microsoft. Der Begriff Composable ERP beschreibt diesen Trend. Composable ERP setzt die jeweils gew\u00fcnschten Komponenten ein, um einen Mehrwert zu schaffen \u2013 und zwar durch Mischung und Anpassung verschiedener Anbieter. Die S\/4-Migration ist der perfekte Zeitpunkt, um zu pr\u00fcfen, wie die Dateninfrastruktur modernisiert werden kann, um eine Art \u201eControl Tower\u201c-Umgebung zu schaffen. Dank dieser werden vollst\u00e4ndig vernetzte Echtzeitdaten generiert, die einen ganzheitlichen \u00dcberblick \u00fcber das Unternehmen in allen vor- und nachgelagerten Lieferketten bieten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Migration und Hybrid Cloud<\/h3>\n\n\n\n<p>Ein Faktor, der S\/4 noch anschlussf\u00e4higer macht, ist die Tatsache, dass es die erste Version des ERP ist, die wirklich Cloud-nativ ist. Diese Eigenschaft er\u00f6ffnet alle Vorteile der Cloud-Migration und die ultimative Flexibilit\u00e4t bei der Platzierung von SAP-Workloads. Die S\/4-Migration muss daher die Nutzung aller strategischen Vorteile der hybriden Cloud-Umgebungen erm\u00f6glichen.<\/p>\n\n\n\n<p>Workloads in hybriden Umgebungen sind jedoch sehr komplex. Der Workload-Bedarf kann sich \u00fcber eine Vielzahl von Umgebungen erstrecken, darunter mehrere Standorte vor Ort sowie Cloud-Partner mit ihren jeweiligen regionalen Knotenpunkten. Die Optimierung der SAP-Infrastruktur in diesen Umgebungen erfordert ein hohes Ma\u00df an Verst\u00e4ndnis.\u00a0<\/p>\n\n\n\n<p>Um dabei zu unterst\u00fctzen, bietet Fujitsu einen neuen Hybrid Cloud Assessment Service f\u00fcr SAP-L\u00f6sungen an, der Millionen von m\u00f6glichen Platzierungsoptionen auf der Grundlage gemessener Arbeitslasten analysiert. Fujitsu BestPlace bietet einen einzigartigen datengesteuerten Ansatz, der die gemessene SAP-IT als DNA kodiert und eine Mini-Evolution mit genetischen Algorithmen simuliert. Dem Prinzip \u201eSurvival of the Fittest\u201c folgend, f\u00fchrt der Prozess zu einem optimalen Design f\u00fcr eine hybride Infrastruktur.&nbsp;<\/p>\n\n\n\n<p>Dabei handelt es sich um einen individualisierten Ansatz, der auf die spezifischen Bed\u00fcrfnisse jedes Kunden eingeht, anstatt einem generischen Modell zu folgen. Der Algorithmus misst den SAP-Betrieb vor Ort \u00fcber einen Zeitraum von etwa vier Wochen, vergleicht alle verschiedenen Platzierungsoptionen mit der IT-Strategie des Kunden und den Gesch\u00e4ftsfachleuten und liefert einen Kostenvergleich f\u00fcr alle gemessenen SAP-Instanz-Workloads in der Cloud oder vor Ort. Um neutrale Ergebnisse zu gew\u00e4hrleisten, wurde dieser Algorithmus extern entwickelt.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"524\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800.jpg\" alt=\"Rohan de Souza, Fujitsu\" class=\"wp-image-120897\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800-400x262.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800-768x503.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800-100x66.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800-480x314.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800-640x419.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/Rohan_de_souza_fujitsu_800-720x472.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:15px\">Auf dem NetApp-Summit im September dieses Jahres in Wien war <strong>Rohan de Souza,<\/strong> Head of SAP Business, European Platform Business at Fujitsu, ein Gastsprecher zum Thema S\/4 Hana, Digitalisierung, Conversion und Datenmanagement. Der Weg in die Cloud kann f\u00fcr SAP-Bestandskunden Vorteile, aber auch viele Herausforderungen mit sich bringen, sodass Unterst\u00fctzung von Partnern gefragt ist. Der NetApp-Summit in Wien wurde gestaltet von Fujitsu, Amazon, Cisco und Red Hat.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Wertsch\u00f6pfung mit Rightsizing<\/h3>\n\n\n\n<p>Effektives ERP sollte Unternehmen in die Lage versetzen, schnell auf Erkenntnisse zuzugreifen, schnelle Entscheidungen zu treffen und den Wert einer Neuausrichtung so schnell wie m\u00f6glich auszusch\u00f6pfen. Typische Beschwerden von Anwendern richten sich an mangelnde Geschwindigkeit und Betriebsfehler. Um hier die Platzierung von Workloads zu optimieren, m\u00fcssen auch die Dimensionierung, Bereitstellung und Wartung der Infrastruktur bewertet werden. SAP-Leistungs- und Service-Level-Probleme k\u00f6nnen mehrere Ursachen haben, und die optimale Konfiguration zu finden war schon immer eine Herausforderung. Ein g\u00e4ngiger Ansatz, um eine L\u00f6sung zu erzwingen: der Kauf und die Installation von mehr Infrastruktur, unabh\u00e4ngig davon, ob damit die eigentliche Ursache behoben wird. Dies ist jedoch eine teure L\u00f6sung.<\/p>\n\n\n\n<p>Wer jetzt migriert, kann davon profitieren, SAP-Implementierungen zu optimieren. Mit neuen L\u00f6sungen k\u00f6nnen reale Daten aus Ihrer Landschaft verwendet werden und so eine datengest\u00fctzte Entscheidungshilfe f\u00fcr jede Migration oder Hardware-Aktualisierung geschaffen werden. Solche Analyse- und Beratungspakete setzen sich mit all diesen Parametern auseinander und vermeiden sp\u00e4tere Mehrausgaben.<\/p>\n\n\n\n<p>L\u00f6sungen wie der Fujitsu-System-Inspection-Service geben klare Empfehlungen zur Verbesserung der On-premises- oder Cloud-IT f\u00fcr SAP-Landschaften, indem Engp\u00e4sse, Leistungsanomalien und realistische Kapazit\u00e4tsanforderungen identifiziert werden. Durch das Rightsizing des neuen S\/4 f\u00fcr On-premises verringert sich die Kostenl\u00fccke zwischen On-premises und Cloud, da Anwender nicht so viel \u00fcbersch\u00fcssige Kapazit\u00e4t kaufen m\u00fcssen, die meist ungenutzt bleibt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Verbrauchsabh\u00e4ngige Preisgestaltung<\/h3>\n\n\n\n<p>Hinsichtlich der Infrastrukturoptionen erm\u00f6glicht Fujitsu Primeflex for SAP Hana das volle Potenzial von Hana-In-memory-Computing. Es handelt sich um eine vorgetestete Infrastrukturl\u00f6sung, die zu 100 Prozent von SAP zertifiziert und f\u00fcr die In-memory-Architektur entwickelt wurde. Sie sch\u00f6pft die vollen M\u00f6glichkeiten des Speichers ohne Bereitstellungs- und Konfigurationsrisiken aus und vereinfacht Betrieb und Wartung mit einem Servicepartner f\u00fcr den gesamten L\u00f6sungsstapel, mit Verf\u00fcgbarkeit as a Service \u00fcber Fujitsu uScale.<\/p>\n\n\n\n<p>Mit As-a-Service-Modellen k\u00f6nnen Unternehmen ihre Infrastruktur auf den neuesten Stand bringen und an sich st\u00e4ndig \u00e4ndernde Anforderungen anpassen. Das vereinfacht den Umgang mit Technologien, erh\u00f6ht die Agilit\u00e4t und senkt die Kosten. Fujitsu uScale bietet eine flexible On-premises-IT-Infrastruktur-as-a-Service-L\u00f6sung, die auf der tats\u00e4chlichen Nutzung basiert, unterst\u00fctzt die Ausfallsicherheit des Unternehmens, erh\u00f6ht die finanzielle und technische Flexibilit\u00e4t. uScale ist auch ideal f\u00fcr Cloud-Transformationsprojekte von SAP-Umgebungen. Resultierend aus der Partnerschaft zwischen Fujitsu und Equinix wird eine komplette Hybrid-Cloud-Konnektivit\u00e4tsl\u00f6sung angeboten, einschlie\u00dflich des Zugangs zu globalen Business-\u00d6kosystemen auf der Equinix-Plattform. Dazu geh\u00f6rt auch die Erstberatung zur Identifizierung des optimalen hybriden Ansatzes, um die SAP-getriebene digitale Transformation zu unterst\u00fctzen und umzusetzen.<\/p>\n\n\n\n<p>Gemeinsam arbeiten Fujitsu und Equinix daran, innovative, differenzierte L\u00f6sungen f\u00fcr den Einsatz in verschiedenen Branchen zu entwickeln. So wird beispielsweise eine Hyperscaler-\u00e4hnliche Umgebung mit dieser M\u00f6glichkeit erstellt, die neben dem Hyperscaler positioniert ist und eine direkte Verbindung zu all Ihren Daten und Anwendungen in der Cloud herstellt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/e3mag.com\/partners\/fujitsu\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU.jpg\" alt=\"https:\/\/e3mag.com\/partners\/fujitsu\/\" class=\"wp-image-11366\" width=\"840\" height=\"94\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-FUJITSU-960x108.jpg 960w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Erst vierzehn Prozent der SAP-Anwender sind in der Cloud \u2013 das schleppende Tempo der Umstellung auf S\/4 ist beunruhigend. Das Z\u00f6gern der SAP-Entscheidungstr\u00e4ger l\u00e4sst vermuten, dass die Vorteile der Migration nicht deutlich sind \u2013 hier muss die Anwendungsmodernisierung den Mehrwert bieten.<\/p>\n","protected":false},"author":2701,"featured_media":120891,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"0","footnotes":""},"categories":[4,42009],"tags":[42055,73,13308,5008,42010,517,3936],"coauthors":[42056],"class_list":["post-120890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-22-12","tag-composable-erp","tag-erp","tag-hybrid","tag-hybrid-cloud","tag-mag-22-12","tag-s4","tag-s4-migration","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-1168x526.jpg",1168,526,true],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",1200,540,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/01\/shutterstock_507145807_GroundPicture-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Erst vierzehn Prozent der SAP-Anwender sind in der Cloud \u2013 das schleppende Tempo der Umstellung auf S\/4 ist beunruhigend. Das Z\u00f6gern der SAP-Entscheidungstr\u00e4ger l\u00e4sst vermuten, dass die Vorteile der Migration nicht deutlich sind \u2013 hier muss die Anwendungsmodernisierung den Mehrwert bieten.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/management\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-22-12\/\" rel=\"category tag\">Mag 22-12<\/a>","author_info_v2":{"name":"Rohan de Souza, Fujitsu","url":"https:\/\/e3mag.com\/de\/author\/rohandesouza\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/120890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2701"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=120890"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/120890\/revisions"}],"predecessor-version":[{"id":137646,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/120890\/revisions\/137646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/120891"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=120890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=120890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=120890"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=120890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}