{"id":119186,"date":"2022-11-14T10:00:00","date_gmt":"2022-11-14T09:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=119186"},"modified":"2024-01-19T15:14:46","modified_gmt":"2024-01-19T14:14:46","slug":"fusionen-uebernahmen-partnerschaften-im-oktober","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/fusionen-uebernahmen-partnerschaften-im-oktober\/","title":{"rendered":"Fusionen, \u00dcbernahmen, Partnerschaften im Oktober 2022"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"boro-milivojevic-neu-bei-devoteam-a-cloud\">Sprung in die Digitalisierung<\/h3>\n\n\n\n<p><strong>Den Kundennutzen im Blick: Pit-Cup und Ceyoniq geben den Ausbau ihrer langj\u00e4hrigen Partnerschaft bekannt.<\/strong><\/p>\n\n\n\n<p>K\u00fcnftig werden die L\u00f6sung f\u00fcr das digitale Informationsmanagement von Ceyoniq, nscale, und pitFM, das System f\u00fcr Computer-Aided Facility Management (CAFM), noch enger verkn\u00fcpft werden. Bereits seit mehreren Jahren setzt Pit-Cup auf das Informations- und Dokumentenmanagementsystem nscale. Nun wurde ein gemeinsames L\u00f6sungskonzept ausgearbeitet, um die Produkte und L\u00f6sungen beider Unternehmen zuk\u00fcnftig besser zu verzahnen. Zielsetzung ist ein optimiertes Produkt f\u00fcr die Anwender. Die bestehende Schnittstelle zwischen beiden Systemen soll in Zukunft zu einem durchg\u00e4ngigen Prozess ohne Medienbr\u00fcche im \u00d6kosystem von Pit-Cup ausgebaut werden. <\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1988535928\"><div id=\"great-3690946490\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Das spart Zeit, schont die Budgets und sorgt f\u00fcr Datensicherheit. \u201ePartnerschaften sind f\u00fcr uns ein wesentlicher und elementarer Baustein, um einen Beitrag f\u00fcr die Digitalisierung in der \u00f6ffentlichen Verwaltung sowie in Unternehmen leisten zu k\u00f6nnen. Allerdings ist die blanke Technologie daf\u00fcr nicht immer ausreichend. Vielmehr ist die entsprechende Branchenkompetenz von immer gr\u00f6\u00dferer Bedeutung. Man muss die Sprache des Kunden verstehen und selbst sprechen k\u00f6nnen. Daher freuen wir uns, einen Partner mit manifestierten Branchenkenntnissen an unserer Seite zu haben\u201c, so Christian Hanisch, Abteilungsleiter Business Development bei Ceyoniq.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"639\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH.jpg\" alt=\"Christian Hanisch, Ceyonic\" class=\"wp-image-119188\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH-768x613.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH-100x80.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH-480x383.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH-640x511.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Christian-Hanisch-Abteilungsleiter-Business-Development-der-Ceyoniq-Technology-GmbH-720x575.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n\n\n\n\n<p style=\"font-size:15px\">&#8220;<em>Partnerschaften sind f\u00fcr uns ein wesentlicher Baustein, um einen Beitrag f\u00fcr die Digitalisierung in der \u00f6ffentlichen Verwaltung zu leisten.<\/em>&#8220;<\/p>\n\n\n\n<p style=\"font-size:15px\">Christian Hanisch, Abteilungsleiter Business Development, Ceyoniq<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"wechsel-der-geschaftsfuhrung-bei-ntt-ltd\">Neue Archivierungskonzepte<\/h3>\n\n\n\n<p><strong>Um auf die dynamische Marktlage effizienter reagieren zu k\u00f6nnen, b\u00fcndeln AFI Solutions und KGS Software ihre Kompetenzen.<\/strong><\/p>\n\n\n\n<p>Ziel der Partnerschaft ist es, den Kommunikations- und Abstimmungsprozess im Kundenkontakt zu verk\u00fcrzen, um so schneller punktgenaue L\u00f6sungen f\u00fcr die Aufgabenstellungen der Kunden anbieten zu k\u00f6nnen. Winfried Althaus, Gesch\u00e4ftsf\u00fchrer von KGS Software, kommentiert: \u201eDurch die Kombination unserer L\u00f6sungen und Expertise maximieren wir die Mehrwerte f\u00fcr unsere gemeinsamen Kunden. Geschwindigkeit wird heute immer mehr zum kritischen Erfolgsfaktor. <\/p>\n\n\n\n<p>Da m\u00f6chten wir zusammen mit AFI Solutions alles Erforderliche leisten, damit die Unternehmen schnellstm\u00f6glich vom Einsatz unserer L\u00f6sungen profitieren.\u201c Damit werden die beiden Unternehmen der Anforderung derjenigen Kunden gerecht, die unter den immer komplexer werdenden Anforderungen der M\u00e4rkte stehen.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs.jpg\" alt=\"Wilfried Althaus, KGS Software\" class=\"wp-image-119189\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs-768x576.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs-100x75.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs-480x360.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs-640x480.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Winfried-Althaus_kgs-720x540.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:15px\">&#8220;<em>Geschwindigkeit wird heute immer mehr zum kritischen Erfolgsfaktor.<\/em>&#8220;<\/p>\n\n\n\n<p style=\"font-size:15px\">Winfried Althaus, Gesch\u00e4ftsf\u00fchrer, KGS Software<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"der-zukunft-einen-schritt-voraus\">xSuite setzt Wachstumskurs mit neuem Anteilseigner fort<\/h3>\n\n\n\n<p><strong>xSuite hat einen neuen Investor f\u00fcr sich gewinnen k\u00f6nnen.<\/strong><\/p>\n\n\n\n<p>Neu an Bord ist die 3i Group (3i), ein internationaler Investmentmanager, der mittelst\u00e4ndische Unternehmen bei der Internationalisierung und Erschlie\u00dfung neuer M\u00e4rkte unterst\u00fctzt. Parallel reinvestieren die bisherigen Eigent\u00fcmer als Minderheitsgesellschafter in das Unternehmen. Bei ihnen handelt es sich um Fonds, die von Pinova beraten werden, sowie das Management-Team von xSuite. Das Unternehmen hat einen wachsenden Kundenstamm von mehr als 1200 Unternehmen in \u00fcber 60 L\u00e4ndern. Die Investition von 3i erm\u00f6glicht es xSuite, den geplanten nordamerikanischen Wachstumskurs noch schneller umzusetzen und eine f\u00fchrende Rolle in den USA einzunehmen. <\/p>\n\n\n\n<p>Durch den Einstieg von 3i ergeben sich auf Gesch\u00e4ftsf\u00fchrungsebene keine Ver\u00e4nderungen. Matthias Lemenk\u00fchler, Richard Nagorny, Andreas Nowottka und Thomas Radestock werden xSuite weiterhin wie gewohnt leiten. Um den bisherigen Wachstumskurs fortzusetzen, sucht xSuite derzeit verst\u00e4rkt neue Besch\u00e4ftigte f\u00fcr verschiedene Gesch\u00e4ftsbereiche und wird dabei k\u00fcnftig ebenfalls von 3i unterst\u00fctzt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"514\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka.jpg\" alt=\"xsuite\" class=\"wp-image-119190\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka-768x493.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka-100x64.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka-480x308.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka-640x411.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Michael-Specht-Matthias-Lemenkuehler-xSuite-Ulf-von-Haacke-Richard-Nagorny-xSuite-Thomas-Radestock-Andreas-Nowottka-720x463.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><em>V. l.: Michael Specht (3i), Matthias Lemenk\u00fchler (xSuite), Ulf von Haacke (3i), Richard Nagorny (xSuite), Thomas Radestock (xSuite), Andreas Nowottka (xSuite). Quelle: xSuite.<\/em><\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Transformationsexpertise ausbauen<\/h3>\n\n\n\n<p><strong>NTT Data Business Solutions \u00fcbernimmt die Mehrheit des digitalen Umzugsunternehmens Natuvion.<\/strong><\/p>\n\n\n\n<p>Natuvion wurde 2014 in Walldorf gegr\u00fcndet und expandierte in den Folgejahren international. Natuvion wird k\u00fcnftig weiterhin als eigenst\u00e4ndige Marke auftreten und Unternehmen automatisiert durch selbstentwickelte Software-Tools beim Umzug gesch\u00e4ftskritischer Daten und Prozesse auf moderne IT-Plattformen und -Systeme unterst\u00fctzen. Zu den typischen Natuvion-Umzugsleistungen geh\u00f6ren Datenmigration, -transformation und -integration sowie Datenqualit\u00e4tssteigerung, -stilllegung und Datenschutz. Beide Unternehmen arbeiten bereits seit mehreren Jahren partnerschaftlich zusammen. <\/p>\n\n\n\n<p>Seit 2020 b\u00fcndeln sie Wissen und Know-how, um anspruchsvolle S\/4-Transformationsprojekte umzusetzen. \u201eMit der mehrheitlichen Beteiligung an Natuvion vertiefen wir die erfolgreiche Zusammenarbeit unserer Unternehmen und bauen unsere Marktposition im Bereich Cloud-Migration weltweit st\u00e4rker aus\u201c, so Norbert Rotter, CEO von NTT Data Business Solutions. \u201eInsbesondere die Produkte von Natuvion rund um das Thema Datentransformation und das Branchen-Know-how, vor allem im Versorgungssektor, er\u00f6ffnen uns gemeinsam neue Wachstumspotenziale.\u201c&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"547\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2.jpg\" alt=\"Norbert Rotter, NTT Data Business Solutions\" class=\"wp-image-119191\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2-768x525.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2-100x68.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2-480x328.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2-640x438.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/10\/Rotter_Itelligence2-720x492.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:15px\">&#8220;<em>Insbesondere die Produkte von Natuvion rund um das Thema Datentransformation er\u00f6ffnen uns gemeinsam neue Wachstumspotenziale.<\/em>&#8220;<\/p>\n\n\n\n<p style=\"font-size:15px\">Norbert Rotter, CEO, NTT Data Business Solutions<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">msg \u00fcbernimmt BTPAG<\/h3>\n\n\n\n<p>Das IT- und Beratungsunternehmen msg \u00fcbernimmt die baeriswyl tschanz &amp; partner ag (BTPAG) mit Sitz in Ittigen\/Bern. Die Unternehmensgruppe treibt so ihre Internationalisierung sowie die weitere Entwicklung auf dem Schweizer Markt voran und sichert langfristig die rund 40 Arbeitspl\u00e4tze von BTPAG. msg ist bereits mit Gruppenmitgliedern wie unter anderem msg systems, Finnova und Optravis in der Schweiz vertreten. Das vorhandene Gesch\u00e4ft mit dem Public Sector \u00fcbertr\u00e4gt das Unternehmen dort an die BTPAG, um die Kr\u00e4fte im Schweizer Markt zu b\u00fcndeln. <\/p>\n\n\n\n<p>BTPAG bleibt als eigenst\u00e4ndiges Unternehmen am Markt bestehen und erh\u00e4lt durch den Verkauf des Aktienpakets an msg als internationaler Partner gro\u00dfes Wachstumspotenzial. Oskar Zodel, CEO von msg Schweiz, \u00fcbernimmt k\u00fcnftig das Verwaltungsratspr\u00e4sidium von BTPAG. Bernhard Emch und Remo Tschanz bekleiden weiterhin die \u00c4mter als Verwaltungsr\u00e4te. Operativ wird das Unternehmen wie bisher durch Remo Tschanz als CEO gef\u00fchrt. Die gesamte Gesch\u00e4ftsleitung bleibt unver\u00e4ndert.<\/p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Sprung in die Digitalisierung Den Kundennutzen im Blick: Pit-Cup und Ceyoniq geben den Ausbau ihrer langj\u00e4hrigen Partnerschaft bekannt. K\u00fcnftig werden die L\u00f6sung f\u00fcr das digitale Informationsmanagement von Ceyoniq, nscale, und pitFM, das System f\u00fcr Computer-Aided Facility Management (CAFM), noch enger verkn\u00fcpft werden. Bereits seit mehreren Jahren setzt Pit-Cup auf das Informations- und Dokumentenmanagementsystem nscale. Nun [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":135508,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[41842,6],"tags":[40675,39891,40645,41871,13577,39850,11237,40074],"coauthors":[19920],"class_list":["post-119186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-22-10","category-wirtschaft","tag-ceyonic","tag-fusionen","tag-kgs-software","tag-mag-22-10","tag-msg-group","tag-ntt-data-business-solutions","tag-xsuite","tag-zuora","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2023\/11\/Fusionen-Uebernahmen-Partnerschaften-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Den Kundennutzen im Blick: Pit-Cup und Ceyoniq geben den Ausbau ihrer langj\u00e4hrigen Partnerschaft bekannt. K\u00fcnftig werden die L\u00f6sung f\u00fcr das digitale Informationsmanagement von Ceyoniq, nscale, und pitFM, das System f\u00fcr Computer-Aided Facility Management (CAFM), noch enger verkn\u00fcpft werden. Bereits seit mehreren Jahren setzt Pit-Cup auf das Informations- und Dokumentenmanagementsystem nscale. Nun wurde ein gemeinsames L\u00f6sungskonzept ausgearbeitet, um die Produkte und L\u00f6sungen beider Unternehmen zuk\u00fcnftig besser zu verzahnen. Zielsetzung ist ein optimiertes Produkt f\u00fcr die Anwender. Die bestehende Schnittstelle zwischen beiden Systemen soll in Zukunft zu einem durchg\u00e4ngigen Prozess ohne Medienbr\u00fcche im \u00d6kosystem von Pit-Cup ausgebaut werden. Das spart Zeit, schont&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/mag-22-10\/\" rel=\"category tag\">Mag 22-10<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/wirtschaft\/\" rel=\"category tag\">Wirtschaft<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3mag.com\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/119186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=119186"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/119186\/revisions"}],"predecessor-version":[{"id":137518,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/119186\/revisions\/137518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/135508"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=119186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=119186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=119186"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=119186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}