{"id":118716,"date":"2022-09-28T14:05:44","date_gmt":"2022-09-28T12:05:44","guid":{"rendered":"http:\/\/e3mag.com\/?p=118716"},"modified":"2024-01-19T12:56:54","modified_gmt":"2024-01-19T11:56:54","slug":"datenaustausch-und-smarte-zusammenarbeit-zwischen-supply-chain-partnern","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/datenaustausch-und-smarte-zusammenarbeit-zwischen-supply-chain-partnern\/","title":{"rendered":"Datenaustausch und smarte Zusammenarbeit zwischen Supply-Chain-Partnern"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Supply Chain<\/h2>\n\n\n\n<p>Es gilt, alle Prozessteilnehmer im Systemverbund zu integrieren. Der Weg vom Transportmanagement zur aktiven Transportsteuerung ist somit keine graue Theorie mehr, sondern l\u00e4ngst Realit\u00e4t, die sich mit einer integrativen Plattforml\u00f6sung abbilden l\u00e4sst.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ver\u00e4nderte Rahmenbedingungen am Transportmarkt<\/h3>\n\n\n\n<p>Nie war der Bedarf an intelligenten, einfach zu bedienenden TMS gr\u00f6\u00dfer, denn der Transportmarkt hat sich gewandelt und kaum eine logistische Disziplin ist so arbeitsteilig wie die Transportlogistik. Frachtraum ist knapp und Spediteure k\u00f6nnen sich aussuchen, mit wem sie zusammenarbeiten. Das f\u00fchrt dazu, dass Unternehmen heute ein Erlebnis schaffen m\u00fcssen, damit Spediteure gerne f\u00fcr sie fahren.&nbsp;<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3973130325\"><div id=\"great-2630655134\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Prozesse wie die Auslieferung von Kundenbestellungen sollten aktiv gesteuert werden. Eine ganzheitliche Informationsversorgung ist f\u00fcr eine gute Zusammenarbeit und einen zufriedenstellenden Kundenservice unerl\u00e4sslich. Dazu geh\u00f6rt heute auch die digitale Transportbeauftragung. J\u00fcngere Anwendergenerationen fordern heute intuitive Apps, die mit minimalem Aufwand integriert werden k\u00f6nnen. Dabei gilt es, die Spediteure zu entlasten und deren Schnittstellen zu nutzen. Gleichzeitig sind interne IT-Ressourcen zu schonen, denn diese sind derzeit mit der SAP-S\/4HANA-Transformation besch\u00e4ftigt. Dementsprechend sind die Anforderungen an Software-Anbieter gestiegen \u2013 sie m\u00fcssen heute SAP-Systeme out of the box anbinden, Software parametrisieren sowie externe Prozesspartner integrieren, um ihren Kunden Mehrwerte zu bieten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Der Knackpunkt: die Anbindung von Partnern<\/h3>\n\n\n\n<p>L\u00f6sen lassen sich diese Aufgaben in Form einer Process-as-a-Service-Plattform mit einem nutzerzentrischen Ansatz wie der myleo \/ dsc von leogistics. Alle Nutzer:innen, also auch die der Spediteure und Lieferanten, m\u00fcssen mit der Plattform arbeiten k\u00f6nnen. Doch viele SaaS-L\u00f6sungen am Markt betrachten nur Teilbereiche der Transportlogistik und schaffen mehr Barrieren, als sie abbauen: Wir haben festgestellt, dass Spediteure die Schnittstellen der SaaS-Anbieter bedienen m\u00fcssen oder verschiedene Daten\u00fcbertragungswege (API, EDI, FTP etc.) nicht bedienen k\u00f6nnen. Gleichzeitig haben Verlader meist keine freien Kapazit\u00e4ten, um die Anbindung der Spediteure IT-technisch zu unterst\u00fctzen.&nbsp;<\/p>\n\n\n\n<p>Im Bereich Real-Time Transportation Visibility (RTTV) wird vollumf\u00e4nglich auf Telematikdaten gesetzt. Doch was bringt die beste Datenbasis, wenn diese nicht in den Prozess integriert ist und genutzt wird? Aus unserer Sicht schafft vor allem die Kombination aus Statusmeldungen via Schnittstelle, Telematik und proaktiven Meldungen einen Vorteil f\u00fcr die Prozessstabilit\u00e4t und erm\u00f6glicht eine effiziente Zusammenarbeit.<\/p>\n\n\n\n<p>Ein pragmatischer Ansatz hierf\u00fcr ist unser \u201eConnectivity on Demand\u201c-Service: also die Schnittstellen der Spediteure ma\u00dfgeschneidert, zum Beispiel per API, EDI oder FTP, anzubinden. Sollte keine technische M\u00f6glichkeit zum Datenaustausch zwischen Supply-Chain-Partnern bestehen, kann ein Web-Portal Abhilfe schaffen. Der gro\u00dfe Vorteil dabei ist, dass Spediteuren durch den elektronischen Datenaustausch (f\u00fcr welchen sie nichts \u00e4ndern m\u00fcssen) Mehrarbeit in Form von Telefonaten, Fax abgenommen wird.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"338\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01.jpg\" alt=\"\" class=\"wp-image-118718\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01-768x324.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01-100x42.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01-480x203.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01-640x270.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_01-720x304.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em>Beispielhafte Integration von Spediteuren mit der myleo \/ dsc von leogistics.<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Zukunftsf\u00e4hige Architekturmodelle im SAP-Kontext<\/h3>\n\n\n\n<p>Mit unserem Plattform-as-a-Service-Ansatz bieten wir verschiedene Nutzungsoptionen im Systemverbund. Dabei sollte es stets das Ziel sein, kollaborative Prozesse so einfach wie m\u00f6glich abzubilden sowie vor- und nachgelagerte Systeme optimal einzubinden. So schafft die myleo \/ dsc es, logistische Objekte mit Prozess- und Gesch\u00e4ftsdaten zu kombinieren und ein H\u00f6chstma\u00df an Transparenz in der Supply Chain herzustellen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"431\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02.jpg\" alt=\"\" class=\"wp-image-118719\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02-768x414.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02-100x54.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02-480x259.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02-640x345.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/220826_myleo_print_LBN_02-720x388.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em>Derzeit vielfach von Verladern nachgefragtes Szenario f\u00fcr einen Systemverbund.<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Option 1: SAP LE-TRA und SAP S\/4HANA TM Basic + myleo \/ dsc<\/h3>\n\n\n\n<p>Diese Variante eignet sich f\u00fcr Unternehmen, welche derzeit das SAP LE-TRA nutzen, bereits auf SAP S\/4HANA Basic Transportation Management umgestellt haben oder sich in der Transformation befinden und bereits jetzt erste Mehrwerte generieren m\u00f6chten. Das Szenario fokussiert sich auf eine schnelle Integration der SAP-Belege mittels vordefinierten Contents.<\/p>\n\n\n\n<p>Die Transporterstellung bzw. B\u00fcndelung und die Auswahl des Frachtf\u00fchrers finden in diesem Szenario noch im SAP-System statt. Die Beauftragung erfolgt jedoch via API, EDI, FTP oder Web-UI in der myleo \/ dsc. Die Anbindung der Spediteure \u00fcbernimmt unser Onboarding-Team. Der Spediteur kann den Auftrag annehmen oder ablehnen, ein Zeitfenster buchen sowie bei Bedarf auch RTTV-Daten \u00fcbermitteln, um den Zulauf f\u00fcr das Yard oder Warehouse Management System transparent zu gestalten.<\/p>\n\n\n\n<p>Nach erfolgreicher Abfertigung wird auch die Belieferung des Warenempf\u00e4ngers bis zum Proof of Delivery (PoD) getrackt und abgewickelt. Daraus resultierende Prozesse wie das Kl\u00e4rungsfallmanagement in der Frachtkostenabrechnung oder das Beh\u00e4ltermanagement finden hochintegrativ in Kombination zwischen SAP-System und myleo \/ dsc sowie dem Spediteur statt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Option 2: SAP S\/4HANA TM Advanced + myleo \/ dsc<\/h3>\n\n\n\n<p>Diese Option ist perfekt f\u00fcr Verlader, die SAP S\/4HANA TM im Einsatz haben oder einf\u00fchren m\u00f6chten. Auch hier wird der SAP-Frachtauftrag schnell und einfach integriert. Die Transportplanung kann auf-seiten SAP stark optimiert, der Laderaum optimal berechnet und der Frachtf\u00fchrer auf Basis verschiedener Kriterien ausgew\u00e4hlt werden. Die Beauftragung erfolgt wiederum mittels API, EDI, FTP oder Web-UI auf unserer Prozessplattform. Der weitere Prozess verh\u00e4lt sich analog zu Option 1.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Option 3: SAP Core + myleo \/ dsc<\/h3>\n\n\n\n<p>Diese Option richtet sich an Unternehmen, die keine Transportkomponente der SAP im Einsatz haben oder einf\u00fchren m\u00f6chten. Auch in diesem Szenario werden SAP-Belege wie Bestellung, Kundenauftrag oder Lieferung integriert. Auf Basis der Informationen des Vorsystems kann bereits heute in der myleo \/ dsc eine Transportb\u00fcndelung und Transportbeauftragung stattfinden. Es besteht die M\u00f6glichkeit, mehrere Belege zu einem Transport zusammenzufassen. Alles weitere \u2013 von der Auftragsannahme durch den Spediteur bis zum PoD \u2013 verl\u00e4uft entsprechend wie bei den Optionen 1 und 2 mithilfe der myleo \/ dsc.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/leogistics-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner.jpg\" alt=\"https:\/\/e3mag.com\/partners\/leogistics-gmbh\/\" class=\"wp-image-66203\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/04\/Leogistics-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Die Erwartungen an Transportmanagementsysteme (TMS) sind in den letzten Jahren aufgrund von Umbr\u00fcchen im Welthandel, Umweltfaktoren und der Corona-Pandemie enorm gestiegen. Systeme, die sich auf die Transportplanung, -verwaltung und -abrechnung fokussieren, reichen nicht mehr aus.<\/p>\n","protected":false},"author":2201,"featured_media":118720,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[26405,41849],"tags":[20119,1390,281,7631,963],"coauthors":[38376],"class_list":["post-118716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advertorial","category-extra-2210","tag-leogistics","tag-s4-hana","tag-saas","tag-scm","tag-supply-chain","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-80x80.jpg",80,80,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/09\/shutterstock_1540519931_IncrediVFX-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die Erwartungen an Transportmanagementsysteme (TMS) sind in den letzten Jahren aufgrund von Umbr\u00fcchen im Welthandel, Umweltfaktoren und der Corona-Pandemie enorm gestiegen. Systeme, die sich auf die Transportplanung, -verwaltung und -abrechnung fokussieren, reichen nicht mehr aus.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/advertorial\/\" rel=\"category tag\">Advertorial<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/extra-2210\/\" rel=\"category tag\">Extra 2210<\/a>","author_info_v2":{"name":"leogistics GmbH","url":"https:\/\/e3mag.com\/de\/author\/leogistics-gmbh\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/118716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2201"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=118716"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/118716\/revisions"}],"predecessor-version":[{"id":137694,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/118716\/revisions\/137694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/118720"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=118716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=118716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=118716"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=118716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}