{"id":118196,"date":"2022-10-12T08:00:00","date_gmt":"2022-10-12T06:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=118196"},"modified":"2022-09-16T12:29:13","modified_gmt":"2022-09-16T10:29:13","slug":"warum-security-experten-keine-sap-experten-sind","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/warum-security-experten-keine-sap-experten-sind\/","title":{"rendered":"Warum Security-Experten keine SAP-Experten sind"},"content":{"rendered":"\n<p>Da sich die Antworten auf diese Frage oft gleichen, gibt es scheinbar grunds\u00e4tzliche Fehlannahmen bez\u00fcglich SAP-Sicherheit. Beim Thema Security landet man schnell beim Menschen. Schlie\u00dflich sind es Hacker, die Cyberattacken fahren. Und darin liegt der Knackpunkt. Nur ausgewiesene Security-Experten haben eine Chance, professionellen Hackern die Stirn zu bieten. W\u00e4hrend Cyberkriminelle hoch spezialisiert sind, m\u00fcssen Fachleute in Unternehmen alle Techniken beherrschen und ausgepr\u00e4gte analytische F\u00e4higkeiten haben. Das kann man selbst vom erfahrensten SAP-Professional nicht erwarten. Zu komplex und zu dynamisch ist die Cybercrime-Branche, als dass er sich mal schnell einarbeiten k\u00f6nnte. Daher ist es zwingend notwendig, SAP mit Security-Spezialisten zusammenzubringen und einen vollst\u00e4ndigen \u00dcberblick \u00fcber die Bedrohungslage zu erhalten. Denn Angreifer interessieren sich nicht f\u00fcr interne Organisationssilos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SAP in der Cloud<\/h3>\n\n\n\n<p>SAP-Systeme in die Cloud zu migrieren ist eine zukunftstr\u00e4chtige Aufgabe. Die Cloud-Adaption ist ein hochkomplexes Vorhaben, das einem steten Wandel unterliegt. Darum m\u00fcssen die Mitarbeitenden hoch qualifiziert sein. Doch manche Firmen sind davon \u00fcberzeugt, ihr IT-Personal k\u00f6nne die Bestands-IT managen und sei zugleich Experte f\u00fcr Cloud-Security. Praktisch ist es aber so, dass unternehmenseigenen Security-Experten h\u00e4ufig das erforderliche SAP-Know-how fehlt \u2013 ebenso, wie SAP-Fachleute oftmals nur \u00fcber rudiment\u00e4re Security-Kenntnisse verf\u00fcgen. Also bilden diese Unternehmen ihre IT-Fachkr\u00e4fte nicht ad\u00e4quat weiter.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1026061108\"><div id=\"great-661753287\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/e3mag.com\/de\/event\/e3-roundtable-it-plattformen-sap-btp-sap-bdc-etc\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26_08_26_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26_08_26_1200x150-1-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Doch fehlendes Fachwissen in Bezug auf die Absicherung einer cloudbasierten SAP-Landschaft erzeugt gef\u00e4hrliche Schwachstellen. So m\u00fcssen Hacker nicht einmal die M\u00fche auf sich nehmen, sich \u2013 gut getarnt in einem trojanischen Pferd \u2013Zugriff auf Daten und Systeme zu verschaffen. Sie laufen mit offenem Visier \u00fcber die heruntergelassene Zugbr\u00fccke durch das sperrangelweit ge\u00f6ffnete Tor und nisten sich in der Burg ein. Bis das auff\u00e4llt, dauert es durchschnittlich rund 100 Tage. Drei Monate, in denen Cyberkriminelle gro\u00dfen Schaden anrichten k\u00f6nnen. Nicht immer sind es aufmerk-samkeitsstarke Ransomware- oder DDoS-Attacken. Mancher Hacker geht sehr subtil vor, etwa indem er vermeintlich unbedeutende Informationen abgreift. Daher m\u00fcssen Unternehmen Security bei der Cloud&#8211;Transformation stets mitdenken.<\/p>\n\n\n\n<p>Erneut stellt sich die Frage: Warum tun Firmen das nicht? Es scheint, als w\u00fcrde kein zielf\u00fchrender Dialog zwischen IT und Management stattfinden. Manchmal hat die Gesch\u00e4ftsf\u00fchrung keine greifbare Vorstellung davon, wie wichtig SAP-Sicherheit f\u00fcr einen reibungslosen Gesch\u00e4ftsbetrieb ist. Und Security-Experten gelingt es zuweilen nicht, die Vorteile ad\u00e4quater Schutzma\u00dfnahmen und ihre positiven Auswirkungen auf das operative Tagesgesch\u00e4ft zu vermitteln. F\u00fcr einen echten Dialog sind Unternehmen gut beraten, die Technologie zun\u00e4chst au\u00dfen vorzulassen. Es geht darum, den M\u00f6glichkeiten der Cloud und der Komplexit\u00e4t von SAP-Security bewusst zu begegnen: Um die SAP-Infrastruktur gegen Hackerangriffe abzusichern, braucht es zwingend ein Verst\u00e4ndnis davon, dass SAP-Sicherheit ein Gesch\u00e4ftsprozess wie jeder andere ist. Ein Prozess, der sorgf\u00e4ltig zu modellieren, mit Metriken zu steuern, mit Tools zu \u00fcberwachen und kontinuierlich zu optimieren ist.<\/p>\n\n\n\n<p>Um den Blick auf SAP-Security zu ver\u00e4ndern, m\u00fcssen Unternehmen mit g\u00e4ngigen Vorurteilen aufr\u00e4umen. Denn das grundlegende Missverst\u00e4ndnis ist die Fehlannahme, Security sei ein IT-Thema. Doch Cloud- und SAP-Sicherheit sind vielmehr in der Unternehmensstrategie nachhaltig zu verankern und erst im zweiten Schritt praktisch umzusetzen. Das ist eine Herausforderung, die weit \u00fcber die IT-Abteilung hinausgeht. Sie betrifft viele Fachbereiche. F\u00fcr eine wirkungsvolle SAP-Security m\u00fcssen alle, wirklich alle an einem Strang ziehen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/arvato-systems-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO.jpg\" alt=\"https:\/\/e3mag.com\/partners\/arvato-systems-gmbh\/\" class=\"wp-image-11355\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-ARVATO-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n\n\n\n\n\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>SAP geh\u00f6rt f\u00fcr viele Unternehmen zur unverzichtbaren IT-Grundausstattung, weil es f\u00fcr einen reibungslosen Gesch\u00e4ftsablauf und eine st\u00f6rungsfreie Produktion zwingend notwendig ist. Doch warum sch\u00fctzen Firmen ihre SAP-Systeme nicht richtig? <\/p>\n","protected":false},"author":2612,"featured_media":2451,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[21,41721],"tags":[20354,31057,1790,41724,41787],"coauthors":[41786],"class_list":["post-118196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-security","category-mag-22-09","tag-arvato","tag-cybercrime","tag-it-security","tag-mag-22-09","tag-security-experte","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",400,172,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-768x331.jpg",768,331,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-100x43.jpg",100,43,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-480x207.jpg",480,207,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-640x276.jpg",640,276,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-720x310.jpg",720,310,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-960x414.jpg",960,414,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",1000,431,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security.jpg",600,259,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2016\/11\/It-Security-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP geh\u00f6rt f\u00fcr viele Unternehmen zur unverzichtbaren IT-Grundausstattung, weil es f\u00fcr einen reibungslosen Gesch\u00e4ftsablauf und eine st\u00f6rungsfreie Produktion zwingend notwendig ist. Doch warum sch\u00fctzen Firmen ihre SAP-Systeme nicht richtig? <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/meinung\/it-security\/\" rel=\"category tag\">IT-Security Kolumne<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-22-09\/\" rel=\"category tag\">Mag 22-09<\/a>","author_info_v2":{"name":"Andreas Nolte, Arvato Systems GmbH","url":"https:\/\/e3mag.com\/de\/author\/andreas-nolte\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/118196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2612"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=118196"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/118196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/2451"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=118196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=118196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=118196"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=118196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}