{"id":116029,"date":"2022-07-04T07:30:00","date_gmt":"2022-07-04T05:30:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=116029"},"modified":"2024-01-19T11:28:15","modified_gmt":"2024-01-19T10:28:15","slug":"in-vier-schritten-zur-naechsten-stufe-der-automatisierten-rechnungsverarbeitung","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/in-vier-schritten-zur-naechsten-stufe-der-automatisierten-rechnungsverarbeitung\/","title":{"rendered":"In vier Schritten zur n\u00e4chsten Stufe der automatisierten Rechnungsverarbeitung"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">1. Vorgelagerte Prozesse standardisieren und automatisieren<\/h3>\n\n\n\n<p>Rechnungen mit Bestellbezug lassen sich schneller und einfacher verarbeiten als solche ohne dazugeh\u00f6rige Bestellung. Wenn im Zuge der Bedarfserfassung bereits alle notwendigen Freigaben erteilt wurden, kann dieser Arbeitsschritt bei der Rechnungsverarbeitung unterbleiben. Damit ist eine Automatisierung bis hin zur Verbuchung komplett im Hintergrund (sogenannte <a href=\"https:\/\/news.xsuite.com\/whitepaper\/dunkelbuchungen?utm_source=e3&amp;utm_medium=e3-adv&amp;utm_campaign=wp-dklbu\" target=\"_blank\" rel=\"noopener\">Dunkelbuchungen<\/a>) m\u00f6glich. Au\u00dferdem kann bei Rechnungen ein 3-Way-Match vorgenommen werden. Dieser Abgleichsmechanismus erh\u00f6ht die Sicherheit des Prozesses: vor Fehlern genauso wie vor <a href=\"https:\/\/www.xsuite.com\/blog\/rechnungsbetrug-mit-gefaelschten-rechnungen-eine-echte-bedrohung\/\" target=\"_blank\" rel=\"noopener\">Betrugsversuchen<\/a>&nbsp;.<\/p>\n\n\n\n<p>Um die Prozesse in der Kreditorenbuchhaltung zu vereinfachen, empfiehlt es sich also, den Anteil von Rechnungen mit Bestellbezug (SAP MM) zu steigern. Am besten erreichen l\u00e4sst sich dies, wenn der Prozess der Bedarfserfassung f\u00fcr den Nutzenden besonders einfach und intuitiv ist und gleichzeitig Standardisierung f\u00fcr den Einkauf bedeutet. Ein digitaler Workflow zur Bedarfserfassung und Bestellpr\u00fcfung und -freigabe kann zu diesem Zweck eingesetzt werden.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1713808876\"><div id=\"great-745452997\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><a id=\"_msocom_1\"><\/a>2. Automatisierung durch KI erh\u00f6hen<\/h3>\n\n\n\n<p>Ein <a href=\"https:\/\/www.xsuite.com\/leistungen-und-loesungen\/rechnungsbearbeitung\/rechnungsverarbeitung-in-sap-xsuite-invoice-cube\/\" target=\"_blank\" rel=\"noopener\">digitaler Workflow zur Verarbeitung von Eingangsrechnungen<\/a>&nbsp;(insbesondere ohne Bestellbezug, SAP FI) kann die Besch\u00e4ftigten in der kreditorischen Buchhaltung bereits deutlich entlasten. Durch den Einsatz von k\u00fcnstlicher Intelligenz werden dabei ganz neue Anwendungsfelder f\u00fcr die Automatisierung er\u00f6ffnet. Konkrete Szenarien sind z.B. selbstlernende Datenextraktion, intelligente Kontierungsvorschl\u00e4ge (aus denen die Besch\u00e4ftigten nur noch ausw\u00e4hlen m\u00fcssen) oder Vorschlagsfunktionen zum Auffinden der richtigen Person f\u00fcr die Bearbeitung bereits w\u00e4hrend der Validierung. Weiteres Automatisierungspotenzial er\u00f6ffnet sich mit Predictive Analytics, Forecasting und Anomalie-Erkennung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Papier ad\u00e9<\/h3>\n\n\n\n<p>Wer den Prozess der Rechnungseingangsverarbeitung im Unternehmen bereits in weiten Teilen automatisiert hat, kennt den Knackpunkt: Die gr\u00f6\u00dfte Fehlerquelle, der gr\u00f6\u00dfte Bremsklotz bei der automatisierten Verarbeitung ist immer das Auslesen von Daten aus eingescannten Belegen. Wer einige Punkte beachtet, kann die Ergebnisse der Beleglesung noch einmal signifikant verbessern. Wie bereits erw\u00e4hnt, kann au\u00dferdem k\u00fcnstliche Intelligenz hier ihren Beitrag leisten. Man darf sich jedoch nichts vormachen \u2013 auf null Prozent wird die Fehlerquote bei der Beleglesung wohl nie sinken, es geht vielmehr um eine gr\u00f6\u00dftm\u00f6gliche Minimierung. Eines zumindest steht fest: Je weniger Papierrechnungen eintreffen, desto h\u00f6her ist der Automatisierungsgrad bei der Rechnungsverarbeitung und desto weniger Erfassungsfehler k\u00f6nnen auftreten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Auslagern in die Cloud<\/h3>\n\n\n\n<p>Die Optimierung der Abl\u00e4ufe ist meist der erste Fokus, wenn es um die digitale Rechnungsverarbeitung geht. Potenzial f\u00fcr Optimierung bietet allerdings auch das Backend. Ein Beispiel daf\u00fcr ist es, bestimmte (Teil-) Prozesse in die Cloud auszulagern. Insbesondere standardisierte Prozesse mit einem hohen Volumen bieten sich daf\u00fcr an. Statt f\u00fcr Prozesse wie die Beleglesung oder die Archivierung on-premises selbst Hard- und Software bereitzustellen und die Systeme zu betreuen, k\u00f6nnen diese Dienste auch aus der Cloud bezogen werden. Dies ist ein weiterer Baustein, um die Automatisierung voranzubringen und viele Unternehmen setzen daher auf &nbsp;<a href=\"https:\/\/www.xsuite.com\/blog\/cloud-first-nicht-cloud-only\/\" target=\"_blank\" rel=\"noopener\">hybride Szenarien<\/a>&nbsp; aus Cloud und on-premises.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fazit: Erst Digitalisierung, dann Optimierung<\/h3>\n\n\n\n<p>Abl\u00e4ufe in der Kreditorenbuchhaltung werden bereits durch die Prozessumstellung der Rechnungsverarbeitung \u2013 von manuell und papierbasiert auf digital \u2013 deutlich vereinfacht. Aber auch nach Digitalisierung der Arbeitsschritte bestehen weitere Optionen den Automatisierungsgrad nochmals zu steigern, um dem Ziel n\u00e4her zu kommen: maximale Quote an Hintergrundverbuchungen bei eingehenden Rechnungen.&nbsp;<\/p>\n\n\n\n<p>Mehr Informationen zum Thema <a rel=\"noreferrer noopener\" href=\"https:\/\/news.xsuite.com\/whitepaper\/dunkelbuchungen?utm_source=e3&amp;utm_medium=e3-adv&amp;utm_campaign=wp-dklbu\" target=\"_blank\">Dunkelbuchungen<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem viele Unternehmen inzwischen mit der Digitalisierung und Automatisierung ihrer Eingangsrechnungsverarbeitung begonnen haben, stehen sie nun vor den n\u00e4chsten Schritten. Wie lassen sich Gesch\u00e4ftsprozesse in Einkauf und Buchhaltung weiter automatisieren? Vier Handlungsfelder zeichnen sich ab. <\/p>\n","protected":false},"author":2147,"featured_media":116032,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[42339],"tags":[37727,11237],"coauthors":[38100],"class_list":["post-116029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-online-advertorial","tag-advertorial","tag-xsuite","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/06\/2022-07-xSuite_titelbild_1000x450-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Nachdem viele Unternehmen inzwischen mit der Digitalisierung und Automatisierung ihrer Eingangsrechnungsverarbeitung begonnen haben, stehen sie nun vor den n\u00e4chsten Schritten. Wie lassen sich Gesch\u00e4ftsprozesse in Einkauf und Buchhaltung weiter automatisieren? Vier Handlungsfelder zeichnen sich ab. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/online-advertorial\/\" rel=\"category tag\">Online-Advertorial<\/a>","author_info_v2":{"name":"Dina Haack, xSuite Group","url":"https:\/\/e3mag.com\/de\/author\/dina-haack-xsuite\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/116029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2147"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=116029"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/116029\/revisions"}],"predecessor-version":[{"id":137489,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/116029\/revisions\/137489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/116032"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=116029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=116029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=116029"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=116029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}