{"id":112763,"date":"2022-03-24T08:02:00","date_gmt":"2022-03-24T07:02:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=112763"},"modified":"2022-04-11T11:47:57","modified_gmt":"2022-04-11T09:47:57","slug":"the-power-of-orange","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/the-power-of-orange\/","title":{"rendered":"The Power of Orange"},"content":{"rendered":"\n<p>Das einzigartige Geheimnis von cbs wird von der Gesch\u00e4ftsf\u00fchrung postuliert: Wir beraten de facto die Weltmarktf\u00fchrer aus der Fertigungsindustrie, im DACH-Raum den Maschinen- und Anlagenbau, Automotive, Chemie, Pharma, Life Science und Medizintechnik. Beispiele daf\u00fcr gibt es in der cbs-Gesch\u00e4ftsf\u00fchrung viele: Phoenix Contact, D\u00fcrr, Roche, Schott, Endress und Hauser, MAN, Miele, Dormakaba, Trumpf, Viessmann, Claas, Hella, Mann und Hummel. Es sind langj\u00e4hrige SAP-Bestandskunden. 70 Prozent der Weltmarktf\u00fchrer im DACH-Raum sind Kunden von cbs \u2013 schon aufgrund der normativen Kraft des Faktischen definiert die Gesch\u00e4ftsf\u00fchrung das Unternehmen als \u201eBerater der Weltmarktf\u00fchrer\u201c.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"536\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800.jpg\" alt=\"cbs Gesch\u00e4ftsf\u00fchrung\" class=\"wp-image-112825\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800-768x515.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800-100x67.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800-480x322.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800-640x429.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-gf-poweroforange-800-720x482.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em>Die cbs-Gesch\u00e4ftsf\u00fchrer Stefan Risse, Rainer Wittwen (CEO) und Holger Scheel (von links).<\/em><\/figcaption><\/figure>\n\n\n\n<p>Ist das ein Zufall, warum ist das so? Es ist das Resultat einer klaren, nachhaltig verfolgten Unternehmensstrategie, die den Fokus bewusst setzt auf diese Zielgruppe. In der cbs-Vision 2025 formulierte das Unternehmen, dass man sich vom Berater der Weltmarktf\u00fchrer selbst zum Weltmarktf\u00fchrer weiterentwickeln will. \u201eWir wollen das weltweit f\u00fchrende High-Performance-Beratungsunternehmen werden, das vorzugsweise innovative, wachstumsstarke und global marktf\u00fchrende Industrieunternehmen bei der Gestaltung ihrer digitalen und globalen E2E-Gesch\u00e4ftsprozessl\u00f6sungen umfassend ber\u00e4t. Wir wollen zum Weltmarktf\u00fchrer der Weltmarktf\u00fchrer werden\u201c, hei\u00dft es bei cbs.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-3290697822\"><div id=\"great-778365682\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>Warum? Nicht nur, weil dieser Markt gro\u00dfes Gesch\u00e4ftspotenzial bietet, sondern weil diese Unternehmen hervorragend zu cbs passen: Gleiche Philosophie, Mentalit\u00e4t, Kultur, Anspruchshaltung, Gestaltungswillen, Innovativit\u00e4t, Strategie. Zudem finden cbs-Berater hier am meisten Spa\u00df und Erf\u00fcllung dabei, ihrer Leidenschaft zu folgen und das zu tun, was besonders wichtig erscheint: Unternehmensweite digitale End-to-End-Gesch\u00e4ftsprozessl\u00f6sungen \u2013 \u201eCorporate Business Solutions\u201c \u2013 f\u00fcr die SAP-Bestandskunden zu schaffen.<\/p>\n\n\n\n<p>Diese Ausrichtung geh\u00f6rt zu der cbs-Gr\u00fcndungsidee und dem einzigartigen Unternehmenskonzept: <em>\u201eWir wollen seit jeher der erste Erfolgspartner mittelgro\u00dfer internationaler Industrieunternehmen sein, die folgende typische Eigenschaften f\u00fcr die Hidden Champions mitbringen: Langfristige strategische Ausrichtung auf einen definierten Zielmarkt. Ein klarer Kompass. Absolute Kunden- und Leistungsorientierung. Hohe Innovationskraft, fachliche Exzellenz, der Ehrgeiz eines Qualit\u00e4tsf\u00fchrers. Eine starke Unternehmenskultur, die unternehmerisches Denken, offene Kommunikation, Verantwortung und Vertrauen in individuelle Gestaltungskraft f\u00f6rdert und fordert. Das sind die Eigenschaften, die cbs mit seinen Kunden verbindet\u201c<\/em>, ist das Bekenntnis der cbs-Gesch\u00e4ftsf\u00fchrung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"527\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800.jpg\" alt=\"Holger Scheel\" class=\"wp-image-112828\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800-768x506.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800-100x66.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800-480x316.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800-640x422.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Holger_01_800-720x474.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em>Wir liefern ein Komplettangebot f\u00fcr die Business Transformation mit der Kultur und Klasse eines Hidden Champions.<\/em> &#8211; <em>Holger Scheel, cbs-Gesch\u00e4ftsf\u00fchrer<\/em><\/figcaption><\/figure>\n\n\n\n<p>Was ist spezifisch und besonders an dem Angebot \u2013 gerade f\u00fcr diese Zielgruppe? Was sind die besondere Eignung, der Vorteil, der Mehrwert f\u00fcr Weltmarktf\u00fchrer? Die Weltmarktf\u00fchrer haben vieles gemeinsam. Besondere F\u00e4higkeiten sind wichtig. Aber f\u00fcr cbs-Kunden z\u00e4hlt auch etwas anderes, das nicht zu untersch\u00e4tzen ist: <em>\u201eWir arbeiten auf der Basis gleicher Werte einfach sehr gut und mit hohem Vertrauen langfristig zusammen. Stichwort au\u00dfergew\u00f6hnliche Kundenorientierung und Partnerschaftlichkeit. Wir setzen uns f\u00fcr unsere Kunden ein, machen ihre Ziele zu unseren Zielen und tun alles daf\u00fcr, diese mit ihnen zu erreichen. Das sch\u00e4tzen die Kunden sehr. Wir m\u00f6gen unsere Kunden, arbeiten gern und engagiert mit ihnen zusammen und unsere Kunden geben uns das zur\u00fcck. Enge pers\u00f6nliche Bindung, gepaart mit hoher Professionalit\u00e4t, da passen die Weltmarktf\u00fchrer und der Berater der Weltmarktf\u00fchrer einfach hervorragend zusammen.\u201c<\/em> Damit bekennt sich die cbs-Gesch\u00e4ftsf\u00fchrung zu einem ganzheitlichen Ansatz.<\/p>\n\n\n\n<p>Die Analysten von Techconsult haben in einer aktuellen Studie diese Wertigkeit erhoben und best\u00e4tigen damit die Marktnachfrage: <em>\u201eDie digitale Entwicklung zeigt, wie wichtig Flexibilit\u00e4t und Individualit\u00e4t in der IT-Architektur geworden sind. Dieser Wandel der digitalen Gesch\u00e4ftsprozesse f\u00fchrte in vielen Unternehmen zu einer deutlichen \u00dcberlastung der IT-Abteilungen. Davon sind auch L\u00f6sungen der SAP immer weiter betroffen. Als Reaktion entwickelt sich die SAP-Landschaft zu cloudbasierten und anpassungsf\u00e4higen Services. Hierdurch sollen die W\u00fcnsche der Unternehmen erf\u00fcllt und gleichzeitig die Digitalisierung unterst\u00fctzt werden.\u201c<\/em> <\/p>\n\n\n\n<p>cbs ist ein Solit\u00e4r in der Beratungswelt, dazu die Gesch\u00e4ftsf\u00fchrung des Heidelberger SAP-Partners: <em>\u201eWir liefern das Angebot der Gro\u00dfen mit der Kultur und Klasse eines Hidden Champions, f\u00fcr einen&nbsp;klar definierten Markt. Ein vergleichbares L\u00f6sungsportfolio, ein Programmangebot f\u00fcr die Business Transformation und die methodisch-strukturierte Pr\u00e4gung suchen die SAP-Bestandskunden sonst typischerweise bei einem globalen Systemintegrator \u2013 vermissen aber die Wellenl\u00e4nge: Die strategische Grundausrichtung, die Kunden- und Qualit\u00e4tsorientierung, die Nahbarkeit und Augenh\u00f6he, die Vertrauensbasis, den mittelst\u00e4ndisch l\u00f6sungsorientierten Pragmatismus, die Leidenschaft und Ambition f\u00fcr die Sache selbst, die Denke, das Wertefundament und die Kultur der Hidden Champions. Kleine und mittlere Beratungsgesellschaften wiederum haben nicht den gesamthaften Antritt und die Augenh\u00f6he, den unternehmensweiten Gestaltungsanspruch und die methodische Expertise, die End-to-End-L\u00f6sungskompetenz in der Breite, fokussieren sich eher auf einzelne fachliche Nischen und sehen f\u00fcr sich nicht die Verantwortung als Generalunternehmer.\u201c<\/em><\/p>\n\n\n\n<p>cbs ist der Berater der Weltmarktf\u00fchrer und der globale Lieferant ihrer auf SAP-<br>Software und Cloud-Technologie basierenden Unternehmensl\u00f6sungen (Corporate Business Solutions). Mit einem einzigartigen Komplettangebot f\u00fcr die Unternehmenstransformation unterst\u00fctzt cbs seine Kunden ganzheitlich auf ihrem Weg zu einem globalen Digitalen Unternehmen. Doch wie zufrieden sind deutsche Unternehmen mit den eingesetzten SAP Services und in welchen Bereichen besteht dringender Handlungsbedarf? Das Research- und Analystenhaus Techconsult stellte die Ergebnisse des \u201eProfessional User Rating: SAP Services 2022\u201c vor und zeigt, wie Dienstleister und ihre SAP Services von beziehenden Anwenderexperten bewertet werden. F\u00fcr Unternehmen, besonders in der DACH-Region, spielen die L\u00f6sungen der SAP schon sehr lang eine wichtige Rolle. <\/p>\n\n\n\n<p>So lang, dass sich gro\u00df gewachsene und lang etablierte Systeme gebildet haben. Doch seit dem Wachstum der Cloud-Technologien sind auch Servicemodelle rund um die L\u00f6sungen wichtiger denn je geworden. Hier kommen SAP Services ins Spiel und helfen dabei, die IT-Abteilungen aktiv zu unterst\u00fctzen. Das Analystenhaus Techconsult hat in diesem Kontext \u00fcber 60 Anbieter von SAP Services von Serviceexperten bewerten lassen. Dabei wurden Services aus insgesamt sieben Kategorien bewertet, die von der Beratung \u00fcber zwei wichtige Funktionsbereiche bis zum Betrieb reichen. Die Dienstleister schneiden durchwachsen ab, insbesondere im Bereich der Serviceportfolios herrscht dringend Nachholbedarf. cbs bietet ein holistisches Angebot, Business Transformation as a Service. Den cbs-L\u00f6sungskern bildet SAP, als nach wie vor de facto und unangefochten beste L\u00f6sung f\u00fcr betriebswirtschaftliche Kernprozesse, erg\u00e4nzt durch Cloud-Software anderer Hersteller, insbesondere auch Salesforce im CX-Umfeld. <\/p>\n\n\n\n<p>Der cbs-Leitgedanke: <em>\u201eWas ist f\u00fcr unsere Kunden die relevanteste und beste End-to-End-L\u00f6sungsarchitektur zur Digitalisierung ihrer Gesch\u00e4ftsprozesse? Auch wir folgen den Trends und Ver\u00e4nderungen im Markt und haben immer den Ehrgeiz, in den Softwarel\u00f6sungen, die wir beraten, der Beste, der Qualit\u00e4ts- und Innovationsf\u00fchrer zu sein. Die Welt ist hybrid, das betrifft nicht nur die technischen Betriebsmodelle und den Einzug der Cloud in die Softwarearchitektur eines Unternehmens, sondern vor allem auch auf der L\u00f6sungsebene die Integration von applikations\u00fcbergreifenden Gesch\u00e4ftsprozessen zu einem optimalen digitalen End-to-End-Gesch\u00e4ftsprozess, mit den \u00fcberzeugendsten Softwarewerkzeugen, die unseren Industriekunden zur Verf\u00fcgung stehen.\u201c<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"519\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800.jpg\" alt=\"Rainer Wittwen, cbs\" class=\"wp-image-112832\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800-768x498.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800-100x65.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800-480x311.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800-640x415.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Rainer_01_800-720x467.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em>cbs ist der Berater der Weltmarktf\u00fchrer und der globale Lieferant ihrer auf<\/em> <em>SAP-Software und Cloud-Technologie basierenden Unternehmensl\u00f6sungen.<\/em> &#8211; <em>Rainer Wittwen, CEO bei cbs<\/em><\/figcaption><\/figure>\n\n\n\n<p>Das cbs-Ziel l\u00e4sst sich demnach folgenderma\u00dfen definieren: L\u00f6sungen nicht nur konzipieren, sondern global umzusetzen! <em>\u201eWir wollen L\u00f6sungen schaffen. Nicht nur den Ansatz, das Konzept, sondern das Ergebnis liefern und die m\u00f6glichst passgenaue, innovative Gesamtl\u00f6sung ins Werk setzen, um Kunden ganzheitlich zu helfen, ihre Gesch\u00e4ftsprozesse unternehmens- und weltweit mithilfe von Business-Applikationen zu gestalten. Business Transformation as a Service, ganz im holistischen Sinne der SAP-Kundeninitiative \u201eRise with SAP\u201c. Dazu geh\u00f6ren im Kern betriebswirtschaftliche Prozess- und Applikationsberatung, Architektur-, Integrations- und Technologieberatung, Datentransformation und Datenmanagement, Implementierung und nachhaltiges L\u00f6sungsmanagement (BSM) mit kontinuierlicher Verbesserung.\u201c<\/em><\/p>\n\n\n\n<p>Die von Techconsult befragten IT-Verantwortlichen bewerten den geschaffenen Nutzenzuwachs durch den bezogenen Service in allen Kategorien hinweg \u00fcberwiegend mit der Note Gut. Einerseits werden die Mitarbeiter, die im komplexen SAP-Umfeld besch\u00e4ftigt sind, durch SAP-Partner entlastet und andererseits werden durch zus\u00e4tzliche Enhancements und das Know-how der SAP-Partner Services optimiert. Zwei wichtige Punkte im Angesicht&nbsp;des Mangels an qualifizierten Mitarbeitern und Know-how. Durch den Einsatz von SAP Services berichtet jedes zweite Unternehmen von unterst\u00fctzenden Entscheidungsfindungen und von gestiegener Produktivit\u00e4t. Damit wird der geschaffene Servicenutzen in jedem zweiten Betrieb mit Gut bis Sehr gut bewertet. Diese Kriterien sind \u00fcberaus wichtig, um eine hohe Zufriedenheit beim SAP-Bestandskunden zu erreichen. Hier schneiden insbesondere die Anbieter in der Kategorie der Application Management Service (ERP) besonders gut ab. <\/p>\n\n\n\n<p>Dort haben 68 Prozent der Servicebezieher den Service mit Gut bis Sehr gut bewertet. Es zeigt die Kompetenzen sowie die Etablierung und das Festhalten an den bew\u00e4hrten ERP-Systemen der SAP im deutschen Markt. Aus den Techconsult-Ergebnissen lassen sich jedoch auch Bereiche mit Verbesserungsbedarf herauslesen. So liegt die durchschnittliche Zufriedenheit mit dem Umfang und dem Angebot von SAP Services bei 35 Prozent. Hier sorgt die Bewertung der Individualisierbarkeit der SAP Services noch f\u00fcr die Gesamtnote Befriedigend. Der SAP-Standard dominiert weiterhin. Abhilfe versuchen die Partner mit branchenspezifischen Leistungen zu schaffen. Doch den Servicebezieher und SAP-Bestandskunden fehlt der Durchblick im SAP-Universum. Service Provider m\u00fcssen die Vorteile ihrer Leistungen st\u00e4rker quantifizieren und den Unternehmen konkrete Use-Cases deutlich hervorheben. TCO-Analysen und das Aufzeigen konkreter Machbarkeitsanalysen sind ein Muss. Hier sind insbesondere die Anbieter von SAP Consulting Services gefragt. Nur jeder Zweite der IT-Verantwortlichen sieht in dieser Service-Kategorie die Provider in ihrer strategischen Beratungskompetenz gut aufgestellt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"506\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800.jpg\" alt=\"Stefan Risse, cbs\" class=\"wp-image-112829\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800-768x486.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800-100x63.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800-480x304.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800-640x405.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/GF_Stefan_01_800-720x455.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em>Der cbs-Leitgedanke: Was ist f\u00fcr unsere Kunden die beste End-2-End-L\u00f6sungsarchitektur zur Digitalisierung ihrer Gesch\u00e4ftsprozesse?<\/em> &#8211; <em>Stefan Risse,<\/em> <em>cbs-Gesch\u00e4ftsf\u00fchrer<\/em><\/figcaption><\/figure>\n\n\n\n<p>Der S\/4-Umstieg ist momentan sicher eine auch die allgemeine Diskussion dominierende Sorge der SAP-Bestandskunden. Der digitale Kern steht im Mittelpunkt der \u00dcberlegungen und Ausschreibungen vieler Kunden. Dabei ist es wichtig, S\/4 nicht isoliert zu betrachten, wei\u00df man bei cbs: <em>\u201eAuch halten wir wenig von einem unreflektierten, rein technischen S\/4-Umstieg mit minimaler Ambition. Dazu ist selbst ein solcher Umstieg meist zu teuer und viele Kunden tun sich schwer, ihn dem Vorstand und sich selbst plausibel betriebswirtschaftlich zu begr\u00fcnden. Erst als Baustein einer umfassenden Digitalisierungs-Roadmap, unter Bewertung aller relevanten Alternativen, kann das sinnvoll sein.\u201c<\/em> Man m\u00f6chte einen Digitalisierungsvorsprung erzielen. Zeit ist der kritische Faktor. Es dauert lang, den digitalen Kern auch wirklich global zur Verf\u00fcgung zu stellen. Das ist ein Anachronismus, der wehtut. Zumal es moderne Referenzmethoden gibt, die dieses Problem adressieren und speziell f\u00fcr die digitale Transformation im SAP-Umfeld gemacht sind. <\/p>\n\n\n\n<p>Das Ziel: Die Verbindung von umfassender Ambition mit schneller Wertsch\u00f6pfung. Das Wertversprechen ist Geschwindigkeit. Es erm\u00f6glicht dem Kunden den Sprung in die \u201eIntelligent Enterprise\u201c. Damit kann ein veritabler Digitalisierungsvorsprung erreicht werden. Die von Techconsult befragten IT- und SAP-Verantwortlichen sind insgesamt mit den bezogenen SAP Services zufrieden. Die Weiterempfehlungsrate der SAP-Partner auf Serviceebene liegt bei durchschnittlich 65 Prozent und auf Anbieterebene durchschnittlich bei 58 Prozent. Zuk\u00fcnftig r\u00fcsten die SAP und das Partnernetzwerk weiter auf. Besonders S\/4, das als Nachfolger der altbew\u00e4hrten SAP-ERP-Systeme folgt, wird als Wegbereiter in die digitale Zukunft gesehen. Auch hat SAP schnell den Weg in die Cloud gefunden und erm\u00f6glicht zuk\u00fcnftig Skalierbarkeit und Flexibilit\u00e4t in der Implementierung. Dies wird durch das Konzept \u201eRise with SAP\u201c im gesamten Partnernetzwerk weitergetragen. <\/p>\n\n\n\n<p>Wie sich die Services und die Zufriedenheit in den Unternehmen in Zukunft entwickelt, wird j\u00e4hrlich in dem von Techconsult durchgef\u00fchrten Projekt \u201eProfessional User Rating SAP Services\u201c vorgestellt.\u00a0 Bei cbs entsteht ein ma\u00dfgeschneidertes \u201eRise with SAP\u201c f\u00fcr die Weltmarktf\u00fchrer, passend zu ihrer typischen Mentalit\u00e4t und Kultur, als ganzheitliche Business Transformation as a Service, mit Blick auf Praktikabilit\u00e4t und schnelle Wertsch\u00f6pfung, eben \u201eFast Value\u201c: <em>\u201eWir beraten mit dem Anspruch, eine innovative digitale Gesamtl\u00f6sung f\u00fcr unsere Kunden zu gestalten und zu liefern. Wir denken in die Zukunft und weit \u00fcber S\/4 als Applikation und den S\/4-Umstieg hinaus. Wir sehen uns als Erfolgspartner f\u00fcr die erfolgreiche digitale Business Transformation insgesamt. Es geht auch um mehr als S\/4. Unsere Kunden suchen den Weg\u00a0 und das Zielbild f\u00fcr die End-to-End-Gesch\u00e4ftsprozessplattform der Zukunft, den Bauplan f\u00fcr das globale, digitale, intelligente Unternehmen und die beste umsetzbare Roadmap in die innovative Corporate Business Solution 2030. Das ist nicht einfach, aber das Salz in der Suppe und unsere spezifische Kompetenz und Passion.\u201c<\/em> <\/p>\n\n\n\n<p>Dazu braucht es Weitblick und eine gute Portion Pragmatismus, den aus Erfahrung gest\u00e4rkten Sinn f\u00fcr das Machbare. Notwendig ist eine mindestens mittelfristige Perspektive. Die R\u00fcckbindung an strategische Unternehmensziele und Schl\u00fcsselherausforderungen ist wichtig. Zusammenfassend hei\u00dft es in der cbs-Gesch\u00e4ftsf\u00fchrung: <em>\u201eDie Weltmarktf\u00fchrer treibt allesamt die Erh\u00f6hung der globalen Steuerungskompetenz um, die Vereinheitlichung und Verschlankung von Strukturen und Prozessen. Mit unserem integrierten L\u00f6sungsangebot ONE Finance schaffen wir beispielsweise bei sehr vielen Kunden die Grundlage daf\u00fcr, im Zuge des Umstiegs nach S\/4, noch im ECC oder nach der S\/4-Erstimplementierung. Die Kunden investieren in ihre Digitalisierungsagenda, m\u00f6chten digitale Technologie-Innovationen f\u00fcr ihre Prozesse und neue Gesch\u00e4ftsmodelle nutzen. Dazu muss die gesamte Zielarchitektur in den Blick. Es geht um die Gestaltung der unternehmensweiten Prozesslandschaft und eine nachhaltige Unternehmensl\u00f6sung f\u00fcr die n\u00e4chsten f\u00fcnf bis zehn Jahre.\u201c<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/cbs-corporate-business-solutions\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS.jpg\" alt=\"https:\/\/e3mag.com\/partners\/cbs-corporate-business-solutions\/\" class=\"wp-image-11360\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/2203_E_3_Magazin_Online_Coverstory.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"125\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg\" alt=\"\" class=\"wp-image-73569\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2021\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Man kann sagen, dass die Uhren und die Herzen bei cbs ein wenig schneller schlagen als in anderen Beratungsh\u00e4usern. Leidenschaft, gepaart mit Technologie- und Prozessexpertise. Ein starkes Kollegennetzwerk und ein F\u00fchrungsstil, der auf Vertrauen setzt. Ein spezieller Spirit. Daraus resultiert eine besondere Kraft. The Power of Orange \u2013 das ist ein zentrales St\u00fcck DNA.<\/p>\n","protected":false},"author":2413,"featured_media":112823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[40562,40563],"tags":[5582,707],"coauthors":[39782,27825],"class_list":["post-112763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-22-04","category-mag-22-04","tag-cbs","tag-coverstory","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/cbs-header-coverstory-2204-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Man kann sagen, dass die Uhren und die Herzen bei cbs ein wenig schneller schlagen als in anderen Beratungsh\u00e4usern. Leidenschaft, gepaart mit Technologie- und Prozessexpertise. Ein starkes Kollegennetzwerk und ein F\u00fchrungsstil, der auf Vertrauen setzt. Ein spezieller Spirit. Daraus resultiert eine besondere Kraft. The Power of Orange \u2013 das ist ein zentrales St\u00fcck DNA.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/coverstorys\/coverstory-22-04\/\" rel=\"category tag\">Coverstory 22-04<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-22-04\/\" rel=\"category tag\">Mag 22-04<\/a>","author_info_v2":{"name":"cbs Corporate Business Solutions","url":"https:\/\/e3mag.com\/de\/author\/cbs-corporate-business-solutions\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/112763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2413"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=112763"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/112763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/112823"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=112763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=112763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=112763"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=112763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}