{"id":112435,"date":"2022-03-03T16:38:00","date_gmt":"2022-03-03T15:38:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=112435"},"modified":"2022-03-04T10:13:09","modified_gmt":"2022-03-04T09:13:09","slug":"funktioniert-doch-agiles-berechtigungsmanagement-in-s-4hana","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/funktioniert-doch-agiles-berechtigungsmanagement-in-s-4hana\/","title":{"rendered":"Funktioniert doch! Agiles Berechtigungsmanagement in S\/4HANA"},"content":{"rendered":"\n<p>Doch S\/4HANA-Berechtigungsprojekte unterliegen aufgrund oft anf\u00e4nglich ungekl\u00e4rter Gesamtstrategie und sich \u00e4ndernden Anforderungen einer starken Dynamik. Wie also damit umgehen? Roozbeh Noori-Amoli, Deputy Head SAP Consulting bei SAST SOLUTIONS, erl\u00e4utert.<\/p>\n\n\n\n<p>Thema ist hier die richtige Vorgehensweise bei Berechtigungsprojekten, ausgehend von initialen \u00dcberlegungen, die vorangestellt werden, um ein Projekt aufzusetzen, bis hin zum Aufzeigen von Herausforderungen und Stolperfallen, um daraus Learnings abzuleiten. Also, welche Elemente spielen eine grundlegende Rolle? Neben dem Vorhaben an sich sind dies technische Faktoren wie die zugrunde liegende Systemarchitektur, verwendete Tools, aber auch organisatorische und Compliance-Anforderungen. Diese geben einen ersten Rahmen vor und bestimmen die Wahl des Projektansatzes und -vorgehens sowie des Berechtigungskonzepts ma\u00dfgeblich. Ihre Zusammenh\u00e4nge sind oft eng kausal verzahnt und der Faktor Mensch darf in keiner \u00dcberlegung fehlen.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-389037190\"><div id=\"great-3904249125\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6Ja0zaCg0ss\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_bdc_2026_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_bdc_2026_1200x150-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Vor dem Projekt<\/h3>\n\n\n\n<p>Die drei ma\u00dfgeblichen initialen Fragen vor Projektbeginn sind: welcher Projektansatz, welches Projektvorgehen, welches Berechtigungskonzept? Zun\u00e4chst zum Projektansatz: Man kann bei Berechtigungsmigrationsprojekten analog zu S\/4HANA-Migrationsprojekten zwischen den Extremen Greenfield- und Brownfield unterscheiden. Greenfield hei\u00dft dann, im Grunde alles neu aufzusetzen, Brownfield bedeutet die \u00dcberf\u00fchrung der ERP-Welt. Diese Wahl ist auch von Budget und Ressourcen abh\u00e4ngig, aber h\u00e4ufig startet man mit einem Greenfield&#8211;Approach, bef\u00fcllt die L\u00fccken mit bew\u00e4hrten Prozessen aus der alten Welt und spricht dann vom Bluefield-Approach, auch Selective-Data-Ansatz genannt. Transformation bedeutet hier Konvertierung der alten Rollen und Integration neuer Elemente. Dies ist oft der goldene Mittelweg, aber dennoch nicht immer die optimale L\u00f6sung f\u00fcr jedes Szenario. Ein konkretes Beispiel: Mitunter funktioniert ein Greenfield-Ansatz mit \u00dcbernahme bew\u00e4hrter Prozesse, aber einer Neu-Definition von BPDs (Business Process Descriptions) f\u00fcr jeden Prozess. Hinzugezogen und transferiert werden dann Traces aus den Altsystemen zur Erg\u00e4nzung der Informationsl\u00fccken und begleitend finden Fachbereichsworkshops und Tests zur Abdeckung der Grauzonen statt.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"463\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk.jpg\" alt=\"\" class=\"wp-image-112443\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk-768x444.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk-100x58.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk-480x278.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk-640x370.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-AKQ_Grafik_S4Hana_01_cmyk-720x417.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Klassisches vs. agiles Projektmanagement<\/h3>\n\n\n\n<p>Ist diese Thematik gekl\u00e4rt, muss die wegweisende Entscheidung zwischen klassischem und agilem Projektvorgehen getroffen werden. Hier kommt es auf Faktoren wie den tats\u00e4chlichen Unternehmensbedarf, Projektziele und Sicherheitsbed\u00fcrfnis, Budget, zeitliche und personelle Ressourcen, aber auch organisatorische Strukturen und Prozesse wie die Anzahl der SAP-User oder die Art und Architektur des Systems an. In der Theorie wird diese Entscheidung oft abh\u00e4ngig gemacht vom sogenannten magischen Dreieck: Ist der Projektumfang fix, sind Kosten und Zeit hingegen variabel, deutet dies auf klassisches Projektmanagement hin. Sind aber Kosten und Zeit fix und der Umfang variabel, dann empfiehlt sich ein agiles Vorgehen. Letztlich l\u00e4sst sich feststellen: Wenn das Mindset daf\u00fcr vorhanden ist oder aufgebaut werden kann, macht agiles Projektmanagement durchaus Sinn.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Berechtigungskonzepte<\/h3>\n\n\n\n<p>Die n\u00e4chste \u00dcberlegung, die Wahl des Berechtigungskonzepts, l\u00e4uft im Grunde auf den Zielkonflikt Minimierung der Risiken und der Vergabe von Berechtigungen versus Vereinheitlichung von Prozessen, Erh\u00f6hung von Transparenz und Minimierung des administrativen Aufwandes hinaus. Aufgrund der gro\u00dfen Vielzahl an Konzepten und ihrer unterschiedlichen Eignung f\u00fcr bestimmte Szenarien seien hier nur zwei Beispiele angef\u00fchrt, um ihre Diversit\u00e4t zu verdeutlichen: Bei einer internationalen Organisation mit vielen gleichen Unternehmensteilen und wiederkehrenden Prozessen funktionieren der Template-Rollenansatz mit Ableitungen nach organisatorischen Einheiten oder das Menu\/Value-Rollenkonzept. Bei einem hohen Sicherheitsbed\u00fcrfnis und dem Wunsch nach einer pr\u00e4zisen Vergabe der Berechtigungen, einer niedrigen Anzahl Transaktionen je User und einem System mit wenigen, aber unterschiedlichen Prozessen empfiehlt sich hingegen das Konzept 1 Transaktion \u2013 1 Rolle.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Herausforderungen und Learnings<\/h3>\n\n\n\n<p>Ein erfolgreiches S\/4HANA-Berechtigungsprojekt ist mit entsprechender Expertise und sorgf\u00e4ltiger Planung m\u00f6glich \u2013 die Vorgehensweise und die Bed\u00fcrfnisse der Stakeholder sind unbedingt im Vorfeld zu bestimmen. Wichtig ist dann, von Beginn an Zeit f\u00fcr das Testing einzuplanen und zwischen dem Test-, dem Schulungsmanagement und dem Berechtigungsteam eine detaillierte Abstimmung sicherzustellen. Hilfreich ist eine Tool-Unterst\u00fctzung, etwa durch die SAST SUITE, um Prozess-Tests zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p>S\/4HANA-Berechtigungsmanagement agil und ganzheitlich anzugehen, wird betr\u00e4chtlich erleichtert, wenn man auf Partner wie SAST SOLUTIONS und ihre SAST SUITE setzt. Mit einem solchen Toolkonzept sparen Verantwortliche durch die signifikante Reduzierung manueller Arbeiten sowohl Zeit als auch Geld. Denn die Software verbessert Analyseergebnisse, gibt eine Empfehlung, ob eine Migration oder eine Neukonzeption der Berechtigungsrollen sinnvoller ist, und liefert direkt Vorschlagswerte. Zudem werden obsolete oder getauschte Transaktionen erkannt und etwa passende FIORI-Apps identifiziert.<\/p>\n\n\n\n<p>In organisatorischer Hinsicht sind besonders der Faktor Mensch zu ber\u00fccksichtigen und die Herausforderungen, die durch den Wechsel auf S\/4HANA entstehen. Kaum jemand ist erpicht auf Ver\u00e4nderung und diese Transformation bedeutet: Prozesse, Transaktionen und die User-Experience \u00e4ndern sich. Eine saubere Projektpolitik und -kommunikation, sodass Endanwender sich abgeholt f\u00fchlen und Neuerungen annehmen, ist daher ma\u00dfgeblich f\u00fcr den Projekterfolg. Der aufgrund sich h\u00e4ufig \u00e4ndernder Anforderungen starken Dynamik von S\/4HANA-Berechtigungsprojekten begegnet man dann optimalerweise mit einem agilen Projektmanagement-Ansatz, der zielgenau auf die Komplexit\u00e4t der Herausforderungen abgestimmt wurde.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dynamisch, reaktionsschnell, flexibel: agiles Projektmanagement<\/h3>\n\n\n\n<p>Agiles Projektmanagement birgt hier gro\u00dfe Vorteile: Integrations-, Regressions- und Berechtigungstests werden etwa nicht separat betrachtet, sondern parallel durchgef\u00fchrt. Es bietet schnelle Reaktionsm\u00f6glichkeiten auf ge\u00e4nderte Anforderungen und einen stetigen Optimierungsprozess. Wichtig ist schlussendlich, ausreichend Zeit und Ressourcen einzuplanen, das Thema kann nicht einfach neben dem Tagesgesch\u00e4ft umgesetzt werden. Die gesamte Thematik muss fr\u00fchzeitig gemeinsam mit den Fachbereichen angegangen werden, schlie\u00dflich gilt es, bereichs\u00fcbergreifende Entscheidungen hinsichtlich der Rollen-Inhalte zu treffen und kundeneigene Kataloge und Gruppen zu erstellen, um nicht auf den \u00fcberladenen SAP-Standard zur\u00fcckgreifen zu m\u00fcssen. <\/p>\n\n\n\n<p>Wichtige Learnings: weg vom Berechtigungsteam, hin zu je einem Verantwortlichen in den Fachabteilungen. Sinnvoll ist eine passgenaue Tool-Unterst\u00fctzung, ben\u00f6tigt werden Standard-Templates f\u00fcr Vorschlagsrollen zum Testen sowie saubere und SoD-freie Rollen. Berechtigungen d\u00fcrfen nicht nur auf Funktionalit\u00e4t getestet werden, sondern es m\u00fcssen auch Negativ-Tests stattfinden. Das Tagesgesch\u00e4ft sollte dabei unbedingt durch einen Safe-go-live-Ansatz gew\u00e4hrleistet bleiben, dann steht einem erfolgreichen agilen Berechtigungsprojekt kaum etwas im Wege.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"581\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk.jpg\" alt=\"\" class=\"wp-image-112439\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk.jpg 800w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk-768x558.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk-100x73.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk-480x349.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk-640x465.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/extra-2203-sast-Roozbeh-Noori-Amoli-02_cmyk-720x523.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><em><em>Roozbeh Noori-Amoli ist Deputy Head Consulting bei SAST SOLUTIONS. Der Partner f\u00fcr ganzheitliche L\u00f6sungen bei SAP Cyber Security &amp; Access Governance bietet neben Consulting die eigenentwickelte Software Suite sowie Managed Services<\/em><\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/e3mag.com\/partners\/sast-solutions-ag\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner.jpg\" alt=\"https:\/\/e3mag.com\/partners\/sast-solutions-ag\/\" class=\"wp-image-69882\" width=\"660\" height=\"73\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2020\/10\/Sast-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Klassische Berechtigungsprojekte basieren auf einem monolithischen Ansatz mit einer linearen Abfolge von Projektphasen mit Meilensteinen. In einem idealtypischen Projektumfeld, in dem sowohl die Projektfaktoren als auch der Endzustand bekannt sind, mag das funktionieren. <\/p>\n","protected":false},"author":2207,"featured_media":112437,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[26405,40494,40469],"tags":[12853,12854,39537],"coauthors":[38401],"class_list":["post-112435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advertorial","category-extra-2203","category-mag-22-03","tag-brownfield","tag-greenfield","tag-sast-solutions","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/03\/shutterstock_1668531934-LookerStudio-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Klassische Berechtigungsprojekte basieren auf einem monolithischen Ansatz mit einer linearen Abfolge von Projektphasen mit Meilensteinen. In einem idealtypischen Projektumfeld, in dem sowohl die Projektfaktoren als auch der Endzustand bekannt sind, mag das funktionieren. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/advertorial\/\" rel=\"category tag\">Advertorial<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/extra-2203\/\" rel=\"category tag\">Extra 2203<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-22-03\/\" rel=\"category tag\">Mag 22-03<\/a>","author_info_v2":{"name":"SAST SOLUTIONS","url":"https:\/\/e3mag.com\/de\/author\/sast-solutions\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/112435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2207"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=112435"}],"version-history":[{"count":0,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/112435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/112437"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=112435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=112435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=112435"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=112435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}