{"id":110177,"date":"2022-02-08T08:00:00","date_gmt":"2022-02-08T07:00:00","guid":{"rendered":"http:\/\/e3mag.com\/?p=110177"},"modified":"2024-01-19T14:48:00","modified_gmt":"2024-01-19T13:48:00","slug":"roadmap-2025-und-mehr","status":"publish","type":"post","link":"https:\/\/e3mag.com\/de\/roadmap-2025-und-mehr\/","title":{"rendered":"Roadmap 2025 und mehr"},"content":{"rendered":"\n<p>F\u00fcr die Zukunft gibt es eine klare Orientierung: Im Jahr 2025 will cbs mit 1000 Beratern in internationalen M\u00e4rkten eine Viertelmilliarde US-Dollar Umsatz erzielen. Gesch\u00e4ftsf\u00fchrer Rainer Wittwen: \u201e<em>Wir sind heute schon der f\u00fchrende Berater f\u00fcr End-to-End-Gesch\u00e4ftsprozessl\u00f6sungen in unserem Stammmarkt. Wir wollen unser Gesch\u00e4ft weiter globalisieren und bis 2025 weltweit f\u00fchrend werden. Daf\u00fcr braucht es engagierte Berater, die als Partner auf Augenh\u00f6he mit dem Kunden die erfolgskritischen Zukunftsl\u00f6sungen f\u00fcr ihn konzipieren und gestalten. Als Entwicklungsplattform f\u00fcr hochqualifizierte Berater wollen wir in unserem Markt der beste und attraktivste Arbeitgeber sein. cbs w\u00e4chst kontinuierlich und stark. Und wir haben einiges zu bieten: Wer will nicht f\u00fcr die beeindruckendsten Industrieunternehmen der Welt arbeiten?<\/em>\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aufbruchstimmung<\/h3>\n\n\n\n<p>Rund anderthalb Jahre waren die Mitarbeiter des Beratungsunternehmens bedingt durch die Pandemie nicht mehr physisch zusammengekommen \u2013 nun war es endlich so weit. \u201e<em>Wir haben eine echte Aufbruchstimmung gesp\u00fcrt und nehmen viel R\u00fcckenwind mit f\u00fcr unser stark wachsendes Beratungsgesch\u00e4ft<\/em>\u201c, sagt CEO und Firmengr\u00fcnder Harald Sulovsky. Auf dem zweit\u00e4gigen Event, an dem Kollegen aus allen 18 Niederlassungen teilnahmen, stellte die Gesch\u00e4ftsf\u00fchrung die gesch\u00e4rfte Zukunftsagenda und den neuen Markenauftritt vor. Als Spezialist f\u00fcr globale und digitale End-to-End-Gesch\u00e4ftsprozessl\u00f6sungen fokussiert sich cbs seit \u00fcber 25 Jahren auf die Champions der internationalen produzierenden Industrie.<\/p><div class=\"great-fullsize-content-de great-entity-placement\" style=\"float: left;\" id=\"great-1555281905\"><div id=\"great-1931854742\" style=\"margin-bottom: 20px;\"><a data-no-instant=\"1\" href=\"https:\/\/www.youtube.com\/watch?v=6ZGXMPyM-nU\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"banner_26-04_29_1200x150\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg\" alt=\"\"  srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3.jpg 1200w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-400x50.jpg 400w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-768x96.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-100x13.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-480x60.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-640x80.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-720x90.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-960x120.jpg 960w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-1168x146.jpg 1168w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-18x2.jpg 18w, https:\/\/e3mag.com\/wp-content\/uploads\/2026\/03\/banner_26-04_29_1200x150-3-600x75.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" width=\"1200\" height=\"150\"  style=\" max-width: 100%; height: auto;\" \/><\/a><\/div><\/div>\n\n\n\n<p>\u201e<em>cbs ist der Berater der Weltmarktf\u00fchrer und hat sich ganz bewusst die Hochleistungskultur dieser Topunternehmen zu eigen gemacht. Unsere Kunden sch\u00e4tzen es, dass wir in diesen Aspekten denken und agieren wie sie \u2013 und sehr ambitioniert sind<\/em>\u201c, betont Gesch\u00e4ftsf\u00fchrer Sulovsky. Langfristige strategische Ausrichtung auf einen definierten Zielmarkt. Absolute Kundenorientierung. Hohe Innovationskraft, fachliche Exzellenz, der Ehrgeiz eines Qualit\u00e4tsf\u00fchrers. Das sind die Eigenschaften, die cbs mit seinen Kunden verbindet. Hinzu kommt eine starke Unternehmenskultur, die unternehmerisches Denken, offene Kommunikation und Vertrauen in individuelle Gestaltungskraft f\u00f6rdert.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hidden Champion<\/h3>\n\n\n\n<p>\u201e<em>Dieser spezielle cbs-Spirit war auf dem Corporate Summit wieder zu sp\u00fcren. Er ist tats\u00e4chlich ein zentraler Faktor f\u00fcr intakte Kundenbeziehungen und viele Projekterfolge. Im Tagesgesch\u00e4ft unterst\u00fctzen sich die Kollegen bereichs\u00fcbergreifend und bilden immer neue Wissensnetzwerke. Das ist ein Riesenplus, das sich am Ende in Mehrwert f\u00fcr den Kunden niederschl\u00e4gt<\/em>\u201c, erkl\u00e4rt Benjamin Krischer, Consulting Director Landscape Transformation.&nbsp;<\/p>\n\n\n\n<p><em>\u201eWir haben einen klaren Fokus auf die Fertigungsindustrie \u2013 das motiviert uns alle, denn jeder will gerne f\u00fcr diese namhaften Kunden arbeiten und innovative Zukunftsl\u00f6sungen mit ihnen entwickeln<\/em>\u201c, erg\u00e4nzt Sebastian Hellmann, Consulting Director bei cbs. \u201e<em>Als Hidden Champion k\u00f6nnen wir damit auch auf dem Bewerbermarkt punkten.<\/em>\u201c<\/p>\n\n\n\n<p>Professor Hermann Simon, Gr\u00fcnder des Weltmarktf\u00fchrers in der Preisberatung, Simon Kucher und Partners, hat das Ph\u00e4nomen \u201eHidden Champions\u201c f\u00fcr Wissenschaft und Managementtheorie entdeckt und genauer untersucht. Im Rahmen des cbs Summit referierte Simon, Managementdenker und Mitglied der \u201eThinkers 50 Hall of Fame\u201c, in einem Exklusivvortrag dar\u00fcber, was diese Weltmarktf\u00fchrer konkret ausmacht: sich eng auf ein Produkt oder einen bestimmten Markt zu fokussieren, der Wille, der Beste sein, ein globaler Auftritt und die Ambition, stetig zu wachsen. \u201e<em>Das alles trifft genau auf cbs zu. Wir verfolgen diese Strategie schon seit vielen Jahren \u2013 und das ganz bewusst<\/em>\u201c, best\u00e4tigt cbs-Gesch\u00e4ftsf\u00fchrer Rainer Wittwen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e3mag.com\/partners\/cbs-corporate-business-solutions\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS.jpg\" alt=\"https:\/\/e3mag.com\/partners\/cbs-corporate-business-solutions\/\" class=\"wp-image-11360\" srcset=\"https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS.jpg 1000w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-768x86.jpg 768w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-100x11.jpg 100w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-480x54.jpg 480w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-640x72.jpg 640w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-720x81.jpg 720w, https:\/\/e3mag.com\/wp-content\/uploads\/2017\/03\/CI-CBS-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Auf dem Corporate Summit pr\u00e4sentiert die Unternehmensberatung ihre Zukunftsagenda und die Weiterentwicklung zur globalen Marke. Mehr als 70 Prozent der Weltmarktf\u00fchrer aus der DACH-Region sind inzwischen cbs-Kunden.<\/p>\n","protected":false},"author":2413,"featured_media":110173,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,40127,161],"tags":[5582,1351,40130,709,39829],"coauthors":[39782],"class_list":["post-110177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-21-12","category-szene","tag-cbs","tag-cbs-corporate-business-solutions","tag-mag-21-12","tag-roadmap","tag-szene","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"thumbnail":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-150x150.jpg",150,150,true],"medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",400,180,false],"medium_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-768x346.jpg",768,346,true],"large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"image-100":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-100x45.jpg",100,45,true],"image-480":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-480x216.jpg",480,216,true],"image-640":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-640x288.jpg",640,288,true],"image-720":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-720x324.jpg",720,324,true],"image-960":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"image-1440":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"image-1920":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"1536x1536":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"2048x2048":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"bricks_large":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",1000,450,false],"bricks_medium":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495.jpg",600,270,false],"profile_24":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3mag.com\/wp-content\/uploads\/2022\/01\/rise-with-sap-shutterstock_1543076495-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Auf dem Corporate Summit pr\u00e4sentiert die Unternehmensberatung ihre Zukunftsagenda und die Weiterentwicklung zur globalen Marke. Mehr als 70 Prozent der Weltmarktf\u00fchrer aus der DACH-Region sind inzwischen cbs-Kunden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3mag.com\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/mag-21-12\/\" rel=\"category tag\">MAG 21-12<\/a>, <a href=\"https:\/\/e3mag.com\/de\/category\/szene\/\" rel=\"category tag\">Szene<\/a>","author_info_v2":{"name":"cbs Corporate Business Solutions","url":"https:\/\/e3mag.com\/de\/author\/cbs-corporate-business-solutions\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/110177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/users\/2413"}],"replies":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/comments?post=110177"}],"version-history":[{"count":1,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/110177\/revisions"}],"predecessor-version":[{"id":137784,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/posts\/110177\/revisions\/137784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media\/110173"}],"wp:attachment":[{"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/media?parent=110177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/categories?post=110177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/tags?post=110177"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3mag.com\/de\/wp-json\/wp\/v2\/coauthors?post=110177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}